{"id":94303,"date":"2022-11-10T17:14:00","date_gmt":"2022-11-10T17:14:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=94303"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/","title":{"rendered":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX, che Fine ha Fatto Sam Bankman-Fried?"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg\" alt=\"FTX\" srcset=\"https:\/\/cimg.co\/news\/94303\/235447\/responsive-images\/cn-cover-3___media_library_original_860_450.jpg 860w, https:\/\/cimg.co\/news\/94303\/235447\/responsive-images\/cn-cover-3___media_library_original_720_377.jpg 720w, https:\/\/cimg.co\/news\/94303\/235447\/responsive-images\/cn-cover-3___media_library_original_600_314.jpg 600w, https:\/\/cimg.co\/news\/94303\/235447\/responsive-images\/cn-cover-3___media_library_original_300_157.jpg 300w\" sizes=\"100vw\" width=\"860\" class=\"content-img\"><figcaption><i>Sam Bankman-Fried. Fonte: una schermata del video, HBO \/ YouTube<\/i><\/figcaption><\/figure><p class=\"wp-block-paragraph\">Il crollo di <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/tags\/ftx\">FTX <\/a>sta gi&agrave; attirando l&#8217;attenzione delle autorit&agrave; di regolamentazione statunitensi, che starebbero gi&agrave; indagando se l&#8217;azienda abbia gestito male i fondi dei clienti. L&#8217;indagine &egrave; cominciata mentre i membri della community iniziavano a chiedersi dove era sparito Sam Bankman-Fried, vista la sua mancanza su Twitter.<\/p><p>Secondo quanto riferito da un<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-11-09\/us-probes-ftx-empire-over-handling-of-client-funds-and-lending\"> rapporto<\/a> di Bloomberg, che ha citato due persone &#8220;a conoscenza della questione&#8221;, le autorit&agrave; di regolamentazione stanno gi&agrave; chiedendo dettagli sulla struttura proprietaria della filiale americana di FTX, FTX US, e della sede di trading internazionale FTX.com.<\/p><p>Le autorit&agrave; sono interessate a qualsiasi sovrapposizione di dirigenti o membri del consiglio di amministrazione tra le due societ&agrave;, che sono state descritte da FTX come due entit&agrave; distinte e separate.<\/p><p>Secondo le fonti di Bloomberg, le autorit&agrave; di regolamentazione hanno chiesto dettagli su come i conti dei clienti sono stati gestiti dalle due entit&agrave; sotto il marchio di FTX e se i conti degli utenti sono stati adeguatamente separati. Tutto ci&ograve; si aggiunge a un esame dei legami tra FTX e la societ&agrave; di trading di Bankman-Fried, Alameda Research.<\/p><h2>Che fine ha fatto Sam Bankman-Fried?<\/h2><span class=\"replacer\"><\/span><p>Non &egrave; chiaro dove si trovi esattamente il CEO di FTX,Sam Bankman-Fried, anche se &egrave; stato riferito che risiede alle Bahamas, dove si trova la sede centrale dell&#8217;exchange. Tuttavia, qualche giorno prima che FTX smettesse di gestire i prelievi dei clienti, l&#8217;account Twitter di FTX ha pubblicato un video, ora cancellato, che mostrava la vista dal nuovo ufficio della societ&agrave; a Miami, in Florida.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/tier10k\/status\/1590431846147362817\"><\/oembed><\/figure><p>Quindi non &egrave; ancora chiaro se Bankman-Fried si trovi attualmente in Florida, alle Bahamas o altrove.<\/p><h2>I regolatori mettono in guardia dalle imprese crypto<\/h2><span class=\"replacer\"><\/span><p>L&#8217;indagine riguardo le operazioni di FTX &egrave; stata guidata dalla Securities and Exchange Commission (SEC) e dalla Commodity Futures Trading Commission (CFTC), che si occupa di derivati.<\/p><p>Il presidente della SEC, Gary Gensler, in passato aveva ripetutamente messo in guardia sui rischi riguardo le criptovalute e, in particolare, sui rischi legati agli exchange crypto. Inoltre aveva sottolineato che alcuni exchange potrebbero violare le leggi sui titoli azionari, offrendo ai clienti americani al dettaglio token considerati titoli azionari non registrati.<\/p><p>Tuttavia, <a href=\"La%20SEC%20d%C3%A0%20la%20caccia%20ai%20Crypto%20Exchange%20e%20alle%20Altcoin\">Gensler ha lanciato un avvertimento<\/a> pi&ugrave; incisivo durante un&#8217;audizione presso la Commissione del Senato degli Stati Uniti per gli affari bancari, abitativi e urbani, in cui ha usato parole dure per attaccare l&#8217;industria crypto:<\/p><blockquote><p>&#8220;Francamente, in questo momento, le crypto sono pi&ugrave; simili al Wild West o al vecchio mondo del &#8216;buyer beware&#8217;, prima che venissero emanate le leggi sui titoli azionari. Questa asset class &egrave; piena di frodi, truffe e abusi in molte applicazioni&#8221;.<\/p><\/blockquote><p><strong>Leggi anche:<\/strong><\/p><ul><li><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/sec-chief-may-be-gunning-for-crypto-exchanges-and-altcoins-it\/\">La SEC d&agrave; la caccia ai Crypto Exchange e alle Altcoin<\/a><\/li><li><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/binance-ci-ripensa-e-non-comprera-lexchange-crypto-ftx-cattiva-gestione-dei-fondi-dei-clienti-e-accertamenti-in-corso-tra-le-ragioni-del-ripensamento\/\">Binance ci Ripensa e non Comprer&agrave; L&#8217;Exchange Crypto FTX, Cattiva Gestione Dei Fondi Dei Clienti e Accertamenti In Corso Tra Le Ragioni Del Ripensamento<\/a><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Sam Bankman-Fried. Fonte: una schermata del video, HBO \/ YouTubeIl crollo di FTX sta gi&agrave; attirando l&#8217;attenzione delle autorit&agrave; di regolamentazione statunitensi, che starebbero gi&agrave; indagando se l&#8217;azienda abbia gestito male i fondi dei clienti. L&#8217;indagine &egrave; cominciata mentre i membri della community iniziavano a chiedersi dove era sparito Sam Bankman-Fried, vista la sua mancanza [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,1],"tags":[595,2541,505],"editors":[],"sponsored_companies":[],"class_list":["post-94303","post","type-post","status-publish","format-standard","hentry","category-blockchain-news","category-news","tag-ftx","tag-sam-bankman-fried","tag-usa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I Regolatori USA Stanno gi\u00e0 Esaminando FTX<\/title>\n<meta name=\"description\" content=\"Il crollo di FTX sta attirando l&#039;attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov&#039;\u00e8 sparito il CEO Sam Bankman-Fried?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I Regolatori USA Stanno gi\u00e0 Esaminando FTX\" \/>\n<meta property=\"og:description\" content=\"Il crollo di FTX sta attirando l&#039;attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov&#039;\u00e8 sparito il CEO Sam Bankman-Fried?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T17:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"I Regolatori USA Stanno gi\u00e0 Esaminando FTX\" \/>\n<meta name=\"twitter:description\" content=\"Il crollo di FTX sta attirando l&#039;attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov&#039;\u00e8 sparito il CEO Sam Bankman-Fried?\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX","description":"Il crollo di FTX sta attirando l'attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov'\u00e8 sparito il CEO Sam Bankman-Fried?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/","og_locale":"it_IT","og_type":"article","og_title":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX","og_description":"Il crollo di FTX sta attirando l'attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov'\u00e8 sparito il CEO Sam Bankman-Fried?","og_url":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-11-10T17:14:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX","twitter_description":"Il crollo di FTX sta attirando l'attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov'\u00e8 sparito il CEO Sam Bankman-Fried?","twitter_image":"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX, che Fine ha Fatto Sam Bankman-Fried?","datePublished":"2022-11-10T17:14:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/"},"wordCount":516,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg","keywords":["FTX","Sam Bankman-Fried","usa"],"articleSection":["Blockchain News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/","url":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/","name":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg","datePublished":"2022-11-10T17:14:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il crollo di FTX sta attirando l'attenzione delle autorit\u00e0 di regolamentazione statunitensi. Dov'\u00e8 sparito il CEO Sam Bankman-Fried?","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#primaryimage","url":"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg","contentUrl":"https:\/\/cimg.co\/news\/94303\/235447\/cn-cover-3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/i-regolatori-usa-stanno-gia-esaminando-ftx-che-fine-ha-fatto-sam-bankman-fried\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"I Regolatori USA Stanno gi\u00e0 Esaminando FTX, che Fine ha Fatto Sam Bankman-Fried?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/94303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=94303"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/94303\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=94303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=94303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=94303"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=94303"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=94303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}