{"id":93896,"date":"2022-11-08T11:00:00","date_gmt":"2022-11-08T11:00:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=93896"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/","title":{"rendered":"Crolla il valore di FTT Dopo le Indiscrezioni sulla Possibile Insolvenza \u2013 3 Crypto to Buy the Dip"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/93873\/234418\/responsive-images\/ftx___media_library_original_1806_945.jpg 1806w, https:\/\/cimg.co\/news\/93873\/234418\/responsive-images\/ftx___media_library_original_1200_628.jpg 1200w, https:\/\/cimg.co\/news\/93873\/234418\/responsive-images\/ftx___media_library_original_900_471.jpg 900w, https:\/\/cimg.co\/news\/93873\/234418\/responsive-images\/ftx___media_library_original_720_377.jpg 720w, https:\/\/cimg.co\/news\/93873\/234418\/responsive-images\/ftx___media_library_original_600_314.jpg 600w, https:\/\/cimg.co\/news\/93873\/234418\/responsive-images\/ftx___media_library_original_300_157.jpg 300w\" sizes=\"100vw\" width=\"1806\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">I prezzi della <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/coins\/\">crypto FTT<\/a> ieri sono sprofondati e continuano a perdere valore dopo le indiscrezioni circa la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.ilsole24ore.com\/art\/cripto-ad-alta-tensione-binance-liquida-sua-posizione-nell-exchange-rivale-ftx-AEioo1EC\">presunta insolvenza di FTX<\/a>. &nbsp;Changpeng Zhao, fondatore e CEO di Binance, principale rivale dell&#8217;exchange FTX, ha annunciato domenica che la sua piattaforma di trading vender&agrave; tutti i propri token FTT.<\/p><p>Per giustificare la sua scelta il CEO di Binance CEO Changpeng &#8220;CZ&#8221; Zhao ha fatto riferimento a &#8220;nuove rivelazioni che sono venute alla luce&#8221; ma non ha specificato pubblicamente a cosa si riferisca n&eacute; ha risposto alle domande che gli sono state rivolte.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/cz_binance\/status\/1589374530413215744?s=20&amp;t=qqXw2aF_H9U5QhmYeASgwQ\"><\/oembed><\/figure><p>In un secondo tweet, Changpeng Zhao ha dichiarato che la liquidazione della posizione di FTT riguarda &#8220;esclusivamente una gestione del rischio post-exit&#8221; facendo riferimento alla lezione appresa dopo il collasso di Terra Luna Classic (LUNC) e l&#8217;impatto che ha avuto sugli attori del mercato.<\/p><p>&#8220;Non supporteremo persone che si tutelano alle spalle degli altri partecipanti al settore&#8221; ha poi aggiunto.<\/p><p>L&#8217;ipotesi pi&ugrave; plausibile &egrave; che <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/previsione-valore-token-ftx-binance-si-libera-di-ftt-per-500-milioni-ftt-riuscira-a-recuperare\/\">la scelta di Binance sia stata influenzata<\/a> dalle recenti notizie trapelate sulla composizione del bilancio di Alameda Research, la compagnia di trading crypto di Sam Bankman-Fried. Secondo i documenti divulgati, <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/attivo-di-146mld-per-alameda-research-di-sam-bankman-tutto-quello-che-ce-da-sapere\/\">gli attivi di Alameda sono composti per miliardi di dollari da token FTX<\/a>.<\/p><h2>Prezzo &amp; Tokenomic FTT&nbsp;<\/h2><span class=\"replacer\"><\/span><p>Al momento il prezzo del token di FTX &egrave; 18$, e il volume di trading nelle 24 ore ammonta a 1,234 miliardi di dollari. Nelle 24 ore FTT ha perso oltre il 18% e oltre il 35% negli ultimi sette giorni. Secondo CoinMarketCap il token adesso si trova al 28&deg; posto, con una capitalizzazione di mercato live di 2,451 miliardi di dollari.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1815\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/93873\/234430\/ftt.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/93873\/234430\/responsive-images\/ftt___media_library_original_1815_918.jpg 1815w, https:\/\/cimg.co\/news\/93873\/234430\/responsive-images\/ftt___media_library_original_1200_607.jpg 1200w, https:\/\/cimg.co\/news\/93873\/234430\/responsive-images\/ftt___media_library_original_900_455.jpg 900w, https:\/\/cimg.co\/news\/93873\/234430\/responsive-images\/ftt___media_library_original_720_364.jpg 720w, https:\/\/cimg.co\/news\/93873\/234430\/responsive-images\/ftt___media_library_original_600_303.jpg 600w, https:\/\/cimg.co\/news\/93873\/234430\/responsive-images\/ftt___media_library_original_300_152.jpg 300w\"><figcaption>Grafico prezzi FTT &#8211; Fonte: Tradingview<\/figcaption><\/figure><h2><strong>Divergenze di opinioni<\/strong><\/h2><span class=\"replacer\"><\/span><p>Nelle ultime settimane il CEO e creatore di FTX, Sam Bankman-Fried, era stato criticato per la sua posizione sulla normativa DeFi. Le proposte espresse in un suo articolo sono state ritenute troppo stringenti per il settore, tanto da essere definite &#8220;DeFi killer&#8221;. Le maggiori critiche sono arrivate in particolare da Changpeng Zhao. In seguito SBF aveva promesso di rivalutare le proprie posizioni sulla quella che era stata definita una proposta normativa .&nbsp;<\/p><p>Per quanto riguarda invece i fondi in FTT di Binance, si tratta di un&#8217;operazione finanziaria effettuata lo scorso anno con cui Binance cedeva la propria quota di partecipazione in FTX. Nel 2019 il colosso tra gli exchange &egrave; stato il primo sostenitore del nascente progetto di SBF, con l&#8217;acquisto di titoli equity.<\/p><p>Secondo quanto riportato da <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.forbes.com\/sites\/zinnialee\/2022\/11\/07\/billionaire-changpeng-zhaos-binance-to-offload-all-remaining-ftt-tokens-of-sam-bankman-frieds-ftx\/\">Zhao<\/a>, nel 2021 la liquidazione delle quote di Binance in FTX &egrave; stata saldata con 2,1 miliardi di dollari in FTT e BUSD, la stablecoin disponibile solo sull&#8217;exchange di CZ.<\/p><p>Changpeng Zhao considera che le attuali condizioni di mercato e la mancanza di liquidit&agrave; imporranno lunghi tempi per completare l&#8217;operazione di liquidazione. Inoltre, ha dichiarato che l&#8217;operazione sar&agrave; effettuata in modo da non danneggiare il valore di mercato di FTT.<\/p><p>Inevitabilmente, per&ograve;, FTT sta gi&agrave; subendo gli effetti di questa contromossa. Sabato, Etherscan ha riferito che 22.999.999 FTT, per un valore di 584 milioni di dollari in quel momento, erano stati trasferiti dall&#8217;exchange di Binance verso un altro indirizzo, sparendo cos&igrave; dalla piattaforma. Si tratta esattamente del 17% della fornitura attuale di FTT.<\/p><h2><strong>Il CEO di Alameda chiarisce la situazione finanziaria<\/strong><\/h2><span class=\"replacer\"><\/span><p>A quanto pare, dicevamo, l&#8217;iniziativa di Changpeng Zhao &egrave; la reazione alla notizia divulgata la scorsa settimana sulla <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/attivo-di-146mld-per-alameda-research-di-sam-bankman-tutto-quello-che-ce-da-sapere\/\">composizione del bilancio di Alameda Research<\/a>. Coindesk ha pubblicato il bilancio della compagnia di trading di Sam Bankman Fried dal quale si evince che, al 30 giugno, parte dell&#8217;attivo della compagnia, 5,8 miliardi di dollari, &egrave; rappresentato da FTT, compresi token FTT usati come garanzia collaterale.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/BkingDan\/status\/1589375211148673024?s=20&amp;t=mtJuaU8YTxcdWS5sgFOzdA\"><\/oembed><\/figure><p>Dai documenti pubblicati emerge che Alameda possiede un attivo di 14,6 miliardi di dollari, 8 miliardi di dollari di passivo, che includono prestiti per 7,4 miliardi di dollari, e holding per 14,6 miliardi di dollari. Sabato, Caroline Ellison, la CEO di Alameda Research, aveva risposto alle accuse su <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/WhaleChart\/status\/1589366618684989440?s=20&amp;t=mtJuaU8YTxcdWS5sgFOzdA\">Twitter<\/a>, sostenendo che Alameda possiede pi&ugrave; di 10 miliardi di dollari di attivo che &#8220;non sono inclusi&#8221; nei fogli di bilancio che sono stati pubblicati.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/WhaleChart\/status\/1589366618684989440?s=20&amp;t=mtJuaU8YTxcdWS5sgFOzdA\"><\/oembed><\/figure><p>Secondo Ellison, Alameda conta su diversi fondi a copertura e ha gi&agrave; pagato gran parte dei propri debiti.&nbsp;<\/p><p>Inoltre, Zhao ha dichiarato pubblicamente di acquistare le eccedenze di FTT al prezzo fisso di 22$ per &#8220;minimizzare gli effetti sul mercato&#8221;.<\/p><h2><strong>La risposta di SBF alla decisione di Binance di scaricare i token FTX<\/strong><\/h2><span class=\"replacer\"><\/span><p>Il CEO di FTX, ha <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/SBF_FTX\/status\/1589598284322328579?s=20&amp;t=y-Xsju1iUEy-iu-ukvMxmw\">commentato la decisione di Binance<\/a> di vendere i propri token FTT. Bankman-Fried ha optato per una strategia diplomatica per risolvere la questione sollevata dalla decisione di CZ di disfarsi degli FTT.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/SBF_FTX\/status\/1589598284322328579?s=20&amp;t=y-Xsju1iUEy-iu-ukvMxmw\"><\/oembed><\/figure><p>Invece di rispondere nel merito, SBF ha fatto appello al senso di cooperazione tra tutti gli attori coinvolti nel settore crypto.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/SBF_FTX\/status\/1589598285798707202?s=20&amp;t=y-Xsju1iUEy-iu-ukvMxmw\"><\/oembed><\/figure><p>Il settore crypto si sta preparando a uno <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/ecco-perche-cz-di-binance-ha-pugnalato-alle-spalle-sbf-di-ftx\/\">scontro serrato tra FTX e Binance<\/a>, i due maggiori exchange crypto al mondo. Gli amministratori di entrambe le compagnie stanno cercando per&ograve; di allentare la tensione.<\/p><p>Lo testimonia l&#8217;intenzione di CZ di liquidare gradualmente la propria posizione per mitigare gli effetti sul mercato di FTT. Specificando che la mossa non mira a ledere FTX.<\/p><p>D&#8217;altra parte, SBF dice di apprezzare il lavoro di CZ all&#8217;interno della community crypto. I leader del mercato, ha sottolineato, dovrebbero concentrarsi sullo sviluppo della blockchain e non alimentare i conflitti.<\/p><h2><strong>3 crypto da comprare al ribasso<\/strong><\/h2><span class=\"replacer\"><\/span><h3><strong>Dash 2 Trade (D2T)<\/strong><\/h3><p>La seconda fase della <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/dash2_trade\/status\/1588984510439477248?s=20&amp;t=bhc5ntOWOeFjLwn2GPPY9A\">prevendita di D2T<\/a> si &egrave; appena conclusa e ha permesso la raccolta di <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/dash2_trade\/status\/1588903817302663168?s=20&amp;t=bhc5ntOWOeFjLwn2GPPY9A\">5,16 milioni di dollari<\/a> in sole due settimane. Dash 2 Trade &egrave; un progetto realizzato da una tra le maggiori compagnie di segnali di trading, Learn 2 Trade, e sar&agrave; lanciato nella seconda met&agrave; del 2023. L&#8217;obiettivo della piattaforma &egrave; offrire agli investitori insight provenienti dal mercato per favorire decisioni di investimento informate.<\/p><p>Per migliorare l&#8217;esperienza di trading D2T offre segnali di trading, analisi social e del sentiment di mercato.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/dash-2-trade\/\">Dash 2 Trade<\/a> punta a fare per le crypto quello che fa il terminale di Bloomberg per trading, stando a quanto dichiara il team degli sviluppatori. La piattaforma comprende processi di automazione e verifica per il trading e l&#8217;ottimizzazione di tutti i metodi di investimento.<\/p><p>Dash 2 Trade offre anche il servizio di notifica delle nuove quotazioni sugli exchange centralizzati, offrendo informazioni in passato disponibili solo per una ristretta cerchia di investitori. Non sorprende che la prevendita di D2T vada a gonfie vele e mostri cos&igrave; tanto potenziale.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/dash-2-trade\/\"><strong>Vai alla presale Dash2Trade<\/strong><\/a><\/p><h3><strong>Calvaria (RIA)<\/strong><\/h3><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/calvaria\/\">Calvaria<\/a>, un nuovo progetto di gaming crypto, &egrave; pensato per stravolgere il settore e diventare uno dei migliori giochi play-to-earn sul mercato. Gli sviluppatori di Calvaria hanno individuato due principali barriere alla diffusione dei giochi su Web3. I giocatori non hanno ancora compreso quello che per gli investitori &egrave; chiaro: il potenziale ad alto rendimento dei giochi su Web3.<\/p><p>Calvaria continua a far bene in prevendita, ha gi&agrave; raggiunto la quarta fase su dieci raccogliendo finora 1,5 milioni di dollari. Il prezzo del token nativo RIA continua a crescere in ogni fase della prevendita, ma attira nuovi investitori interessati alla rapida espansione dei progetti GameFi.<\/p><p>I token &egrave; venduto a 0,025$ nella quarta fase della prevendita, ma il prezzo &egrave; destinato ad aumentare passando a 0,03$ nella fase cinque e nella decima fase raggiunger&agrave; il valore di 0,055$.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/calvaria\/\"><strong>Vai alla presale di Calvaria<\/strong><\/a><\/p><h2><strong>IMPT<\/strong><\/h2><span class=\"replacer\"><\/span><p>L&#8217;obiettivo del team di IMPT &egrave; rendere il mercato dei crediti di carbonio nettamente pi&ugrave; efficiente trasferendolo sulla blockchain. Finora, il sistema della compensazione delle emissioni di carbonio &egrave; stato incredibilmente opaco. Si rivolgeva solo alle imprese, e il sistema di trading era inefficiente e datato. Grazie a questo progetto &egrave; possibile scambiare i crediti in forma di NFT sulla blockchain 24 ore al giorno, sette giorni su sette.<\/p><p>Secondo Broadridge Financial Solutions, entro il 2030 il mercato dei crediti di carbonio potrebbe valere oltre 50 miliardi di dollari, mentre l&#8217;intero settore degli investimenti ESG potrebbe superare i 30 trilioni di dollari.<\/p><p>Al momento, oltre 25.000 compagnie hanno scelto di partecipare alla piattaforma dedicata allo shopping online di <a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/impt\/\">IMPT<\/a>. Tra questi ci sono nomi di spicco come Microsoft, Calzedonia, Amazon e Samsung. Finora, la prevendita di IMPT ha gi&agrave; permesso di raccogliere oltre 12 milioni di dollari e si avvicina rapidamente all&#8217;obiettivo finale.<\/p><p>Il prezzo del token IMPT cresce in ogni fase della prevendita e adesso &egrave; di 0,023$.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/impt\/\"><strong>Vai alla prevendita di IMPT<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>I prezzi della crypto FTT ieri sono sprofondati e continuano a perdere valore dopo le indiscrezioni circa la presunta insolvenza di FTX. &nbsp;Changpeng Zhao, fondatore e CEO di Binance, principale rivale dell&#8217;exchange FTX, ha annunciato domenica che la sua piattaforma di trading vender&agrave; tutti i propri token FTT.Per giustificare la sua scelta il CEO di [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[188,2326,2213,2182],"editors":[],"sponsored_companies":[],"class_list":["post-93896","post","type-post","status-publish","format-standard","hentry","category-altcoin-news","category-news","tag-cz","tag-d2t","tag-impt","tag-sbf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FTX sull&#039;orlo del baratro: Binance liquida l&#039;intera posizione FTT<\/title>\n<meta name=\"description\" content=\"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FTX sull&#039;orlo del baratro: Binance liquida l&#039;intera posizione FTT\" \/>\n<meta property=\"og:description\" content=\"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-08T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"FTX sull&#039;orlo del baratro: Binance liquida l&#039;intera posizione FTT\" \/>\n<meta name=\"twitter:description\" content=\"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/93896\/234464\/cn-cover.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FTX sull'orlo del baratro: Binance liquida l'intera posizione FTT","description":"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/","og_locale":"it_IT","og_type":"article","og_title":"FTX sull'orlo del baratro: Binance liquida l'intera posizione FTT","og_description":"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.","og_url":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-11-08T11:00:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"FTX sull'orlo del baratro: Binance liquida l'intera posizione FTT","twitter_description":"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.","twitter_image":"https:\/\/cimg.co\/news\/93896\/234464\/cn-cover.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/"},"author":{"name":"lauradimariatnf","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/f301a2fe5b1b74682fd70e7a2502d752"},"headline":"Crolla il valore di FTT Dopo le Indiscrezioni sulla Possibile Insolvenza \u2013 3 Crypto to Buy the Dip","datePublished":"2022-11-08T11:00:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/"},"wordCount":1405,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg","keywords":["CZ","D2T","IMPT","SBF"],"articleSection":["Altcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/","url":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/","name":"FTX sull'orlo del baratro: Binance liquida l'intera posizione FTT","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg","datePublished":"2022-11-08T11:00:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"CZ ha rimosso tutti i token FTT dalla piattaforma come misura di sicurezza dopo le rivelazioni sul bilancio di Alameda Research.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#primaryimage","url":"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg","contentUrl":"https:\/\/cimg.co\/news\/93873\/234418\/ftx.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/crolla-il-valore-di-ftx-dopo-le-indiscrezioni-sulla-possibile-insolvenza-3-crypto-to-buy-the-dip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Crolla il valore di FTT Dopo le Indiscrezioni sulla Possibile Insolvenza \u2013 3 Crypto to Buy the Dip"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/93896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=93896"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/93896\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=93896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=93896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=93896"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=93896"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=93896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}