{"id":91198,"date":"2022-10-17T15:41:00","date_gmt":"2022-10-17T15:41:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=91198"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/","title":{"rendered":"Previsioni Bitcoin ed Ethereum: il FMI Promuove i CBDC per l&#8217;Inclusione Finanziaria"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/91070\/228032\/responsive-images\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3___media_library_original_1280_853.jpg 1280w, https:\/\/cimg.co\/news\/91070\/228032\/responsive-images\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3___media_library_original_1200_800.jpg 1200w, https:\/\/cimg.co\/news\/91070\/228032\/responsive-images\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/91070\/228032\/responsive-images\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/91070\/228032\/responsive-images\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/91070\/228032\/responsive-images\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1280\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra del livello di supporto immediato di $ 19.000. Ethereum, d&#8217;altra parte, ha guadagnato oltre il 3% a $ 1.300.<\/p><p>Le principali criptovalute sono state scambiate in verde all&#8217;inizio della sessione asiatica, poich&eacute; la capitalizzazione di mercato globale delle criptovalute &egrave; cresciuta dello 0,44% rispetto a ieri toccando il valore di $ 920 miliardi.<br>Il volume totale dell&#8217;economia DeFi &egrave; attualmente di 3,6 miliardi di dollari, mentre il volume totale di tutte le stablecoin ha raggiunto i 35,55 miliardi di dollari.<\/p><h2>Migliori altcoin del giorno<\/h2><span class=\"replacer\"><\/span><p>I migliori risultati nella sessione asiatica sono stati quelli delle crypto Casper (CSPR), Synthetix (SNX) e Quant (QNT). Il prezzo di Casper (CSPR) &egrave; aumentato di oltre il 16% a $ 0,049, mentre il valore di SNX &egrave; cresciuto di quasi l&#8217;8% a $ 2,27. Inoltre, il prezzo di QNT &egrave; salito di oltre il 7% a $ 199.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1280\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91070\/228019\/coin360-2.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91070\/228019\/responsive-images\/coin360-2___media_library_original_1280_735.jpg 1280w, https:\/\/cimg.co\/news\/91070\/228019\/responsive-images\/coin360-2___media_library_original_1200_689.jpg 1200w, https:\/\/cimg.co\/news\/91070\/228019\/responsive-images\/coin360-2___media_library_original_900_516.jpg 900w, https:\/\/cimg.co\/news\/91070\/228019\/responsive-images\/coin360-2___media_library_original_720_413.jpg 720w, https:\/\/cimg.co\/news\/91070\/228019\/responsive-images\/coin360-2___media_library_original_600_344.jpg 600w, https:\/\/cimg.co\/news\/91070\/228019\/responsive-images\/coin360-2___media_library_original_300_172.jpg 300w\"><figcaption><i>Heatmap del mercato crypto | Fonte: Coin360<\/i><\/figcaption><\/figure><p>Il prezzo del token Huobi (HT) sta mostrando una correzione al rialzo, guadagnando quasi il 7% nelle ultime 24 ore a 7,78$. Il prezzo di TerraClassicUSD &egrave; sceso di oltre il 2% per scambiare vicino a $ 0,0387.<\/p><p>Ecco alcuni degli eventi relativi alle criptovalute che possono influenzare il mercato:<\/p><p>Il FMI promuove i CBDC programmabili e controllabili per incentivare l&#8217;inclusione finanziaria<br>Le valute digitali delle banche centrali (CBDC) sono state promosse dal Fondo monetario internazionale (FMI) come mezzo per ampliare l&#8217;accesso ai servizi bancari per i finanziariamente esclusi. Tuttavia, potrebbero esserci dei risvolti negativi legati alla sorveglianza e alla privacy associati al loro uso diffuso.<\/p><p>La scorsa settimana, all&#8217;incontro annuale FMI-Banca mondiale, il vicedirettore generale Bo Li ha osservato che la programmabilit&agrave; di una CBDC potrebbe aiutare a espandere l&#8217;accesso ai servizi bancari per le persone a basso e medio reddito.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/EconWithNick\/status\/1581332286338842624?s=20&amp;t=RVdsMhJyqhC0AIayZY-YMg\"><\/oembed><\/figure><p><br>Per approfondire, ha detto:<\/p><blockquote><p>&#8220;Una CBDC pu&ograve; consentire alle agenzie governative e agli attori del settore privato di programmare, creare contratti intelligenti e consentire politiche economiche mirate&#8221;.<\/p><\/blockquote><p>Nel frattempo, il mercato delle criptovalute guadagna terreno e pu&ograve; essere scambiato positivamente.<\/p><h2>Prezzo Bitcoin<\/h2><span class=\"replacer\"><\/span><p>La principale criptovaluta, Bitcoin, si sta consolidando vicino al livello di $ 19.500, con un volume di scambi di $ 18 miliardi in 24 ore. Bitcoin &egrave; aumentato di quasi il 2% nelle ultime 24 ore. CoinMarketCap &egrave; attualmente al primo posto, con una capitalizzazione di mercato in tempo reale di $ 373 miliardi.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1197\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91198\/228234\/prezzo-bitcoin-17-10.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91198\/228234\/responsive-images\/prezzo-bitcoin-17-10___media_library_original_1197_345.jpg 1197w, https:\/\/cimg.co\/news\/91198\/228234\/responsive-images\/prezzo-bitcoin-17-10___media_library_original_900_259.jpg 900w, https:\/\/cimg.co\/news\/91198\/228234\/responsive-images\/prezzo-bitcoin-17-10___media_library_original_720_207.jpg 720w, https:\/\/cimg.co\/news\/91198\/228234\/responsive-images\/prezzo-bitcoin-17-10___media_library_original_600_172.jpg 600w, https:\/\/cimg.co\/news\/91198\/228234\/responsive-images\/prezzo-bitcoin-17-10___media_library_original_300_86.jpg 300w\"><\/figure><p>Bitcoin sembra aver trovato supporto vicino a $ 19.500, ma ha anche superato la media mobile a 50 giorni, indicando un trend ribassista.<\/p><p>Una rottura al di sotto di $ 19.000 potrebbe far scendere BTC al precedente supporto del triplo minimo vicino a $18.600, mentre un&#8217;ulteriore rottura al ribasso potrebbe far scendere BTC a $18.250.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1804\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91070\/228026\/btc.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91070\/228026\/responsive-images\/btc___media_library_original_1804_842.jpg 1804w, https:\/\/cimg.co\/news\/91070\/228026\/responsive-images\/btc___media_library_original_1200_560.jpg 1200w, https:\/\/cimg.co\/news\/91070\/228026\/responsive-images\/btc___media_library_original_900_420.jpg 900w, https:\/\/cimg.co\/news\/91070\/228026\/responsive-images\/btc___media_library_original_720_336.jpg 720w, https:\/\/cimg.co\/news\/91070\/228026\/responsive-images\/btc___media_library_original_600_280.jpg 600w, https:\/\/cimg.co\/news\/91070\/228026\/responsive-images\/btc___media_library_original_300_140.jpg 300w\"><figcaption><i>Grafico prezzi Bitcoin &#8211; Fonte: Tradingview<\/i><\/figcaption><\/figure><p>Al rialzo, la resistenza si trova ancora vicino a $ 19.500. Se il prezzo supera i 19.500 dollari, gli investitori probabilmente prenderanno in considerazione l&#8217;acquisto fino a 19.850 dollari.<\/p><h2>Prezzo Ethereum<\/h2><span class=\"replacer\"><\/span><p>Il prezzo attuale di Ethereum &egrave; di $ 1.300, con un volume di scambi nelle 24 ore di $ 7,8 miliardi. Nelle ultime 24 ore, Ethereum &egrave; sceso di oltre l&#8217;1%, rimane al secondo posto con una capitalizzazione di mercato in tempo reale di $ 159 miliardi.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"839\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91070\/228030\/eth.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91070\/228030\/responsive-images\/eth___media_library_original_839_343.jpg 839w, https:\/\/cimg.co\/news\/91070\/228030\/responsive-images\/eth___media_library_original_720_294.jpg 720w, https:\/\/cimg.co\/news\/91070\/228030\/responsive-images\/eth___media_library_original_600_245.jpg 600w, https:\/\/cimg.co\/news\/91070\/228030\/responsive-images\/eth___media_library_original_300_122.jpg 300w\"><figcaption><i>Grafico prezzi Ethereum &#8211; Fonte: coinmarketcap<\/i><\/figcaption><\/figure><p>La coppia ETH\/USD &egrave; attualmente scambiata a un livello di supporto critico di $1.300, supportato dalla media mobile a 50 giorni. Al di sopra di questo livello, &egrave; probabile che ETH mostri un&#8217;inversione rialzista, ma la linea di tendenza al ribasso vicino a $ 1.340 funger&agrave; da barriera.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1799\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91070\/228029\/eth.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91070\/228029\/responsive-images\/eth___media_library_original_1799_834.jpg 1799w, https:\/\/cimg.co\/news\/91070\/228029\/responsive-images\/eth___media_library_original_1200_556.jpg 1200w, https:\/\/cimg.co\/news\/91070\/228029\/responsive-images\/eth___media_library_original_900_417.jpg 900w, https:\/\/cimg.co\/news\/91070\/228029\/responsive-images\/eth___media_library_original_720_333.jpg 720w, https:\/\/cimg.co\/news\/91070\/228029\/responsive-images\/eth___media_library_original_600_278.jpg 600w, https:\/\/cimg.co\/news\/91070\/228029\/responsive-images\/eth___media_library_original_300_139.jpg 300w\"><figcaption><strong>Ethereum Price Chart &#8211; Source: Tradingview<\/strong><\/figcaption><\/figure><p>Una rottura al ribasso sotto il supporto di $ 1.292 potrebbe esporre ETH a testare i livelli di $ 1.269 o $ 1.225. Poich&eacute; l&#8217;RSI e il MACD indicano una tendenza all&#8217;acquisto, &egrave; probabile che gli investitori puntino a un rialzo di ETH fino a sopra il livello psicologico di $1.300.<\/p><h2>Nuove prevendite di criptovalute<\/h2><span class=\"replacer\"><\/span><p>Le previsioni per i prezzi di Bitcoin ed Ethereum indicano una lenta ripresa rialzista. Inoltre, le prevendite e le nuove altcoin si trovano in una situazione in cui i trader pi&ugrave; speculativi possono realizzare rapidamente un grande profitto, anche in un mercato ribassista.<\/p><p>Abbiamo seguito la prevendita del token IMPT, una nuova criptovaluta che ha recentemente raccolto oltre $ 5 milioni.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/impt\/\"><strong>Visita IMPT.io<\/strong><\/a><\/p><h2><strong>Trova il miglior prezzo per comprare\/vendere criptovalute<\/strong><\/h2><span class=\"replacer\"><\/span><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1249\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91070\/228031\/tracker.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91070\/228031\/responsive-images\/tracker___media_library_original_1249_676.jpg 1249w, https:\/\/cimg.co\/news\/91070\/228031\/responsive-images\/tracker___media_library_original_1200_649.jpg 1200w, https:\/\/cimg.co\/news\/91070\/228031\/responsive-images\/tracker___media_library_original_900_487.jpg 900w, https:\/\/cimg.co\/news\/91070\/228031\/responsive-images\/tracker___media_library_original_720_389.jpg 720w, https:\/\/cimg.co\/news\/91070\/228031\/responsive-images\/tracker___media_library_original_600_324.jpg 600w, https:\/\/cimg.co\/news\/91070\/228031\/responsive-images\/tracker___media_library_original_300_162.jpg 300w\"><figcaption><i>Price Tracker &#8211; Fonte: <\/i><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/price-tracker\/\"><i>Cryptonews<\/i><\/a><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra del livello di supporto immediato di $ 19.000. Ethereum, d&#8217;altra parte, ha guadagnato oltre il 3% a $ 1.300.Le principali criptovalute sono state scambiate in verde all&#8217;inizio della sessione asiatica, poich&eacute; la capitalizzazione di mercato globale delle criptovalute &egrave; cresciuta [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,569,53],"editors":[],"sponsored_companies":[],"class_list":["post-91198","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-cdbc","tag-ethereum"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022<\/title>\n<meta name=\"description\" content=\"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022\" \/>\n<meta property=\"og:description\" content=\"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-17T15:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022\" \/>\n<meta name=\"twitter:description\" content=\"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/91070\/228019\/coin360-2.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@balducciopoma\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022","description":"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/","og_locale":"it_IT","og_type":"article","og_title":"Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022","og_description":"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.","og_url":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-10-17T15:41:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022","twitter_description":"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.","twitter_image":"https:\/\/cimg.co\/news\/91070\/228019\/coin360-2.jpg","twitter_creator":"@balducciopoma","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/"},"author":{"name":"baldassare","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/201d71e1050421b7c02ec0c5b5109364"},"headline":"Previsioni Bitcoin ed Ethereum: il FMI Promuove i CBDC per l&#8217;Inclusione Finanziaria","datePublished":"2022-10-17T15:41:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/"},"wordCount":699,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg","keywords":["bitcoin","CBDC","ethereum"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/","url":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/","name":"Previsioni Bitcoin ed Ethereum del 17 Ottobre 2022","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg","datePublished":"2022-10-17T15:41:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il 17 ottobre, il prezzo di Bitcoin viene scambiato leggermente al rialzo, al di sopra dei $ 19.000. Ethereum ha guadagnato oltre il 3% con un prezzo di $ 1.300.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#primaryimage","url":"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg","contentUrl":"https:\/\/cimg.co\/news\/91070\/228032\/copy-of-copy-of-copy-of-copy-of-farm-to-table-3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-ed-ethereum-il-fmi-promuove-i-cbdc-per-linclusione-finanziaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Previsioni Bitcoin ed Ethereum: il FMI Promuove i CBDC per l&#8217;Inclusione Finanziaria"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/91198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=91198"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/91198\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=91198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=91198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=91198"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=91198"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=91198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}