{"id":90300,"date":"2022-10-10T10:55:00","date_gmt":"2022-10-10T10:55:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=90300"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/","title":{"rendered":"I Prezzi delle Schede Grafiche per Computer Scendono di Quasi il 60% dopo il Merge di Ethereum"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg\" alt=\"schede grafiche\" srcset=\"https:\/\/cimg.co\/news\/90295\/226347\/responsive-images\/webp-net-resizeimage-media-library-original-1216-811___media_library_original_1216_811.jpeg 1216w, https:\/\/cimg.co\/news\/90295\/226347\/responsive-images\/webp-net-resizeimage-media-library-original-1216-811___media_library_original_1200_800.jpeg 1200w, https:\/\/cimg.co\/news\/90295\/226347\/responsive-images\/webp-net-resizeimage-media-library-original-1216-811___media_library_original_900_600.jpeg 900w, https:\/\/cimg.co\/news\/90295\/226347\/responsive-images\/webp-net-resizeimage-media-library-original-1216-811___media_library_original_720_480.jpeg 720w, https:\/\/cimg.co\/news\/90295\/226347\/responsive-images\/webp-net-resizeimage-media-library-original-1216-811___media_library_original_600_400.jpeg 600w, https:\/\/cimg.co\/news\/90295\/226347\/responsive-images\/webp-net-resizeimage-media-library-original-1216-811___media_library_original_300_200.jpeg 300w\" sizes=\"100vw\" width=\"1216\" class=\"content-img\"><figcaption><i>Fonte: Adobe\/Photocreo Bednarek<\/i><\/figcaption><\/figure><p class=\"wp-block-paragraph\">In seguito all&#8217;aggiornamento della blockchain di Ethereum, noto come &#8220;Merge&#8221;, grazie al quale la blockchain ora utilizza l&#8217;algoritmo di consenso Proof-of-Stake, i <strong>prezzi <\/strong><i><strong>delle unit&agrave; di elaborazione grafica (GPU)<\/strong><\/i><strong> sono crollati di quasi il 60%<\/strong>: i venditori cinesi hanno dichiarato che i prezzi delle unit&agrave; hanno raggiunto il &#8220;livello pi&ugrave; basso di sempre&#8221;. <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/migliori-crypto-proof-of-stake\/\">Scopri le migliori crypto Proof of Stake su cui investire nel 2022<\/a><\/p><h2>I prezzi delle schede grafiche crollano di quasi il 60%<\/h2><span class=\"replacer\"><\/span><p>Secondo quanto <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.scmp.com\/tech\/tech-trends\/article\/3193272\/ethereum-merge-pushes-gpu-prices-china-lowest-level-shift-away\">riportato <\/a>dal South China Morning Post, i venditori locali di GPU, un tempo molto ricercate dai miner crypto, come quelle che utilizzano GeForce RTX 3080, RTX 3080 Ti e RTX 3090 di Nvidia, in passato chiedevano fino al triplo del loro prezzo di vendita. Tuttavia, a causa dell&#8217;ultimo Merge di ETH, la domanda di GPU potenti &egrave; diminuita rapidamente negli ultimi mesi nel mercato cinese.&nbsp;<\/p><p>Le persone della Cina continentale che desiderano acquistare una RTX 3080 devono essere pronte a spendere circa 5.000 RMB (700 dollari). Fino a tre mesi fa, secondo un commerciante di elettronica locale, lo stesso prodotto costava circa 8.000 RMB.<\/p><p>Nel frattempo, i prezzi delle GPU consumer prodotte dai principali produttori, come Nvidia e AMD, stavano gi&agrave; diminuendo all&#8217;indomani del giro di vite cinese su bitcoin.<\/p><p>Lo scorso agosto, la Cyberspace Administration of China, l&#8217;azienda che si occupa di supervisione e regolamentazione di Internet nel Paese, ha colpito ancora una volta nella lotta di Pechino contro il trading di criptovalute, chiudendo circa 12.000 account.&nbsp;<\/p><p>Sono stati cancellati circa 51.000 post e 105 siti web sono stati messi offline per aver presumibilmente ospitato materiale di &#8220;marketing sulle criptovalute&#8221;, ovvero tutorial che spiegano come i cittadini della Cina continentale possano effettuare transazioni transfrontaliere e come effettuare il mining crypto.&nbsp;<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/it\/news\/la-mappa-dei-miners-americani-dopo-il-ban-della-cina\/\">Nonostante il giro di vite del 2021<\/a>, avviato dalla People&#8217;s Bank of China (PBoC), che ha invitato le aziende cinesi a prendere misure contro i clienti di trading crypto, le discussioni incentrate sulle criptovalute sulle popolari piattaforme di social media cinesi rimangono ampiamente diffuse.<\/p><p><br>&nbsp;<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.impt.io\/it?clickId=fx_b17428_1e71f4c68cf092982582281485409759_1\"><strong>Investi su IMPT<\/strong><\/a><\/p><p><i>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: Adobe\/Photocreo BednarekIn seguito all&#8217;aggiornamento della blockchain di Ethereum, noto come &#8220;Merge&#8221;, grazie al quale la blockchain ora utilizza l&#8217;algoritmo di consenso Proof-of-Stake, i prezzi delle unit&agrave; di elaborazione grafica (GPU) sono crollati di quasi il 60%: i venditori cinesi hanno dichiarato che i prezzi delle unit&agrave; hanno raggiunto il &#8220;livello pi&ugrave; basso di sempre&#8221;. [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,1],"tags":[47,95,53,352],"editors":[306],"sponsored_companies":[],"class_list":["post-90300","post","type-post","status-publish","format-standard","hentry","category-ethereum-news","category-news","tag-blockchain","tag-eth","tag-ethereum","tag-prezzi","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I Prezzi delle Schede Grafiche Scendono di Quasi il 60%<\/title>\n<meta name=\"description\" content=\"In seguito all&#039;aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I Prezzi delle Schede Grafiche Scendono di Quasi il 60%\" \/>\n<meta property=\"og:description\" content=\"In seguito all&#039;aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T10:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"I Prezzi delle Schede Grafiche Scendono di Quasi il 60%\" \/>\n<meta name=\"twitter:description\" content=\"In seguito all&#039;aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I Prezzi delle Schede Grafiche Scendono di Quasi il 60%","description":"In seguito all'aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/","og_locale":"it_IT","og_type":"article","og_title":"I Prezzi delle Schede Grafiche Scendono di Quasi il 60%","og_description":"In seguito all'aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.","og_url":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-10-10T10:55:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"I Prezzi delle Schede Grafiche Scendono di Quasi il 60%","twitter_description":"In seguito all'aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.","twitter_image":"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"I Prezzi delle Schede Grafiche per Computer Scendono di Quasi il 60% dopo il Merge di Ethereum","datePublished":"2022-10-10T10:55:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/"},"wordCount":374,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg","keywords":["blockchain","eth","ethereum","prezzi"],"articleSection":["Ethereum News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/","url":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/","name":"I Prezzi delle Schede Grafiche Scendono di Quasi il 60%","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg","datePublished":"2022-10-10T10:55:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"In seguito all'aggiornamento della blockchain di Ethereum, noto come Merge, i prezzi delle unit\u00e0 di elaborazione grafica (GPU) sono crollati di quasi il 60%.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#primaryimage","url":"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg","contentUrl":"https:\/\/cimg.co\/news\/90295\/226347\/webp-net-resizeimage-media-library-original-1216-811.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/i-prezzi-delle-schede-grafiche-per-computer-scendono-di-quasi-il-60-dopo-il-merge-di-ethereum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"I Prezzi delle Schede Grafiche per Computer Scendono di Quasi il 60% dopo il Merge di Ethereum"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/90300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=90300"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/90300\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=90300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=90300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=90300"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=90300"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=90300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}