{"id":82570,"date":"2022-07-03T13:58:00","date_gmt":"2022-07-03T13:58:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=82570"},"modified":"2024-05-03T23:11:01","modified_gmt":"2024-05-03T23:11:01","slug":"defi-suffers-from-too-much-centralization-what-can-be-done-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/","title":{"rendered":"DeFi soffre di troppa centralizzazione, cosa fare?"},"content":{"rendered":"<p class=\"wp-block-paragraph\"> <\/p><figure class=\"image\"><img decoding=\"async\" class=\"content-img\" src=\"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg\" alt=\"DeFi\" width=\"1188\">\r\n<figcaption>Fonte: Adobe\/Oligo<\/figcaption>\r\n<\/figure><p><i>&#8220;Se una qualsiasi parte del loro modello di business incorpora la <strong>centralizzazione <\/strong>, allora &egrave; centralizzata indipendentemente dalle altre funzionalit&agrave; decentralizzate che implementa&#8221;.<\/i><\/p><p><i>&#8220;&Egrave; fondamentale che le persone capiscano come vengono utilizzati gli asset che stanno impegnando a favore di un&#8217;entit&agrave; centralizzata&#8221;.<\/i><\/p><p><i>&#8220;Se gli utenti richiedono una maggiore <strong>decentralizzazione <\/strong>all&#8217;interno del prestito crypto, devono semplicemente votare con i loro fondi spostandoli&#8221;.<\/i><br><i>_____<\/i><\/p><p>Come gran parte del settore delle criptovalute, la <i>finanza decentralizzata <\/i>(<strong>DeFi<\/strong>) sta attraversando un periodo difficile. Non solo il suo valore totale bloccato &egrave; diminuito del 70% (secondo i dati di DefiLlama) da dicembre, ma varie piattaforme all&#8217;interno del settore DeFi non cos&igrave; decentralizzate sono state minacciate di collasso, con l&#8217;ultima interruzione dei <a href=\"https:\/\/cryptonews.com\/it\/news\/100o-celsius-industry-debating-possible-impact-lenders-reassuring-users-nexo-offers-help-it\/\" target=\"_blank\" rel=\"noopener\">prelievi da parte di Celsius <\/a>&#8211; e forse la pi&ugrave; drammatica: la manifestazione della crisi in corso.<\/p><p>Sebbene l&#8217;inclusione di Celsius nel sottosettore DeFi la renda nominalmente una piattaforma &#8220;decentralizzata&#8221; (almeno nell&#8217;uso delle blockchain), il controllo sui fondi degli utenti dimostra quanto fosse centralizzata. Insieme al crollo di <a href=\"https:\/\/cryptonews.com\/it\/tags\/terra\/\" target=\"_blank\" rel=\"noopener\">Terra <\/a>(la <a href=\"https:\/\/web.archive.org\/web\/20220508135317\/https:\/\/defillama.com\/chain\/Terra\" target=\"_blank\" rel=\"noopener\">seconda<\/a> piattaforma DeFi pi&ugrave; grande), ha sollevato seri interrogativi sulla necessit&agrave; e sulla possibilit&agrave; di una maggiore decentralizzazione della DeFi.<\/p><p>L&#8217;opinione su questo &egrave; mista, con alcune figure del settore che affermano che la centralizzazione offre vari vantaggi rispetto alle piattaforme veramente decentralizzate. Allo stesso tempo, sembra esserci accordo sul fatto che il decentramento da solo non sia una garanzia contro i crolli.<\/p><h2>Troppa DeFi non &egrave; realmente decentralizzata<\/h2><span class=\"replacer\"><\/span><p>Le cifre all&#8217;interno del settore concordano pi&ugrave; o meno sul fatto che i recenti eventi che coinvolgono Celsius e altre piattaforme evidenziano lo scomodo livello di centralizzazione all&#8217;interno della DeFi.<\/p><p>Timo Lehes, co-fondatore del protocollo DeFi Swarm ha affermato: &#8220;I recenti eventi riguardanti Celsius, Three Arrows Capital e Lido mostrano che la mancanza di decentramento rappresenta un problema per la DeFi&#8221;.<\/p><p>Secondo Lehes, parte del problema in DeFi &egrave; che il decentramento avviene su scala mobile, con le piattaforme composte da un mix di elementi decentralizzati e centralizzati.<\/p><blockquote>\r\n<p>&ldquo;Individui e istituzioni possono ancora trarre vantaggio dall&#8217;architettura e dall&#8217;implementazione dell&#8217;innovazione DeFi, come l&#8217;autocustodia e la trasparenza, anche se altre parti di un servizio sono in qualche modo centralizzate. Tuttavia, il problema evidenziato dai recenti eventi delle principali piattaforme di prestito &egrave; in parte una questione di centralizzazione, ma anche una preoccupazione di trasparenza, inclusa la supervisione di ci&ograve; che accade all&#8217;interno di un protocollo&#8221;, ha detto a Cryptonews.com.<\/p>\r\n<\/blockquote><p>Guardando in particolare Celsius, anch&#8217;esso &egrave; un mix di elementi decentralizzati e centralizzati. Tuttavia, &egrave; discutibile che fosse centralizzato proprio nelle aree pi&ugrave; sensibili.<\/p><p>Ryan Shea, un crypto-economista presso la piattaforma di trading Trakx ha affermato: &#8220;Utilizza gli smart contract e l&#8217;infrastruttura del ledger della DeFi, ma i fondi dei clienti vengono aggregati in wallet custodial, che sono controllati dalla societ&agrave;&#8221;.<\/p><p>Secondo Shea, la decentralizzazione\/centralizzazione &egrave; una questione binaria, il che significa che la centralizzazione in una sola area importante &egrave; sufficiente per rendere una piattaforma sostanzialmente centralizzata.<\/p><p>Inoltre ha detto a Cryptonews.com: &#8220;Se una qualsiasi parte del loro modello di business incorpora la centralizzazione, come l&#8217;aggregazione dei fondi dei clienti in un wallet custodial controllato dalla societ&agrave; di prestito, allora &egrave; centralizzata indipendentemente dalle altre funzionalit&agrave; decentralizzate che implementa. Detto questo, molti altri prestatori di criptovalute di grandi dimensioni come <a href=\"https:\/\/cryptonews.com\/it\/tags\/blockfi\/\" target=\"_blank\" rel=\"noopener\">BlockFi<\/a> e Crypto.com implementano anche strutture centralizzate come hot wallet per condurre transazioni&#8221;.<\/p><p>Se una piattaforma o un&#8217;azienda DeFi vuole essere &#8220;veramente&#8221; decentralizzata, deve operare su una base pi&ugrave; o meno completamente peer-to-peer, con tutte le transazioni eseguite utilizzando smart contract eseguiti su una rete distribuita di computer.<\/p><blockquote>\r\n<p>&ldquo;Buoni esempi di tali piattaforme includono <a href=\"https:\/\/cryptonews.com\/it\/tags\/aave\" target=\"_blank\" rel=\"noopener\">AAVE<\/a>, <a href=\"https:\/\/cryptonews.com\/it\/coins\/maker\/\" target=\"_blank\" rel=\"noopener\">Maker<\/a> e <a href=\"https:\/\/cryptonews.com\/it\/coins\/compound\/\" target=\"_blank\" rel=\"noopener\">Compound<\/a>. A differenza di CeFi [finanza centralizzata], gli utenti non devono fidarsi della societ&agrave; di prestito, ma devono fidarsi dell&#8217;integrit&agrave; del codice che esegue gli smart contract &#8220;, ha aggiunto Shea.<\/p>\r\n<\/blockquote><p>Altri sono d&#8217;accordo con l&#8217;opinione che, se esiste un controllo centralizzato dei fondi degli utenti, nessuna piattaforma DeFi &egrave; davvero decentralizzata, indipendentemente da cos&#8217;altro potrebbe operare su base distribuita. Dan Keller, co-fondatore della rete computazionale decentralizzata Flux ha detto: &ldquo;&Egrave; il caso della maggior parte delle piattaforme DeFi, che sono decentralizzate solo di nome, ma non nella realt&agrave;, come Celsius. Per evitare che questo problema vada avanti, i partecipanti al settore dovrebbero concentrarsi sulla spinta per un decentramento pi&ugrave; profondo, che a sua volta porter&agrave; a un prodotto complessivo migliore&#8221;. Naturalmente, anche con il decentramento di fondi e trasferimenti, la centralizzazione in altre aree pu&ograve; comunque causare problemi alle piattaforme DeFi e alle criptovalute pi&ugrave; in generale. Inoltre Timo Lehes ha detto: &#8220;Ad esempio, se troppi nodi su Lido sono gestiti su AWS [Amazon Web Services, una piattaforma di cloud computing], rende la rete pi&ugrave; attaccabile, mettendo a repentaglio l&#8217;obiettivo dell&#8217;infrastruttura di rete distribuita e della governance&#8221;.<\/p><h2>Cosa pu&ograve; fare la DeFi per diventare pi&ugrave; decentralizzata?<\/h2><span class=\"replacer\"><\/span><p>Lehes sostiene che, se la DeFi vuole diventare pi&ugrave; decentralizzata, &egrave; necessario introdurre strutture conformi, attraverso un misto di regolamentazione e autoregolamentazione.<\/p><p>Inoltre ha affermato: &#8220;L&#8217;intera configurazione end-to-end delle strutture dei nodi e l&#8217;implementazione di smart contract dovrebbe essere verificabile e chiara per gli investitori. Questo non &egrave; un problema specifico dell&#8217;attuale turbolenza del mercato, ma qualcosa di pi&ugrave; fondamentale nell&#8217;infrastruttura della DeFi&#8221;.<\/p><p>Il crollo di Celsius, che ha utilizzato i fondi degli utenti per effettuare investimenti su altre piattaforme, evidenzia che un ingrediente essenziale del decentramento dovrebbe essere la trasparenza.<\/p><blockquote>\r\n<p>&ldquo;&Egrave; fondamentale che le persone comprendano come vengono utilizzate gli asset che stanno impegnando a favore di un&#8217;entit&agrave; centralizzata. Il problema con l&#8217;affidamento di attivit&agrave; a controparti non regolamentate &egrave; la scatola nera della reipoteca e la mancanza di ricorso se qualcosa dovesse andare storto&#8221;, ha aggiunto Lehes.<\/p>\r\n<\/blockquote><p>Nella finanza tradizionale, gli istituti di deposito come le banche hanno una serie di regole che disciplinano il modo in cui possono utilizzare il capitale dei clienti e sono costantemente monitorati. Sar&agrave; necessario qualcosa del genere per costringere la DeFi a operare su una base costantemente decentralizzata, ma Lehes afferma anche che le piattaforme e gli utenti allo stesso modo dovrebbero spingere per una maggiore auto-custodia.<\/p><p>Inoltre ha affermato: &ldquo;Il modo pi&ugrave; semplice per impedire alle istituzioni di essere creative con i fondi dei clienti &egrave; tenerne la custodia. L&#8217;architettura della DeFi ti consente di mantenere il pieno controllo sui tuoi asset: aggiungi a questo un livello normativo e avrai una combinazione vincente&#8221;.<\/p><p>Ryan Shea afferma anche che gli utenti dovrebbero spingere per una maggiore decentralizzazione, inclusa l&#8217;autocustodia.<\/p><blockquote>\r\n<p>&ldquo;Le aziende e i prestatori di criptovalute non sono diversi, rispondendo principalmente alla domanda dei clienti, perch&eacute; senza clienti non c&#8217;&egrave; azienda. Esistono gi&agrave; numerosi istituti di credito DeFi funzionanti, quindi se gli utenti richiedono una maggiore decentralizzazione all&#8217;interno del prestito crypto devono semplicemente votare con i loro fondi spostandoli da istituti di credito centralizzati a istituti di credito decentralizzati&#8221;, ha affermato.<\/p>\r\n<\/blockquote><h2>La centralizzazione ha i suoi vantaggi<\/h2><span class=\"replacer\"><\/span><p>Tuttavia, Shea offre anche alcuni avvertimenti in relazione alla spinta verso un maggiore decentramento, suggerendo che CeFi abbia alcuni vantaggi.<\/p><p>Inoltre ha affermato: &ldquo;In primo luogo, gli istituti di credito CeFi storicamente hanno avuto la tendenza a offrire rendimenti pi&ugrave; elevati sui loro prodotti rispetto agli exchange DeFi. Questa capacit&agrave; di offrire rendimenti migliori ha spinto a ipotizzare che tendano a investire in prodotti pi&ugrave; rischiosi o a migliorare il rendimento tramite rehypothecation, per cui la garanzia viene nuovamente prestata per sostenere un altro prestito generando pagamenti di interessi aggiuntivi&#8221;.<\/p><p>Inoltre, molte piattaforme DeFi non offrono rampe di accensione e spegnimento fiat, il che significa che molti utenti mainstream continueranno a preferire la comodit&agrave; di CeFi.<\/p><p>Ha detto: &#8220;La regolamentazione del governo viene applicata sempre pi&ugrave; spesso alle transazioni crypto e l&#8217;obiettivo principale &egrave; la rampa on-off. In effetti, &egrave; l&#8217;unico obiettivo praticabile per i governi di applicare normative, come le regole KYC [conosci il tuo cliente] e AML [antiriciclaggio], perch&eacute; possono minacciare l&#8217;esclusione dai servizi finanziari tradizionali per le societ&agrave; crypto non conformi&#8221;.<\/p><p>C&#8217;&egrave; anche l&#8217;argomento secondo cui il decentramento da solo non causer&agrave; una riduzione significativa dei tipi di crolli a cui il mercato ha assistito nelle ultime settimane.<\/p><p>Shea disse: &ldquo;Quello che conta davvero &egrave; la qualit&agrave; del team dietro il progetto. Detto questo, lo stesso vale anche per gli istituti di credito DeFi: il team (anche uno che &egrave; crowd-sourced o esegue software open source) &egrave; di qualit&agrave; sufficiente per garantire che i bug del software e\/o la progettazione degli smart contract siano sufficientemente robusti? resistere a drammatici eventi di mercato?&rdquo;.<\/p><p>In definitiva, &egrave; discutibile che solo la regolamentazione e la trasparenza possono garantire un sostanziale calo del rischio quando si tratta di DeFi, indipendentemente da quanto sia centralizzata o meno una piattaforma.<\/p><blockquote>\r\n<p>Come conclude Timo Lehes, &ldquo;La regolamentazione offre livelli di trasparenza ai prodotti esistenti e all&#8217;innovazione. Nel futuro, gli investitori dovrebbero essere avvisati di impegnarsi solo con prodotti DeFi in cui i processi e gli smart contract sono completamente verificabili, c&#8217;&egrave; un percorso di ricorso in caso di negligenza e hanno piena trasparenza su come viene utilizzata la garanzia&#8221;.<\/p>\r\n<\/blockquote><p>_____<\/p><p><i>Seguici sui nostri canali social:<\/i> <\/p><p>Telegram: <a href=\"https:\/\/t.me\/ItaliaCryptonews\" target=\"_blank\" rel=\"noopener\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter: <a href=\"https:\/\/twitter.com\/cryptonews_IT\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/cryptonews_IT<\/a><br> _______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211; Per acquistare le tue criptovalute su <a href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\" target=\"_blank\" rel=\"noopener\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211; Per proteggere le tue criptovalute su portafogli come <a href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0=CN-IT\" target=\"_blank\" rel=\"noopener\">Ledger<\/a> e <a href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\" target=\"_blank\" rel=\"noopener\">Trezor<\/a><\/p><p>&#8211; Per effettuare transazioni in modo anonimo con <a href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\" target=\"_blank\" rel=\"noopener\">NordVPN<\/a><\/p><p>___<br><br>Per saperne di pi&ugrave;:<br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/5-risks-to-know-before-using-centralized-crypto-lending-platforms-it\/\" target=\"_blank\" rel=\"noopener\">5 rischi sulle piattaforme di prestiti crypto centralizzate<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/decentralization-in-crypto-is-a-hard-to-measure-ideal-it\/\" target=\"_blank\" rel=\"noopener\">Come si misura la decentralizzazione nelle criptovalute?<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/vitalik-buterin-confirms-post-merge-ethereum-centralization-concerns-urges-not-to-overly-catastrophize-it-it\/\" target=\"_blank\" rel=\"noopener\">Vitalik Buterin &egrave; preoccupato per Ethereum dopo The Merge<\/a><\/p><p>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/solana-based-defi-lender-solend-goes-for-whale-hunting-and-backpedals-instantly-it\/\" target=\"_blank\" rel=\"noopener\">Solend basato su Solana va a caccia di balene<\/a><\/p><p>&#8211;  <a href=\"https:\/\/cryptonews.com\/news\/makerdao-endgame-plan-calls-for-specialized-daos-says-protocol-held-back-by-complexity\/\" target=\"_blank\" rel=\"noopener\">MakerDAO &lsquo;Endgame Plan&rsquo; Calls for Specialized DAOs, Says Protocol is Held Back by Complexity<\/a><\/p><p>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/more-work-to-be-done-as-eu-imposes-strict-new-crypto-regulations-it\/\" target=\"_blank\" rel=\"noopener\">L&#8217;UE impone nuove normative stringenti sulle criptovalute<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/imfs-defi-governance-recommendations-include-these-two-steps-it\/\" target=\"_blank\" rel=\"noopener\">FMI: raccomandazioni sulla governance della DeFi<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: Adobe\/Oligo &#8220;Se una qualsiasi parte del loro modello di business incorpora la centralizzazione , allora &egrave; centralizzata indipendentemente dalle altre funzionalit&agrave; decentralizzate che implementa&#8221;.&#8220;&Egrave; fondamentale che le persone capiscano come vengono utilizzati gli asset che stanno impegnando a favore di un&#8217;entit&agrave; centralizzata&#8221;.&#8220;Se gli utenti richiedono una maggiore decentralizzazione all&#8217;interno del prestito crypto, devono semplicemente [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,5],"tags":[380,102],"editors":[],"sponsored_companies":[],"class_list":["post-82570","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-features","tag-decentralizzazione","tag-defi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DeFi soffre di troppa centralizzazione, cosa fare?<\/title>\n<meta name=\"description\" content=\"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DeFi soffre di troppa centralizzazione, cosa fare?\" \/>\n<meta property=\"og:description\" content=\"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-03T13:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T23:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"DeFi soffre di troppa centralizzazione, cosa fare?\" \/>\n<meta name=\"twitter:description\" content=\"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DeFi soffre di troppa centralizzazione, cosa fare?","description":"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/","og_locale":"it_IT","og_type":"article","og_title":"DeFi soffre di troppa centralizzazione, cosa fare?","og_description":"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.","og_url":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-07-03T13:58:00+00:00","article_modified_time":"2024-05-03T23:11:01+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"DeFi soffre di troppa centralizzazione, cosa fare?","twitter_description":"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.","twitter_image":"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"DeFi soffre di troppa centralizzazione, cosa fare?","datePublished":"2022-07-03T13:58:00+00:00","dateModified":"2024-05-03T23:11:01+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/"},"wordCount":1712,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg","keywords":["decentralizzazione","defi"],"articleSection":["Exclusives","In evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/","url":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/","name":"DeFi soffre di troppa centralizzazione, cosa fare?","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg","datePublished":"2022-07-03T13:58:00+00:00","dateModified":"2024-05-03T23:11:01+00:00","description":"Per alcuni del settore la centralizzazione offre vantaggi rispetto alle piattaforme decentralizzate, ma il decentramento non \u00e8 una garanzia contro i crolli.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg","contentUrl":"https:\/\/cimg.co\/news\/82570\/209125\/webp-net-resizeimage11-min.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/exclusives\/defi-suffers-from-too-much-centralization-what-can-be-done-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"DeFi soffre di troppa centralizzazione, cosa fare?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/82570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=82570"}],"version-history":[{"count":2,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/82570\/revisions"}],"predecessor-version":[{"id":175988,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/82570\/revisions\/175988"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=82570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=82570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=82570"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=82570"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=82570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}