{"id":80314,"date":"2022-06-03T12:30:00","date_gmt":"2022-06-03T12:30:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=80314"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/","title":{"rendered":"New York vieta bitcoin alimentato dal carbonio"},"content":{"rendered":"<p class=\"wp-block-paragraph\">&nbsp;<\/p><figure class=\"image\"><img decoding=\"async\" class=\"content-img\" src=\"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg\" alt=\"Carbonio\" width=\"1207\">\r\n<figcaption>Una centrale geotermica in Kenya. Fonte: Adobe\/Belikova Oksana<\/figcaption>\r\n<\/figure><p>Le autorit&agrave; di regolamentazione di tutto il mondo lavorano per adottare posizioni diverse sul mining di criptovalute, lo stato americano di <i><strong>New York<\/strong> e il paese dell&#8217;Africa orientale del <strong>Kenya<\/strong> offrono due esempi di come i legislatori possono contrastare o promuovere l&#8217;innovazione crypto attraverso le loro iniziative.<\/i><\/p><p>Citando la necessit&agrave; di limitare il consumo energetico dello stato, il Senato di New York ha approvato un<a href=\"https:\/\/www.nysenate.gov\/legislation\/bills\/2021\/s6486\/amendment\/d\" target=\"_blank\" rel=\"noopener\"> disegno di legge <\/a>che introduce una moratoria su alcune operazioni di mining di criptovalute, con l&#8217;uso di metodi di autenticazione<i> proof-of-work (<\/i><i>PoW<\/i><i>)<\/i> per convalidare le transazioni blockchain. La moratoria di due anni riguarda tutti i nuovi progetti di mining PoW gestiti con l&#8217;uso di combustibili a base di <strong>carbonio<\/strong>, inclusi&nbsp;<a href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\" target=\"_blank\" rel=\"noopener\"><strong>bitcoin<\/strong> (BTC)<\/a> e altri crypto asset.<\/p><p>Dopo essere stato approvato dal Senato e dall&#8217;Assemblea dello Stato di New York, la camera bassa della legislatura dello stato, il disegno di legge &egrave; stato consegnato al governatore di New York. A meno che il governatore in carica, la democratica Kathy Hochul, non metta il veto al disegno di legge, le sue disposizioni entreranno in vigore.<\/p><p>Il disegno di legge afferma che &#8220;il funzionamento continuato e ampliato delle operazioni di mining di criptovaluta, che eseguono metodi di autenticazione proof-of-work per convalidare le transazioni blockchain, aumenter&agrave; notevolmente la quantit&agrave; di consumo di energia nello stato di New York avr&agrave; un impatto sulla conformit&agrave; con il Climate Leadership and Community Protection Act&#8221;.<\/p><h2>Kenya promuove BTC verde<\/h2><span class=\"replacer\"><\/span><p>D&#8217;altra parte, la societ&agrave; di produzione energetica del Kenya KenGen ha adottato un approccio diverso alle criptovalute, dichiarando i suoi piani per offrire <i>alle societ&agrave; di mining di BTC l&#8217;energia geotermica in eccesso di KenGen.<\/i> Quartz <a href=\"https:\/\/qz.com\/africa\/2172437\/kengen-is-offering-geothermal-power-to-bitcoin-miners\/\" target=\"_blank\" rel=\"noopener\">riferisce che <\/a>questo &egrave; progettato per aiutare gli operatori del settore a soddisfare i loro bisogni energetici.<\/p><p>Il business energetico afferma che, offrendo energia pulita, contribuir&agrave; a ridurre le emissioni di CO2 del mining di criptovalute innescate dal mining di bitcoin.<\/p><p>In qualit&agrave; di principale produttore di energia geotermica dell&#8217;Africa, il Kenya ha una capacit&agrave; installata di 863 MW, la maggior parte della quale &egrave; garantita da KenGen. Lo stato ha un potenziale geotermico stimato di circa 10.000 MW situato lungo il circuito della Rift Valley, che potrebbe essere utilizzato per promuovere il mining di criptovalute verdi da parte degli attori del settore locale.<\/p><p>____<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a href=\"https:\/\/t.me\/ItaliaCryptonews\" target=\"_blank\" rel=\"noopener\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a href=\"https:\/\/twitter.com\/cryptonews_IT\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\" target=\"_blank\" rel=\"noopener\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0=CN-IT\" target=\"_blank\" rel=\"noopener\">Ledger<\/a> e <a href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\" target=\"_blank\" rel=\"noopener\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\" target=\"_blank\" rel=\"noopener\">NordVPN<\/a><\/p><p>_______<\/p><p>Per saperne di pi&ugrave;:<br>&#8211; <a href=\"https:\/\/cryptonews.com\/news\/another-bitcoin-mining-scrutiny-layoffs-at-crypto-exchanges-binance-in-canada-more-news\/\" target=\"_blank\" rel=\"noopener\">Another Bitcoin Mining Scrutiny<\/a><br>&#8211;<a href=\"https:\/\/cryptonews.com\/it\/news\/bitcoin-mining-can-be-a-force-for-good-or-bad-banning-it-doesnt-solve-anything-ftxus-president-it\/\" target=\"_blank\" rel=\"noopener\"> Vietare il mining di bitcoin non risolve nulla<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/news\/kenyan-crypto-entrepreneurs-urge-cma-to-create-regulatory-fr-5558\/\" target=\"_blank\" rel=\"noopener\">Kenyan Crypto Entrepreneurs Urge CMA to Create Regulatory Framework, Not Demons<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/videos\/bitcoin-in-kenya-w-roselyne-wanjiru\/\" target=\"_blank\" rel=\"noopener\">Bitcoin in Kenya w\/ Roselyne Wanjiru<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/cryptos-need-for-sustainability-standard-setting-starts-here-it\/\" target=\"_blank\" rel=\"noopener\">Standard di sostenibilit&agrave; per le criptovalute<\/a><br>&#8211;<a href=\"https:\/\/cryptonews.com\/it\/news\/bitcoin-mining-efficiency-up-63-in-year-sustainable-electricity-mix-jumped-59-bitcoin-mining-council-it\/\" target=\"_blank\" rel=\"noopener\">L&#8217;efficienza del mining di BTC &egrave; aumentata del 63% nell&#8217;anno&nbsp;<\/a><\/p><p><a href=\"https:\/\/cryptonews.com\/news\/bitcoin-mining-efficiency-up-63-in-year-sustainable-electricity-mix-jumped-59-bitcoin-mining-council\/\" target=\"_blank\" rel=\"noopener\">&#8211; Bitcoin Mining Council<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/mozilla-turns-from-pow-to-pos-cryptos-citing-energy-concerns-wikipedia-may-follow-it\/\" target=\"_blank\" rel=\"noopener\">Mozilla non accetter&agrave; crypto PoW per problemi energetici<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/the-compromises-and-benefits-of-ethereum-switching-to-a-proof-of-stake-network-it\/\" target=\"_blank\" rel=\"noopener\">Vantaggi e compromessi del passaggio di ETH a Proof-of-Stake<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp;Una centrale geotermica in Kenya. Fonte: Adobe\/Belikova OksanaLe autorit&agrave; di regolamentazione di tutto il mondo lavorano per adottare posizioni diverse sul mining di criptovalute, lo stato americano di New York e il paese dell&#8217;Africa orientale del Kenya offrono due esempi di come i legislatori possono contrastare o promuovere l&#8217;innovazione crypto attraverso le loro iniziative.Citando la [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[115,45,142],"editors":[306],"sponsored_companies":[],"class_list":["post-80314","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-altcoin","tag-bitcoin","tag-mining","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New York vieta bitcoin alimentato dal carbonio<\/title>\n<meta name=\"description\" content=\"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New York vieta bitcoin alimentato dal carbonio\" \/>\n<meta property=\"og:description\" content=\"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T12:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"New York vieta bitcoin alimentato dal carbonio\" \/>\n<meta name=\"twitter:description\" content=\"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New York vieta bitcoin alimentato dal carbonio","description":"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/","og_locale":"it_IT","og_type":"article","og_title":"New York vieta bitcoin alimentato dal carbonio","og_description":"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.","og_url":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-06-03T12:30:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"New York vieta bitcoin alimentato dal carbonio","twitter_description":"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.","twitter_image":"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"New York vieta bitcoin alimentato dal carbonio","datePublished":"2022-06-03T12:30:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/"},"wordCount":560,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg","keywords":["altcoin","bitcoin","mining"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/","url":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/","name":"New York vieta bitcoin alimentato dal carbonio","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg","datePublished":"2022-06-03T12:30:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Lo Stato di New York vieta bitcoin alimentato dal carbonio, il mining di altcoin, mentre il Kenya promuove BTC verde.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg","contentUrl":"https:\/\/cimg.co\/news\/80314\/201561\/adobestock-59661532-min.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/new-york-state-to-ban-carbon-powered-bitcoin-altcoin-mining-while-kenya-fosters-green-btc-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"New York vieta bitcoin alimentato dal carbonio"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/80314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=80314"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/80314\/revisions"}],"predecessor-version":[{"id":173758,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/80314\/revisions\/173758"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=80314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=80314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=80314"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=80314"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=80314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}