{"id":78029,"date":"2022-05-06T08:58:00","date_gmt":"2022-05-06T08:58:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=78029"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/","title":{"rendered":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" class=\"content-img\" src=\"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg\" alt=\"CBDC banche centrali\" width=\"1200\">\r\n<figcaption>Fonte: AdobeStock \/ Proxima Studio<\/figcaption>\r\n<\/figure><p class=\"wp-block-paragraph\">&nbsp;<\/p><p>Un numero crescente di <strong>Banche Centrali<\/strong> a livello globale ha l&#8217;autorit&agrave; legale di emettere &#8220;valute digitali della banca centrale&#8221; (<a href=\"https:\/\/cryptonews.com\/it\/tags\/cbdc\/\" target=\"_blank\" rel=\"noopener\"><strong>CBDC<\/strong><\/a>) e, rispetto all&#8217;anno precedente, la percentuale di banche centrali che stanno attualmente sviluppando una CBDC o eseguendo un progetto pilota &egrave; quasi raddoppiata dal 14% al 26%, secondo un nuovo rapporto della <i>Banca dei Regolamenti Internazionali<\/i> (BRI)<\/p><p>Il rapporto ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti correlati o test di prova.<\/p><h2>CBDC al dettaglio e all&#8217;ingrosso<\/h2><span class=\"replacer\"><\/span><p>L&#8217;indagine, nell&#8217;ambito della quale la BRI ha raccolto le risposte entro la fine di dicembre 2021, mostra che il lavoro sulle CBDC al dettaglio &egrave; in una fase pi&ugrave; sviluppata rispetto al lavoro sulle CBDC all&#8217;ingrosso. Quasi il 20% delle banche centrali sta avanzando o testando una CBDC al dettaglio. &Egrave; il doppio della quota di banche centrali che costruiscono o pilotano una CBDC all&#8217;ingrosso, secondo il documento.<\/p><blockquote>\r\n<p>&#8220;A livello globale, pi&ugrave; di due terzi delle banche centrali ritengono che probabilmente emetteranno o potrebbero emettere una CBDC al dettaglio nel breve o medio termine&#8221;, si legge nel rapporto.<\/p>\r\n<\/blockquote><p>Secondo la BRI, 9 banche centrali su 10 stanno esplorando le CBDC e:<\/p><blockquote>\r\n<p>&#8220;Pi&ugrave; della met&agrave; le sta sviluppando o sta conducendo esperimenti concreti. In particolare, il lavoro sulle CBDC al dettaglio &egrave; passato a fasi pi&ugrave; avanzate&#8221;.<\/p>\r\n<\/blockquote><p>La banca dice che sia la pandemia COVID-19 che l&#8217;emergere di stablecoin e crypto hanno accelerato il lavoro delle banche centrali sulle CBDC, in particolare nelle economie avanzate, dove gli istituti intervistati hanno dichiarato che la stabilit&agrave; finanziaria &egrave; aumentata di importanza come motivazione per il coinvolgimento in progetti CBDC.<\/p><p>In media, il 79% delle banche centrali delle economie avanzate ha dichiarato che l&#8217;emergere di stablecoin e criptoasset ha accelerato il loro lavoro sulle CBDC, rispetto al 48% delle banche centrali dei mercati emergenti e delle economie in via di sviluppo.<\/p><p>La BRI trova anche che assicurare l&#8217;efficienza dei pagamenti transfrontalieri &egrave; sempre pi&ugrave; una ragione alla base del lavoro sulle CBDC all&#8217;ingrosso.<\/p><blockquote>\r\n<p>&#8220;Le banche centrali considerano le CBDC in grado di alleviare punti dolenti chiave come gli orari di funzionamento limitati degli attuali sistemi di pagamento e la lunghezza delle attuali catene di transazioni&#8221;, dice il documento.<\/p>\r\n<\/blockquote><p>Con sede a Basilea, in Svizzera, la BRI dice di essere di propriet&agrave; congiunta delle 62 banche centrali del mondo, che rappresentano paesi che insieme costituiscono circa il 95% del prodotto interno lordo (PIL) globale.<\/p><p>_______<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a href=\"https:\/\/t.me\/ItaliaCryptonews\" target=\"_blank\" rel=\"noopener\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a href=\"https:\/\/twitter.com\/cryptonews_IT\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\" target=\"_blank\" rel=\"noopener\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0=CN-IT\" target=\"_blank\" rel=\"noopener\">Ledger<\/a> e <a href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\" target=\"_blank\" rel=\"noopener\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\" target=\"_blank\" rel=\"noopener\">NordVPN<\/a><\/p><p>_______<\/p><p>Per saperne di pi&ugrave;:<br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/work-multi-cbdc-platform-revealed-more-questions-than-answers-bis-it\/\" target=\"_blank\" rel=\"noopener\">Piattaforma multi-CBDC rivela pi&ugrave; domande che risposte<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/news\/bis-indicates-cbdc-issuance-may-hinge-on-private-sector-coll-8507\/\" target=\"_blank\" rel=\"noopener\">BIS Indicates CBDC Issuance May Hinge on Private Sector Collaboration<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/russia-sanctions-may-lead-more-countries-consider-cbdcs-ex-central-banker-says-it\/\" target=\"_blank\" rel=\"noopener\">Sanzioni russe: pi&ugrave; paesi potrebbero considerare le CBDC<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/russian-tax-body-suggests-allowing-crypto-pay-trade-deals-digital-ruble-may-ready-by-2023-it\/\" target=\"_blank\" rel=\"noopener\">Russia: aziende commerciali potranno pagare in criptovalute?<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/news\/digital-yuan-now-being-used-pay-taxes-chinese-pilot-zones\/\" target=\"_blank\" rel=\"noopener\">Digital Yuan Now Being Used to Pay Taxes in Chinese Pilot Zones<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/news\/us-senator-suggests-banning-fed-from-issuing-direct-consumer-cbdc-it\/\" target=\"_blank\" rel=\"noopener\">Senatore USA vieta di emettere CBDC diretta al privato<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/cbdcs-2022-new-trials-competition-with-crypto-it\/\" target=\"_blank\" rel=\"noopener\">CBDC nel 2022: nuovi pilot e concorrenza con le crypto<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: AdobeStock \/ Proxima Studio&nbsp;Un numero crescente di Banche Centrali a livello globale ha l&#8217;autorit&agrave; legale di emettere &#8220;valute digitali della banca centrale&#8221; (CBDC) e, rispetto all&#8217;anno precedente, la percentuale di banche centrali che stanno attualmente sviluppando una CBDC o eseguendo un progetto pilota &egrave; quasi raddoppiata dal 14% al 26%, secondo un nuovo rapporto [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[422,569,51],"editors":[306],"sponsored_companies":[],"class_list":["post-78029","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-banca-centrale","tag-cdbc","tag-stablecoin","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC<\/title>\n<meta name=\"description\" content=\"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC\" \/>\n<meta property=\"og:description\" content=\"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-06T08:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC\" \/>\n<meta name=\"twitter:description\" content=\"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/78018\/189700\/adobestock-proxima-studio-1-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC","description":"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/","og_locale":"it_IT","og_type":"article","og_title":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC","og_description":"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.","og_url":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-05-06T08:58:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC","twitter_description":"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.","twitter_image":"https:\/\/cimg.co\/news\/78018\/189700\/adobestock-proxima-studio-1-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/"},"author":{"name":"michellebattivacl","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/bd64bdc321d80e524a345a9344a55ed5"},"headline":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC","datePublished":"2022-05-06T08:58:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/"},"wordCount":565,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg","keywords":["banca centrale","CBDC","stablecoin"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/","url":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/","name":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg","datePublished":"2022-05-06T08:58:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il rapporto della BRI ha rilevato che circa il 62% delle banche centrali sta eseguendo esperimenti o proofs-of-concept relativi alle CBDC.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg","contentUrl":"https:\/\/cimg.co\/news\/78029\/189709\/cbdc-banche-centrali.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/number-of-central-banks-involved-in-cbdc-projects-almost-doubles-year-on-year-bis-report-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sempre pi\u00f9 Banche Centrali stanno sviluppando una CBDC"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/78029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=78029"}],"version-history":[{"count":2,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/78029\/revisions"}],"predecessor-version":[{"id":173166,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/78029\/revisions\/173166"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=78029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=78029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=78029"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=78029"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=78029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}