{"id":76269,"date":"2022-04-14T10:03:00","date_gmt":"2022-04-14T10:03:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=76269"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/","title":{"rendered":"Avalanche verso nuovo round di finanziamento; AVAX impenna"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg\" alt=\"AVAX Avalanche\" srcset=\"https:\/\/cimg.co\/news\/76269\/180584\/responsive-images\/avax-avalanche___media_library_original_1200_804.jpg 1200w, https:\/\/cimg.co\/news\/76269\/180584\/responsive-images\/avax-avalanche___media_library_original_900_603.jpg 900w, https:\/\/cimg.co\/news\/76269\/180584\/responsive-images\/avax-avalanche___media_library_original_720_482.jpg 720w, https:\/\/cimg.co\/news\/76269\/180584\/responsive-images\/avax-avalanche___media_library_original_600_402.jpg 600w, https:\/\/cimg.co\/news\/76269\/180584\/responsive-images\/avax-avalanche___media_library_original_300_201.jpg 300w\" width=\"1200\" class=\"content-img\"><figcaption>Fonte: AdobeStock \/ AndriiKoval<\/figcaption><\/figure><p class=\"wp-block-paragraph\">&nbsp;<\/p><p>Con <i>Ava Labs<\/i>, lo sviluppatore principale della blockchain <strong>Avalanche<\/strong>, che sembra voler perseguire un nuovo round di finanziamento possibilmente diventando una delle startup cripto-focalizzate pi&ugrave; valutate, il prezzo della sua moneta nativa <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/avax-avalanche\/\"><strong>AVAX<\/strong><\/a> sta accelerando verso l&#8217;alto.<\/p><p>Al fine di sostenere la sua ulteriore espansione, l&#8217;azienda sta cercando circa 350 milioni di dollari di finanziamento ad una valutazione di circa 5,25 miliardi di dollari, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.bloomberg.com\/news\/articles\/2022-04-14\/crypto-startup-ava-labs-is-said-to-raise-at-5-billion-valuation\">ha dichiarato<\/a> a Bloomberg una persona vicina al progetto.<\/p><p>Alle 8:34 UTC, il prezzo di AVAX era in aumento del 4,8% su un periodo di 24 ore. Negli ultimi 30 giorni, il prezzo dell&#8217;altcoin &egrave; aumentato del 18%, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.coingecko.com\/en\/coins\/avalanche\">secondo<\/a> i dati di Coingecko.com. Questo d&agrave; ad AVAX una capitalizzazione di mercato attuale di 21,74 miliardi di dollari.<\/p><h2>Il prezzo di AVAX in 24h<\/h2><span class=\"replacer\"><\/span><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"AVAX capitalizzazione\" width=\"708\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/76269\/180586\/avax-capitalizzazione.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/76269\/180586\/responsive-images\/avax-capitalizzazione___media_library_original_708_645.jpg 708w, https:\/\/cimg.co\/news\/76269\/180586\/responsive-images\/avax-capitalizzazione___media_library_original_600_546.jpg 600w, https:\/\/cimg.co\/news\/76269\/180586\/responsive-images\/avax-capitalizzazione___media_library_original_300_273.jpg 300w\"><figcaption>Grafico del prezzo di AVAX 24h. Fonte: coingecko.com<\/figcaption><\/figure><p>Avalanche si &egrave; impegnata per competere contro blockchain pi&ugrave; importanti, offrendo ai suoi utenti velocit&agrave; relativamente elevate e basse commissioni di transazione per varie applicazioni, tra cui il trading, il prestito e il gaming.<\/p><p>Ava Labs sostiene che &#8220;Avalanche &egrave; la pi&ugrave; veloce piattaforma di smart contract nell&#8217;industria blockchain, come misurato dal time-to-finality&#8221; e che ha &#8220;il maggior numero di validatori che garantiscono la sua attivit&agrave; di qualsiasi protocollo proof-of-stake&#8221;. I fondatori hanno dichiarato che la blockchain offre una finalit&agrave; transazionale di meno di due secondi.<\/p><p>Sostengono anche che l&#8217;implementazione di &#8220;smart contract su Avalanche costano solo un decimo di quello che costano su <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/ethereum\/\">Ethereum<\/a>&#8220;.<\/p><p>Lo scorso settembre, un investimento di 230 milioni di dollari nella blockchain &egrave; stato guidato da <i>Polychain<\/i> e <i>Three Arrows Capital<\/i>, affiancati da <i>R\/Crypto Fund, Dragonfly, CMS Holdings, Collab+Currency, Lvna Capital<\/i>, cos&igrave; come un gruppo di investitori informali e family office, la <i>Fondazione Avalanche<\/i> ha detto in una <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/medium.com\/avalancheavax\/polychain-capital-three-arrows-capital-lead-230m-investment-in-avalanche-ecosystem-1f0622fdf03a\">dichiarazione<\/a>.<\/p><p>La fondazione ha detto che mira a utilizzare i fondi acquisiti per sostenere e accelerare la crescita della finanza decentralizzata (<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/tags\/defi\">DeFi<\/a>), applicazioni aziendali e altri casi d&#8217;uso sulla blockchain pubblica Avalanche, affermando che: &#8220;Il sostegno ai progetti includer&agrave; sovvenzioni, acquisti di token e varie forme di investimenti e supporto tecnologico&#8221;.<\/p><p>_______<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0=CN-IT\">Ledger<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><\/p><p>_______<\/p><p>Per saperne di pi&ugrave;:&nbsp;<br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/april-is-historically-very-strong-month-for-btc-avax-luna-show-potential-say-exchanges-analysts-it\/\">Aprile &egrave; storicamente un &#8220;mese molto forte&#8221; per BTC<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/avalanche-announces-bitcoin-bridge-new-wallet-coinbase-cloud-launches-avalanche-developer-tools-suite-it\/\">Avalanche annuncia Bitcoin Bridge e un nuovo wallet<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/new-usd-560m-crypto-fund-binance-ceo-eyed-abramovichs-chelsea-visa-mastercard-fees-more-news\/\">Avalanche Foundation Launches Avalanche Multiverse<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/crypto-bottom-massive-rally-awaits-pantera-capital-predicts-it\/\">CEO di Pantera Capital: crypto market attende un forte rally<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: AdobeStock \/ AndriiKoval&nbsp;Con Ava Labs, lo sviluppatore principale della blockchain Avalanche, che sembra voler perseguire un nuovo round di finanziamento possibilmente diventando una delle startup cripto-focalizzate pi&ugrave; valutate, il prezzo della sua moneta nativa AVAX sta accelerando verso l&#8217;alto.Al fine di sostenere la sua ulteriore espansione, l&#8217;azienda sta cercando circa 350 milioni di dollari [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[102,496],"editors":[306],"sponsored_companies":[],"class_list":["post-76269","post","type-post","status-publish","format-standard","hentry","category-altcoin-news","category-news","tag-defi","tag-investimenti","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avalanche verso nuovo round di finanziamento; AVAX impenna<\/title>\n<meta name=\"description\" content=\"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l&#039;alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avalanche verso nuovo round di finanziamento; AVAX impenna\" \/>\n<meta property=\"og:description\" content=\"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l&#039;alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-14T10:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Avalanche verso nuovo round di finanziamento; AVAX impenna\" \/>\n<meta name=\"twitter:description\" content=\"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l&#039;alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avalanche verso nuovo round di finanziamento; AVAX impenna","description":"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l'alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/","og_locale":"it_IT","og_type":"article","og_title":"Avalanche verso nuovo round di finanziamento; AVAX impenna","og_description":"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l'alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.","og_url":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-04-14T10:03:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Avalanche verso nuovo round di finanziamento; AVAX impenna","twitter_description":"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l'alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.","twitter_image":"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/"},"author":{"name":"michellebattivacl","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/bd64bdc321d80e524a345a9344a55ed5"},"headline":"Avalanche verso nuovo round di finanziamento; AVAX impenna","datePublished":"2022-04-14T10:03:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/"},"wordCount":470,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg","keywords":["defi","investimenti"],"articleSection":["Altcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/","url":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/","name":"Avalanche verso nuovo round di finanziamento; AVAX impenna","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg","datePublished":"2022-04-14T10:03:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il prezzo della moneta nativa AVAX di Avalanche sta accelerando verso l'alto mentre il suo sviluppatore cerca 350M di dollari di finanziamento.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg","contentUrl":"https:\/\/cimg.co\/news\/76269\/180584\/avax-avalanche.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/avax-price-rides-wave-as-avalanche-developer-reportedly-seeks-usd-350m-in-funding-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Avalanche verso nuovo round di finanziamento; AVAX impenna"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/76269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=76269"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/76269\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=76269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=76269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=76269"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=76269"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=76269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}