{"id":73111,"date":"2022-03-08T09:59:00","date_gmt":"2022-03-08T09:59:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=73111"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"these-are-latest-crypto-regulatory-moves-by-us-eu-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/","title":{"rendered":"Le ultime mosse sulla regolamentazione crypto di USA e UE"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg\" alt=\"Regolamentazione USA UE\" srcset width class=\"content-img\"><figcaption>Joe Biden. Fonte: a video screenshot, CNBC television \/ YouTube<\/figcaption><\/figure><p class=\"wp-block-paragraph\">&nbsp;<\/p><p>Mentre il presidente degli Stati Uniti Joe Biden starebbe per firmare un nuovo ordine esecutivo relativo alle criptovalute e alle valute digitali delle banche centrali (<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/tags\/cbdc\/\">CBDC<\/a>), l&#8217;Unione europea &egrave; pronta per un voto sul tanto discusso quadro <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/a-new-wave-of-regulatory-obligations-over-crypto-players-in-7733\/\">MiCA<\/a> (Markets in Crypto Assets).<\/p><h2>USA si avvicinano alla creazione di una CBDC<\/h2><span class=\"replacer\"><\/span><p>Biden dovrebbe firmare l&#8217;ordine esecutivo questa settimana, incaricando diverse agenzie federali di esplorare la sicurezza nazionale e l&#8217;impatto economico degli asset digitali, cos&igrave; come di studiare le ramificazioni della creazione di una CBDC.<\/p><p>L&#8217;ordine fisserebbe una scadenza di 180 giorni per le agenzie (il <i>Dipartimento del Tesoro, il Dipartimento del Commercio<\/i>, la National Science Foundation e le Agenzie per la sicurezza nazionale), per consegnare rapporti sugli asset digitali e &#8220;il futuro del denaro&#8221;, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.reuters.com\/business\/finance\/biden-sign-executive-order-cryptocurrencies-this-week-source-2022-03-07\/\">ha riportato<\/a> Reuters, citando persone che sono vicine alla questione.<\/p><blockquote><p>&#8220;Potremmo vedere un cambiamento significativo in 180 giorni. Questo &egrave; un probabile passo verso la creazione di una valuta digitale della banca centrale&#8221;, ha detto il rapporto.<\/p><\/blockquote><p>Pi&ugrave; specificamente, l&#8217;ordine dovrebbe chiedere al Dipartimento di Giustizia di esplorare se una nuova legge &egrave; necessaria per gestire gli asset digitali, mentre la Federal Trade Commission, la Consumer Financial Protection Commission, e altre agenzie si concentrerebbero principalmente sull&#8217;impatto sui consumatori.<\/p><p>L&#8217;ordine arriva nel momento in cui sono aumentate le preoccupazioni per l&#8217;uso delle criptovalute da parte di &#8220;Vladimir Putin e i suoi compari&#8221; per eludere le sanzioni economiche internazionali.<\/p><p>&#8220;I criminali possono usare le criptovalute per spostare denaro nell&#8217;ombra, aprendo una porta per Putin e i suoi compari per eludere le sanzioni economiche&#8221;, ha detto la senatrice Elizabeth Warren, chiedendo al Tesoro degli Stati Uniti di garantire che le criptovalute non compromettano l&#8217;efficienza delle sanzioni.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/SenWarren\/status\/1499380461587496962\"><\/oembed><\/figure><p>Tuttavia, i veterani delle crypto hanno smentito questa affermazione, sostenendo che la loro natura trasparente le rende uno strumento inefficiente per gli evasori di sanzioni.<\/p><p>&#8220;Gli asset digitali possono effettivamente migliorare la nostra capacit&agrave; di rilevare e scoraggiare l&#8217;evasione rispetto al sistema finanziario tradizionale&#8221;, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/crypto-can-better-deter-sanction-evasion-compared-tradfi-coinbase-it\/\">ha detto<\/a> Paul Grewal, Chief Legal Officer (CLO) del famoso crypto exchange <a target=\"_blank\" rel=\"noopener  sponsored nofollow\" href=\"https:\/\/rapi.cryptonews.com\/ext\/coinbase\/en\">Coinbase<\/a>.<\/p><h2>L&#8217;UE verso una regolamentazione crypto all&#8217;avanguardia<\/h2><span class=\"replacer\"><\/span><p>Nell&#8217;UE, nel frattempo, il <i>comitato monetario<\/i> del parlamento dell&#8217;Unione europea ha programmato un voto sul quadro dei mercati delle criptovalute (MiCA) il 14 marzo dopo la presentazione di una bozza finale del disegno di legge.<\/p><p>Una prima bozza del disegno di legge includeva una formulazione che avrebbe potuto vietare le criptovalute proof-of-work (PoW) come il <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\">bitcoin (BTC)<\/a>. Tuttavia, Stefan Berger, un membro del Parlamento europeo incaricato di guidare il MiCA, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/DrStefanBerger\/status\/1500852921419902991\">ha affermato<\/a> che &#8220;una discussione separata&#8221; sulla PoW non &egrave; pi&ugrave; prevista.<\/p><blockquote><p>&#8220;Con MiCA, l&#8217;UE pu&ograve; stabilire standard globali&#8221;, si legge in una traduzione approssimativa del tweet di Berger. &#8220;Pertanto, tutte le persone coinvolte sono ora invitate a sostenere il progetto presentato e a votare per MiCA. Un forte sostegno al MiCA &egrave; un forte segnale dal <i>Parlamento europeo<\/i> per un settore finanziario neutrale dal punto di vista tecnologico e favorevole all&#8217;innovazione&#8221;.<\/p><\/blockquote><p>Berger ha sostenuto che il quadro MiCA offre una &#8220;regolamentazione delle criptovalute all&#8217;avanguardia in termini di innovazione, protezione dei consumatori, certezza del diritto e la creazione di strutture di vigilanza affidabili nel settore dei crypto asset.&#8221;<\/p><p>_______<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0=CN-IT\">Ledger<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><\/p><p>_______<\/p><p>Per saperne di pi&ugrave;:<\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/council-of-european-union-advances-talks-on-mica-dora-regulations\/\">Council of European Union Advances Talks On MiCA, DORA Regulations<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/germany-led-group-wants-new-eu-watchdog-regulate-crypto-firms-it\/\"><u>UE vuole un&#8217;autorit&agrave; di controllo per gli exchange crypto<\/u><\/a><br><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/us-fed-wants-answers-22-questions-about-digital-dollar-it\/\"><u>Fed USA cerca risposte a 22 domande sul dollaro digitale<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/us-regulator-launches-probe-into-nft-sales-it\/\"><u>Regolatore statunitense lancia indagine sulle vendite di NFT<\/u><\/a><br><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/washington-europe-vow-target-russian-crypto-sanctions-evasion-efforts-it\/\"><u>USA e EU mirano i tentativi russi di evasione nelle crypto<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/crypto-can-better-deter-sanction-evasion-compared-tradfi-coinbase-it\/\"><u>Le crypto possono contrastare meglio l&#8217;evasione di sanzioni<\/u><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Joe Biden. Fonte: a video screenshot, CNBC television \/ YouTube&nbsp;Mentre il presidente degli Stati Uniti Joe Biden starebbe per firmare un nuovo ordine esecutivo relativo alle criptovalute e alle valute digitali delle banche centrali (CBDC), l&#8217;Unione europea &egrave; pronta per un voto sul tanto discusso quadro MiCA (Markets in Crypto Assets).USA si avvicinano alla creazione [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[569,72,505],"editors":[],"sponsored_companies":[],"class_list":["post-73111","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-cdbc","tag-regolamentazione","tag-usa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le ultime mosse sulla regolamentazione crypto di USA e UE<\/title>\n<meta name=\"description\" content=\"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l&#039;UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le ultime mosse sulla regolamentazione crypto di USA e UE\" \/>\n<meta property=\"og:description\" content=\"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l&#039;UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-08T09:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le ultime mosse sulla regolamentazione crypto di USA e UE\" \/>\n<meta name=\"twitter:description\" content=\"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l&#039;UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/73105\/165173\/jb-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le ultime mosse sulla regolamentazione crypto di USA e UE","description":"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l'UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/","og_locale":"it_IT","og_type":"article","og_title":"Le ultime mosse sulla regolamentazione crypto di USA e UE","og_description":"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l'UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.","og_url":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-03-08T09:59:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Le ultime mosse sulla regolamentazione crypto di USA e UE","twitter_description":"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l'UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.","twitter_image":"https:\/\/cimg.co\/news\/73105\/165173\/jb-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/"},"author":{"name":"michellebattivacl","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/bd64bdc321d80e524a345a9344a55ed5"},"headline":"Le ultime mosse sulla regolamentazione crypto di USA e UE","datePublished":"2022-03-08T09:59:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/"},"wordCount":693,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg","keywords":["CBDC","regolamentazione","usa"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/","url":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/","name":"Le ultime mosse sulla regolamentazione crypto di USA e UE","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg","datePublished":"2022-03-08T09:59:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il presidente degli USA sta per firmare un nuovo ordine esecutivo relativo alle crypto e alle CBDC; l'UE \u00e8 pronta per un voto sul tanto discusso quadro MiCA.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg","contentUrl":"https:\/\/cimg.co\/news\/73111\/165256\/regolamentazione-usa-ue.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/these-are-latest-crypto-regulatory-moves-by-us-eu-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Le ultime mosse sulla regolamentazione crypto di USA e UE"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/73111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=73111"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/73111\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=73111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=73111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=73111"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=73111"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=73111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}