{"id":71490,"date":"2022-02-16T11:46:00","date_gmt":"2022-02-16T11:46:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=71490"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/","title":{"rendered":"FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg\" alt=\"FSB defi crypto\" srcset=\"https:\/\/cimg.co\/news\/71490\/66486\/responsive-images\/fsb-defi-crypto___media_library_original_1200_812.jpg 1200w, https:\/\/cimg.co\/news\/71490\/66486\/responsive-images\/fsb-defi-crypto___media_library_original_900_609.jpg 900w, https:\/\/cimg.co\/news\/71490\/66486\/responsive-images\/fsb-defi-crypto___media_library_original_720_487.jpg 720w, https:\/\/cimg.co\/news\/71490\/66486\/responsive-images\/fsb-defi-crypto___media_library_original_600_406.jpg 600w, https:\/\/cimg.co\/news\/71490\/66486\/responsive-images\/fsb-defi-crypto___media_library_original_300_203.jpg 300w\" sizes=\"100vw\" width=\"1200\"><figcaption>Fonte: AdobeStock \/ Jarretera<\/figcaption><\/figure><p class=\"wp-block-paragraph\">&nbsp;<\/p><p>Il <i>Financial Stability Board<\/i> (<strong>FSB<\/strong>), un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi&ugrave; spesso l&#8217;allarme sulle <strong>crypto<\/strong>. L&#8217;ultimo <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.fsb.org\/wp-content\/uploads\/P160222.pdf\">rapporto<\/a> dell&#8217;istituzione sostiene che i mercati di criptoasset sono in rapida evoluzione e potrebbero raggiungere un punto in cui rappresentano una minaccia alla stabilit&agrave; finanziaria globale a causa della loro scala, delle vulnerabilit&agrave; strutturali, cos&igrave; come della crescente interconnessione con il sistema finanziario tradizionale.<\/p><p>&#8220;La capitalizzazione di mercato delle criptovalute &egrave; cresciuta di 3,5 volte nel 2021 raggiungendo i 2,6 trilioni di dollari, eppure le criptovalute rimangono una piccola parte degli asset del sistema finanziario globale&#8221;, ha detto l&#8217;FSB in una <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.fsb.org\/2022\/02\/assessment-of-risks-to-financial-stability-from-crypto-assets\/\">dichiarazione<\/a> che riassume i risultati del rapporto. Le connessioni dirette tra criptovalute e istituzioni finanziarie di rilevanza e i mercati finanziari di base, ha detto, pur crescendo rapidamente, sono attualmente limitate.<\/p><p>Allo stesso tempo, il coinvolgimento istituzionale nei mercati delle criptovalute, sia come investitori che come fornitori di servizi, &egrave; cresciuto nell&#8217;ultimo anno.<\/p><blockquote><p>&#8220;Se l&#8217;attuale traiettoria di crescita e interconnessione delle criptovalute alle istituzioni dovesse continuare, questo potrebbe avere implicazioni per la stabilit&agrave; finanziaria globale&#8221;, secondo il consiglio.<\/p><\/blockquote><p>L&#8217;FSB percepisce che la finanza decentralizzata (<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/tags\/defi\/\">DeFi<\/a>) si &egrave; affermata come un settore in rapida ascesa, mentre un numero relativamente piccolo di piattaforme di trading di criptovalute aggregano vari tipi di servizi e attivit&agrave;, come il prestito e la custodia.&nbsp;<\/p><p>Alcune di queste piattaforme eseguono le loro operazioni al di fuori del quadro normativo di una giurisdizione, o non sono in conformit&agrave; con le leggi e i regolamenti nazionali applicabili che potrebbero potenzialmente portare a una concentrazione di rischi, e sottolineerebbero la mancanza di trasparenza sulle loro attivit&agrave;, hanno sostenuto.<\/p><blockquote><p>&#8220;In parte a causa dell&#8217;emergere della DeFi, la crescita delle stablecoin &egrave; continuata, nonostante le preoccupazioni circa la conformit&agrave; normativa, la qualit&agrave;, la sufficienza delle riserve, e gli standard di gestione del rischio e di governance&#8221;, secondo l&#8217;organismo.<\/p><\/blockquote><p>Le stablecoin, attualmente, sono utilizzate principalmente come un ponte tra le valute fiat e le criptovalute, il che porta implicazioni per la stabilit&agrave; e il funzionamento dei mercati globali delle criptovalute. Tuttavia, se un&#8217;importante stablecoin dovesse fallire, &egrave; possibile che la liquidit&agrave; all&#8217;interno del pi&ugrave; ampio ecosistema di criptoasset che include DeFi potrebbe diventare limitata e potrebbe interrompere il trading, innescando potenzialmente lo stress in quei mercati, ha detto l&#8217;FSB.<\/p><blockquote><p>&#8220;Questo potrebbe anche riversarsi sui mercati di finanziamento a breve termine qualora le riserve di stablecoin fossero liquidate in modo disordinato&#8221;, afferma il consiglio.<\/p><\/blockquote><h2>FSB continuer&agrave; a monitorare DeFi e Crypto<\/h2><span class=\"replacer\"><\/span><p>Il FSB dice che intende continuare a monitorare gli sviluppi e i rischi nel campo delle criptovalute, esplorare le potenziali implicazioni normative e di supervisione di tali asset non garantiti per affrontare le minacce alla stabilit&agrave; finanziaria.<\/p><p>Considerando il panorama delle criptovalute, il rapporto dell&#8217;FSB ha elencato le seguenti aree per la vigilanza continua:<\/p><ul><li>crescente coinvolgimento del settore bancario nell&#8217;ecosistema delle criptovalute, in particolare dove le attivit&agrave; danno origine a un&#8217;esposizione di bilancio alle criptovalute, non coperta da, o non conforme a, un trattamento normativo appropriato;<\/li><li>gli investitori istituzionali che espandono le loro esposizioni alle criptovalute rispetto alle dimensioni dei loro portfolio; i rischi potrebbero aumentare ulteriormente se tali esposizioni utilizzano alti livelli di leva finanziaria, anche attraverso l&#8217;uso di derivati basati sulle criptovalute;<\/li><li>accelerazione nell&#8217;adozione delle criptovalute per i pagamenti &#8211; questo potrebbe essere fatto attraverso partnership con imprese di pagamento consolidate o rivenditori\/network sociali;<\/li><li>l&#8217;aumento, il ruolo e i rischi associati alle piattaforme di trading di criptovalute;<\/li><li>le perdite nelle criptovalute, quando sono accompagnate da leva finanziaria, mancanza di liquidit&agrave; e interconnessioni con il sistema finanziario tradizionale, possono rafforzare i rischi sistemici derivanti dagli effetti di ricchezza; la perdita di fiducia nelle stablecoin potrebbe anche portare alla vendita delle loro riserve, con un potenziale impatto sul funzionamento dei mercati di finanziamento a breve termine;<\/li><li>la rapida crescita della DeFi, in assenza di intermediari chiaramente identificabili o di parti responsabili della governance, sfida le discipline e le dottrine di regolamentazione e supervisione del nucleo finanziario (stabilit&agrave;);<\/li><li>i diversi approcci normativi potrebbero innescare l&#8217;arbitraggio regolamentare, aumentando i potenziali rischi sistemici;<\/li><li>lacune di dati che impediscono la valutazione del rischio e la calibrazione delle opzioni di policy.<\/li><\/ul><p>_______<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0=CN-IT\">Ledger<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><\/p><p>_______<\/p><p>Per saperne di pi&ugrave;:<br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/during-april-btc-peak-61-of-surveyed-financial-institutions-said-crypto-access-extremely-important-it\/\"><u>L&#8217;importanza delle crypto per le istituzioni finanziarie<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/hard-regulate-crypto-without-global-consensus-admits-top-imf-official-it\/\"><u>FMI &#8220;Per regolare le criptovalute serve un consenso globale&#8221;<\/u><\/a><br><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/hard-regulate-crypto-without-global-consensus-admits-top-imf-official-it\/\"><u>FMI &#8220;Per regolare le criptovalute serve un consenso globale&#8221;<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/us-senators-fail-find-stable-ground-stablecoins\/\">US Senators Fail to Find Stable Ground on Stablecoins<\/a><br><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/2022-crypto-regulation-trends-focus-on-defi-stablecoins-nfts-and-more-it\/\"><u>Tendenze 2022 della regolamentazione crypto<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/defi-trends-2022-growing-interest-regulation-new-roles-for-daos-dexes-nfts-gaming-it\/\"><u>Previsioni 2022 del settore DeFi<\/u><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: AdobeStock \/ Jarretera&nbsp;Il Financial Stability Board (FSB), un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi&ugrave; spesso l&#8217;allarme sulle crypto. L&#8217;ultimo rapporto dell&#8217;istituzione sostiene che i mercati di criptoasset sono in rapida evoluzione e potrebbero raggiungere un punto in cui rappresentano una minaccia alla stabilit&agrave; finanziaria globale a [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[102,536,72,51],"editors":[306],"sponsored_companies":[],"class_list":["post-71490","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-defi","tag-mercato","tag-regolamentazione","tag-stablecoin","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi<\/title>\n<meta name=\"description\" content=\"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l&#039;allarme sulle crypto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi\" \/>\n<meta property=\"og:description\" content=\"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l&#039;allarme sulle crypto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-16T11:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi\" \/>\n<meta name=\"twitter:description\" content=\"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l&#039;allarme sulle crypto.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi","description":"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l'allarme sulle crypto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/","og_locale":"it_IT","og_type":"article","og_title":"Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi","og_description":"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l'allarme sulle crypto.","og_url":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2022-02-16T11:46:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi","twitter_description":"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l'allarme sulle crypto.","twitter_image":"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/"},"author":{"name":"michellebattivacl","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/bd64bdc321d80e524a345a9344a55ed5"},"headline":"FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi","datePublished":"2022-02-16T11:46:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/"},"wordCount":860,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg","keywords":["defi","Mercato","regolamentazione","stablecoin"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/","url":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/","name":"Il FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg","datePublished":"2022-02-16T11:46:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il FSB, un organismo internazionale che monitora e prepara avvertimenti sul sistema finanziario globale, suona sempre pi\u00f9 spesso l'allarme sulle crypto.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg","contentUrl":"https:\/\/cimg.co\/news\/71490\/66486\/fsb-defi-crypto.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/global-watchdog-points-at-growing-force-of-crypto-with-another-usual-warning-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"FSB lancia sempre pi\u00f9 avvertimenti sulle crypto e la DeFi"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/71490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=71490"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/71490\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=71490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=71490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=71490"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=71490"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=71490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}