{"id":66252,"date":"2021-12-07T16:14:00","date_gmt":"2021-12-07T16:14:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=66252"},"modified":"2023-02-08T12:44:36","modified_gmt":"2023-02-08T12:44:36","slug":"aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/","title":{"rendered":"Exchange di criptovalute crolla per accuse di fondi mancanti"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg\" alt=\"criptovalute\" width=\"1200\" class=\"content-img\"><figcaption>Fonte: AdobeStock \/ Clivia<\/figcaption><\/figure><p class=\"wp-block-paragraph\">L&#8217;<strong>exchange<\/strong> di <strong>criptovalute<\/strong> australiano <i>myCryptoWallet<\/i> &egrave; crollato a seguito di un&#8217;ondata di lamentele da parte degli utenti e accuse di <strong>fondi <\/strong>mancanti, lasciando potenzialmente alle spalle innumerevoli clienti privati &#8203;&#8203;dell&#8217;accesso ai loro asset <strong>crypto<\/strong>.<\/p><p>Secondo quanto <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.smh.com.au\/business\/companies\/troubled-exchange-mycryptowallet-bites-the-dust-after-barrage-of-complaints-20211207-p59fg4.html\">riportato<\/a> dal Sydney Morning Herald, la societ&agrave; di insolvenza SV Partners &egrave; stata nominata liquidatore dell&#8217;azienda in difficolt&agrave;.<\/p><p>Il sito web dell&#8217;exchange, che rimane attivo nonostante i suoi problemi finanziari, pubblicizza myCryptoWallet come &#8220;Il primo exchange di criptovalute a zero fees in Australia&#8221; e incoraggia gli utenti ad acquistare, vendere e scambiare criptovalute come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\">bitcoin (BTC)<\/a>, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/ethereum\">ethereum (ETH)<\/a> e<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/litecoin\"> litecoin (LTC)<\/a>, tra l&#8217;altro, utilizzando i suoi servizi.<\/p><p>Il sito web afferma che l&#8217;exchange australiano ha servito circa 30.000 clienti, scambiando circa 20 milioni di AUD (14,2 milioni di dollari) di criptovalute e fornendo supporto agli utenti con sede in 12 paesi.<\/p><p>Nonostante queste affermazioni, un&#8217;indagine, condotta dal quotidiano australiano The Age e The Sydney Morning Herald lo scorso aprile, ha rivelato che myCryptoWallet era a malapena funzionante e un certo numero di utenti ha segnalato problemi con l&#8217;accesso o il prelievo dei propri fondi.<\/p><p>Alcuni dei clienti dell&#8217;azienda hanno affermato che le loro criptovalute erano completamente scomparse.<\/p><p>Di conseguenza, i clienti insoddisfatti hanno presentato numerosi reclami all&#8217;autorit&agrave; di regolamentazione finanziaria del paese, l&#8217;Australian Securities and Investments Commission (ASIC). L&#8217;agenzia ha confermato che stava valutando i problemi segnalati e, a seguito della sua indagine, alcuni utenti hanno affermato di essere stati in grado di recuperare parte dei loro fondi dall&#8217;exchange.<\/p><p>Questo, tuttavia, non &egrave; stato il caso per la maggior parte dei clienti dell&#8217;azienda che ancora non possono accedere ai propri asset.<\/p><p>Istituito nel 2017 e con sede a Melbourne, l&#8217;exchange di criptovalute &egrave; stato fondato dall&#8217;imprenditore locale Jaryd Koenigsmann.<\/p><p>L&#8217;ultimo sviluppo segna un altro crollo di uno exchange di criptovalute australiano.&nbsp;<\/p><p>Secondo quanto <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.afr.com\/companies\/financial-services\/failed-crypto-company-collapses-owing-21m-20211103-p595n3\">riportato<\/a> dall&#8217;Australian Financial Review, all&#8217;inizio di quest&#8217;anno, Blockchain Global (BGL), la controllante dell&#8217;exchange locale di criptovalute ACX, &egrave; entrata in amministrazione controllata mentre doveva ai suoi creditori circa 21 milioni di AUD (14,9 milioni di dollari).<\/p><p>____<\/p><p>Seguici sui nostri canali social:<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;<\/p><p>Clicca sui nostri link di affiliazione:<\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/products\/crypto-starter-pack?r=12b53b98a1c0&amp;tracker=CN-IT\">Ledger<\/a>&nbsp;e&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><\/p><p>____<\/p><p>Per saperne di pi&ugrave;:<\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/final-and-binding-mt-gox-resolution-agreed-it\/\">Risoluzione &#8220;definitiva e vincolante&#8221; di Mt. Gox concordata<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/french-crypto-investor-sues-australian-firm-after-klaytn-dea-9748-it\/\">Investitore cripto francese fa causa a una societ&agrave; australiana dopo che l&#8217;accordo di Klaytn &egrave; andato male<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/australian-bank-to-begin-offering-customers-bitcoin-eth-altcoin-services-in-2022-it\/\">Banca Australiana offrir&agrave; servizi per Bitcoin, Eth e Altcoin<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/australian-crypto-focused-etf-hits-record-spot-based-btc-eth-etfs-expected\/\">Australian Crypto-Focused ETF Hits Record, Spot-Based BTC, ETH ETFs Expected<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/check-these-12-crypto-regulation-recommendations-by-aussie-senate-committee-it\/\">Australia: 12 raccomandazioni sulla regolamentazione crypto<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/aussie-senator-says-crypto-blockchain-legislation-may-be-passed-next-year\/\">Aussie Senator Says Crypto, Blockchain Legislation May Be Passed Next Year<\/a><\/p><p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: AdobeStock \/ CliviaL&#8217;exchange di criptovalute australiano myCryptoWallet &egrave; crollato a seguito di un&#8217;ondata di lamentele da parte degli utenti e accuse di fondi mancanti, lasciando potenzialmente alle spalle innumerevoli clienti privati &#8203;&#8203;dell&#8217;accesso ai loro asset crypto.Secondo quanto riportato dal Sydney Morning Herald, la societ&agrave; di insolvenza SV Partners &egrave; stata nominata liquidatore dell&#8217;azienda in [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[56,757,100,112],"editors":[306],"sponsored_companies":[],"class_list":["post-66252","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-criptovalute","tag-crypto","tag-exchange","tag-trading","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exchange di criptovalute crolla per accuse di fondi mancanti<\/title>\n<meta name=\"description\" content=\"L&#039;exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un&#039;ondata di lamentele da parte degli utenti e accuse di fondi mancanti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exchange di criptovalute crolla per accuse di fondi mancanti\" \/>\n<meta property=\"og:description\" content=\"L&#039;exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un&#039;ondata di lamentele da parte degli utenti e accuse di fondi mancanti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-07T16:14:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T12:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Exchange di criptovalute crolla per accuse di fondi mancanti\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un&#039;ondata di lamentele da parte degli utenti e accuse di fondi mancanti.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/66247\/45716\/adobestock-clivia-1-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exchange di criptovalute crolla per accuse di fondi mancanti","description":"L'exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un'ondata di lamentele da parte degli utenti e accuse di fondi mancanti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/","og_locale":"it_IT","og_type":"article","og_title":"Exchange di criptovalute crolla per accuse di fondi mancanti","og_description":"L'exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un'ondata di lamentele da parte degli utenti e accuse di fondi mancanti.","og_url":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-12-07T16:14:00+00:00","article_modified_time":"2023-02-08T12:44:36+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Exchange di criptovalute crolla per accuse di fondi mancanti","twitter_description":"L'exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un'ondata di lamentele da parte degli utenti e accuse di fondi mancanti.","twitter_image":"https:\/\/cimg.co\/news\/66247\/45716\/adobestock-clivia-1-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"Exchange di criptovalute crolla per accuse di fondi mancanti","datePublished":"2021-12-07T16:14:00+00:00","dateModified":"2023-02-08T12:44:36+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/"},"wordCount":510,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg","keywords":["criptovalute","CRYPTO","exchange","trading"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/","url":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/","name":"Exchange di criptovalute crolla per accuse di fondi mancanti","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg","datePublished":"2021-12-07T16:14:00+00:00","dateModified":"2023-02-08T12:44:36+00:00","description":"L'exchange di criptovalute australiano myCryptoWallet \u00e8 crollato a seguito di un'ondata di lamentele da parte degli utenti e accuse di fondi mancanti.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg","contentUrl":"https:\/\/cimg.co\/news\/66252\/45720\/adobestock-clivia-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/aussie-crypto-exchange-sinks-amid-complaints-missing-fund-allegations-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Exchange di criptovalute crolla per accuse di fondi mancanti"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/66252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=66252"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/66252\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=66252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=66252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=66252"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=66252"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=66252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}