{"id":64763,"date":"2021-11-17T11:18:00","date_gmt":"2021-11-17T11:18:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=64763"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/","title":{"rendered":"Sandbox svela il prossimo evento Metaverso &#8211; Rally di SAND"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg\" alt=\"The Sandbox\" srcset=\"https:\/\/cimg.co\/news\/64763\/40241\/responsive-images\/the-sandbox___media_library_original_1200_800.jpg 1200w, https:\/\/cimg.co\/news\/64763\/40241\/responsive-images\/the-sandbox___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/64763\/40241\/responsive-images\/the-sandbox___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/64763\/40241\/responsive-images\/the-sandbox___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/64763\/40241\/responsive-images\/the-sandbox___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1200\" class=\"content-img\"><figcaption>Fonte: The Sandbox<\/figcaption><p class=\"wp-block-paragraph\">La piattaforma di gioco <strong>The Sandbox<\/strong> ha annunciato &#8220;The Sandbox Alpha&#8221;, un evento imminente che permetter&Atilde;&nbsp; ai giocatori di esplorare il <strong>metaverso<\/strong> dell&#8217;ecosistema per la prima volta e guadagnare premi nel processo.<\/p><p>La notizia aveva spinto <strong>SAND<\/strong>, il token nativo dell&#8217;ecosistema The Sandbox, al suo nuovo massimo storico di 3,63 USD, scendendo poi di quasi il 10%. Detto questo, ha guadagnato oltre il 28% nelle ultime 24 ore, secondo i dati di CoinGecko, cos&Atilde;&not; come quasi il 40% in una settimana. Alle 9:39 UTC, la 66a moneta per capitalizzazione di mercato ha un valore di 3,43 USD.<\/p><h2>Prezzo di SAND (7 giorni)<\/h2><span class=\"replacer\"><\/span><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"SAND token\" sizes=\"100vw\" width=\"840\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/64763\/40242\/sand-token.png\" data-srcset=\"https:\/\/cimg.co\/news\/64763\/40242\/responsive-images\/sand-token___media_library_original_840_593.png 840w, https:\/\/cimg.co\/news\/64763\/40242\/responsive-images\/sand-token___media_library_original_720_508.png 720w, https:\/\/cimg.co\/news\/64763\/40242\/responsive-images\/sand-token___media_library_original_600_423.png 600w, https:\/\/cimg.co\/news\/64763\/40242\/responsive-images\/sand-token___media_library_original_300_211.png 300w\"><figcaption>Grafico del prezzo a 7 giorni di SAND. Fonte: CoinGecko.com<\/figcaption><\/figure><p>&#8220;The Sandbox Alpha &Atilde;&uml; un evento aperto <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/play-to-earn-gaming-is-booming-from-axies-to-lightnite-heres-whats-out-there-it\/\">Play-to-Earn<\/a> di pi&Atilde;\u00b9 settimane che inizia il 29 novembre all&#8217;1PM UTC, in cui i giocatori avranno l&#8217;opportunit&Atilde;&nbsp; di esplorare il Metaverso di The Sandbox per la prima volta, attraverso 18 esperienze create dai team di The Sandbox&#8221;, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/medium.com\/sandbox-game\/introducing-the-sandbox-alpha-2052db44a9f9\">ha detto<\/a> il progetto.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/TheSandboxGame\/status\/1460599573987143684\"><\/oembed><\/figure><h2>Coun un Sandbox Alpha Pass premi fino a 1.000 dollari<\/h2><span class=\"replacer\"><\/span><p>I giocatori con un Alpha Pass, ovvero un biglietto con un token non fungibile (<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/tags\/nft\/\">NFT<\/a>) che permetter&Atilde;&nbsp; l&#8217;accesso completo a tutte le esperienze, saranno in grado di guadagnare fino a 1.000 dollari in SAND pi&Atilde;\u00b9 tre esclusive ricompense NFT. I giocatori senza un Alpha Pass, d&#8217;altra parte, possono accedere a tre esperienze e a una serie di missioni di gioco.<\/p><p>Il progetto mira a offrire 1.000 biglietti Alpha Pass a coloro che possiedono LAND in The Sandbox, un mondo virtuale dove i giocatori possono &#8220;costruire, possedere e monetizzare le loro esperienze di gioco&#8221;. Altri modi per ottenere un biglietto includono la partecipazione a concorsi social quotidiani o all&#8217;acquisto del biglietto sul marketplace di NFT <i>OpenSea<\/i>.<\/p><h2>Il valore dei terreni in The Sandbox<\/h2><span class=\"replacer\"><\/span><p>Nel frattempo, il valore dei terreni virtuali in The Sandbox &Atilde;&uml; salito alle stelle di recente. &#8221; Il terreno che &Atilde;&uml; stato venduto per 48 USD in una prevendita nel dicembre 2019 ora ha un prezzo di base di pi&Atilde;\u00b9 di 4.000 USD &#8220;, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/dappradar.com\/blog\/demand-virtual-land-in-the-sandbox-metaverse-reaches-record-heights\">ha riferito DappRadar<\/a> all&#8217;inizio di questo mese.<\/p><p>Durante il periodo di 7 giorni prima del 3 novembre, The Sandbox ha registrato un volume di trading di 7 milioni di dollari, con un aumento del 645%. Inoltre, il progetto ha registrato 4,2 milioni di dollari in volume di trading solo nei primi tre giorni di novembre, con il numero di trader cresciuto del 300%, secondo DappRadar.<\/p><p>4,2 milioni di dollari &Atilde;&uml; &#8220;pi&Atilde;\u00b9 di quanto la dapp ha generato nell&#8217;intero mese di settembre&#8221;, hanno detto, aggiungendo che &#8220;novembre diventer&Atilde;&nbsp; il pi&Atilde;\u00b9 grande mese di trading nella storia di The Sandbox&#8221;.<\/p><p>Nonostante l&#8217;aumento del prezzo del token, c&#8217;&Atilde;&uml; una grande richiesta di terreni virtuali in The Sandbox. I terreni si vendeono quasi istantaneamente, con un prezzo regolare di 1011 SAND (3.290 USD) per lotto. I terreni premium, quelli che circondano i principali social hub e che si prevede abbiano un maggiore traffico, si vendono ad un prezzo pi&Atilde;\u00b9 alto.<\/p><h2>The sandbox: vendite medie vs prezzo SAND<\/h2><span class=\"replacer\"><\/span><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"The sendbox SAND\" sizes=\"100vw\" width=\"1086\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/64763\/40243\/the-sendbox-sand.png\" data-srcset=\"https:\/\/cimg.co\/news\/64763\/40243\/responsive-images\/the-sendbox-sand___media_library_original_1086_450.png 1086w, https:\/\/cimg.co\/news\/64763\/40243\/responsive-images\/the-sendbox-sand___media_library_original_900_373.png 900w, https:\/\/cimg.co\/news\/64763\/40243\/responsive-images\/the-sendbox-sand___media_library_original_720_299.png 720w, https:\/\/cimg.co\/news\/64763\/40243\/responsive-images\/the-sendbox-sand___media_library_original_600_249.png 600w, https:\/\/cimg.co\/news\/64763\/40243\/responsive-images\/the-sendbox-sand___media_library_original_300_124.png 300w\"><figcaption>Fonte: DappRadar<\/figcaption><\/figure><p>All&#8217;inizio di giugno, un lotto di terreno virtuale &Atilde;&uml; stato venduto per 3,6 milioni di SAND, o circa 650.000 USD al momento dell&#8217;asta.<\/p><p>_______<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/products\/crypto-starter-pack?r=12b53b98a1c0&amp;tracker=CN-IT\">Ledger<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><\/p><p>_______<\/p><p>Per saperne di pi&Atilde;\u00b9:<\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/watch-microsoft-ceo-showcasing-metaverse-use-cases\/\">Watch Microsoft CEO Showcasing Metaverse Use-cases<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/\"><u>Il crypto-gaming sta esplodendo nel futuro dei giochi<\/u><\/a><br><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/tinder-bumble-fall-head-over-heels-for-crypto-metaverse-it\/\"><u>Tinder e Bumble verso il metaverso e le crypto<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/seoul-to-launch-metaverse-public-service-platform-in-2022-it\/\"><u>Seul lancer&Atilde;&nbsp; la piattaforma di servizio pubblico &#8216;Metaverso&#8217;<\/u><\/a><br><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/metaverse-tokens-extend-rally-after-facebooks-meta-move-it\/\"><u>Facebook cambia nome in Meta: rally per i token del Metaverso<\/u><\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/zuckerberg-makes-another-meta-move-coinbase-subscription-more-news\/\">Zuckerberg Makes Another Meta Move, Coinbase Subscription + More News<\/a><\/p><\/figure>","protected":false},"excerpt":{"rendered":"<p>Fonte: The SandboxLa piattaforma di gioco The Sandbox ha annunciato &#8220;The Sandbox Alpha&#8221;, un evento imminente che permetter&Atilde;&nbsp; ai giocatori di esplorare il metaverso dell&#8217;ecosistema per la prima volta e guadagnare premi nel processo. La notizia aveva spinto SAND, il token nativo dell&#8217;ecosistema The Sandbox, al suo nuovo massimo storico di 3,63 USD, scendendo poi [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,5],"tags":[102,259,964,481],"editors":[],"sponsored_companies":[],"class_list":["post-64763","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-features","tag-defi","tag-gaming","tag-metaverso","tag-nft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sandbox svela il prossimo evento Metaverso - Rally di SAND<\/title>\n<meta name=\"description\" content=\"La piattaforma di gioco The Sandbox ha annunciato &quot;The Sandbox Alpha&quot;, un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sandbox svela il prossimo evento Metaverso - Rally di SAND\" \/>\n<meta property=\"og:description\" content=\"La piattaforma di gioco The Sandbox ha annunciato &quot;The Sandbox Alpha&quot;, un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-17T11:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sandbox svela il prossimo evento Metaverso - Rally di SAND\" \/>\n<meta name=\"twitter:description\" content=\"La piattaforma di gioco The Sandbox ha annunciato &quot;The Sandbox Alpha&quot;, un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sandbox svela il prossimo evento Metaverso - Rally di SAND","description":"La piattaforma di gioco The Sandbox ha annunciato \"The Sandbox Alpha\", un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/","og_locale":"it_IT","og_type":"article","og_title":"Sandbox svela il prossimo evento Metaverso - Rally di SAND","og_description":"La piattaforma di gioco The Sandbox ha annunciato \"The Sandbox Alpha\", un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.","og_url":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-11-17T11:18:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Sandbox svela il prossimo evento Metaverso - Rally di SAND","twitter_description":"La piattaforma di gioco The Sandbox ha annunciato \"The Sandbox Alpha\", un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.","twitter_image":"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"Sandbox svela il prossimo evento Metaverso &#8211; Rally di SAND","datePublished":"2021-11-17T11:18:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/"},"wordCount":681,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg","keywords":["defi","gaming","Metaverso","nft"],"articleSection":["Exclusives","In evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/","url":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/","name":"Sandbox svela il prossimo evento Metaverso - Rally di SAND","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg","datePublished":"2021-11-17T11:18:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"La piattaforma di gioco The Sandbox ha annunciato \"The Sandbox Alpha\", un evento che permetter\u00e0 ai giocatori di esplorare il metaverso e guadagnare premi.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg","contentUrl":"https:\/\/cimg.co\/news\/64763\/40241\/the-sandbox.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/exclusives\/sand-rallies-as-sandbox-unveils-its-upcoming-metaverse-event-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sandbox svela il prossimo evento Metaverso &#8211; Rally di SAND"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/64763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=64763"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/64763\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=64763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=64763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=64763"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=64763"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=64763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}