{"id":64061,"date":"2021-11-05T15:59:00","date_gmt":"2021-11-05T15:59:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=64061"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"metaverse-five-things-to-know-and-what-it-could-mean-for-you-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/","title":{"rendered":"5 cose da sapere sul Metaverso"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg\" alt=\"Metaverso\" srcset=\"https:\/\/cimg.co\/news\/64061\/37723\/responsive-images\/webp-net-resizeimage-media-library-original-1233-822___media_library_original_1233_822.jpg 1233w, https:\/\/cimg.co\/news\/64061\/37723\/responsive-images\/webp-net-resizeimage-media-library-original-1233-822___media_library_original_1200_800.jpg 1200w, https:\/\/cimg.co\/news\/64061\/37723\/responsive-images\/webp-net-resizeimage-media-library-original-1233-822___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/64061\/37723\/responsive-images\/webp-net-resizeimage-media-library-original-1233-822___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/64061\/37723\/responsive-images\/webp-net-resizeimage-media-library-original-1233-822___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/64061\/37723\/responsive-images\/webp-net-resizeimage-media-library-original-1233-822___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1233\" class=\"content-img\"><figcaption>Fonte: Adobe\/Dumitru<\/figcaption><p class=\"wp-block-paragraph\">Sulla scia del <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/metaverse-nfts-and-gaming-token-prices-soar-as-facebook-goes-meta-it\/\">rebranding di Facebook come <strong>Meta<\/strong><\/a>, che riflette la sua attenzione sul &#8220;<strong>metaverso<\/strong>&#8220;, anche <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/watch-microsoft-ceo-showcasing-metaverse-use-cases-it\/\">Microsoft <\/a>ha annunciato che si lancer&Atilde;&nbsp; in questo settore.<\/p><p>Meta sostiene che il metaverso ci permetter&Atilde;&nbsp; di impegnarci in contesti educativi, lavorativi e sociali, mentre Microsoft sembra concentrarsi per ora specificamente sulla sfera dell&#8217;ufficio virtuale.<\/p><p><i>Ma cos&#8217;&Atilde;&uml; in realt&Atilde;&nbsp; il metaverso? Fino a che punto dovremmo credere che la visione che ci viene presentata sar&Atilde;&nbsp; davvero centrale nella nostra vita quotidiana?<\/i><\/p><p>L&#8217;idea in s&Atilde;&copy; non &Atilde;&uml; nuova. L&#8217;autore di fantascienza Neal Stephenson ha coniato il termine &#8220;metaverso&#8221; nel suo romanzo cyberpunk del 1992 <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.wired.com\/2021\/10\/geeks-guide-snow-crash\/\">Snow Crash<\/a>, presentando un mondo virtuale 3D in cui le persone, rappresentate come avatar, potrebbero interagire tra loro e con agenti artificialmente intelligenti.<\/p><p>Come con qualsiasi grande visione di un futuro che non esiste ancora, molte persone hanno cercato di imprimere le proprie definizioni sul metaverso. Se l&#8217;idea &Atilde;&uml; nuova per te, potrebbe essere utile comprendere alcune delle propriet&Atilde;&nbsp; che puoi aspettarti da un metaverso.<\/p><h2>5 caratteristiche del Metaverso<\/h2><span class=\"replacer\"><\/span><p>1. <i><u>Un mondo virtuale<\/u><\/i><u>:<\/u> questa &Atilde;&uml;, a mio avviso, la caratteristica pi&Atilde;\u00b9 importante di un metaverso. Puoi esplorarlo utilizzando un computer, una console di gioco, un dispositivo mobile, una tecnologia indossabile o un altro dispositivo, sperimentando grafica e suoni 3D lungo il percorso. L&#8217;idea &Atilde;&uml; che questo ti faccia sentire sempre pi&Atilde;\u00b9 presente nel metaverso e presumibilmente meno presente nel mondo di tutti i giorni (dove il tuo corpo rimane ostinatamente).<\/p><p>Per saperne di pi&Atilde;\u00b9: <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/theconversation.com\/facebook-relaunches-itself-as-meta-in-a-clear-bid-to-dominate-the-metaverse-170543\">Facebook si chiamer&Atilde;&nbsp; &#8220;Meta&#8221; nel chiaro tentativo di dominare il metaverso<\/a><\/p><p>2. <i><u>Realt&Atilde;&nbsp; virtuale<\/u><\/i>. Avete bisogno di un visore di realt&Atilde;&nbsp; virtuale per questo. L&#8217;idea qui &Atilde;&uml; che tu ti possa immergere nel mondo virtuale, quindi che tu ti possa sentire ancora pi&Atilde;\u00b9 <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/11710246\/\">presente<\/a>, almeno fino a quando non ti imbatti in qualcosa del mondo di tutti i giorni, come il tavolino da caff&Atilde;&uml;.<\/p><p><i><u>3. Altre persone<\/u><\/i>. Il metaverso &Atilde;&uml; sociale. Ci sono molte altre persone rappresentate come avatar. Alcuni di questi avatar potrebbero essere bot, agenti virtuali e manifestazioni di intelligenza artificiale. Puoi uscire con altre persone o anche fare cose insieme. &Atilde;&#136; probabile che l&#8217;aspetto sociale sia centrale nel metaverso di Facebook, data la sua storia come social network.<\/p><p>I fan del metaverso e alcuni ricercatori ritengono che la <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/dl.acm.org\/doi\/10.1145\/223904.223935\">comunicazione<\/a> possa essere pi&Atilde;\u00b9 naturale rispetto alla videoconferenza perch&Atilde;&copy;, ad esempio, si pu&Atilde;\u00b2 usare lo sguardo per mostrare a chi ci si rivolge (il tuo avatar pu&Atilde;\u00b2 girare la testa per guardare un&#8217;altra persona). Il tuo avatar potrebbe anche avvicinarsi e sedersi accanto all&#8217;avatar di qualcun altro per iniziare una conversazione.<\/p><p><i><u>4. Persistenza.<\/u><\/i> Ci&Atilde;\u00b2 significa che il mondo virtuale &Atilde;&uml; disponibile ogni volta che vuoi visitarlo. Puoi cambiarlo aggiungendo nuovi edifici virtuali o altri oggetti e, soprattutto, le modifiche rimangono in vigore la prossima volta che visiti. Potresti essere in grado di prendere la residenza e possederne un po&#8217;. Il metaverso si baser&Atilde;&nbsp; sui tuoi contenuti generati dagli utenti, le tue creazioni digitali e le tue storie personali, allo stesso modo in cui fanno oggi i social media.<\/p><p><i><u>5. Connessione al mondo reale<\/u><\/i>. In alcune visioni del metaverso, le cose virtuali nel mondo virtuale rappresentano in realt&Atilde;&nbsp; cose reali nel mondo reale. Ad esempio, potresti pilotare un drone virtuale nel metaverso per guidare un drone reale nel mondo reale. La gente parla del reale e del virtuale come i &#8220;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/ieeexplore.ieee.org\/document\/8424832\">gemelli digitali<\/a>&#8220;.<\/p><h2>Cosa posso fare in un metaverso?<\/h2><span class=\"replacer\"><\/span><p>Diverse societ&Atilde;&nbsp; avranno probabilmente le proprie visioni o anche versioni locali del metaverso ma, come Internet, saranno tutte connesse, quindi puoi spostarti dall&#8217;una all&#8217;altra.<\/p><p>&Atilde;&#136; probabile che alcune cose saranno pi&Atilde;\u00b9 attraenti e pratiche di altre. Giocare sembrerebbe un salto ragionevole, poich&Atilde;&copy; molti giocatori gi&Atilde;&nbsp; si divertono con i giochi online e alcuni giochi, in una certa misura, sono gi&Atilde;&nbsp; entrati nel <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.wired.com\/story\/these-companies-already-live-in-zuckerberg-metaverse\/\">metaverso<\/a> (ripensa alle caratteristiche elencate sopra).<\/p><p>Anche l&#8217;idea di poter socializzare o incontrarsi con gli altri e sentirsi come se fossi davvero l&Atilde;&not; con loro di persona &Atilde;&uml; allettante, in particolare nell&#8217;era della pandemia di oggi.<\/p><p>Non abbiamo ancora un&#8217;idea particolarmente chiara delle offerte del metaverso di Meta. Nell&#8217;annunciare il rebranding, l&#8217;amministratore delegato Mark Zuckerberg ha menzionato <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.independent.co.uk\/life-style\/gadgets-and-tech\/facebook-meta-name-new-metaverse-b1947245.html\">diverse possibilit&Atilde;&nbsp;<\/a>. Potresti essere in grado di apparire in una vera riunione come un ologramma o giocare a scacchi con qualcuno in tutto il mondo su una scacchiera virtuale sovrapposta al mondo reale.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"People in a room wearing VR headsets.\" sizes=\"100vw\" class=\" lazyload\" data-src=\"https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=45&amp;auto=format&amp;w=754&amp;fit=clip\" data-srcset=\"https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=45&amp;auto=format&amp;w=600&amp;h=400&amp;fit=crop&amp;dpr=1 600w, https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=30&amp;auto=format&amp;w=600&amp;h=400&amp;fit=crop&amp;dpr=2 1200w, https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=15&amp;auto=format&amp;w=600&amp;h=400&amp;fit=crop&amp;dpr=3 1800w, https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=45&amp;auto=format&amp;w=754&amp;h=503&amp;fit=crop&amp;dpr=1 754w, https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=30&amp;auto=format&amp;w=754&amp;h=503&amp;fit=crop&amp;dpr=2 1508w, https:\/\/images.theconversation.com\/files\/430256\/original\/file-20211104-15-1im1lom.jpg?ixlib=rb-1.1.0&amp;q=15&amp;auto=format&amp;w=754&amp;h=503&amp;fit=crop&amp;dpr=3 2262w\"><\/figure><p>Il metaverso potrebbe rappresentare il nostro futuro digitale? Non necessariamente. <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.shutterstock.com\/image-photo\/people-sit-3d-virtual-reality-glasses-1801629010\">Zhuravlev Andrey\/Shutterstock<\/a><\/p><p>La visione di Facebook del metaverso &Atilde;&uml; come la nostra futura interfaccia per Internet. Ma resta da vedere se un giorno avremo accesso a tutti i servizi Internet, attraverso mondi virtuali 3D e visori per la realt&Atilde;&nbsp; virtuale.<\/p><p>Le cuffie sembrano ancora essere una tecnologia in qualche modo di nicchia, nonostante i tentativi di molte grandi aziende di portarli sul mercato negli ultimi anni, incluso Facebook con l&#8217;acquisto di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/theconversation.com\/oculus-rift-brings-a-whole-new-dimension-to-communication-24864\">Oculus<\/a>.<\/p><p>Sospetto che Facebook vorr&Atilde;&nbsp; essere presente a lungo termine e che la sua visione del metaverso debba ancora rimanere una realt&Atilde;&nbsp; (virtuale) per molti anni.<\/p><p>Per saperne di pi&Atilde;\u00b9: <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/theconversation.com\/what-is-the-metaverse-2-media-and-information-experts-explain-165731\">cos&#8217;&Atilde;&uml; il metaverso? lo spiegano 2 esperti di media e informazione<\/a><\/p><h2>Ultima osservazione sul metaverso<\/h2><span class=\"replacer\"><\/span><p>La visione originale di Stephenson del metaverso era molto eccitante, ma anche piena di possibilit&Atilde;&nbsp; per danni sia online che reali, dalla dipendenza, alla criminalit&Atilde;&nbsp;, all&#8217;erosione delle istituzioni democratiche. &Atilde;&#136; interessante notare che il metaverso di Stephenson era per lo pi&Atilde;\u00b9 di propriet&Atilde;&nbsp; di grandi societ&Atilde;&nbsp;, con i governi relegati ad essere avamposti in gran parte insignificanti per il rimescolamento della carta.<\/p><p>Date le attuali tensioni tra la grande tecnologia e i governi di tutto il mondo sulla privacy, la libert&Atilde;&nbsp; di parola e i danni online, dovremmo considerare seriamente che tipo di metaverso vogliamo creare e chi pu&Atilde;\u00b2 crearlo, possederlo e regolarlo.<\/p><p>&nbsp;<\/p><p>&nbsp;<\/p><p><i>Steve Benford, Professore di Collaborative Computing, Universit&Atilde;&nbsp; di Nottingham.<\/i><\/p><p>&nbsp;<\/p><p><i>Questo articolo &Atilde;&uml; stato ripubblicato da <\/i><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/theconversation.com\/\"><i>The Conversation<\/i><\/a><i> con una licenza Creative Commons. Leggi l&#8217;<\/i><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/theconversation.com\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-171061\"><i>articolo originale<\/i><\/a><i>.<\/i><\/p><p><i>____<\/i><\/p><p>Seguici sui nostri canali social:<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><br>&nbsp;<\/p><p>Clicca sui nostri link di affiliazione:<\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/products\/crypto-starter-pack?r=12b53b98a1c0&amp;tracker=CN-IT\">Ledger<\/a>&nbsp;e&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><\/p><p>____<\/p><p>Per saperne di pi&Atilde;\u00b9:<br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/zuckerberg-makes-another-meta-move-coinbase-subscription-more-news\/\">Zuckerberg Makes Another Meta Move<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/nike-microsoft-rush-into-metaverse-thai-banking-giant-goes-crypto-more-news\/\">Nike &amp; Microsoft Rush Into Metaverse<\/a><\/p><p>&#8211; &nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/should-we-let-facebookmeta-rule-the-metaverse-too-it\/\">Dovremmo lasciare che Facebook\/Meta governi il Metaverso?<\/a><br>&#8211;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/investing-in-the-metaverse-4-ways-to-invest-in-virtual-future-it\/\"> Investire nel Metaverso:4 Modi per Investire nel Futuro Virtuale<\/a><\/p><\/figure>","protected":false},"excerpt":{"rendered":"<p>Fonte: Adobe\/DumitruSulla scia del rebranding di Facebook come Meta, che riflette la sua attenzione sul &#8220;metaverso&#8220;, anche Microsoft ha annunciato che si lancer&Atilde;&nbsp; in questo settore. Meta sostiene che il metaverso ci permetter&Atilde;&nbsp; di impegnarci in contesti educativi, lavorativi e sociali, mentre Microsoft sembra concentrarsi per ora specificamente sulla sfera dell&#8217;ufficio virtuale. Ma cos&#8217;&Atilde;&uml; in [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,4],"tags":[81,259,1264,964],"editors":[1293],"sponsored_companies":[],"class_list":["post-64061","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-opinions","tag-facebook","tag-gaming","tag-meta","tag-metaverso","editors-steve-benford"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 cose da sapere sul Metaverso<\/title>\n<meta name=\"description\" content=\"Cos&#039;\u00e8 in realt\u00e0 il metaverso? Se l&#039;idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 cose da sapere sul Metaverso\" \/>\n<meta property=\"og:description\" content=\"Cos&#039;\u00e8 in realt\u00e0 il metaverso? Se l&#039;idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T15:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"5 cose da sapere sul Metaverso\" \/>\n<meta name=\"twitter:description\" content=\"Cos&#039;\u00e8 in realt\u00e0 il metaverso? Se l&#039;idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/64056\/37719\/webp-net-resizeimage.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 cose da sapere sul Metaverso","description":"Cos'\u00e8 in realt\u00e0 il metaverso? Se l'idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/","og_locale":"it_IT","og_type":"article","og_title":"5 cose da sapere sul Metaverso","og_description":"Cos'\u00e8 in realt\u00e0 il metaverso? Se l'idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.","og_url":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-11-05T15:59:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"5 cose da sapere sul Metaverso","twitter_description":"Cos'\u00e8 in realt\u00e0 il metaverso? Se l'idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.","twitter_image":"https:\/\/cimg.co\/news\/64056\/37719\/webp-net-resizeimage.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"5 cose da sapere sul Metaverso","datePublished":"2021-11-05T15:59:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/"},"wordCount":1192,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg","keywords":["facebook","gaming","Meta","Metaverso"],"articleSection":["Exclusives","Opinioni"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/","url":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/","name":"5 cose da sapere sul Metaverso","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg","datePublished":"2021-11-05T15:59:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Cos'\u00e8 in realt\u00e0 il metaverso? Se l'idea \u00e8 nuova per te, potrebbe essere utile comprendere alcune delle sue caratteristiche.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg","contentUrl":"https:\/\/cimg.co\/news\/64061\/37723\/webp-net-resizeimage-media-library-original-1233-822.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/exclusives\/metaverse-five-things-to-know-and-what-it-could-mean-for-you-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"5 cose da sapere sul Metaverso"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/64061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=64061"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/64061\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=64061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=64061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=64061"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=64061"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=64061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}