{"id":60128,"date":"2021-09-12T09:42:00","date_gmt":"2021-09-12T09:42:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=60128"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"crypto-gaming-is-exploding-into-the-playful-future-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/","title":{"rendered":"Il crypto-gaming sta esplodendo nel futuro dei giochi"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg\" alt=\"crypto gaming\" srcset=\"https:\/\/cimg.co\/news\/60124\/24225\/responsive-images\/webp-net-resizeimage___media_library_original_1228_819.jpg 1228w, https:\/\/cimg.co\/news\/60124\/24225\/responsive-images\/webp-net-resizeimage___media_library_original_1200_800.jpg 1200w, https:\/\/cimg.co\/news\/60124\/24225\/responsive-images\/webp-net-resizeimage___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/60124\/24225\/responsive-images\/webp-net-resizeimage___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/60124\/24225\/responsive-images\/webp-net-resizeimage___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/60124\/24225\/responsive-images\/webp-net-resizeimage___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1228\"><figcaption>Source: Adobe\/nuclear_lily<\/figcaption><\/figure><ul><li>I giochi basati su criptovalute sono inizialmente buoni giochi, che hanno trovato il pubblico giusto al momento giusto.<\/li><li>Sta succedendo qualcosa di pi&ugrave; profondo del semplice dare alle persone l&#8217;opportunit&agrave; di fare soldi mentre giocano.<\/li><li>Gli NFT rimarranno l&#8217;elemento chiave del <strong>cripto-gaming<\/strong> per qualche tempo a venire.<\/li><\/ul><p class=\"wp-block-paragraph\">Uno dei pi&ugrave; grandi sottosettori all&#8217;interno delle criptovalute in questo momento &egrave; il <strong>gaming<\/strong>.<\/p><p>Secondo CoinMarketCap, 162 token legati al gaming ora vantano una capitalizzazione di mercato totale di circa 13 miliardi di dollari, dopo aver raggiunto solo 7,9 miliardi di dollari a fine Luglio e 3,6 miliardi di dollari a met&agrave; Giugno.<\/p><p>Questo salto mostra anche quanto sia diventata popolare l&#8217;intersezione tra gaming e criptovalute, con i crypto games che attirano una base di fan in crescita soprattutto perch&eacute; mescolano uno dei passatempi preferiti del mondo con l&#8217;opportunit&agrave; di guadagnare una sorta di reddito. Tuttavia, gli operatori del settore che parlano con <i>Cryptonews.com<\/i> affermano che i cripto-gaming offrono pi&ugrave; della semplice opportunit&agrave; di guadagnare, con la possibilit&agrave; di guadagnare una parte del mondo di gioco e la capacit&agrave; di connettersi con altre persone che sono altre importanti attrattive.<\/p><p>In futuro, la maggior parte degli analisti concorda sul fatto che l&#8217;uso di token non fungibili (<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/tags\/non-fungible-tokens\/\"><u>NFT<\/u><\/a>) e modelli <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/exclusives\/axie-infinity-games-where-people-earn-and-transform-gaming-11181\/\">play-to-earn<\/a> (gioca per guadagnare) continuer&agrave; a essere dominante. D&#8217;altra parte, avvertono che il cripto-gaming dovr&agrave; affrontare una serie di ostacoli normativi e di accessibilit&agrave; prima che possa raggiungere il suo vero potenziale.<\/p><h2><strong>Crypto + gaming = divertimento, reddito, costruzione, comunit&agrave;<\/strong><\/h2><span class=\"replacer\"><\/span><p>Va detto che, se non fossero stati divertenti da giocare, pochi o nessuno dei pi&ugrave; grandi crypto-games (ad esempio Axie Infinity, Sandbox <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/decentraland-sees-a-record-usd-913-000-virtual-land-sale-10744\/\"><u>Decentraland<\/u><\/a>, My Neighbor Alice, Alien Worlds, Illuvium) avrebbero attirato cos&igrave; rapidamente un sostanziale base di utenti.<\/p><blockquote><p>&#8220;Se queste attivit&agrave; non fossero principalmente divertenti, i vantaggi delle economie di propriet&agrave; dei giocatori e della vera propriet&agrave; non sarebbero sufficienti per attirare e trattenere gli utenti su larga scala, come stiamo ora assistendo&#8221;, ha affermato Sebastien Borget, il co-fondatore e Ufficiale capo delle operazioni presso Sandbox.<\/p><\/blockquote><p>Secondo lui, all&#8217;inizio questi sono buoni giochi, che hanno trovato il pubblico giusto al momento giusto, e attraverso la perseveranza e la dedizione del team che costruisce questi prodotti &#8220;c&#8217;&egrave; un mercato adatto&#8221;.<\/p><p>Naturalmente, c&#8217;&egrave; qualcosa di unico nei <strong>crypto-games<\/strong>, in quanto forniscono ai giocatori l&#8217;opportunit&agrave; di guadagnare dei soldi come effetto collaterale del loro gioco. Detto questo, i partecipanti al settore affermano che la relazione qui &egrave; un po&#8217; pi&ugrave; complicata e sfumata rispetto al semplice &#8220;guadagnare denaro&#8221;.<\/p><p>&ldquo;Da un punto di vista micro [&hellip;] questi giochi sono progettati per essere un ciclo riflessivo: amplifica significativamente gli effetti del cambiamento narrativo e le aspettative dei giocatori e dei partecipanti. Ad esempio, a causa del prezzo in aumento di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/axs-gold\/\"><u>AXS<\/u><\/a> e della perfetta narrativa di consentire ai giocatori a basso reddito di avventurarsi e combattere per guadagnare entrate reali; ha portato pi&ugrave; domanda all&#8217;allevamento di Axies che porta a prendere pi&ugrave; AXS e SLP [token Smooth Love Potion che possono essere guadagnati come ricompense dai giocatori di Axie Infinity] fuori dall&#8217;offerta mentre aumenta la domanda di AXS (che &egrave; necessario per far entrare i nuovi giocatori), &rdquo; ha detto Joe Zhou fondatore del <i>protocollo Dawn<\/i>.<\/p><p>In effetti, molti commentatori sostengono che sta accadendo qualcosa di pi&ugrave; profondo del semplice dare alle persone l&#8217;opportunit&agrave; di fare soldi mentre giocano. In molti casi, suggeriscono che il successo del cripto-gaming risiede nel modo in cui offrono ai giocatori la possibilit&agrave; di partecipare e aiutare a sviluppare una comunit&agrave;.<\/p><blockquote><p>&ldquo;Essere in grado di guadagnare giocando &egrave; un affare grande, ma il risultato &egrave; che le persone interagiscono, fanno trading, regalano, danno la mancia e comunicano molto di pi&ugrave; tra loro. Fondamentalmente ci&ograve; che sta accadendo &egrave; la connessione a molti livelli, che &egrave; un bisogno umano fondamentale&#8221;, ha affermato David Elvion, membro della Dacoco di Zurigo, che supervisiona lo sviluppo di Alien Worlds.<\/p><\/blockquote><p>Mentre altri commentatori concordano sul fatto che l&#8217;attrattiva del crypto-gaming sta esplodendo nel futuro dei giochi opera a vari livelli, alcuni suggeriscono che ci siano ragioni macroeconomiche per il recente aumento delle applicazioni decentralizzate (dapps) come Axie Infinity e altri.<\/p><p>&#8220;Da un punto di vista macro, il successo di molti cripto-giochi, in particolare Axie, in questo ciclo ha beneficiato notevolmente del cambiamento narrativo ciclico quando il mercato si raffredda e un numero crescente di partecipanti cercava ritorni al di fuori della <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/tags\/defi\/\"><u>DeFi<\/u><\/a>\/yield farming. Naturalmente, cercano di allocare il loro denaro in attivit&agrave; pi&ugrave; rischiose&#8221;, ha osservato Joe Zhou.<\/p><p>Nonostante ci&ograve;, i cripto-giochi offrono un perfezionamento significativo sui modelli di gioco pi&ugrave; tradizionali, uno che rappresenta il loro fascino unico. In particolare, Sebastien Borget osserva che la tecnologia blockchain ha consentito ai contenuti generati dagli utenti (UGC) &#8211; che esistevano gi&agrave; in giochi come World of Warcraft &#8211; di entrare nel regno della vera propriet&agrave;.<\/p><blockquote><p>&#8220;Le tecnologie blockchain hanno creato nuove opportunit&agrave; per gli utenti e nel 2017\/18 &#8211; quando il gaming NFT era nella sua prima forma &#8211; studi pionieri come Axie Infinity o The Sandbox hanno visto il potenziale per creare un nuovo tipo di giochi o piattaforma in cui l&#8217;economia &egrave; veramente di propriet&agrave; dei suoi giocatori, il che significa che tutto il contenuto, l&#8217;economia e persino la governance del gioco o del mondo virtuale potrebbero essere nelle mani dei giocatori, dei creatori e degli utenti che contribuiscono a questi giochi &#8220;, ha detto a Cryptonews.com .<\/p><\/blockquote><p>Secondo lui, questo ha portato a una nuova generazione di giochi come My Neighbor Alice e Alien Worlds, che hanno anche migliorato l&#8217;idea di base e si sono espansi in DeFi, staking e nuovi gameplay.<\/p><h2><strong>NFT e play-to-earn<\/strong><\/h2><span class=\"replacer\"><\/span><p>In futuro, la maggior parte dei partecipanti e degli osservatori afferma che gli NFT rimarranno l&#8217;elemento chiave del crypto-gaming sta esplodendo nel futuro dei giochi per qualche tempo a venire.<\/p><p>&#8220;Play-to-earn si affermer&agrave; come un nuovo genere permanente nell&#8217;industria dei giochi e credo che altri nuovi generi possibili solo attraverso la tecnologia NFT debbano ancora emergere&#8221;, ha affermato David Hanson.<\/p><p>David Elvion sostiene inoltre che gli NFT continueranno ad essere l&#8217;essenza del cripto-gaming, se non altro perch&eacute; praticamente qualsiasi oggetto, area o personaggio di gioco pu&ograve; essere programmato come token non fungibile.<\/p><p>&#8220;Gli NFT sono le &#8220;cose&#8221; utilizzate nei giochi, come oggetti tangibili nel mondo reale, che possono essere utilizzati per identificare e utilizzare la prova di propriet&agrave; per varie funzioni del gioco. Non vedo questa tendenza scomparire, ma piuttosto espandersi per collegare oggetti virtuali e reali molto di pi&ugrave; nel prossimo futuro&#8221;, ha affermato.<\/p><p>Ma mentre gli NFT sono stati sicuramente un ingrediente chiave nel successo dei giochi basati su criptovalute, alcuni commentatori suggeriscono che &egrave; troppo presto per dire quali saranno le caratteristiche o le tendenze dominanti relative al cripto-gioco in un futuro pi&ugrave; lontano.<\/p><blockquote><p>&#8220;Siamo in un settore ancora giovane ed &egrave; difficile prevedere ci&ograve; che funziona ora alla fine funzioner&agrave; ancora a lungo termine&#8221;, ha sottolineato Sebastien Borget. &#8220;Mentre i giochi basati su NFT offrono nuove incredibili opportunit&agrave; per giocatori, sviluppatori di giochi e brand, ogni nuovo cambiamento di paradigma vede attriti e sfide mentre si espande&#8221;.<\/p><\/blockquote><h2><strong>Giocare con le sfide<\/strong><\/h2><span class=\"replacer\"><\/span><p>Parlando di sfide, la maggior parte delle figure del settore &egrave; abbastanza umile da ammettere che i giochi basati su criptovalute dovranno superare vari ostacoli prima di ottenere un&#8217;adozione diffusa.<\/p><p>&#8220;L&#8217;unico punto cieco che direi che molti partecipanti non vedono &egrave; il potenziale <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/exclusives\/money-laundering-might-taint-nfts-too-prepare-for-tighter-co-9689\/\">rischio antiriciclaggio<\/a> una volta che puoi consentire agli utenti di fare trading di questi elementi NFT contro le criptovalute, in particolare le stablecoin, altrimenti non prevedo alcuna regolamentazione sul gioco per guadagnarsi da solo&#8221;, ha detto Joe Zhou.<\/p><p>Tuttavia, mentre gli sviluppatori concordano sul fatto che l&#8217;industria deve essere consapevole degli ostacoli normativi, la maggior parte suggerisce che le maggiori sfide siano in realt&agrave; interne.<\/p><p>&ldquo;L&#8217;accessibilit&agrave; &egrave; il principale ostacolo all&#8217;adozione mainstream, cos&igrave; come gli strumenti di sviluppo e l&#8217;accesso a clienti di facile utilizzo; simile a ci&ograve; che la costruzione dell&#8217;infrastruttura di Ultra consentir&agrave; agli sviluppatori di giochi di realizzare&#8221;, ha affermato David Hanson.<\/p><p>Al contrario, David Elvion suggerisce che l&#8217;opportunit&agrave; di guadagnare tramite il gaming pu&ograve; favorire alcuni abusi tra i giocatori e che l&#8217;industria dovr&agrave; lavorare sodo per prevenire tali abusi.<\/p><blockquote><p>&#8220;La sfida pi&ugrave; grande che vedo nel settore delle criptovalute &egrave; la prova della personalit&agrave;, assicurandosi che un gioco play-to-earn non venga giocato da giocatori che utilizzano le automazioni per ottenere vantaggi ingiusti&#8221;, ha spiegato.<\/p><\/blockquote><p>A parte tali ostacoli, sembra che il cripto-gaming potrebbe non affrontare gravi difficolt&agrave; nel suo prossimo futuro. E dato che la capacit&agrave; di guadagnare, fare trading e trarre profitto dagli oggetti di gioco sembra davvero un&#8217;evoluzione naturale e logica nei giochi, sembra davvero che un settore dell&#8217;industria delle criptovalute sia qui per restare.<\/p><p>____<\/p><p><i>Seguici sui nostri canali social:<\/i>&nbsp;<\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\"><u>https:\/\/twitter.com\/cryptonews_IT<\/u><\/a><br>&nbsp;_______<\/p><p><i>Clicca sui nostri link di affiliazione:<\/i><\/p><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\">PrimeXBT<\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/products\/crypto-starter-pack?r=12b53b98a1c0&amp;tracker=CN-IT\">Ledger<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\">Trezor<\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\">NordVPN<\/a><br>____<br>Per saperne di pi&ugrave;:<br><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/what-is-the-metaverse-a-high-tech-plan-to-facebookify-the-wo-11437-it\/\">&#8211; Metaverso: un piano high-tech per trasformare Facebook<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/videos\/blockchain-gaming-exeedme-w-nuno-fernandes\/\"><u>Blockchain Gaming &amp; Exeedme w\/ Nuno Fernandes<\/u><\/a><br><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/blockchain-gaming-may-be-key-to-mass-adoption-outpacing-defi-11494-it\/\">&#8211; Il gaming su blockchain pu&ograve; superare nft e defi<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/videos\/alexis-ohanian-s-big-bet-on-blockchain-gaming\/\"><u>Alexis Ohanian&#8217;s Big Bet on Blockchain Gaming<\/u><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Source: Adobe\/nuclear_lily I giochi basati su criptovalute sono inizialmente buoni giochi, che hanno trovato il pubblico giusto al momento giusto. Sta succedendo qualcosa di pi&ugrave; profondo del semplice dare alle persone l&#8217;opportunit&agrave; di fare soldi mentre giocano. Gli NFT rimarranno l&#8217;elemento chiave del cripto-gaming per qualche tempo a venire. Uno dei pi&ugrave; grandi sottosettori all&#8217;interno [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,5],"tags":[47,259,481,551],"editors":[],"sponsored_companies":[],"class_list":["post-60128","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-features","tag-blockchain","tag-gaming","tag-nft","tag-token-non-fungibili"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il crypto-gaming sta esplodendo nel futuro dei giochi<\/title>\n<meta name=\"description\" content=\"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming vantano una capitalizzazione totale di circa 13 miliardi di dollari\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il crypto-gaming sta esplodendo nel futuro dei giochi\" \/>\n<meta property=\"og:description\" content=\"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming vantano una capitalizzazione totale di circa 13 miliardi di dollari\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-12T09:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Il crypto-gaming sta esplodendo nel futuro dei giochi\" \/>\n<meta name=\"twitter:description\" content=\"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming  vantano una capitalizzazione totale di circa 13 miliardi di dollari\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il crypto-gaming sta esplodendo nel futuro dei giochi","description":"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming vantano una capitalizzazione totale di circa 13 miliardi di dollari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/","og_locale":"it_IT","og_type":"article","og_title":"Il crypto-gaming sta esplodendo nel futuro dei giochi","og_description":"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming vantano una capitalizzazione totale di circa 13 miliardi di dollari","og_url":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-09-12T09:42:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Il crypto-gaming sta esplodendo nel futuro dei giochi","twitter_description":"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming  vantano una capitalizzazione totale di circa 13 miliardi di dollari","twitter_image":"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"Il crypto-gaming sta esplodendo nel futuro dei giochi","datePublished":"2021-09-12T09:42:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/"},"wordCount":1644,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg","keywords":["blockchain","gaming","nft","Token Non Fungibili"],"articleSection":["Exclusives","In evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/","url":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/","name":"Il crypto-gaming sta esplodendo nel futuro dei giochi","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg","datePublished":"2021-09-12T09:42:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il cripto-gaming sta prendendo piede, secondo CoinMarketCap 162 token legati al gaming vantano una capitalizzazione totale di circa 13 miliardi di dollari","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg","contentUrl":"https:\/\/cimg.co\/news\/60124\/24225\/webp-net-resizeimage.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/exclusives\/crypto-gaming-is-exploding-into-the-playful-future-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il crypto-gaming sta esplodendo nel futuro dei giochi"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/60128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=60128"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/60128\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=60128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=60128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=60128"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=60128"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=60128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}