{"id":56559,"date":"2021-07-15T14:00:00","date_gmt":"2021-07-15T14:00:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=56559"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/","title":{"rendered":"L&#8217;hashrate globale di Bitcoin in Cina era in calo prima della repressione"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Sembra che la Grande Migrazione dei <strong>Miner<\/strong> sia iniziata ancor prima dell&#8217;ultimo esodo dalla Cina. La quota di <strong>hashrate<\/strong> globale di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\"><strong>Bitcoin<\/strong> (<strong>BTC<\/strong>)<\/a> del paese ha iniziato a diminuire prima dell&#8217;ultima repressione del governo. Quella in altri paesi ha visto un aumento, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.jbs.cam.ac.uk\/insight\/2021\/new-data-reveals-timeline-of-chinas-bitcoin-mining-exodus\/\">secondo <\/a>il <i>Cambridge Center for Alternative Finance<\/i> (CCAF) presso la <i>Cambridge Judge Business School<\/i>.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg\" alt=\"hashrate mining bitcoin btc\" srcset=\"https:\/\/cimg.co\/news\/56559\/20613\/responsive-images\/hashrate-bitcoin-btc___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/56559\/20613\/responsive-images\/hashrate-bitcoin-btc___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/56559\/20613\/responsive-images\/hashrate-bitcoin-btc___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/56559\/20613\/responsive-images\/hashrate-bitcoin-btc___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"900\" loading=\"auto\" class=\"content-img\"><\/figure><p>Fonte: Adobe\/agnormark<\/p><p>La &#8220;guerra&#8221; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/tags\/cina\/\">cinese <\/a>contro i miner di Bitcoin &egrave; (ri)iniziata nel giugno 2021. Ha portato un certo numero di importanti miner a chiudere i negozi e decidere se trasferirsi in paesi pi&ugrave; favorevoli. Ha anche messo all&#8217;angolo i piccoli miner, poich&eacute; non possono permettersi di spostarsi. Tuttavia, gli addetti ai lavori di criptovalute concordano sul fatto che questa migrazione sia vantaggiosa per la rete in quanto porta alla diffusione dell&#8217;hashrate a livello globale, piuttosto che alla concentrazione in Cina.<\/p><h2>Cosa suggeriscono i nuovi dati<\/h2><span class=\"replacer\"><\/span><p>Ma i nuovi dati del Cambridge Bitcoin Electricity Consumption Index (CBECI), una piattaforma indipendente per informazioni e approfondimenti sul consumo di elettricit&agrave; di Bitcoin, suggeriscono che l&#8217;hashrate del paese (la potenza di calcolo) &egrave; in un &#8220;significativo calo da qualche tempo&#8221; prima dell&#8217;effettiva repressione sul mining, secondo Michel Rauchs, Digital Assets Lead presso il CCAF.<\/p><p>I nuovi dati raccolti dal CCAF mostrano che la quota cinese della potenza di mining totale di Bitcoin &egrave; passata dal 75,5% di settembre 2019 al 46% di aprile 2021.<\/p><p>C&#8217;&egrave; stato infatti un aumento della quota dell&#8217;hashrate totale di Bitcoin negli Stati Uniti nello stesso periodo, dal 4% al 17%, mettendolo al secondo posto, afferma il rapporto.<\/p><p>Inoltre, c&#8217;&egrave; stato un aumento di quasi sei volte questa quota in Kazakistan, dall&#8217;1,4% nel settembre 2019 all&#8217;8% nell&#8217;aprile 2021, balzando cos&igrave; al terzo posto nella quota di potere minerario globale.<\/p><p>Il quarto e il quinto posto sono occupati dalla Federazione Russa (7%) e dall&#8217;Iran (5%).<\/p><h2>I dati sul hashrate di Bitcoin (BTC)<\/h2><span class=\"replacer\"><\/span><p>I nuovi dati di geolocalizzazione sono stati raccolti in collaborazione con quattro mining pool di Bitcoin: <strong>BTC.com<\/strong>, <strong>Poolin<\/strong>, <strong>ViaBTC <\/strong>e <strong>Foundry<\/strong>. L&#8217;insieme dei dati, che rappresenta circa il 37% della potenza di calcolo totale della rete Bitcoin, fornisce una visione empirica dell&#8217;evoluzione geografica del mining di Bitcoin e &#8220;conferma per la prima volta i modelli migratori stagionali in Cina che in precedenza erano stati osservati solo in modo aneddotico&#8221;.<\/p><p>Mostra i miner che migrano dalla provincia settentrionale dello Xinjiang nella stagione secca, alla provincia meridionale del Sichuan nella stagione delle piogge. Mostra anche che la quota del Sichuan della potenza di mining totale di Bitcoin della Cina aumenta dal 15% all&#8217;inizio della stagione delle piogge al 61% durante il picco nel 2020.<\/p><p>&#8220;Questa migrazione stagionale ha sostanzialmente influenzato il profilo energetico dell&#8217;estrazione di Bitcoin in Cina, che fino ad ora &egrave; stato di gran lunga il pi&ugrave; grande &#8220;mercato di mining&#8221;, illustrando la complessit&agrave; della valutazione degli effetti ambientali del mining&#8221;, ha affermato Rauchs.<\/p><p>Dato che le operazioni di mining nel paese sono state vietate, questo modello migratorio stagionale all&#8217;interno della Cina potrebbe finire. A seguito del divieto, l&#8217;hashrate cinese &egrave; scomparso durante la notte, ha detto Rauchs. Ha suggerito che i miner e le loro attrezzature sono in movimento, ma la domanda su dove stiano andando rimane.<\/p><p>&#8220;I guadagni negli Stati Uniti e in Kazakistan potrebbero essere un indicatore, ma i prossimi dati che riflettono l&#8217;impatto del divieto di mining cinese forniranno maggiore chiarezza su dove si &egrave; spostato l&#8217;hashrate&#8221;, ha affermato Rauchs.<\/p><h4><i><strong>Clicca sui nostri link di affiliazione:<\/strong><\/i><\/h4><p>&#8211;&nbsp;Per acquistare le tue criptovalute su&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\"><strong>PrimeXBT<\/strong><\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/products\/crypto-starter-pack?r=12b53b98a1c0&amp;tracker=CN-IT\"><strong>Ledger<\/strong><\/a>&nbsp;e&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\"><strong>Trezor<\/strong><\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\"><strong>NordVPN<\/strong><\/a>&nbsp; &nbsp;<br>___<br><strong>Per saperne di pi&ugrave;:<\/strong><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/surprise-an-esg-conscious-giant-increases-indirect-exposure-11042\/\">Surprise! An ESG-Conscious Giant Increases Indirect Exposure to Bitcoin<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/bitcoin-mining-profitability-jumps-hashrate-starts-picking-u-10976\/\">Bitcoin Mining Profitability Jumps, Hashrate Starts Picking Up Too<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/crypto-mining-rigs-selling-like-scrap-metal-as-mainland-chin-10850\/\">Crypto Mining Rigs &lsquo;Selling Like Scrap Metal&rsquo; as Mainland China Mood Darkens<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Sembra che la Grande Migrazione dei Miner sia iniziata ancor prima dell&#8217;ultimo esodo dalla Cina. La quota di hashrate globale di Bitcoin (BTC) del paese ha iniziato a diminuire prima dell&#8217;ultima repressione del governo. Quella in altri paesi ha visto un aumento, secondo il Cambridge Center for Alternative Finance (CCAF) presso la Cambridge Judge Business [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,223,142,505],"editors":[],"sponsored_companies":[],"class_list":["post-56559","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-cina","tag-mining","tag-usa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;hashrate di Bitcoin (BTC) era in calo prima della repressione<\/title>\n<meta name=\"description\" content=\"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell&#039;ultima repressione del governo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;hashrate di Bitcoin (BTC) era in calo prima della repressione\" \/>\n<meta property=\"og:description\" content=\"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell&#039;ultima repressione del governo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-15T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;hashrate di Bitcoin (BTC) era in calo prima della repressione\" \/>\n<meta name=\"twitter:description\" content=\"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell&#039;ultima repressione del governo.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/56555\/19788\/60f00651e56a7.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'hashrate di Bitcoin (BTC) era in calo prima della repressione","description":"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell'ultima repressione del governo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/","og_locale":"it_IT","og_type":"article","og_title":"L'hashrate di Bitcoin (BTC) era in calo prima della repressione","og_description":"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell'ultima repressione del governo.","og_url":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-07-15T14:00:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"L'hashrate di Bitcoin (BTC) era in calo prima della repressione","twitter_description":"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell'ultima repressione del governo.","twitter_image":"https:\/\/cimg.co\/news\/56555\/19788\/60f00651e56a7.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/"},"author":{"name":"aidadigitalituncp","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/354196ac2a79f86c035a1b3e98d519db"},"headline":"L&#8217;hashrate globale di Bitcoin in Cina era in calo prima della repressione","datePublished":"2021-07-15T14:00:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/"},"wordCount":680,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg","keywords":["bitcoin","cina","mining","usa"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/","url":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/","name":"L'hashrate di Bitcoin (BTC) era in calo prima della repressione","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg","datePublished":"2021-07-15T14:00:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"La quota di hashrate globale di Bitcoin (BTC) della Cina ha iniziato a diminuire prima dell'ultima repressione del governo.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#primaryimage","url":"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg","contentUrl":"https:\/\/cimg.co\/news\/56559\/20613\/hashrate-bitcoin-btc.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/china-s-global-bitcoin-hashrate-was-on-decline-before-crackd-11077-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;hashrate globale di Bitcoin in Cina era in calo prima della repressione"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/56559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=56559"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/56559\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=56559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=56559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=56559"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=56559"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=56559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}