{"id":55643,"date":"2021-07-01T16:42:00","date_gmt":"2021-07-01T16:42:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=55643"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/","title":{"rendered":"A partire da oggi, 4.000 fondi tedeschi possono iniziare a investire in criptovalute"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/dserver.bundestag.de\/btd\/19\/276\/1927631.pdf\">legislazione<\/a> tedesca, entrata in vigore il 1 luglio, consente a circa 4.000 dei cosiddetti fondi speciali del paese di <strong>investire in asset cripto<\/strong>, aprendo eventualmente la strada ad un aumento dell&#8217; esposizione alle criptovalute da parte degli investitori tedeschi.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/60d\/dc6a3e4916.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/60d\/dc6a3e4916.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/60d\/dc6a3e4916.jpg 900w\" sizes=\"100vw\"><\/figure><p>Fonte: iStock\/HamidEbrahimi<\/p><p>In base alle nuove regole, gli Spezialfonds tedeschi potranno investire fino al 20% dei loro portafogli in asset cripto.<\/p><p>A maggio, Dominik Tyrybon, associato presso lo studio legale austriaco <strong>Schoenherr Attorneys at Law<\/strong>, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.mondaq.com\/germany\/fin-tech\/1069926\/germany-introduces-a-new-law-that-allows-funds-to-invest-into-crypto-assets\">ha previsto<\/a> che la legislazione &#8220;aumenter&agrave; senza dubbio la posizione della Germania, come centro di investimenti finanziari&#8221; e rappresenta &#8220;un importante passo successivo verso la legittimazione degli asset cripto come asset class&#8221; nell&#8217;economia tedesca.&nbsp;<\/p><p>Inoltre ha affermato che &#8220;gli esperti di mercato si aspettano gi&agrave; che il nuovo regolamento scatener&agrave; investimenti significativi nei mercati delle criptovalute&#8221;.<\/p><p>L&#8217;avvocato ha citato le stime di Sven Hildebrandt, CEO della societ&agrave; tedesca Distributed Ledger Consulting (DLC), che vede un potenziale afflusso di 350 miliardi di euro (415 miliardi di dollari) alle criptovalute.<\/p><p>Tyrybon ha scritto che &ldquo;si tratterebbe di un quinto del patrimonio di circa 1,87 trilioni di euro, attualmente vincolato a circa 4.000 fondi speciali nazionali aperti. La domanda rimane: chi &egrave; il prossimo?&#8221;.<\/p><p>Nel frattempo, Frank Dornseifer, amministratore delegato dell&#8217;Associazione federale tedesca per gli investimenti alternativi (BAI), &egrave; stato <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t3n.de\/news\/fondsstandortgesetz-krypto-in-kraft-1375731\/\">citato<\/a> dal sito di notizie locale T3N.de, secondo cui le nuove regole dovrebbero applicarsi non solo ai fondi speciali, ma a un gruppo pi&ugrave; ampio di istituzioni finanziarie, che dovrebbero includere anche i fondi pubblici, che trattengono inutilmente una parte del capitale privato.<\/p><p>La legislazione Fondsstandortgesetz &egrave; stata redatta dal Ministero delle Finanze e dal Ministero dell&#8217;Economia e dell&#8217;Energia, che sono gestiti rispettivamente da Olaf Scholz del Partito socialdemocratico tedesco (SPD) e Peter Altmaier dell&#8217;Unione Cristiano Democratica (CDU).<\/p><p>L&#8217;attuazione della legge segue una precedente decisione della Germania di consentire alle banche di vendere e conservare criptovalute a partire dal 1&deg; gennaio 2020. La mossa <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/weg-bank-plans-crypto-custody-with-new-partnership-8117\/\">ha stimolato <\/a>una serie di partnership tra banche tedesche e fornitori di custodia di criptovalute.<br>___<\/p><h4><i><strong>Clicca sui nostri link di affiliazione:<\/strong><\/i><\/h4><p>&#8211;&nbsp;Per acquistare le tue criptovalute su <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.primexbt.com\/click?pid=396&amp;offer_id=12&amp;l=1594449634&amp;sub1=Italian\"><strong>PrimeXBT<\/strong><\/a>, la piattaforma di trading di nuova generazione<\/p><p>&#8211;&nbsp;Per proteggere le tue criptovalute su portafogli come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.ledger.com\/products\/crypto-starter-pack?r=12b53b98a1c0&amp;tracker=CN-IT\"><strong>Ledger<\/strong><\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/shop.trezor.io\/?offer_id=83&amp;aff_id=1814\"><strong>Trezor<\/strong><\/a><\/p><p>&#8211;&nbsp;Per effettuare transazioni in modo anonimo con <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/go.nordvpn.net\/aff_c?offer_id=252&amp;aff_id=54152&amp;url_id=14818&amp;aff_sub=Italy\"><strong>NordVPN<\/strong><\/a>&nbsp; &nbsp;<br>____<br><br><strong>Per saperne di pi&ugrave;:<\/strong>&nbsp;<br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/nydig-and-ncr-team-up-to-bring-bitcoin-to-650-us-banks-credi-10879\/\">NYDIG and NCR Team Up To Bring Bitcoin To 650 US Banks, Credit Unions<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/deutsche-borse-group-tp-icap-make-crypto-bets-with-new-plans-10858\/\">Deutsche B&ouml;rse Group, TP ICAP Make Crypto Bets With New Plans, Investments<\/a><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/paypal-visa-other-investors-double-down-on-their-crypto-inve-10789\/\">PayPal, Visa &amp; Other Investors Double Down On Their Crypto Investments<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/guggenheim-doubles-down-on-its-bitcoin-plans-10550\/\">Guggenheim Doubles Down On Its Bitcoin Plans<\/a><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/german-regulator-refuses-to-budge-in-binance-stock-token-dis-10194\/\">German Regulator Refuses to Budge in Binance Stock Token Dispute<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/europe-gets-its-new-crypto-unicorn-bitpanda-9553\/\">Europe Gets Its New Crypto Unicorn, Bitpanda<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La legislazione tedesca, entrata in vigore il 1 luglio, consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo eventualmente la strada ad un aumento dell&#8217; esposizione alle criptovalute da parte degli investitori tedeschi.Fonte: iStock\/HamidEbrahimiIn base alle nuove regole, gli Spezialfonds tedeschi potranno investire fino al 20% dei loro [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,75,835,836],"editors":[306],"sponsored_companies":[],"class_list":["post-55643","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-cripto","tag-investimenti-cripto","tag-regolamentazione-cripto","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>4.000 fondi tedeschi possono iniziare a investire in criptovalute<\/title>\n<meta name=\"description\" content=\"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell&#039;esposizione degli investitori tedeschi alle criptovalute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4.000 fondi tedeschi possono iniziare a investire in criptovalute\" \/>\n<meta property=\"og:description\" content=\"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell&#039;esposizione degli investitori tedeschi alle criptovalute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-01T16:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"4.000 fondi tedeschi possono iniziare a investire in criptovalute\" \/>\n<meta name=\"twitter:description\" content=\"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell&#039;esposizione degli investitori tedeschi alle criptovalute.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/55639\/19432\/60ddc6af74314.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4.000 fondi tedeschi possono iniziare a investire in criptovalute","description":"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell'esposizione degli investitori tedeschi alle criptovalute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/","og_locale":"it_IT","og_type":"article","og_title":"4.000 fondi tedeschi possono iniziare a investire in criptovalute","og_description":"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell'esposizione degli investitori tedeschi alle criptovalute.","og_url":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-07-01T16:42:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"4.000 fondi tedeschi possono iniziare a investire in criptovalute","twitter_description":"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell'esposizione degli investitori tedeschi alle criptovalute.","twitter_image":"https:\/\/cimg.co\/news\/55639\/19432\/60ddc6af74314.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"A partire da oggi, 4.000 fondi tedeschi possono iniziare a investire in criptovalute","datePublished":"2021-07-01T16:42:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/"},"wordCount":473,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg","keywords":["bitcoin","cripto","Investimenti Cripto","Regolamentazione Cripto"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/","url":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/","name":"4.000 fondi tedeschi possono iniziare a investire in criptovalute","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg","datePublished":"2021-07-01T16:42:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"La legislazione tedesca entrata in vigore il 1 luglio consente a circa 4.000 dei cosiddetti fondi speciali del paese di investire in asset cripto, aprendo forse la strada a un picco nell'esposizione degli investitori tedeschi alle criptovalute.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/dc6a3e4916.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/starting-today-4-000-german-funds-can-start-investing-in-cry-10894-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"A partire da oggi, 4.000 fondi tedeschi possono iniziare a investire in criptovalute"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/55643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=55643"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/55643\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=55643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=55643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=55643"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=55643"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=55643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}