{"id":55586,"date":"2021-06-30T20:06:00","date_gmt":"2021-06-30T20:06:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=55586"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/","title":{"rendered":"Lympo collabora con Binance per ospitare NFT di atleti e personalit\u00e0 dello sport"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><i>Dichiarazione di non responsabilit\u00e0: il testo seguente \u00e8 un comunicato stampa che non \u00e8 stato scritto da Cryptonews.com.<\/i><\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg\" alt=\"Lympo x Binance NFT\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/60d\/c8de5d1233.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/60d\/c8de5d1233.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/60d\/c8de5d1233.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/60d\/c8de5d1233.jpg 1200w\" sizes=\"100vw\"><\/figure><p>30 giugno 2021 \u2014 Tallinn, Estonia \u2014<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/lympo.com\/\"> <strong>Lympo<\/strong><\/a>, una consociata di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.animocabrands.com\/\">Animoca Brands<\/a>, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/nft.binance.com\/\">Binance NFT<\/a>. <strong>Binance<\/strong> <strong>NFT<\/strong> ospiter\u00e0 i token non fungibili (NFT) relativi allo sport basati su IP di Lympo, comprese le future aste NFT di speciali carte uniche, che rappresentano atleti e star dello sport.<\/p><p>Binance NFT \u00e8 un marketplace che riunisce artisti, creatori e appassionati di criptovalute di tutto il mondo, con una ricca gamma di mostre di prim&#8217;ordine e collaborazioni NFT.<\/p><p>La<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/nft.lympo.io\/\"> piattaforma di conio Lympo NFT <\/a>invita gli appassionati di NFT a puntare token LMT e a coniare NFT di campioni del mondo e atleti famosi. \u00c8 previsto un grande drop di nuovi NFT una volta che la piattaforma di conio Lympo NFT sar\u00e0 migrata su Binance Smart Chain (BSC). All&#8217;inizio di questa primavera, Lympo ha collegato il suo token LMT a BSC e lo ha quotato sull&#8217; exchange decentralizzato PancakeSwap.<\/p><p>Ada Jonuse, CEO di Lympo, ha dichiarato: &#8220;Questo segna il prossimo importante passo nell&#8217;integrazione di Lympo nell&#8217;ecosistema Binance. Per i nostri utenti significa non solo commissioni di transazione molto pi\u00f9 economiche per coniare, trasferire e scambiare NFT, ma anche esposizione alla piattaforma e alla community di Binance, il principale exchange di criptovalute al mondo. Non vedo l&#8217;ora di ospitare le nostre aste sul marketplace NFT di Binance, mentre portiamo sul mercato NFT che, oltre ad essere unici e preziosi, hanno anche utilit\u00e0 speciali, come la funzionalit\u00e0 di staking.<\/p><h2>L&#8217;ecosistema Lympo NFT<\/h2><span class=\"replacer\"><\/span><p>L&#8217;ecosistema Lympo NFT, che \u00e8 alimentato da LMT, viene sviluppato in due fasi. Nella prima fase di oggetti da collezione digitali vengono emessi vari NFT di atleti, club, influencer e appassionati di fama mondiale in varie rarit\u00e0, per stabilire una fornitura di base. Lympo ha lanciato due pool NFT che consentono ai titolari di LMT di puntare i propri token e coniare NFT Lympo &#8211; ulteriori informazioni sono disponibili qui:<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/nft.lympo.io\/\"> https:\/\/nft.lympo.io.<\/a><\/p><p>Nella seconda fase di sviluppo di contenuti e media, verranno avviate varie attivit\u00e0, inclusi giochi che utilizzano LMT, come token di utilit\u00e0 principale e valuta di gioco. Questi giochi implementeranno un modello Play-to-Earn. I giocatori potranno utilizzare i loro NFT Lympo per creare e potenziare i loro eroi sportivi, quindi formare squadre, giocare contro altri giocatori e partecipare a tornei per guadagnare ricompense con valore reale. Inoltre, i collezionisti di NFT Lympo potranno puntare i propri NFT per ottenere ricompense speciali, aumentando cos\u00ec il valore di questi oggetti da collezione. Maggiori informazioni sull&#8217;ecosistema Lympo NFT sono disponibili <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.lympo.io\/\">qui<\/a>.<\/p><h2>Informazioni su Binance<\/h2><span class=\"replacer\"><\/span><p>Binance \u00e8 il principale ecosistema blockchain al mondo e fornitore di infrastrutture per criptovalute, con una suite di prodotti finanziari che include il pi\u00f9 grande exchange di asset digitali per volume. Scelto da milioni di persone in tutto il mondo, la piattaforma Binance \u00e8 dedicata ad aumentare la libert\u00e0 di denaro per gli utenti e presenta un portafoglio di prodotti e offerte cripto, tra cui: trading e finanza, istruzione, dati e ricerca, bene sociale, investimenti e incubazione, decentralizzazione e soluzioni infrastrutturali e altro ancora.<\/p><p>Per ulteriori informazioni, visitare: <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.binance.com\/ng\">https:\/\/www.binance.com<\/a><br>Fai trading in movimento con l&#8217;app di trading di criptovalute mobile di Binance. Scarica per <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.binance.dev&amp;utm_source=Zendesk&amp;utm_medium=Announcement&amp;utm_term=Android\">Android<\/a> o <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/apps.apple.com\/hk\/app\/binance\/id1436799971?l=en&amp;utm_source=Zendesk&amp;utm_medium=Announcement&amp;utm_term=iOS\">iOS<\/a>.<\/p><p><u>Informazioni sul marketplace di Binance NFT<\/u><br>Binance NFT Marketplace offre un mercato aperto per artisti, creatori, appassionati di criptovalute, collezionisti di NFT e fan creativi di tutto il mondo con la migliore liquidit\u00e0 e commissioni minime. Composto da due parti, eventi premium e un mercato, Binance NFT offre preziosi oggetti da collezione e un mercato di trading facilmente accessibile per tutti i suoi utenti.<\/p><p>Per ulteriori informazioni, visitare <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/nft.binance.com\/\">https:\/\/nft.binance.com\/<\/a><br>Per la collaborazione di creatori e artisti; e-mail di contatto: <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/nft@binance.com\/\">nft@binance.com<\/a><br>\u200b<br><u>A proposito di Lympo<\/u><br>Lympo, una consociata di Animoca Brands, sta costruendo un ecosistema di NFT sportivi basato su atleti e societ\u00e0 sportive di fama mondiale. L&#8217;ecosistema Lympo includer\u00e0 stelle dello sport, club e personaggi sportivi personalizzati creati da vari artisti e influencer sportivi. Lympo \u00e8 stato lanciato nel 2018 insieme al suo token LYM, scambiato su vari exchange come token per incentivare uno stile di vita sano. Scopri di pi\u00f9 su <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.lympo.com\/\">www.lympo.com <\/a>o ricevi aggiornamenti su <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/lympo_io\">Twitter<\/a> o <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/lympo\">Telegram<\/a>.<\/p><h2>Informazioni sui marchi Animoca<\/h2><span class=\"replacer\"><\/span><p>Animoca Brands, classificata nell&#8217;elenco del Financial Times delle societ\u00e0 ad alta crescita Asia-Pacifico 2021, \u00e8 leader nell&#8217;intrattenimento digitale, blockchain, gamification e intelligenza artificiale. Animoca Brands sviluppa e pubblica un ampio portafoglio di prodotti tra cui il <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/revvmotorsport.com\/\">token REVV<\/a> e il <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.sandbox.game\/\">token SAND<\/a>; giochi originali tra cui <i>The Sandbox<\/i>, <i>Crazy Kings<\/i> e <i>Crazy Defense<\/i> <i>Heroes<\/i>; e prodotti che utilizzano propriet\u00e0 intellettuali popolari tra cui Formula 1\u00ae, Marvel, WWE, Power Rangers, MotoGP\u2122 e Doraemon. Il suo portafoglio di investimenti e partnership blockchain include<i> Sky Mavis<\/i> <i>(Axie Infinity)<\/i>, <i>Dapper Labs<\/i> <i>(CryptoKitties e NBA Top Shot)<\/i>, OpenSea, Harmony, Bitski e <i>Alien Worlds<\/i>. Le sue filiali includono The Sandbox, Quidd, Gamee, nWay, Pixowl e Lympo. Per maggiori informazioni visita <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.animocabrands.com\/\">www.animocabrands.com<\/a> o ricevi aggiornamenti seguendo Animoca Brands su <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.facebook.com\/animocabrands\">Facebook<\/a> o <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/animocabrands\">Twitter.<\/a><\/p><p>Contatto globale:<br><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/press@animocabrands.com\">press@animocabrands.com<\/a><br>&nbsp;<\/p><p>____<\/p><p><i>Seguici sui nostri canali social:<\/i><\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dichiarazione di non responsabilit\u00e0: il testo seguente \u00e8 un comunicato stampa che non \u00e8 stato scritto da Cryptonews.com.30 giugno 2021 \u2014 Tallinn, Estonia \u2014 Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace di Binance NFT. Binance NFT ospiter\u00e0 i token non fungibili (NFT) relativi allo sport basati [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,11],"tags":[59,47,75,259,481],"editors":[63],"sponsored_companies":[],"class_list":["post-55586","post","type-post","status-publish","format-standard","hentry","category-news","category-press-releases","tag-binance","tag-blockchain","tag-cripto","tag-gaming","tag-nft","editors-linas-kmieliauskas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lympo collabora con Binance per NFT di star dello sport<\/title>\n<meta name=\"description\" content=\"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lympo collabora con Binance per NFT di star dello sport\" \/>\n<meta property=\"og:description\" content=\"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-30T20:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Lympo collabora con Binance per NFT di star dello sport\" \/>\n<meta name=\"twitter:description\" content=\"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/55583\/19404\/60dc8dfd1bef0.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lympo collabora con Binance per NFT di star dello sport","description":"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Lympo collabora con Binance per NFT di star dello sport","og_description":"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.","og_url":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-06-30T20:06:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Lympo collabora con Binance per NFT di star dello sport","twitter_description":"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.","twitter_image":"https:\/\/cimg.co\/news\/55583\/19404\/60dc8dfd1bef0.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/"},"author":{"name":"aidadigitalituncp","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/354196ac2a79f86c035a1b3e98d519db"},"headline":"Lympo collabora con Binance per ospitare NFT di atleti e personalit\u00e0 dello sport","datePublished":"2021-06-30T20:06:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/"},"wordCount":882,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg","keywords":["Binance","blockchain","cripto","gaming","nft"],"articleSection":["News","Rassegna Stampa"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/","url":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/","name":"Lympo collabora con Binance per NFT di star dello sport","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg","datePublished":"2021-06-30T20:06:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Lympo, una consociata di Animoca Brands, \u00e8 lieta di annunciare una collaborazione con il nuovo marketplace NFT di Binance.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60d\/c8de5d1233.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/press-releases\/lympo-collaborates-with-binance-nft-marketplace-to-host-nfts-10883-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Lympo collabora con Binance per ospitare NFT di atleti e personalit\u00e0 dello sport"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/55586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=55586"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/55586\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=55586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=55586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=55586"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=55586"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=55586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}