{"id":54504,"date":"2021-06-10T21:03:00","date_gmt":"2021-06-10T21:03:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=54504"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/","title":{"rendered":"&#8220;Siamo ai ferri corti&#8221;: l&#8217;universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l&#8217;universo cripto ha trovato errate, per non dire altro, comprese le preoccupazioni ambientali, gli investimenti e l&#8217;utilit&agrave; di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\">Bitcoin (BTC)<\/a>, l&#8217;uso per scopo illecito, la necessit&agrave; di una regolamentazione rigorosa, tra le altre cose.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/60c\/1ebbebada0.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/60c\/1ebbebada0.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/60c\/1ebbebada0.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/60c\/1ebbebada0.jpg 1385w\" sizes=\"100vw\"><\/figure><p>Elisabetta Warren. Fonte: uno screenshot video, Youtube\/Bloomberg Politics<\/p><p>&#8220;La lotta degli Stati Uniti contro Bitcoin &egrave; iniziata&#8221;, ha <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/marcvanderchijs\/status\/1402822690168213511\">affermato<\/a> il finanziatore Marc van der Chijs in risposta alle numerose affermazioni di Warren sulle criptovalute. &#8220;I fatti non contano per il senatore Warren, &egrave; tutto un grande FUD. Ma credo che Bitcoin vincer&agrave; questo, il mondo &egrave; cambiato troppo per fermarlo&#8221;, ha aggiunto.<\/p><p>Parlando alla prima audizione della sottocommissione bancaria del Senato sulle valute digitali da lei presieduta, Warren ha sostenuto che la quantit&agrave; di energia che alimenta la rete Bitcoin minaccia l&#8217;ambiente.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/SenWarren\/status\/1402725005113364486\"><\/oembed><\/figure><p>Parecchie persone definiscono Warren un&#8217;ipocrita su praticamente tutti i problemi che ha menzionato, e l&#8217;affermazione sulla preoccupazione ambientale &egrave; stata immediatamente contrastata (soprattutto perch&eacute; lei stessa sta <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/BitcoinIsSaving\/status\/1402818182960799746?s=20\">usando<\/a> un jet privato), con l&#8217;universo cripto che sostiene che ci sono state gi&agrave;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/exclusives\/a-closer-look-at-the-environmental-impact-of-bitcoin-mining-9869-it\/\"> tante discussioni<\/a> su questo, e che <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/CryptoCobain\/status\/1402772814114009090\">questa<\/a> disinformazione pu&ograve; essere &#8221; facilmente smentita&#8221;. Ad esempio, contrariamente a quanto affermato, le transazioni BTC non utilizzano elettricit&agrave; extra.<\/p><p>Natalie Smolenski, Responsabile dello sviluppo aziendale di <strong>Hyland Credentials<\/strong>, ad esempio, ha <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/NSmolenski\/status\/1402726528136450055?s=20\">scritto<\/a> che BTC &egrave; &#8220;uno dei driver pi&ugrave; potenti che spingono il mondo verso l&#8217;energia pulita&#8221;, aggiungendo che &#8220;non risolverai la crisi climatica adottando una posizione anti-tecnologia. .&#8221;<\/p><p>Circa il 75% dei miner utilizza un qualche tipo di energia rinnovabile, secondo gli studi di Cambridge, mentre le energie rinnovabili rappresentano meno del 40% dell&#8217;energia totale utilizzata.<\/p><p>In un&#8217;intervista separata, Warren ha descritto il mercato delle criptovalute come il &#8220;Selvaggio West&#8221;. Ha continuato affermando che la valuta digitale &#8220;non &egrave; un buon modo per comprare e vendere cose e non &egrave; un buon investimento ed &egrave; un disastro ambientale&#8221;.<\/p><div class=\"raw-html-embed\"><iframe width=\"560\" height=\"405\" class=\"lazyload\" data-src=\"https:\/\/www.bloomberg.com\/multimedia\/api\/embed\/iframe?id=fe1786e0-595c-4398-8f6e-567be52ee091\" allowscriptaccess=\"always\" frameborder=\"0\"><\/iframe><\/div><p>Sam Trabucco, un trader di criptovalute quantitativo presso <strong>Alameda Research<\/strong>, tra gli altri, ha risposto che &#8220;asset volatile = non un buon investimento, &egrave; un errore comune&#8221;. Anche se probabilmente non &egrave; l&#8217;idea migliore per i pensionati investire tutti i loro soldi in criptovalute, &#8220;l&#8217;alta ricompensa ad alto rischio &egrave; la cosa tipicamente migliore su cui fare investire i giovani&#8221;, ha detto.<\/p><p><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/lawrencehwhite1\/status\/1402814848728240130?s=20\">Secondo<\/a> Lawrence H. White, professore di economia alla George Mason University, Warren &egrave; &#8220;l&#8217;host di podcast meno genuino di sempre&#8221;.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/thecryptosheet\/status\/1402727119143194632?ref_src=twsrc%5Etfw\"><\/oembed><\/figure><p>Alcuni dei suggerimenti dei testimoni dell&#8217;udienza includevano i governi mondiali che reprimevano Bitcoin e le criptovalute in generale, forse addirittura vietando la loro conversione in USD, come ha <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/Super_Crypto\/status\/1402826855405670403?s=20\">affermato<\/a> l&#8217;economista finanziario Darrell Duffie.<\/p><p>Secondo Warren, il governo del paese dovrebbe aumentare la supervisione di questo mercato e trovare la protezione dei consumatori dalle truffe portate avanti dalla rapida ascesa delle criptovalute, includendo possibilmente alcune normative che esistono in altre parti del sistema finanziario, affermando che il suo comitato prevede di tenere udienze relative alle criptovalute anche in futuro.<\/p><p>Anche molti commentatori hanno trovato falsa questa affermazione.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/Travis_Kling\/status\/1402804776962768896?ref_src=twsrc%5Etfw\"><\/oembed><\/figure><p>Warren ha anche menzionato di aver portato le opinioni di diverse parti interessate a queste discussioni, ma in particolare, stava parlando di diversi regolatori, come la <strong>Securities and Exchange Commission<\/strong> (SEC) e i regolatori bancari, senza menzionare nessuno dell&#8217;industria stessa delle criptovalute. Ha detto che gli Stati Uniti sono indietro quando si tratta di criptovalute, ma per quanto riguarda la loro regolamentazione.<\/p><p>In entrambi i casi, tornando al tweet di van der Chijs, Nic Carter, partner di <strong>Castle Island Ventures<\/strong>, ha<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/nic__carter\/status\/1402759923054821376\"> scritto<\/a> che &#8220;siamo ai ferri corti&#8221;, con i politici &#8220;che si muovono contro di noi in modo rapido e aggressivo&#8221;, e che &#8220;non possono sostenere la causa contro di noi senza mentire costantemente&#8221;. Per Carter, Warren ha deliberatamente rilasciato false dichiarazioni sul consumo di energia di Bitcoin, la sua utilit&agrave;, l&#8217;uso per scopi illeciti e altri.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/nic__carter\/status\/1402759923054821376?s=20\"><\/oembed><\/figure><p>_____<\/p><p>Altre reazioni:<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/craigwarmke\/status\/1402817875241492480?s=20\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/InflationRinse\/status\/1402742444219793411?s=20\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/jbddc\/status\/1402789799250087936?s=20\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/brucefenton\/status\/1402751008531521539?ref_src=twsrc%5Etfw\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/EpsilonTheory\/status\/1402842358870331392?s=20\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/Cycloud616\/status\/1402838095867912192?s=20\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/DavidNage\/status\/1402814817086357506?s=20\"><\/oembed><\/figure><p>__<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/gladstein\/status\/1402816542618783744?s=20\"><\/oembed><\/figure><p>____<br><strong>Per saperne di pi&ugrave;:<\/strong><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/proof-of-bitcoin-needed-as-critics-competitors-unite-to-play-10017\/\">Proof-Of-Bitcoin Needed As Critics &amp; Competitors Unite To Play Climate Card<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/the-btc-colonial-pipeline-fud-gives-a-lesson-on-bitcoin-secu-10604\/\">The BTC-Colonial Pipeline FUD Gives A Lesson On Bitcoin Security<\/a><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/new-crypto-fud-round-incoming-as-us-gunning-for-ransomware-c-10569\/\">New Crypto FUD Round Incoming as US Gunning for Ransomware Crackdown<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/russia-could-use-crypto-to-dodge-us-sanctions-political-insi-10606\/\">Russia Could Use Crypto to Dodge US Sanctions &#8211; Political Insider<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/crypto-mom-worried-tight-regulation-could-thwart-crypto-inn-10624\/\">SEC Commissioner Worried Tight Regulation Could Thwart Crypto Innovation<\/a><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/bitcoin-evolves-from-tulips-into-a-geopolitical-weapon-as-us-9842\/\">Bitcoin Evolves From Tulips Into A Geopolitical Weapon As US Warned Again<\/a><br>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/el-salvador-brings-new-global-puzzle-what-is-bitcoin-how-to-10622\/\">El Salvador Brings New Global Puzzle &#8211; What Is Bitcoin &amp; How To Tax It?<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l&#8217;universo cripto ha trovato errate, per non dire altro, comprese le preoccupazioni ambientali, gli investimenti e l&#8217;utilit&agrave; di Bitcoin (BTC), l&#8217;uso per scopo illecito, la necessit&agrave; di una regolamentazione rigorosa, tra le altre cose.Elisabetta Warren. Fonte: uno screenshot video, Youtube\/Bloomberg [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,56,142,612,72,836,505],"editors":[],"sponsored_companies":[],"class_list":["post-54504","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-criptovalute","tag-mining","tag-politica","tag-regolamentazione","tag-regolamentazione-cripto","tag-usa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Siamo ai ferri corti&quot;: l&#039;universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti<\/title>\n<meta name=\"description\" content=\"La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l&#039;universo cripto ha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Siamo ai ferri corti&quot;: l&#039;universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti\" \/>\n<meta property=\"og:description\" content=\"La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l&#039;universo cripto ha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-10T21:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/54470\/18938\/60c1ebc6596db.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Siamo ai ferri corti\": l'universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti","description":"La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l'universo cripto ha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/","og_locale":"it_IT","og_type":"article","og_title":"\"Siamo ai ferri corti\": l'universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti","og_description":"La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l'universo cripto ha","og_url":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-06-10T21:03:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/54470\/18938\/60c1ebc6596db.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"&#8220;Siamo ai ferri corti&#8221;: l&#8217;universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti","datePublished":"2021-06-10T21:03:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/"},"wordCount":767,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg","keywords":["bitcoin","criptovalute","mining","Politica","regolamentazione","Regolamentazione Cripto","usa"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/","url":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/","name":"\"Siamo ai ferri corti\": l'universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg","datePublished":"2021-06-10T21:03:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"La popolare senatrice democratica statunitense Elizabeth Warren ha rilasciato alcune dichiarazioni relative alle criptovalute che l'universo cripto ha","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60c\/1ebbebada0.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/knives-coming-out-as-cryptoverse-responds-to-btc-fud-by-us-10635-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;Siamo ai ferri corti&#8221;: l&#8217;universo cripto risponde al FUD su BTC provocato dal senatore degli Stati Uniti"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/54504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=54504"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/54504\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=54504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=54504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=54504"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=54504"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=54504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}