{"id":53867,"date":"2021-05-31T10:59:00","date_gmt":"2021-05-31T10:59:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=53867"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/","title":{"rendered":"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave; vicino a scendere anche al di sotto del punteggio di 5, dove non lo vedevamo da un po &#8216;di tempo. Secondo il sito di analisi del sentimento del mercato delle criptovalute <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/guides\/how-to-get-predicoin-discount\/\"><strong>Omenics<\/strong><\/a>, il punteggio medio del sentiment del mercato delle criptovalute a 7 giorni (sentscore) per dieci monete principali &egrave; ora 5,03 rispetto ai 5,49 visto <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-drops-further-bitcoin-deep-in-the-ne-10431-it\/\">la scorsa settimana<\/a>. Inoltre, tutte le monete sono cadute dalla zona positiva.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/60b\/4bd112ee55.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/60b\/4bd112ee55.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/60b\/4bd112ee55.jpg 900w\" sizes=\"100vw\"><\/figure><p>Source: iStock\/Koonsiri Boonnak<\/p><p>L&#8217;intero elenco delle dieci monete principali &egrave; diventato rosso, tranne per una moneta, che &egrave; per impostazione predefinita il nostro vincitore della settimana. Il sentscore di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\">Bitcoin (BTC)<\/a> &egrave; aumentato del 3% negli ultimi sette giorni, dopo due cali consecutivi.<\/p><p>Se guardiamo alla lunga lista delle monete in rosso, il calo pi&ugrave; alto, quello di quasi il 13% e l&#8217;unico a doppia cifra, &egrave; stato visto da <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/ripple\/\">XRP<\/a>. Seguono <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/polkadot-iou\/\">Polkadot (DOT)<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/coins\/cardano\/\">cardano<\/a> rispettivamente con il 9,5% e il 9%. Il calo pi&ugrave; basso &egrave; quello di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/ethereum\/\">ethereum (ETH)<\/a>, inferiore all&#8217;1%.<\/p><p>L&#8217;ascesa di Bitcoin, tuttavia, non &egrave; stata sufficiente per riportare il suo sentscore verso l&#8217;alto, poich&eacute; ethereum mantiene ancora quel posto, sebbene anche lui sia ora fuori dalla zona positiva. Il sentscore di ETH &egrave; 5.9, rispetto ai 5.6 di BTC.<\/p><p><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/tether\/\">Tether (USDT)<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/uni-uniswap\/\">uniswap (UNI)<\/a> hanno un punteggio di 5,2 ciascuno, mentre cardano e polkadot sono a 5,1. Le monete rimanenti hanno tutte punteggi inferiori a 5, con il pi&ugrave; basso di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/binance-coin\/\">binance coin (BNB)<\/a> e XRP 4. Ci&ograve; lascia USD coin (USDC) e chainlink (LINK), entrambi a quasi 5.<\/p><p>Ci sono stati un paio di cambiamenti nella lista ancora una volta questa settimana: questa volta, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/litecoin\/\">litecoin (LTC)<\/a> e <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/tron\/\">tron (TRX)<\/a> sono fuori, sostituiti da USDC e DOT.<\/p><p><strong>Cambio di sentimento tra le prime 10 monete nella scorsa settimana*:<\/strong><br>Interpretazione della scala del sentscore:<br>&#8211; da 0 a 2,5: molto negativo<br>&#8211; da 2 a 3,9: zona alquanto negativa<br>&#8211; da 4 a 5.9: zona neutra<br>&#8211; da 6 a 7,49: zona piuttosto positiva<br>&#8211; da 7,5 a 10: molto positiva<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" class=\" lazyload\" data-src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4b94bba9ab.png\" data-srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4b94bba9ab.png 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/60b\/4b94bba9ab.png 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/60b\/4b94bba9ab.png 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/60b\/4b94bba9ab.png 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/60b\/4b94bba9ab.png 1014w\"><\/figure><p>Fonte: Omenics, 8:43 UTC<\/p><p>Anche la situazione quotidiana ha continuato a peggiorare. Il punteggio di 24 ore per le prime 10 monete ha fatto un altro passo indietro, attestandosi attualmente a 4,79 rispetto ai 4,96 registrati luned&igrave; scorso. Due monete hanno visto aumentare i loro punteggi nell&#8217;ultimo giorno, ovvero BNB e ADA, che sono aumentate rispettivamente del 3%, 2% e 0,3%, mentre USDC &egrave; quasi invariata. Il resto della lista &egrave; in ribasso, tra il 9% di DOT e quasi il 2% registrato sia da BTC che da XRP. Ethereum &egrave; ancora in testa alla lista, con un punteggio di 5,8, ma rispetto a luned&igrave; scorso bitcoin &egrave; ora passato da 5,1 a 5,6. USDC &egrave; l&#8217;unica altra moneta con un punteggio superiore a 5 (5,1), mentre il resto si trova nell&#8217;intervallo 4,1 (tether) &#8211; 4,9 (uniswap).<\/p><p><strong>Variazione giornaliera del punteggio di Bitcoin nell&#8217;ultimo mese:<\/strong><\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" class=\" lazyload\" data-src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4b9728ad3b.png\" data-srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4b9728ad3b.png 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/60b\/4b9728ad3b.png 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/60b\/4b9728ad3b.png 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/60b\/4b9728ad3b.png 900w\"><\/figure><p>Fonte: Omenics<\/p><p>Ma Omenics valuta altre 25 monete oltre alle prime 10. Nel corso dell&#8217;ultima settimana, tutte tranne una sono diminuite. L&#8217;unico sentscore a salire a malapena &egrave; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/coins\/republic-protocol\/\">REN<\/a>, con lo 0,3%. Nel frattempo, il calo maggiore &egrave; del 22% visto dal sentscore di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/coins\/aave-new\/\">AAVE<\/a> e il pi&ugrave; basso &egrave; del 2% di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/coins\/qtum\/\">QTUM<\/a>. Un cambiamento significativo rispetto alla scorsa settimana &egrave; che non una singola moneta ora risiede nella zona positiva, il che significa che l&#8217;intero elenco di 35 monete &egrave; ora nel territorio neutro. Solo otto monete tra le 25 ora hanno punteggi superiori a 5, il pi&ugrave; alto &egrave; il 5.6 di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/coins\/algo-algorand\/\">algorand (ALGO)<\/a>. I punteggi della maggioranza sono, quindi, al di sotto del punteggio di 5, e ora, dopo diverse settimane, abbiamo di nuovo una moneta nella zona negativa &#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/coins\/0x\/\">0x (ZRX)<\/a> che ora si trova a 3,5.<\/p><p>____<\/p><p><strong>* &#8211; Metodologia:<\/strong><\/p><p><i>Omenics misura il sentimento del mercato calcolando il SentScore, che aggrega il sentimento di notizie, social media, analisi tecnica, tendenze virali e fondamentali delle monete in base ai loro algoritmi proprietari.<\/i><br><i>Come spiega il loro sito web, &#8220;Omenics aggrega articoli di tendenza e post virali sui social media in una piattaforma di dati all-in-one, dove puoi anche analizzare i sentimenti dei contenuti&#8221;, aggiungendo in seguito, &#8220;Omenics combina i 2 indicatori di sentimento delle notizie e dei social media con 3 verticali aggiuntivi quali l&#8217;analisi tecnica, i fondamentali delle monete e il &#8220;brusio&#8221; delle voci di corridoio, con un conseguente SentScore che riporta una prospettiva generale per ogni moneta. &#8220;Per ora analizzano 39 criptovalute.<\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave; vicino a scendere anche al di sotto del punteggio di 5, dove non lo vedevamo da un po &#8216;di tempo. Secondo il sito di analisi del sentimento del mercato delle criptovalute [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,321,255,53,508,114,50,463,244],"editors":[],"sponsored_companies":[],"class_list":["post-53867","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-cardano","tag-chainlink","tag-ethereum","tag-polkadot","tag-sentimento","tag-tether","tag-uniswap","tag-xrp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna<\/title>\n<meta name=\"description\" content=\"Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna\" \/>\n<meta property=\"og:description\" content=\"Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-31T10:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/53861\/18663\/60b4bd185acf7.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna","description":"Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/","og_locale":"it_IT","og_type":"article","og_title":"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna","og_description":"Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave;","og_url":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-05-31T10:59:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/53861\/18663\/60b4bd185acf7.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna","datePublished":"2021-05-31T10:59:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/"},"wordCount":735,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg","keywords":["bitcoin","cardano","chainlink","ethereum","polkadot","sentimento","tether","uniswap","xrp"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/","url":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/","name":"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg","datePublished":"2021-05-31T10:59:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Forse non sorprende che, dato il recente mercato in rosso, il sentimento del mercato delle criptovalute &egrave; sceso ancora una volta, ma ora &egrave;","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/60b\/4bd112ee55.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/crypto-market-sentiment-keeps-dropping-bitcoin-wins-week-eth-10516-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il sentimento del mercato cripto continua a diminuire; Bitcoin vince la settimana, Ethereum regna"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/53867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=53867"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/53867\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=53867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=53867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=53867"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=53867"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=53867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}