{"id":52576,"date":"2021-05-11T11:04:00","date_gmt":"2021-05-11T11:04:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=52576"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/","title":{"rendered":"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Forse stanco di personaggi del calibro di <a href=\"https:\/\/cryptonews.com\/tags\/elon-musk\/\" target=\"_blank\" rel=\"noopener\">Elon Musk<\/a> e <a href=\"https:\/\/cryptonews.com\/tags\/Mark-Cuban\/\" target=\"_blank\" rel=\"noopener\">Mark Cuban<\/a> che dominano la stampa delle Cripto, il supremo di <strong>Facebook <\/strong>Mark Zuckerberg &egrave; emerso dall&#8217;ombra con una sua mossa da prima pagina: chiamando la sua nuova capra domestica come il pi&ugrave; grande criptoasset del mondo: <a href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\" target=\"_blank\" rel=\"noopener\">bitcoin (BTC)<\/a> .<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png\" alt=\"\"><\/figure><p>Fonte: Adobe \/ kovop58<\/p><p>&#8220;Bitcoin the Goat&#8221; &egrave; diventato Il Discorso di punta in rete dopo che Zuckerberg ha pubblicato una foto dell&#8217;animale che si scatena in quello che sembrava essere un fienile, con un compagno di giochi di nome Max, sulla sua pagina Facebook.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" class=\" lazyload\" data-src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a34cb68762.png\" data-srcset=\"\"><\/figure><p>Fonte: facebook.com<\/p><p>La comunit&agrave; di BTC ha discusso sul significato della capra e del suo soprannome. Su Twitter, Madelon Vos, editorialista olandese e bitcoiner, si &egrave; concessa qualche gioco di parole, scherzando sul fatto che il messaggio segreto dietro la denominazione era che i fan di Bitcoin sono GOAT (Greatest Of All Time &#8211; i migliori di sempre). In effetti, altri fan di Bitcoin hanno usato giochi di parole molto <a href=\"https:\/\/twitter.com\/muellerberndt\/status\/1391987399283068929\" target=\"_blank\" rel=\"noopener\">simili <\/a>&#8211; una gradita distrazione questa, forse per lo <a href=\"https:\/\/cryptonews.com\/it\/news\/bitcoin-and-ethereum-extend-correction-altcoins-trim-gains-10251-it\/\" target=\"_blank\" rel=\"noopener\">scivolone irregolare<\/a> del token al di sotto di 55.000 USD nelle ultime ore.<\/p><p>Il consulente e investitore cripto Anndy Lian &egrave; stato un altro a saltare sul carrozzone dello scherzo su Bitcoin, ma ha anche chiesto se la scelta del nome indicava che Zuckerberg era pronto ad abbandonare gli investimenti in azioni a favore di un portafoglio cripto.<\/p><p>Un altro appassionato di criptovalute, il CEO e co-fondatore di <strong>CoinCorner <\/strong>Danny Scott, <a href=\"https:\/\/twitter.com\/CoinCornerDanny\/status\/1391991648649981957\" target=\"_blank\" rel=\"noopener\">ha chiesto<\/a> se l&#8217;amore per Bitcoin di Zukerberg significasse che si era disinnamorato di Libra, il progetto di stablecoin della sua azienda ora noto come Diem.<\/p><p>Tra l&#8217;allegria e l&#8217;eccitazione, alcune anime sobrie si sono fatte sentire a gran voce. Il trader di bitcoin e il tweeter di criptovalute @BitBitCrypto <a href=\"https:\/\/twitter.com\/BitBitCrypto\/status\/1391889857031688193\" target=\"_blank\" rel=\"noopener\">ha scritto:<\/a><\/p><blockquote>\r\n<p>&#8220;Zuckerberg ne sa di bitcoin ma non &egrave; ancora nel bilancio di Facebook. Invece, ha chiamato la sua capra Bitcoin. Ragazzi? Non sono sicuro che questo sia un segnale di acquisto. &#8220;<\/p>\r\n<\/blockquote><p>Ma oggi a tali voci non sarebbe stato concesso molto tempo di trasmissione, con Francis Pouliot, CEO e fondatore di <strong>Bull Bitcoin<\/strong>, che rispondeva scherzosamente:<\/p><blockquote>\r\n<p>&#8220;Perch&eacute; [Zuckerberg] dovrebbe volerlo mettere sul bilancio di Facebook invece di sopprimere il prezzo abbastanza a lungo da accumularne come un imperatore?&#8221;<\/p>\r\n<\/blockquote><p>La tempistica del post di Zuckerberg suggerisce che potrebbe aver prestato molta attenzione a <i>Cryptonews.com<\/i>, che alla fine del mese scorso ha delineato<a href=\"https:\/\/cryptonews.com\/it\/exclusives\/3-reasons-facebook-should-buy-and-hold-bitcoin-10087-it\/\" target=\"_blank\" rel=\"noopener\"> tre motivi convincenti<\/a> per cui la sua azienda dovrebbe assumere una posizione in bitcoin.<\/p><p>Ma c&#8217;&egrave; stata una svolta macabra in tutto questo divertimento a tema Capra &#8211; poich&eacute; alcuni con una buona memoria hanno ricordato la bizzarra storia di come Zuckerberg una volta uccise una capra che possedeva&#8230; e poi la serv&igrave; al boss di <strong>Twitter <\/strong>Jack Dorsey.<\/p><p>Nel 2019, Rolling Stone <a href=\"https:\/\/www.rollingstone.com\/culture\/culture-features\/twitter-ceo-jack-dorsey-rolling-stone-interview-782298\/\" target=\"_blank\" rel=\"noopener\">ha fatto&nbsp;<\/a> un&#8217;intervista a Dorsey, in cui quest&#8217;ultimo ha spiegato che Zuckerberg uccise una capra che aveva allevato, &#8220;probabilmente con una pistola stordente e un coltello&#8221;, prima di mandarla al macellaio.<\/p><blockquote>\r\n<p>&#8220;Evidentemente a Palo Alto esiste una regola o un regolamento secondo cui si possono avere sei bestie su qualsiasi lotto di terra, quindi all&#8217;epoca aveva sei capre&#8221;, ha detto Dorsey.<\/p>\r\n<\/blockquote><p>La carne della capra uccisa &egrave; stata quindi messa nel forno, ma non &egrave; uscita come previsto.<\/p><p>Dorsey ha continuato:<\/p><blockquote>\r\n<p>&ldquo;Andammo in sala da pranzo. Mark mette la capra nel tavolo. Era ancora fredda. &Egrave; stato memorabile. Non so se sia tornata nel forno. Io ho solo mangiato la mia insalata. &#8220;<\/p>\r\n<\/blockquote><p>Zuck uccider&agrave; Bitcoin? Lo manger&agrave; a pranzo? O il Bitcoin apparir&agrave; nel bilancio di Facebook? Resta sintonizzato su <i>Cryptonews.com<\/i> per scoprirlo!<br>___<br><strong>Per saperne di pi&ugrave;:<\/strong><br>&#8211; <a href=\"https:\/\/cryptonews.com\/exclusives\/3-reasons-facebook-should-buy-and-hold-bitcoin-10087\/\" target=\"_blank\" rel=\"noopener\">3 Reasons Facebook Should Buy and Hold Bitcoin<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/exclusives\/why-this-bitcoin-believing-startup-bets-on-facebook-s-diem-i-9576\/\" target=\"_blank\" rel=\"noopener\">Why This Bitcoin-Believing Startup Bets on Facebook&#8217;s Diem Instead<\/a><\/p><p>&#8211; <a href=\"https:\/\/cryptonews.com\/news\/bitcoin-bulls-just-got-a-new-friend-the-bitcoin-cow-bitkoink-9522\/\" target=\"_blank\" rel=\"noopener\">Bitcoin Bulls Just Got A New Friend &#8211; The Bitcoin Cow, Bitkoinka<\/a><br>&#8211; <a href=\"https:\/\/cryptonews.com\/exclusives\/meet-the-fastest-cryptocurrency-in-the-world-she-has-four-le-5266\/\" target=\"_blank\" rel=\"noopener\">Meet the Fastest Cryptocurrency in the World; She has Four Legs<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Forse stanco di personaggi del calibro di Elon Musk e Mark Cuban che dominano la stampa delle Cripto, il supremo di Facebook Mark Zuckerberg &egrave; emerso dall&#8217;ombra con una sua mossa da prima pagina: chiamando la sua nuova capra domestica come il pi&ugrave; grande criptoasset del mondo: bitcoin (BTC) .Fonte: Adobe \/ kovop58&#8220;Bitcoin the Goat&#8221; [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,81],"editors":[],"sponsored_companies":[],"class_list":["post-52576","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-facebook"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?<\/title>\n<meta name=\"description\" content=\"Forse stanco di personaggi del calibro di Elon Musk e Mark Cuban che dominano la stampa delle Cripto, il supremo di Facebook Mark Zuckerberg &egrave;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?\" \/>\n<meta property=\"og:description\" content=\"Forse stanco di personaggi del calibro di Elon Musk e Mark Cuban che dominano la stampa delle Cripto, il supremo di Facebook Mark Zuckerberg &egrave;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-11T11:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/52573\/18167\/609a3589899df.png\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?","description":"Forse stanco di personaggi del calibro di Elon Musk e Mark Cuban che dominano la stampa delle Cripto, il supremo di Facebook Mark Zuckerberg &egrave;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/","og_locale":"it_IT","og_type":"article","og_title":"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?","og_description":"Forse stanco di personaggi del calibro di Elon Musk e Mark Cuban che dominano la stampa delle Cripto, il supremo di Facebook Mark Zuckerberg &egrave;","og_url":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/","og_site_name":"Cryptonews Italia","article_published_time":"2021-05-11T11:04:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/52573\/18167\/609a3589899df.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/"},"author":{"name":"irenesalmasoygfv","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/2dfccc675e194e58c94137e52cdd3c1d"},"headline":"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?","datePublished":"2021-05-11T11:04:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/"},"wordCount":674,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png","keywords":["bitcoin","facebook"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/","url":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/","name":"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png","datePublished":"2021-05-11T11:04:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Forse stanco di personaggi del calibro di Elon Musk e Mark Cuban che dominano la stampa delle Cripto, il supremo di Facebook Mark Zuckerberg &egrave;","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/609\/a357b08444.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/will-facebook-s-mark-zuckerberg-kill-or-save-bitcoin-the-goa-10252-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il fondatore di Facebook Mark Zuckerberg uccider\u00e0 o salver\u00e0 (la sua capra) Bitcoin?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/52576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=52576"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/52576\/revisions"}],"predecessor-version":[{"id":171886,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/52576\/revisions\/171886"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=52576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=52576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=52576"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=52576"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=52576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}