{"id":44205,"date":"2020-09-09T17:49:05","date_gmt":"2020-09-09T17:49:05","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=44205"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/","title":{"rendered":"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso <a href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\">bitcoin (BTC) <\/a> ed altre criptovalute, ha affermato un dirigente di<b>Morgan Stanley <\/b>.<\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5f5\/8ccf2dc972.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5f5\/8ccf2dc972.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5f5\/8ccf2dc972.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5f5\/8ccf2dc972.jpg 1207w\" alt=\"\" class=\"content-img\"><figcaption>Fonte: Adobe\/wolterke<\/figcaption><\/figure><p>In un&#8217;intervista con la CNN, il responsabile dei mercati emergenti e del Global Macro Ruchir Sharma di Morgan Stanley, ha affermato che le azioni delle banche centrali stavano spingendo i singoli investitori in tutto il mondo a cercare asset alternativi come bitcoin poich&eacute; i tassi di interesse rimangono deboli.<\/p><p>Le banche centrali di tutto il mondo hanno avviato programmi di acquisto di buoni del tesoro volti a riavviare le economie lente che sono state rallentate dalle misure di blocco per il<a href=\"https:\/\/cryptonews.com\/tags\/coronavirus\/\">coronavirus <\/a>, stampando efficacemente milioni di dollari in fiat nelle principali economie.<\/p><p>Sharma ha dichiarato,<\/p><blockquote class=\"left\"><p>&ldquo;Penso che alcuni degli [investitori] pi&ugrave; anziani stiano ancora acquistando oro, e che alcuni dei pi&ugrave; giovani, i millennial, stiano acquistando bitcoin e [criptoasset]. Ma in generale, penso che ci&ograve; ci stia mostrando che c&#8217;&egrave; questa persistente sensazione l&agrave; fuori, dato quello che le banche centrali stanno facendo in termini di stampa di cos&igrave; tanti soldi, di una ricerca di asset alternativi. &#8220;<\/p><\/blockquote><p>Il dirigente di Morgan Stanley ha aggiunto che le quotazioni azionarie alle stelle e un crescente senso di distacco dallo stato generale dell&#8217;economia potrebbero indurre gli investitori a reinvestire i propri fondi in metalli preziosi e criptovalute.<\/p><p>Le osservazioni di Sharma fanno eco ai recenti commenti di Nigel Green, amministratore delegato e fondatore della societ&agrave; di consulenza finanziaria internazionale <b>deVere <\/b>.<\/p><p>Il capo deVere <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2020-09-08\/bitcoin-s-breach-of-10-000-mark-may-portend-for-deeper-losses\">ha detto a <\/a> Bloomberg che&#8221; i fondamentali che rendono il bitcoin un investimento interessante si stanno rafforzando &#8220;nonostante un recente calo dei prezzi che ha visto BTC scendere brevemente sotto quota 10.000 USD.<\/p><p>Green ha dichiarato,<\/p><blockquote class=\"left\"><p>&ldquo;I cinici nei confronti delle cripto e i tradizionalisti finanziari useranno l&#8217;attuale &#8211; e temporanea &#8211; caduta di bitcoin come scusa per abbattere i suoi punti di forza intrinseci per adattarsi ai propri programmi. Tuttavia, la realt&agrave; &egrave; che la possibilit&agrave; per bitcoin di esplodere quest&#8217;anno &egrave; pi&ugrave; forte che mai &#8220;, <\/p><\/blockquote><p>Green ha anche affermato che &egrave; probabile che le iniziative di stimolo economico della banca centrale spingano ancora pi&ugrave; investitori verso BTC. Ha anche preso nota degli attraenti &#8220;fondamentali sottostanti&#8221; del token.<\/p><p>Green ha previsto che un aumento dell&#8217;interesse da parte degli investitori potrebbe probabilmente facilitare un forte rimbalzo dei prezzi per il token.<\/p><p>In questo preciso momento (12:33 PM UTC), BTC viene scambiato a 10.197 USD e aumenta dell&#8217;1,6% in un giorno, riducendo le sue perdite settimanali a meno dell&#8217;11%. Anche il prezzo &egrave; sceso del 13% in un mese ed &egrave; pressoch&eacute; invariato in un anno.<br>\n__<br>\nGuarda l&#8217;intervista con Ruchir Sharma di seguito:<\/p><div class=\"tweet tweetContainer\"><blockquote class=\"twitter-tweet\" data-lang=\"en\"><p lang=\"en\" dir=\"ltr\">$GOLD, $BTC, $XRP or $SPX?<\/p>&mdash; Julia Chatterley (@jchatterleyCNN) <a href=\"https:\/\/twitter.com\/jchatterleyCNN\/status\/1303351136095789059\"><\/a><\/blockquote><script>!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");<\/script><\/div><p>__<br>\n<b>Scopri di pi&ugrave;:<\/b> <a href=\"https:\/\/cryptonews.com\/news\/gold-and-bitcoin-surge-exposes-generational-divide-jp-morgan-7331\/\">Il rally di Oro e Bitcoin espone il divario generazionale &#8211; JP Morgan<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso bitcoin (BTC) ed altre criptovalute, ha affermato un dirigente diMorgan Stanley .Fonte: Adobe\/wolterkeIn un&#8217;intervista con la CNN, il responsabile dei mercati emergenti e del Global Macro Ruchir Sharma di Morgan Stanley, ha affermato che le azioni delle banche centrali stavano spingendo i singoli investitori [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[422,45,375,56],"editors":[306],"sponsored_companies":[],"class_list":["post-44205","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-banca-centrale","tag-bitcoin","tag-coronavirus","tag-criptovalute","editors-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin<\/title>\n<meta name=\"description\" content=\"Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso bitcoin (BTC) ed altre criptovalute, ha affermato un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin\" \/>\n<meta property=\"og:description\" content=\"Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso bitcoin (BTC) ed altre criptovalute, ha affermato un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-09T17:49:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/33139\/10647\/5f58cd2f5f4d4.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin","description":"Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso bitcoin (BTC) ed altre criptovalute, ha affermato un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/","og_locale":"it_IT","og_type":"article","og_title":"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin","og_description":"Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso bitcoin (BTC) ed altre criptovalute, ha affermato un","og_url":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/","og_site_name":"Cryptonews Italia","article_published_time":"2020-09-09T17:49:05+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/33139\/10647\/5f58cd2f5f4d4.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin","datePublished":"2020-09-09T17:49:05+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/"},"wordCount":490,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg","keywords":["banca centrale","bitcoin","coronavirus","criptovalute"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/","url":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/","name":"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg","datePublished":"2020-09-09T17:49:05+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Le banche centrali potrebbero spingere inavvertitamente una generazione di investitori verso bitcoin (BTC) ed altre criptovalute, ha affermato un","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f5\/8ccf2dc972.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/central-banks-are-driving-people-to-bitcoin-morgan-stanley-e-5670\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dirigente Morgan Stanley: le banche centrali spingono le persone verso Bitcoin"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/44205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=44205"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/44205\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=44205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=44205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=44205"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=44205"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=44205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}