{"id":44191,"date":"2020-09-02T18:17:14","date_gmt":"2020-09-02T18:17:14","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=44191"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/","title":{"rendered":"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) &#8211; e spinto da questo &#8211; alcuni analisti si aspettano che <a href=\"https:\/\/cryptonews.com\/coins\/wrapped-bitcoin\/\">wrapped bitcoin<\/a> continui ad essere un ponte in crescita sul quale <a href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\">bitcoin (BTC)<\/a> verrebbe portato su <a href=\"https:\/\/cryptonews.com\/it\/coins\/ethereum\/\">Ethereum (ETH)<\/a>. <\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5f4\/f879c63b9e.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5f4\/f879c63b9e.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5f4\/f879c63b9e.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5f4\/f879c63b9e.jpg 1188w\" alt=\"\" class=\"content-img\"><figcaption>Fonte: Adobe\/Aania<\/figcaption><\/figure><p>Il fornitore di dati del mercato cripto Messari <a href=\"https:\/\/us17.campaign-archive.com\/?u=5b89525c77acdd986027c25d1&amp;id=178ec2852b\" target=\"_blank\" rel=\"noopener\">ha notato<\/a> una migrazione di stablecoin verso Ethereum &#8220;in massa, rendendo il valore fiat interoperabile con le applicazioni basate su ETH&#8221;. A questo, hanno aggiunto: &#8220;Ora, attratti dal fascino del fiorente ecosistema DeFi di Ethereum, stiamo iniziando a vedere una tendenza simile con Bitcoin&#8221;.<\/p><p>Quello che descrivono &egrave; un ponte attraverso il quale i possessori di BTC hanno spostato &#8220;pi&ugrave; di mezzo miliardo di dollari di bitcoin su Ethereum&#8221;. Il ponte principale qui, secondo l&#8217;azienda, &egrave; il wrapped bitcoin fornito dalla principale societ&agrave; di custodia di criptovalute <b><a href=\"https:\/\/cryptonews.com\/tags\/bitgo\/\">BitGo<\/a><\/b>, wBTC. <\/p><p>Come <a href=\"https:\/\/cryptonews.com\/news\/what-wrapped-bitcoin-is-and-what-s-so-special-about-it-3295\/\">riportato<\/a> in precedenza, wBTC &egrave; entrato in funzione sulla blockchain di Ethereum nel gennaio 2019. Si tratta di un token ERC20 destinato a rappresentare bitcoin e, secondo quanto riferito, &egrave; supportato 1-1 da BTC. Presenta diversi vantaggi, come un trasferimento pi&ugrave; veloce del bitcoin, nonch&eacute; la sua integrazione con l&#8217;intero ecosistema Ethereum, comprese le dapps (app decentralizzate), i contratti intelligenti e s&igrave;, la fiorente DeFi che ne deriva. <a href=\"https:\/\/wbtc.network\/dashboard\/audit\" target=\"_blank\" rel=\"noopener\">wBTC<\/a> &egrave; tenuto presso il Bitgo Trust. <\/p><p>Gli utenti inviano BTC a BitGo che lo custodisce per loro conto e conia i corrispondenti token ERC20 ancorati a BTC su Ethereum. &#8220;Questi token ancorati a BTC possono quindi essere utilizzati in vari protocolli DeFi. Attualmente, su Ethereum sono stati coniati circa [USD] 440 milioni in wBTC&#8221;, secondo Messari.<\/p><p>E sebbene questa sia una soluzione centralizzata per un wrapped BTC, <b>Keep Network<\/b> e <a href=\"https:\/\/cryptonews.com\/coins\/republic-protocol\/\">RenVM<\/a> ha affidato il proprio tBTC e renBTC ad una rete di depositari decentralizzata. Mentre Keep Network &egrave; stato lanciato a maggio e poi ha dovuto sospendere i depositi a causa di una vulnerabilit&agrave; scoperta, RenVM &#8220;ha facilitato pi&ugrave; di 380 milioni di dollari in volume tra le catene e attualmente custodisce pi&ugrave; di 130 milioni di dollari in asset (quasi interamente in bitcoin)&#8221;, ha aggiunto Messari . <\/p><figure style=\"max-width: 675px\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" sizes=\"(min-width: 640px) 675px, 100vw\" alt=\"\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f857f83165.jpg\" data-srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f857f83165.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5f4\/f857f83165.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5f4\/f857f83165.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5f4\/f857f83165.jpg 900w\"><figcaption>In milioni di dollari. Fonte: Messari<\/figcaption><\/figure><p> <\/p><blockquote><p>&#8220;Questo comportamento &egrave; indicativo di quello che probabilmente sar&agrave; il caso d&#8217;uso principale per l&#8217;interoperabilit&agrave; nel prossimo futuro. Dato che Ethereum &egrave; il centro dell&#8217;universo finanziario decentralizzato, l&#8217;interoperabilit&agrave; a breve termine servir&agrave; a portare diversi asset da e verso Ethereum. Con solo lo 0,3% di tutti i bitcoin su Ethereum, l&#8217;opportunit&agrave; di ponti decentralizzati tra le due catene &egrave; difficile da perdere&#8221;, ha affermato l&#8217;azienda.<\/p><\/blockquote><p>Nel frattempo, <a href=\"https:\/\/defipulse.com\/\" target=\"_blank\" rel=\"noopener\">secondo<\/a> Defi Pulse,il valore totale bloccato (TVL) nella DeFi al momento &egrave; di 9,5 miliardi di dollari. Ha visto un massiccio aumento negli ultimi tre mesi. wBTC si trova al 9&deg; posto, preceduto da <b>Balancer <\/b> e seguito da RenVM. La TVL in wBTC &egrave; di 468 milioni di dollari, con un aumento dell&#8217;1.111% da met&agrave; giugno.<\/p><p>Alle 10:15 UTC, il prezzo di wBTC &egrave; di 11.620 USD, con un calo del 5,6% in un giorno. Si &egrave; apprezzato, 1,5% in una settimana. Il prezzo di BTC &egrave; 11.739. &Egrave; diminuito dell&#8217;1,6% in un giorno e &egrave; aumentato del 3% in una settimana.<\/p><p>Il Cryptoverso non ha dimenticato il wrapped bitcoin e il suo potenziale. E mentre alcuni si chiedevano cosa rappresentasse in realt&agrave;, altri pensavano che potesse essere utile nella frenesia della <a href=\"https:\/\/cryptonews.com\/news\/liquidity-mining-is-like-uber-giving-shares-to-early-drivers-7047\/\">yield farming<\/a>. <\/p><p>Ecco alcune reazioni:<\/p><div class=\"tweet tweetContainer\"><blockquote class=\"twitter-tweet\" data-lang=\"en\"><p lang=\"en\" dir=\"ltr\">@VentureCoinist Debt<\/p>&mdash; Alex Thorn (@intangiblecoins) <a href=\"https:\/\/twitter.com\/intangiblecoins\/status\/1301003396946817025\"><\/a><\/blockquote><script>!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");<\/script><\/div><p>__<\/p><div class=\"tweet tweetContainer\"><blockquote class=\"twitter-tweet\" data-lang=\"en\"><p lang=\"en\" dir=\"ltr\">@kaiynne Caulk it up as a culture difference.<\/p>&mdash; DavidHoffman.eth ? (@TrustlessState) <a href=\"https:\/\/twitter.com\/TrustlessState\/status\/1301036436469153792\"><\/a><\/blockquote><script>!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");<\/script><\/div><p>__<\/p><div class=\"tweet tweetContainer\"><blockquote class=\"twitter-tweet\" data-lang=\"en\"><p lang=\"en\" dir=\"ltr\">@Dogetoshi By the end of this bull market, I wouldn&#8217;t be surprised if a teenager who just learned Solidity and crea&hellip; <a href=\"https:\/\/t.co\/E4ZKLCwYZE\">https:\/\/t.co\/E4ZKLCwYZE<\/a><\/p>&mdash; DCinvestor.eth &#10208; aftab.eth (@iamDCinvestor) <a href=\"https:\/\/twitter.com\/iamDCinvestor\/status\/1300857046158520320\"><\/a><\/blockquote><script>!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) &#8211; e spinto da questo &#8211; alcuni analisti si aspettano che wrapped bitcoin continui ad essere un ponte in crescita sul quale bitcoin (BTC) verrebbe portato su Ethereum (ETH). Fonte: Adobe\/AaniaIl fornitore di dati del mercato cripto Messari ha notato una migrazione di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[45,102,53,406],"editors":[],"sponsored_companies":[],"class_list":["post-44191","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-bitcoin","tag-defi","tag-ethereum","tag-finanza-decentralizzata"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo<\/title>\n<meta name=\"description\" content=\"A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) - e spinto da questo - alcuni analisti si aspettano che wrapped\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo\" \/>\n<meta property=\"og:description\" content=\"A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) - e spinto da questo - alcuni analisti si aspettano che wrapped\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-02T18:17:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/28419\/10584\/5f4f87a50f429.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo","description":"A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) - e spinto da questo - alcuni analisti si aspettano che wrapped","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/","og_locale":"it_IT","og_type":"article","og_title":"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo","og_description":"A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) - e spinto da questo - alcuni analisti si aspettano che wrapped","og_url":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/","og_site_name":"Cryptonews Italia","article_published_time":"2020-09-02T18:17:14+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/28419\/10584\/5f4f87a50f429.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo","datePublished":"2020-09-02T18:17:14+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/"},"wordCount":634,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg","keywords":["bitcoin","defi","ethereum","finanza decentralizzata"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/","url":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/","name":"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg","datePublished":"2020-09-02T18:17:14+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"A seguito del recente massiccio aumento dei progetti di finanza decentralizzata (DeFi) - e spinto da questo - alcuni analisti si aspettano che wrapped","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5f4\/f879c63b9e.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/prompted-by-booming-defi-a-bridge-between-bitoin-and-ethereu-5605\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Spinto dal boom della DeFi, un ponte tra Bitcoin ed Ethereum sta crescendo"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/44191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=44191"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/44191\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=44191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=44191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=44191"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=44191"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=44191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}