{"id":44011,"date":"2020-06-10T06:00:00","date_gmt":"2020-06-10T06:00:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=44011"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/","title":{"rendered":"L&#8217;ascesa e la caduta della star blockchain cinese Kaiying Network"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Solo quattro anni fa, Wang Yue veniva festeggiato <a href=\"https:\/\/www.forbes.com\/sites\/russellflannery\/2016\/01\/03\/kingnets-wang-yue-is-chinas-latest-web-game-billionaire\/#216c56e5dd82\" target=\"_blank\" rel=\"noopener\">da attori del calibro di <\/a> Forbes come uno dei &#8220;miliardari pi&ugrave; giovani del mondo&#8221;. A 32 anni, aveva il mondo ai suoi piedi, come capo del colosso dei giochi <b>Shanghai Kingnet Technology <\/b>, noto anche come <b>Shanghai Kaiying Network Technology <\/b> o semplicemente <b>Kaiying Network <\/b> &#8211; una societ&agrave; che ha fondato da zero nel 2008.<\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5ed\/fb8820a5c0.jpeg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5ed\/fb8820a5c0.jpeg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5ed\/fb8820a5c0.jpeg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5ed\/fb8820a5c0.jpeg 2999w\" alt=\"\" class=\"content-img\"><figcaption>Fonte: Adobe\/Mariia Korneeva<\/figcaption><\/figure><p>Nel 2018, il mondo degli affari cinese ha trattenuto il respiro quando ha annunciato che la societ&agrave; si stava immergendo nel settore della tecnologia blockchain.<\/p><p>Solo due anni dopo, il sogno della blockchain della Kaiying Network &egrave; a pezzi &#8211; e la societ&agrave; dice che ha voltato le spalle alla blockchain, probabilmente per sempre, con Wang messo dietro le sbarre.<\/p><p>La blockchain della compagnia &egrave; diventata spettacolare.<\/p><p>Fino a pochi mesi fa, la Borsa di Shenzhen stava ancora posizionando Kaiying sul suo Blockchain 50 Index, accanto a pesi massimi come <b>Ping An <\/b>.<\/p><p>I piani blockchain di Wang Yue suonavano grandiosi in quel momento e si concentravano su una piattaforma di condivisione di contenuti che attirava l&#8217;attenzione di giganti dei media come <b>Xinhua<\/b>. But, <a href=\"https:\/\/www.bishijie.com\/shendu\/41096.html\" target=\"_blank\" rel=\"noopener\">secondo<\/a> un rapporto di Bi Shi Jie dell&#8217;anno scorso, Wang Yue era gi&agrave; in gravi difficolt&agrave; finanziarie quando ha fatto l&#8217;annuncio.<\/p><p>I prezzi delle azioni sono crollati nel 2018 e le sue stesse finanze hanno sofferto pi&ugrave; di tutti, con un calo delle quotazioni del 90%.<\/p><p>La piattaforma blockchain &egrave; stata l&#8217;ultimo lancio di dadi di Wang Yue, anche se poche persone tranne lui lo sanno al momento. Quando l&#8217;interesse per la piattaforma si &egrave; raffreddato rapidamente nel corso del 2018, probabilmente in coincidenza con la caduta dei prezzi delle criptovalute, Wang Yue &egrave; andato nel panico.<\/p><p>Voci di nefasti accordi dietro le quinte hanno iniziato a emergere all&#8217;inizio del 2019 ed &egrave; scomparso completamente, anche la societ&agrave; che ha fondato di cui possedeva ancora oltre il 20% non riusciva a raggiungerlo. &Egrave; stato rimosso come CEO e da maggio dell&#8217;anno scorso &#8220;non ha pi&ugrave; ricoperto alcuna posizione nella societ&agrave;&#8221;, secondo una dichiarazione ufficiale.<\/p><p>Giorni dopo, come <a href=\"https:\/\/kr-asia.com\/chinese-gaming-company-kingnet-confirms-its-boss-has-been-arrested-for-market-manipulation\" target=\"_blank\" rel=\"noopener\">raccontato da<\/a> KR-Asia, &egrave; stato rintracciato dalla polizia di Shanghai e arrestato con l&#8217;accusa di manipolazione del mercato dei titoli, con un tribunale che ha congelato le sue azioni.<\/p><p>La societ&agrave; &egrave; stata scossa ancora una volta nel dicembre dello scorso anno, quando ha perso una causa per violazione del copyright contro il colosso sudcoreano del gioco <b>WeMade<\/b> (attualmente in cerca di riposizionarsi come un grande protagonista della blockchain). Come <a href=\"https:\/\/biz.chosun.com\/site\/data\/html_dir\/2019\/12\/31\/2019123101724.html\" target=\"_blank\" rel=\"noopener\">riportato da<\/a> Chosun, Kaiying &egrave; stato condannato a risarcire danni per 3,4 milioni di dollari e un risarcimento di oltre 34.000 dollari.<\/p><p>I piani blockchain della societ&agrave; cinese erano stati di fatto in un limbo da allora, ma JRJ <a href=\"https:\/\/bc.jrj.com.cn\/2020\/06\/09102029878957.shtml\" target=\"_blank\" rel=\"noopener\">riporta<\/a> che in una recente call per le relazioni con gli investitori della Kaiying Network, sembra abbia finalmente cancellato i suoi piani una volta grandiosi per la blockchain.<\/p><p>Un investitore ha chiesto:<\/p><blockquote class=\"left\"><p>&ldquo;Kaiying si &egrave; completamente ritirato dal business della blockchain?&#8221;<\/p><\/blockquote><p>La societ&agrave; ha risposto che ora si stava concentrando sul suo core business dei giochi, &#8220;avendo gi&agrave; esplorato blockchain e altri campi&#8221;, aggiungendo che investimenti blockchain &#8220;non erano pi&ugrave;&#8221; all&#8217;orizzonte.<\/p>","protected":false},"excerpt":{"rendered":"<p>Solo quattro anni fa, Wang Yue veniva festeggiato da attori del calibro di Forbes come uno dei &#8220;miliardari pi&ugrave; giovani del mondo&#8221;. A 32 anni, aveva il mondo ai suoi piedi, come capo del colosso dei giochi Shanghai Kingnet Technology , noto anche come Shanghai Kaiying Network Technology o semplicemente Kaiying Network &#8211; una societ&agrave; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,1],"tags":[47,56,259],"editors":[],"sponsored_companies":[],"class_list":["post-44011","post","type-post","status-publish","format-standard","hentry","category-blockchain-news","category-news","tag-blockchain","tag-criptovalute","tag-gaming"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ascesa e la caduta della star blockchain cinese Kaiying Network<\/title>\n<meta name=\"description\" content=\"Solo quattro anni fa, Wang Yue veniva festeggiato da attori del calibro di Forbes come uno dei &quot;miliardari pi&ugrave; giovani del mondo&quot;. A 32 anni, aveva\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ascesa e la caduta della star blockchain cinese Kaiying Network\" \/>\n<meta property=\"og:description\" content=\"Solo quattro anni fa, Wang Yue veniva festeggiato da attori del calibro di Forbes come uno dei &quot;miliardari pi&ugrave; giovani del mondo&quot;. A 32 anni, aveva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/27609\/9808\/5edfb892a3a5e.jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ascesa e la caduta della star blockchain cinese Kaiying Network","description":"Solo quattro anni fa, Wang Yue veniva festeggiato da attori del calibro di Forbes come uno dei \"miliardari pi&ugrave; giovani del mondo\". A 32 anni, aveva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/","og_locale":"it_IT","og_type":"article","og_title":"L'ascesa e la caduta della star blockchain cinese Kaiying Network","og_description":"Solo quattro anni fa, Wang Yue veniva festeggiato da attori del calibro di Forbes come uno dei \"miliardari pi&ugrave; giovani del mondo\". A 32 anni, aveva","og_url":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/","og_site_name":"Cryptonews Italia","article_published_time":"2020-06-10T06:00:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/27609\/9808\/5edfb892a3a5e.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"L&#8217;ascesa e la caduta della star blockchain cinese Kaiying Network","datePublished":"2020-06-10T06:00:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/"},"wordCount":550,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg","keywords":["blockchain","criptovalute","gaming"],"articleSection":["Blockchain News","News"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/","url":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/","name":"L'ascesa e la caduta della star blockchain cinese Kaiying Network","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg","datePublished":"2020-06-10T06:00:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Solo quattro anni fa, Wang Yue veniva festeggiato da attori del calibro di Forbes come uno dei \"miliardari pi&ugrave; giovani del mondo\". A 32 anni, aveva","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5ed\/fb8820a5c0.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/the-rise-and-fall-of-a-chinese-blockchain-star-kaiying-netwo-4828\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;ascesa e la caduta della star blockchain cinese Kaiying Network"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/44011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=44011"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/44011\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=44011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=44011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=44011"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=44011"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=44011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}