{"id":43903,"date":"2020-04-20T14:57:29","date_gmt":"2020-04-20T14:57:29","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=43903"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/","title":{"rendered":"&#8216;Enorme colpo&#8217; alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L&#8217;industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un territorio inesplorato. La notizia &egrave; anche resa peggiore dal fatto che la vulnerabilit&agrave; utilizzata &egrave; nota.<\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5e9\/d76fd961bc.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5e9\/d76fd961bc.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5e9\/d76fd961bc.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5e9\/d76fd961bc.jpg 1286w\" alt=\"\" class=\"content-img\"><figcaption>Fonte: Adobe\/lensw0rld<\/figcaption><\/figure><p>Una societ&agrave; di sicurezza blockchain <b>PeckShield <\/b> ha gettato uno sguardo dettagliato agli attacchi e alla loro esecuzione,<a href=\"https:\/\/medium.com\/@peckshield\/uniswap-lendf-me-hacks-root-cause-and-loss-analysis-50f3263dcc09\" target=\"_blank\" rel=\"noopener\">affermando<\/a> che questa sia una vulnerabilit&agrave; di rientro nota che si &egrave; verificata per la prima volta il 18 aprile su <b>Uniswap <\/b>, un protocollo per lo scambio automatico di token su pool di liquidit&agrave; <a href=\"https:\/\/cryptonews.com\/it\/coins\/ethereum\/\">Ethereum (ETH)<\/a>, contro imBTC (un token Ethereum valutato  1:1 del valore di <a href=\"https:\/\/cryptonews.com\/it\/coins\/bitcoin\/\">bitcoin (BTC)<\/a>). Questo &egrave; stato seguito da un attacco simile su <b>Lendf.Me <\/b>, il protocollo di prestito nella rete &#8220;protocollo di finanza decentralizzata&#8221; <b>dForce <\/b>, il giorno dopo.<\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" sizes=\"(min-width: 640px) 720px, 100vw\" alt=\"\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d752ab1c06.png\" data-srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d752ab1c06.png 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5e9\/d752ab1c06.png 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5e9\/d752ab1c06.png 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5e9\/d752ab1c06.png 900w\"><figcaption>Fonte: Defi Pulse<\/figcaption><\/figure><p>La vulnerabilit&agrave; consente a un hacker di dirottare una transazione e vendere pi&ugrave; volte lo stesso batch di token. Circa 1.278 ETH (232.000 USD) furono rubati nel primo attacco, e circa 25,2 milioni di dollari USA dal secondo.<\/p><p>Il sito Lendf.Me al momento della scrittura non &egrave; in linea. Sul suo account Twitter ufficiale, il CEO di <b>dForce Foundation <\/b> Mindao Yang ha condiviso la spiegazione della rete su ci&ograve; che &egrave; accaduto questo fine settimana, confermando l&#8217;attacco descritto da PeckShield. &#8220;Il meccanismo di callback di ERC777 (imBTC) ha consentito all&#8217;hacker di fornire e ritirare ripetutamente imBTC prima dell&#8217;aggiornamento del saldo&#8221;,<a href=\"https:\/\/medium.com\/dforcenet\/a-summary-of-the-attack-on-lendf-me-on-april-19-2020-e2f1c5d96640\" target=\"_blank\" rel=\"noopener\">scrive<\/a> Yang.<\/p><blockquote class=\"twitter-tweet\" data-conversation=\"none\"><p lang=\"en\" dir=\"ltr\">Here you can see the loss distribution among top 7 lenders on <a href=\"https:\/\/twitter.com\/LendfMe?ref_src=twsrc%5Etfw\">@LendfMe<\/a> for these pools. More charts, analysis and also the data will be in DefiWeekly (<a href=\"https:\/\/twitter.com\/kermankohli?ref_src=twsrc%5Etfw\">@kermankohli<\/a>) in the coming days.<br><br>P.S.: I don&rsquo;t have much time for designing charts now? <a href=\"https:\/\/t.co\/U1ji8IoHl2\">pic.twitter.com\/U1ji8IoHl2<\/a><\/p>&mdash; Frank Topbottom (@FrankResearcher) <a href=\"https:\/\/twitter.com\/FrankResearcher\/status\/1251860639905198080?ref_src=twsrc%5Etfw\">April 19, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p>Inoltre, Yang afferma che gli hacker &#8220;hanno tentato di contattarci e abbiamo intenzione di entrare in trattativa con loro&#8221;. Ci sono <a href=\"https:\/\/twitter.com\/tzhen\/status\/1251924055214579719\" target=\"_blank\" rel=\"noopener\">report<\/a> che gli aggressori abbiano riconsegnato 126,014 <a href=\"https:\/\/cryptonews.com\/coins\/paxos-standard-token\/\" target=\"_blank\" rel=\"noopener\">PAX<\/a>, 320 HBTC, e 381,000 HUSD.<\/p><blockquote class=\"twitter-tweet\" data-conversation=\"none\"><p lang=\"en\" dir=\"ltr\">Hacker repay assets from <a href=\"https:\/\/twitter.com\/compoundfinance?ref_src=twsrc%5Etfw\">@compoundfinance<\/a> and <a href=\"https:\/\/twitter.com\/AaveAave?ref_src=twsrc%5Etfw\">@AaveAave<\/a> <a href=\"https:\/\/t.co\/2CcYkuaqyb\">https:\/\/t.co\/2CcYkuaqyb<\/a><a href=\"https:\/\/t.co\/kyBNba6YEl\">https:\/\/t.co\/kyBNba6YEl<\/a><\/p>&mdash; Frank Topbottom (@FrankResearcher) <a href=\"https:\/\/twitter.com\/FrankResearcher\/status\/1251953828355805189?ref_src=twsrc%5Etfw\">April 19, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p>Mentre la societ&agrave; sta lavorando con le forze dell&#8217;ordine e gli exchange per identificare gli aggressori, nonch&eacute; per una valutazione della sicurezza pi&ugrave; completa di Lendf. Come si dice, Yang afferma che l&#8217;attacco &egrave; stato un suo fallimento. &#8220;Anche se non l&#8217;ho eseguito, avrei dovuto anticiparlo e intraprendere azioni per impedirlo&#8221;, scrive.<\/p><p>Esiste persino un meccanismo di mitigazione per bloccare tali attacchi di rientro, il cosiddetto modello di progettazione Checks-Effects-Interactions, secondo PeckShield. Concludono che &#8220;L&#8217;hacking di Lendf.Me sia un duro colpo per l&#8217;attuale comunit&agrave; DeFi&#8221;.<\/p><p>Inoltre, il loro rapporto rileva che, sebbene &#8220;ERC777 stesso sia uno standard di token stabilito dalla comunit&agrave; con le sue funzionalit&agrave; avanzate per vari scenari, [&#8230;] queste funzionalit&agrave; avanzate potrebbero non essere compatibili con alcuni scenari DeFi. Peggio ancora, tale incompatibilit&agrave; potrebbe portare ulteriormente a conseguenze indesiderate (ad es. rientro). Notiamo anche che altri standard di token (ad es. ERC1155) sono stati progettati in modo simile per avere una funzione di richiamata. &#8220;<\/p><p>Inoltre, <b>Tokenlon <\/b>, la societ&agrave; dietro imBTC, <a href=\"https:\/\/medium.com\/imtoken\/about-recent-uniswap-and-lendf-me-reentrancy-attacks-7cebe834cb3\" target=\"_blank\" rel=\"noopener\">ha scritto<\/a>in un rapporto post mortem che &#8220;Lo standard del token ERC-777 non presenta &#8211; a nostra conoscenza &#8211; nessuna vulnerabilit&agrave; di sicurezza. Tuttavia, la combinazione di utilizzo di token ERC777 e contratti Uniswap \/ Lendf.Me consente gli attacchi di rientro di cui sopra.&#8221; Notano che questo exploit era gi&agrave; <a href=\"https:\/\/github.com\/OpenZeppelin\/exploit-uniswap#why-it-works\" target=\"_blank\" rel=\"noopener\">pubblicato<\/a> su GitHub torna a luglio 2019 da <b>OpenZeppelin <\/b>, una societ&agrave; che esegue audit di sicurezza per piattaforme di criptovaluta.<\/p><p>Per Jason Choi, Head of Research presso <b>Spartan Group <\/b>, una societ&agrave; di consulenza e investimento blockchain, &egrave; successo ancora prima, nel 2016.<\/p><blockquote class=\"twitter-tweet\" data-conversation=\"none\"><p lang=\"en\" dir=\"ltr\">This exploit was used in the $150M DAO hack:<br><br>In simplistic terms, during the hack, you:<br><br>&#8211; Submit a legitimate withdrawal<br>&#8211; Before the contract could update your balance&#8230; <br>&#8211; &#8230;recursively withdrew more than you are entitled to<a href=\"https:\/\/t.co\/yPCZL1nprd\">https:\/\/t.co\/yPCZL1nprd<\/a><br><br>4\/x<\/p>&mdash; Jason Choi &#34081;&#28009;&#38662; (@mrjasonchoi) <a href=\"https:\/\/twitter.com\/mrjasonchoi\/status\/1251857661806522368?ref_src=twsrc%5Etfw\">April 19, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p>Spencer Noon, capo degli investimenti cripto presso <b>DTC Capital<\/b>, <a href=\"https:\/\/twitter.com\/spencernoon\/status\/1251716786732650499\" target=\"_blank\" rel=\"noopener\">trova<\/a> che l&#8217;attacco a Lendf.Me non sia affatto sorprendente, mentre l&#8217;utente di Twitter Patrcik Tsoi <a href=\"https:\/\/twitter.com\/PatrcikTsoi\/status\/1252018525595561984\" target=\"_blank\" rel=\"noopener\">crede<\/a> che questa vulnerabilit&agrave; &#8220;debba far parte dell&#8217;auditing degli smart contract prima del lancio del prodotto Defi&#8221;.<\/p><p>L&#8217;attacco a Lendf.Me segue l&#8217;<a href=\"https:\/\/multicoin.capital\/2020\/04\/14\/our-investment-in-dforce-the-defi-super-network\/\" target=\"_blank\" rel=\"noopener\">annuncio<\/a> da parte della societ&agrave; di venture capital di criptovalute <b>Multicoin Capital <\/b> che ha guidato un round di 1,5 milioni di dollari in dForce.<br>\n___<\/p><h3 data-param=\"2\" id=\"altre-reazioni:\">Altre reazioni:<\/h3><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Decentralized finance. Decentralized. We paused it. We paused decentralized finance. ? <a href=\"https:\/\/t.co\/7ATrBWstR6\">pic.twitter.com\/7ATrBWstR6<\/a><\/p>&mdash; ungrubles (@notgrubles) <a href=\"https:\/\/twitter.com\/notgrubles\/status\/1251966619187896320?ref_src=twsrc%5Etfw\">April 19, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p>__<\/p><blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Is <a href=\"https:\/\/twitter.com\/multicoincap?ref_src=twsrc%5Etfw\">@MulticoinCap<\/a> going to do the right thing and make the users whole?<a href=\"https:\/\/t.co\/Hh2arusMRd\">https:\/\/t.co\/Hh2arusMRd<\/a><\/p>&mdash; Pierrrrrrrrrrrrre Rrrrrrrrrrrrocharrrrrrrrrrrrrrrd (@pierre_rochard) <a href=\"https:\/\/twitter.com\/pierre_rochard\/status\/1251963419168854016?ref_src=twsrc%5Etfw\">April 19, 2020<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p>__<\/p><div class=\"tweet tweetContainer\"><blockquote class=\"twitter-tweet\" data-lang=\"en\"><p lang=\"en\" dir=\"ltr\">@Excellion The average person only heard about capitalism when something implodes.<\/p>&mdash; Eating and breathing are both important, mkay? (@SchalkDormehl) <a href=\"https:\/\/twitter.com\/SchalkDormehl\/status\/1252168718613983232\"><\/a><\/blockquote><script>!function(d,s,id){var js,fjs=d.getElementsByTagName(s)[0];if(!d.getElementById(id)){js=d.createElement(s);js.id=id;js.src=\"\/\/platform.twitter.com\/widgets.js\";fjs.parentNode.insertBefore(js,fjs);}}(document,\"script\",\"twitter-wjs\");<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>L&#8217;industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un territorio inesplorato. La notizia &egrave; anche resa peggiore dal fatto che la vulnerabilit&agrave; utilizzata &egrave; nota.Fonte: Adobe\/lensw0rldUna societ&agrave; di sicurezza blockchain PeckShield ha gettato uno sguardo dettagliato agli attacchi e alla loro esecuzione,affermando che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,1],"tags":[102,406,60,258],"editors":[],"sponsored_companies":[],"class_list":["post-43903","post","type-post","status-publish","format-standard","hentry","category-defi-news","category-news","tag-defi","tag-finanza-decentralizzata","tag-hack","tag-hacker"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;Enorme colpo&#039; alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0<\/title>\n<meta name=\"description\" content=\"L&#039;industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;Enorme colpo&#039; alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0\" \/>\n<meta property=\"og:description\" content=\"L&#039;industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-20T14:57:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/27171\/9392\/5e9d7709624c0.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"'Enorme colpo' alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0","description":"L'industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/","og_locale":"it_IT","og_type":"article","og_title":"'Enorme colpo' alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0","og_description":"L'industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un","og_url":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/","og_site_name":"Cryptonews Italia","article_published_time":"2020-04-20T14:57:29+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/27171\/9392\/5e9d7709624c0.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"&#8216;Enorme colpo&#8217; alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0","datePublished":"2020-04-20T14:57:29+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/"},"wordCount":818,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg","keywords":["defi","finanza decentralizzata","hack","hacker"],"articleSection":["DeFi News","News"],"inLanguage":"it-IT","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/","url":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/","name":"'Enorme colpo' alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg","datePublished":"2020-04-20T14:57:29+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"L'industria DeFi (finanza decentralizzata) ha appena subito un altro colpo che ci ricorda quanto la DeFi (Finanza Decentralizzata) sia ancora un","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5e9\/d76fd961bc.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/huge-blow-to-defi-as-hackers-exploit-known-vulnerability-4413\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"&#8216;Enorme colpo&#8217; alla DeFi, hackers sfruttano una nota vulnerabilit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/43903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=43903"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/43903\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=43903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=43903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=43903"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=43903"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=43903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}