{"id":43318,"date":"2019-06-06T14:46:00","date_gmt":"2019-06-06T14:46:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=43318"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/","title":{"rendered":"Facebook Coin sar\u00e0 svelato a giugno, &#8216;Nodi&#8217; e Bancomat in arrivo"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il gigante dei social media <b>Facebook<\/b> dovrebbe svelare la sua moneta digitale a giugno e sta cercando sostenitori esterni che possano fungere da &#8220;nodi&#8221; per la rete di questa nuova moneta, secondo The Information, citando persone non specificate informate sui fatti.<\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5cf\/8a03299fa3.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5cf\/8a03299fa3.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5cf\/8a03299fa3.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5cf\/8a03299fa3.jpg 1318w\" alt=\"\" class=\"content-img\"><figcaption>Source: iStock\/Enes Evren<\/figcaption><\/figure><p>Il social network ha parlato con le maggiori istituzioni finanziarie e tecnologiche del mondo per unirsi in una fondazione che apporti capitali ed aiuti a governare la moneta digitale, cos&igrave; ha riferito il <a href=\"https:\/\/www.theinformation.com\/articles\/facebook-plans-outside-foundation-to-govern-cryptocurrency?\" target=\"_blank\" rel=\"noopener\">report<\/a> (paywall), aggiungendo che tali sostenitori potrebbero anche rassicurare i regolatori.<\/p><p>Facebook potrebbe richiedere 10 milioni di dollari per il privilegio di diventare un membro della fondazione, ha aggiunto CNBC, citando la storia paywall su The Information.<\/p><p>Avvocato ed appassionato di blockchain, Preston Byrne ha reagito:<\/p><blockquote class=\"twitter-tweet\" data-lang=\"en\"><p lang=\"en\" dir=\"ltr\">Invece di farti pagare per gli annunci, elimina il tuo business sulle pubblicit&agrave;, vendi i dati non elaborati e lascia che altri paghino costosi impiegati per rivenderei i dati. Davvero un genio.<\/p>&mdash; Preston Byrne (@prestonjbyrne) <a href=\"https:\/\/twitter.com\/prestonjbyrne\/status\/1136434191309135872?ref_src=twsrc%5Etfw\">June 6, 2019<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><p>&#8220;Il problema di questo approccio alla Globalcoin, ovviamente, &egrave; come renderlo cos&igrave; facile da capire per chiunque abbia meno di 60 anni, e che chiunque sia in grado di utilizzarlo intuitivamente senza che debba chiamare i suoi figli per farsi aiutare&#8221;, ha poi aggiunto.<\/p><p>Inoltre, il gigante social media dar&agrave; la possibilit&agrave; ai propri dipendenti che lavorano sul progetto di pagamento digitale, chiamato &#8220;Libra&#8221;, di ricevere lo stipendio nella nuova valuta e sta pianificando macchine simili a Bancomato dove gli utenti potranno acquistare la valuta, secondo il rapporto.<\/p><p>Come riferito ad aprile, Facebook <a href=\"https:\/\/cryptonews.com\/news\/journalist-facebook-wants-external-funding-for-its-cryptocur-3659\/\">potrebbe essere alla ricerca di 1 miliardo di dollari<\/a> in finanziamenti esterni per la sua criptovaluta di prossima uscita, che sar&agrave;, secondo quanto riferito, una stablecoin.<\/p><p>Sar&agrave; promossa in modo aggressivo nei paesi in via di sviluppo dove le valute sostenute dal governo sono pi&ugrave; volatili, ha aggiunto The Information, reiterando le informazioni precedenti.<\/p><p>Se il rapporto recente fosse vero, ci&ograve; significherebbe che la moneta di Facebook, denominata internamente &#8220;GlobalCoin&#8221;, non sarebbe necessariamente disponibile subito dopo l&#8217;annuncio di giugno.<\/p><p>Secondo i rapporti precedenti, il sistema di pagamenti digitali di Facebook mira ad iniziare con una dozzina di paesi <a href=\"https:\/\/cryptonews.com\/news\/telegram-s-ton-comes-in-q3-facebook-coin-in-2020-reports-3922\/\">entro il primo trimestre del 2020<\/a> in quanto la societ&agrave; vuole iniziare a testare ila sua moneta entro la fine di quest&#8217;anno.<\/p><p>Inoltre, la societ&agrave; &egrave; solo in &ldquo;<a href=\"https:\/\/cryptonews.com\/news\/facebook-in-talks-with-another-top-regulator-over-its-global-3973\/\">fase iniziale di dialogo<\/a>&#8221; con alcuni dei maggiori regolatori.<\/p><p>Si stima che il Facebook coin <a href=\"https:\/\/cryptonews.com\/exclusives\/facebook-coin-to-compete-with-paypal-credit-cards-not-with-c-3844\/\">sar&agrave; in concorrenza<\/a> con famosi sistemi di pagamento quali <b>PayPal<\/b>, carte di credito e non le criptovalute.<\/p><p>In ogni caso, un recente <a href=\"https:\/\/cryptonews.com\/news\/survey-just-showed-a-use-case-for-facebook-coin-3948\/\">sondaggio<\/a> ha mostrato che il 18% degli adulti intervistati sarebbe interessato ad investire nella moneta di Facebook per poterla utilizzare sul Marketplace.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il gigante dei social media Facebook dovrebbe svelare la sua moneta digitale a giugno e sta cercando sostenitori esterni che possano fungere da &#8220;nodi&#8221; per la rete di questa nuova moneta, secondo The Information, citando persone non specificate informate sui fatti.Source: iStock\/Enes EvrenIl social network ha parlato con le maggiori istituzioni finanziarie e tecnologiche del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[56,81],"editors":[63],"sponsored_companies":[],"class_list":["post-43318","post","type-post","status-publish","format-standard","hentry","category-altcoin-news","category-news","tag-criptovalute","tag-facebook","editors-linas-kmieliauskas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facebook Coin sar\u00e0 svelato a giugno, &#039;Nodi&#039; e Bancomat in arrivo<\/title>\n<meta name=\"description\" content=\"Facebook Coin sar\u00e0 svelato a giugno, &#039;Nodi&#039; e Bancomat in arrivo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facebook Coin sar\u00e0 svelato a giugno, &#039;Nodi&#039; e Bancomat in arrivo\" \/>\n<meta property=\"og:description\" content=\"Facebook Coin sar\u00e0 svelato a giugno, &#039;Nodi&#039; e Bancomat in arrivo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-06T14:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Facebook Coin sar\u00e0 svelato a giugno, &#039;Nodi&#039; e Bancomat in arrivo\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/24875\/7146\/5cf8a04a2bc95.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","description":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/","og_locale":"it_IT","og_type":"article","og_title":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","og_description":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","og_url":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/","og_site_name":"Cryptonews Italia","article_published_time":"2019-06-06T14:46:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_description":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","twitter_image":"https:\/\/cimg.co\/news\/24875\/7146\/5cf8a04a2bc95.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"Facebook Coin sar\u00e0 svelato a giugno, &#8216;Nodi&#8217; e Bancomat in arrivo","datePublished":"2019-06-06T14:46:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/"},"wordCount":460,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg","keywords":["criptovalute","facebook"],"articleSection":["Altcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/","url":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/","name":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg","datePublished":"2019-06-06T14:46:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Facebook Coin sar\u00e0 svelato a giugno, 'Nodi' e Bancomat in arrivo","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5cf\/8a03299fa3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/facebook-coin-to-be-unveiled-in-june-nodes-atms-coming-repor-2178\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Facebook Coin sar\u00e0 svelato a giugno, &#8216;Nodi&#8217; e Bancomat in arrivo"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/43318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=43318"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/43318\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=43318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=43318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=43318"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=43318"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=43318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}