{"id":224125,"date":"2025-10-16T09:32:16","date_gmt":"2025-10-16T09:32:16","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=224125"},"modified":"2025-10-16T09:32:16","modified_gmt":"2025-10-16T09:32:16","slug":"il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/","title":{"rendered":"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all&#8217;ultimo posto"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il tema della <strong>decentralizzazione delle blockchain <\/strong>\u00e8 da sempre al centro degli studi di sviluppatori e analisti, e riveste un tono centrale in qualsiasi discussione che riguardi il Web3. Del resto \u00e8 uno dei tre pilastri del \u201c<em>trilemma della blockchain<\/em>\u201d, insieme a scalabilit\u00e0 e sicurezza.<\/p><p class=\"wp-block-paragraph\">Il <strong>trilemma della blockchain<\/strong>, teorizzato da Vitalik Buterin, fondatore di Ethereum, rivela il difficile equilibrio tra <strong>decentralizzazione, sicurezza e scalabilit\u00e0<\/strong>. <\/p><p class=\"wp-block-paragraph\">Ogni blockchain, a suo avviso, deve fare una scelta: la decentralizzazione riduce l&#8217;efficienza, la sicurezza richiede risorse, e la velocit\u00e0 (o scalabilit\u00e0), spesso implica una maggiore centralizzazione. In sintesi, nessuna blockchain pu\u00f2 massimizzare questi fattori contemporaneamente.<\/p><h2 class=\"wp-block-heading\">Come si misura la decentralizzazione di una blockchain?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Il livello di decentralizzazione di una blockchain viene spesso misurato tramite il numero dei <strong>validatori<\/strong>, un elemento utile, ma non decisivo. Non tutti i validatori hanno lo stesso peso: alcuni controllano stake o risorse maggiori, altri operano aggregati sotto lo stesso provider. <\/p><p class=\"wp-block-paragraph\">Possono esserci anche 100 validatori, ma se le risorse sono controllate solo da 10, \u00e8 facile intuire che non si tratta di un sistema decentralizzato.<\/p><p class=\"wp-block-paragraph\">Ed \u00e8 qui che entra in gioco il <em>Nakamoto Coefficient<\/em>, un termometro pi\u00f9 chiaro di quanto una rete resti fedele al principio della decentralizzazione.<\/p><h2 class=\"wp-block-heading\">Che cos\u2019\u00e8 il Nakamoto Coefficient?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Il Nakamoto Coefficient<strong> misura quante entit\u00e0 indipendenti servono per compromettere una rete blockchain.<\/strong> Pi\u00f9 alto \u00e8 il coefficiente, pi\u00f9 \u00e8 difficile che qualcuno prenda il controllo. Non \u00e8 importante solo quanti validatori ci sono, ma quanto potere concentrano. <\/p><p class=\"wp-block-paragraph\">Secondo l\u2019ultimo <strong>report Chainspect 2025<\/strong>, la decentralizzazione \u00e8 ormai merce rara.<\/p><figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16083937\/Nakamoto-Coefficeinte-dati.jpg\" alt=\"\" class=\"wp-image-224290\" srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16083937\/Nakamoto-Coefficeinte-dati.jpg 800w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16083937\/Nakamoto-Coefficeinte-dati-300x169.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16083937\/Nakamoto-Coefficeinte-dati-640x360.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16083937\/Nakamoto-Coefficeinte-dati-768x432.jpg 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16083937\/Nakamoto-Coefficeinte-dati-450x253.jpg 450w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><figcaption class=\"wp-element-caption\"><em>Classifica 2025 delle blockchain pi\u00f9 decentralizzate secondo il Nakamoto Coefficient &#8211; Fonte: Chainspect \u2013 Most Decentralized Blockchains by Nakamoto Coefficient (aggiornamento 2025).<\/em><\/figcaption><\/figure><p class=\"wp-block-paragraph\">In cima alla classifica delle blockchain pi\u00f9 decentralizzate spiccano <strong>Polkadot<\/strong>, <strong>Kusama <\/strong>e <strong>Moonbeam<\/strong>, con un coefficiente record di 157, seguite da Crust Network (83) e TON (27). Pi\u00f9 indietro <strong>Avalanche <\/strong>(25) e <strong>Cardano <\/strong>(20), che rimangono tra le blockchain <em>proof of stake<\/em> pi\u00f9 equilibrate. <\/p><p class=\"wp-block-paragraph\"><strong>Solana <\/strong>si ferma a 18, in lieve ripresa dopo anni di concentrazione, mentre in fondo alla lista troviamo <strong>BNB<\/strong>, Tron, Polygon e Cronos, ferme tra 4 e 5. In altre parole, <strong>bastano quattro o cinque entit\u00e0 per coordinare un attacco<\/strong> contro alcune delle blockchain pi\u00f9 popolari al mondo.<\/p><h2 class=\"wp-block-heading\">Il paradosso: Bitcoin ed Ethereum in fondo alla classifica<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">E qui arriva la parte pi\u00f9 sorprendente. Anche se non \u00e8 incluso in questa infografica, Il coefficiente Nakamoto di Bitcoin \u00e8 3, mentre quello di Ethereum \u00e8 5.<\/p><p class=\"wp-block-paragraph\">Per Bitcoin ci sono<strong> <a href=\"https:\/\/forklog.com\/en\/what-is-the-nakamoto-coefficient-and-how-to-calculate-it\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">i dati <\/a><\/strong>di <strong>ForkLog, <\/strong>che indicano chiaramente come BTC possa essere controllato tramite soli tre gruppi di mining: Foundry USA con il 30,6% dell\u2019hashrate, AntPool con il 17,1% e ViaBTC con il 15,4%. Sommati insieme hanno il 63,1%, ben oltre il 51% necessario.<\/p><figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1393\" height=\"418\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"Grafico distribuzione hashrate Bitcoin 2025 tra principali mining pool.\" class=\"wp-image-224295 lazyload\" sizes=\"auto, (max-width: 1393px) 100vw, 1393px\" data-src=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16085011\/unnamed.png\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16085011\/unnamed.png 1393w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16085011\/unnamed-300x90.png 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16085011\/unnamed-640x192.png 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16085011\/unnamed-768x230.png 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16085011\/unnamed-450x135.png 450w\"><figcaption class=\"wp-element-caption\"><em>Distribuzione dell\u2019hashrate di Bitcoin tra i principali mining pool al 1\u00b0 maggio 2025: Foundry USA, AntPool e ViaBTC controllano oltre il 60% della potenza totale di calcolo. Fonte: Hashrate Index (maggio 2025).<\/em><\/figcaption><\/figure><p class=\"wp-block-paragraph\">Discorso simile per <strong>Ethereum<\/strong>, dove a controllare la blockchain sono soprattutto le societ\u00e0 che effettuano lo staking collettivo.<\/p><figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"524\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" class=\"wp-image-224300 lazyload\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" data-src=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth.png\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth.png 1600w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth-300x98.png 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth-640x210.png 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth-768x252.png 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth-1536x503.png 1536w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16090323\/eth-450x147.png 450w\"><figcaption class=\"wp-element-caption\"><em>Distribuzione dello staking di Ethereum aggiornata a maggio 2025: i cinque principali operatori, Lido, Coinbase, Binance, ether.fi e Kiln, controllano complessivamente oltre il 51% dello stake totale della rete. Fonte: Dune Analytics \u2013 Dashboard ETH Stakers di @hildobby (aggiornamento maggio 2025).<\/em><\/figcaption><\/figure><p class=\"wp-block-paragraph\">Insomma, basterebbero tre mining pool di Bitcoin o cinque operatori di staking di Ethereum per alterare la produzione dei blocchi. E non si tratta di un&#8217;esagerazione, ma di una fotografia dell&#8217;attuale situazione.<\/p><p class=\"wp-block-paragraph\">Nel caso di Bitcoin, il potere \u00e8 concentrato nei <strong>grandi mining pool <\/strong>(Foundry USA, AntPool, ViaBTC).<\/p><p class=\"wp-block-paragraph\">Nel caso di Ethereum, nei principali<strong> staking provider <\/strong>(Lido, Coinbase, Binance).<\/p><p class=\"wp-block-paragraph\">In altre parole, la decentralizzazione di questi due giganti non sempre coincide con la distribuzione reale del potere operativo.<\/p><h2 class=\"wp-block-heading\">Decentralizzazione: ideologia o metrica?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Il coefficiente Nakamoto ricorda che<strong> la decentralizzazione non \u00e8 uno slogan o un valore etico<\/strong>, ma una metrica quantificabile. Un dato che rivela quanto una blockchain  sia \u201cresistente\u201d al controllo. E se Bitcoin ed Ethereum continuano a rappresentare i pilastri del mondo crypto, oggi sono altri ecosistemi a incarnare lo spirito originario di Satoshi Nakamoto.<\/p><p class=\"wp-block-paragraph\">Un coefficiente basso non significa per\u00f2 che una blockchain sia \u201cinsicura\u201d. Nel caso di Bitcoin o Ethereum, la concentrazione del potere in pochi operatori<strong> non implica un rischio reale di collusione.<\/strong><\/p><p class=\"wp-block-paragraph\">Questo perch\u00e9 i soggetti che dovrebbero \u201cmettersi d\u2019accordo\u201d per manipolare la rete avrebbero tutto da perdere: gli incentivi economici, la reputazione e gli enormi capitali investiti nel mantenere l\u2019infrastruttura verrebbero annientati da qualsiasi tentativo di sabotaggio. <\/p><p class=\"wp-block-paragraph\">In altre parole,<strong> il costo di un attacco supererebbe il potenziale guadagno<\/strong>. E questo \u00e8 ci\u00f2 che, di fatto, tiene in piedi la sicurezza dei grandi network: non solo la matematica del consenso, ma anche l\u2019economia degli incentivi.<\/p><p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Bitcoin ed Ethereum sono fanalini di coda in una speciale classifica molto importante ma purtroppo sottovalutata. <\/p>\n","protected":false},"author":141,"featured_media":224313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[45,8066,380],"editors":[2173],"sponsored_companies":[],"class_list":["post-224125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","tag-bitcoin","tag-coefficiente-nakamoto","tag-decentralizzazione","editors-christian-boscolo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all&#039;ultimo posto<\/title>\n<meta name=\"description\" content=\"Bitcoin ed Ethereum sono fanalini di coda in una speciale classifica molto importante ma purtroppo sottovalutata.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all&#039;ultimo posto\" \/>\n<meta property=\"og:description\" content=\"Bitcoin ed Ethereum sono fanalini di coda in una speciale classifica molto importante ma purtroppo sottovalutata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T09:32:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all'ultimo posto","description":"Bitcoin ed Ethereum sono fanalini di coda in una speciale classifica molto importante ma purtroppo sottovalutata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/","og_locale":"it_IT","og_type":"article","og_title":"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all'ultimo posto","og_description":"Bitcoin ed Ethereum sono fanalini di coda in una speciale classifica molto importante ma purtroppo sottovalutata.","og_url":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/","og_site_name":"Cryptonews Italia","article_published_time":"2025-10-16T09:32:16+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/"},"author":{"name":"christianboscoloczvh","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/674a071a36e0e74b5de8cab751183e36"},"headline":"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all&#8217;ultimo posto","datePublished":"2025-10-16T09:32:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/"},"wordCount":763,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg","keywords":["bitcoin","Coefficiente Nakamoto","decentralizzazione"],"articleSection":["Bitcoin News"],"inLanguage":"it-IT","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/","url":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/","name":"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all'ultimo posto","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg","datePublished":"2025-10-16T09:32:16+00:00","description":"Bitcoin ed Ethereum sono fanalini di coda in una speciale classifica molto importante ma purtroppo sottovalutata.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2025\/10\/16091718\/1760606238-nakamoto.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/il-coefficiente-di-nakamoto-ironia-della-sorte-bitcoin-e-allultimo-posto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il coefficiente di Nakamoto: ironia della sorte Bitcoin \u00e8 all&#8217;ultimo posto"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/224125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=224125"}],"version-history":[{"count":17,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/224125\/revisions"}],"predecessor-version":[{"id":224331,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/224125\/revisions\/224331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/224313"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=224125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=224125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=224125"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=224125"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=224125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}