{"id":189485,"date":"2024-10-04T17:00:00","date_gmt":"2024-10-04T17:00:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=189485"},"modified":"2024-10-04T17:00:00","modified_gmt":"2024-10-04T17:00:00","slug":"gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/","title":{"rendered":"Gli analisti consigliano di puntare sulle meme coin durante il calo del mercato"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Mentre i conflitti in Medio Oriente scatenano la paura tra gli investitori, alcuni esperti del settore crypto suggeriscono di approfittare dell&#8217;attuale ribasso del mercato per investire nelle meme coin e altri asset. <strong>Ran Neuner<\/strong>, trader crypto della CNBC, &egrave; stato il primo a suggerirlo.<\/p><p class=\"wp-block-paragraph\">Ha chiarito che, a meno che gli investitori non credano che il conflitto si intensificher&agrave; a livello internazionale, adesso potrebbe essere un <strong>buon momento per <a href=\"https:\/\/cryptonews.com\/it\/guides\/investire-in-criptovalute\/\">investire in crypto<\/a><\/strong>, visto il recente calo dei prezzi. <\/p><p class=\"wp-block-paragraph\">Bitcoin, dopo aver toccato i 66.000 dollari, &egrave; crollato al livello di <a href=\"https:\/\/cryptonews.com\/it\/news\/mercato-crypto-in-rosso-bitcoin-rischia-di-perdere-il-livello-chiave-dei-60-000-dollari\/\"><strong>60.000 dollari<\/strong>.<\/a> Al momento del tweet di Ran, <strong>Bitcoin ($BTC)<\/strong> stava scambiando al livello di 61.660 dollari. Oggi sta scambiando a 61.554 dollari, con un rialzo dell&#8217;1,78% in 24 ore.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Unless you believe this is WW3, you should probably start buying! ($61,660).<\/p>&mdash; Ran Neuner (@cryptomanran) <a href=\"https:\/\/twitter.com\/cryptomanran\/status\/1841170328778678638?ref_src=twsrc%5Etfw\">October 1, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">Inoltre, la<em> <\/em>CNBC ha intervistato il managing partner e responsabile della ricerca della societ&agrave; di ricerca sui mercati azionari Fundstrat. Anche lui ha consigliato ai<strong> trader azionari di comprare durante il ribasso<\/strong>, visto che il mercato sta vivendo un &ldquo;periodo molto difficile&rdquo;.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">&quot;I think we&#39;re still in the midst of a very tricky period,&quot; says Tom Lee of <a href=\"https:\/\/twitter.com\/fundstrat?ref_src=twsrc%5Etfw\">@fundstrat<\/a>. &quot;If we get a dip, I think you still want to buy that dip because the setup into year-end has a lot of tailwinds.&quot; <a href=\"https:\/\/t.co\/QIkp52C8uW\">pic.twitter.com\/QIkp52C8uW<\/a><\/p>&mdash; Squawk Box (@SquawkCNBC) <a href=\"https:\/\/twitter.com\/SquawkCNBC\/status\/1841438856077328696?ref_src=twsrc%5Etfw\">October 2, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><h2 class=\"wp-block-heading\" id=\"h-e-un-buon-momento-per-investire-nelle-meme-coin\"><strong>&Egrave; un buon momento per investire nelle meme coin?<\/strong><\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Verso la met&agrave; del mese scorso, la <strong>Federal Reserve statunitense<\/strong> ha deciso di ridurre i <a href=\"https:\/\/cryptonews.com\/it\/news\/la-fed-taglia-i-tassi-di-50-punti-base-bitcoin-e-le-crypto-volano\/\"><strong>tassi di interesse di 50 punti <\/strong><\/a>base.<\/p><p class=\"wp-block-paragraph\">La decisione &egrave; arrivata dopo due anni di aumenti, con ben 11 rialzi consecutivi che avevano portato i tassi a un massimo ventennale la scorsa estate.<\/p><p class=\"wp-block-paragraph\">Dopo la riduzione, i costi dei prestiti sono scesi e le criptovalute hanno iniziato a risalire. Ora, per&ograve;, stanno crescendo i timori di una possibile escalation della guerra in Medio Oriente, soprattutto dopo l&#8217;invasione di terra del Libano da parte di Israele e il bombardamento di obiettivi <a href=\"https:\/\/cryptonews.com\/it\/news\/bitcoin-scende-a-60-000-dopo-lattacco-missilistico-contro-israele\/\"><strong>militari israeliani da parte dell&#8217;Iran.<\/strong><\/a><\/p><p class=\"wp-block-paragraph\">La notizia ha portato molti investitori a lasciar perdere i titoli azionari, spostando la loro attenzione sul petrolio, il cui<strong> <a href=\"https:\/\/finance.yahoo.com\/news\/japan-stocks-poised-rebound-yen-223635526.html?guccounter=1&amp;guce_referrer=aHR0cHM6Ly93d3cuZ29vZ2xlLmNvbS8&amp;guce_referrer_sig=AQAAAAC8wmi1WUYUlTCvz6uEbp97XJwYOQ53QtIeBg5TVSdGIannQ96PW5LJAW_swJKCgtPtIMSXMrE0Tf_tEKVHQENM0k_S40p7GR3JsX9J5SUa6hj2NMvabBD1gE31gbbLvQuLfPcH_q6uC42Oxxxyi-c7BiFmCXbiUHSjeFaKqMgU\">prezzo<\/a><\/strong><a href=\"https:\/\/finance.yahoo.com\/news\/japan-stocks-poised-rebound-yen-223635526.html?guccounter=1&amp;guce_referrer=aHR0cHM6Ly93d3cuZ29vZ2xlLmNvbS8&amp;guce_referrer_sig=AQAAAAC8wmi1WUYUlTCvz6uEbp97XJwYOQ53QtIeBg5TVSdGIannQ96PW5LJAW_swJKCgtPtIMSXMrE0Tf_tEKVHQENM0k_S40p7GR3JsX9J5SUa6hj2NMvabBD1gE31gbbLvQuLfPcH_q6uC42Oxxxyi-c7BiFmCXbiUHSjeFaKqMgU\"> <\/a>&egrave; aumentato negli ultimi cinque giorni.<\/p><p class=\"wp-block-paragraph\">Sembra quindi che le criptovalute siano diventate l&#8217;ultima preoccupazione per la maggior parte delle persone, rendendo questo un ottimo momento per entrare nel mercato crypto.<\/p><h2 class=\"wp-block-heading\" id=\"h-flockerz-flock-la-nuova-meme-coin-con-meccanismo-vote-to-earn\"><strong>Flockerz ($FLOCK), la nuova meme coin con meccanismo <\/strong> <strong>vote-to-earn<\/strong><\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Le meme coin prive di utility, come <strong>Dogecoin ($DOGE) e Pepe ($PEPE)<\/strong>, potrebbero presto lasciare spazio a nuovi progetti. Nel mercato sono emersi nuovo progetti in fase di prevendita che stanno raccogliendo milioni di dollari e che offrono nuove e interessanti opportunit&agrave; di guadagno nel segmento delle meme coin.<\/p><p class=\"wp-block-paragraph\">Una di queste &egrave; <strong>Flockerz ($FLOCK).<\/strong><\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">The bird party\u2019s just getting started, and we\u2019re about to turn it up! \ud83c\udf7e <a href=\"https:\/\/t.co\/HCwr8xSewy\">pic.twitter.com\/HCwr8xSewy<\/a><\/p>&mdash; Flockerz (@FlockerzToken) <a href=\"https:\/\/twitter.com\/FlockerzToken\/status\/1841658477770637623?ref_src=twsrc%5Etfw\">October 3, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">La sua prevendita &egrave; stata lanciata questo mese e ha raccolto rapidamente 373.000 dollari. Flockerz introduce un nuovo meccanismo <strong>vote-to-earn<\/strong>, premi di staking elevati e una vasta community.<\/p><h3 class=\"wp-block-heading\" id=\"h-che-cos-e-il-meccanismo-vote-to-earn-e-come-funziona\">Che cos&#8217;&egrave; il meccanismo vote-to-earn e come funziona? <\/h3><p class=\"wp-block-paragraph\">I titolari di Flockerz sono tutti membri di <strong>un&#8217;organizzazione autonoma decentralizzata (DAO)<\/strong> chiamata <strong>Flocktopia<\/strong>.<\/p><p class=\"wp-block-paragraph\">In Flocktopia, i membri possono redigere e votare su proposte per migliorare il progetto, assicurandosi che tutte le decisioni importanti siano prese insieme e non da un&rsquo;autorit&agrave; centralizzata.<\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Flockerz, con il suo innovativo vota e guadagna, pronto a volare\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/eUj9ZKAhvFc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><p class=\"wp-block-paragraph\">Flockerz premia i votanti con <strong>$FLOCK<\/strong>, incentivando cos&igrave; l&rsquo;impegno attivo della community e allineando gli interessi di tutti verso il successo del progetto. Pi&ugrave; si partecipa, maggiori saranno le ricompense, rendendo la sua community potenzialmente pi&ugrave; fedele rispetto a quella di DogWifHat.<\/p><p class=\"wp-block-paragraph\">Circa il 25% dei 12 miliardi di token $FLOCK del progetto sono destinati allo staking, con il protocollo che offre un rendimento elevato del 6.065% sui token messi in staking per un periodo di due anni.<\/p><p class=\"wp-block-paragraph\">Flockerz &egrave; un progetto trasparente e completamente controllato. <strong><a href=\"https:\/\/coinsult.net\/projects\/flockerz\/\">Coinsult<\/a> <\/strong>ha verificato il suo smart contract, per garantire agli investitori la massima tranquillit&agrave;.<\/p><p class=\"wp-block-paragraph\">Oltre alla prevendita, Flockerz punta a raggiungere i listing exchange centralizzati e decentralizzati (CEX e DEX), puntando a diventare una delle principali meme coin insieme a DogWIfHat.  Il meccanismo di <strong>vote-to-earn<\/strong> sar&agrave; lanciato dopo il listing.<\/p><p class=\"wp-block-paragraph\">Per rimanere aggiornati sugli ultimi sviluppi del progetto, &egrave; possibile seguire Flockerz su <strong><a href=\"https:\/\/x.com\/FlockerzToken\">X<\/a> <\/strong>e <strong><a href=\"https:\/\/t.me\/flockerz\">Telegram<\/a>.<\/strong><\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/ext\/flockerz-token\/\" rel=\"nofollow noindex\">Scopri Flockerz<\/a><\/div><p class=\"has-text-align-center wp-block-paragraph\"><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><h3 class=\"wp-block-heading\" id=\"h-leggi-anche\">Leggi anche:<\/h3><ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/migliori-crypto-presale.htm\"><strong>Tutte le nuove criptovalute da comprare nel 2024<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/migliori-crypto-presale.htm\"><strong>Le migliori crypto presale del 2024 &ndash; Le criptovalute in prevendita da non perdere<\/strong><\/a><\/li>\n<\/ul><p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Mentre i conflitti in Medio Oriente scatenano la paura tra gli investitori, alcuni esperti del settore crypto suggeriscono di approfittare dell&#8217;attuale ribasso del mercato per investire nelle meme coin e altri asset. Ran Neuner, trader crypto della CNBC, &egrave; stato il primo a suggerirlo.Ha chiarito che, a meno che gli investitori non credano che il [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":189513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[56,2040,536],"editors":[3235],"sponsored_companies":[],"class_list":["post-189485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-criptovalute","tag-meme-coin","tag-mercato","editors-massimo-de-vincenti2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli analisti consigliano di puntare sulle meme coin durante il ribasso<\/title>\n<meta name=\"description\" content=\"Alcuni esperti del settore crypto suggeriscono di approfittare dell&#039;attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli analisti consigliano di puntare sulle meme coin durante il ribasso\" \/>\n<meta property=\"og:description\" content=\"Alcuni esperti del settore crypto suggeriscono di approfittare dell&#039;attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-04T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gli analisti consigliano di puntare sulle meme coin durante il ribasso\" \/>\n<meta name=\"twitter:description\" content=\"Alcuni esperti del settore crypto suggeriscono di approfittare dell&#039;attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli analisti consigliano di puntare sulle meme coin durante il ribasso","description":"Alcuni esperti del settore crypto suggeriscono di approfittare dell'attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/","og_locale":"it_IT","og_type":"article","og_title":"Gli analisti consigliano di puntare sulle meme coin durante il ribasso","og_description":"Alcuni esperti del settore crypto suggeriscono di approfittare dell'attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.","og_url":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/","og_site_name":"Cryptonews Italia","article_published_time":"2024-10-04T17:00:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Gli analisti consigliano di puntare sulle meme coin durante il ribasso","twitter_description":"Alcuni esperti del settore crypto suggeriscono di approfittare dell'attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"Gli analisti consigliano di puntare sulle meme coin durante il calo del mercato","datePublished":"2024-10-04T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/"},"wordCount":708,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg","keywords":["criptovalute","Meme Coin","Mercato"],"articleSection":["News"],"inLanguage":"it-IT","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/","url":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/","name":"Gli analisti consigliano di puntare sulle meme coin durante il ribasso","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg","datePublished":"2024-10-04T17:00:00+00:00","description":"Alcuni esperti del settore crypto suggeriscono di approfittare dell'attuale ribasso del mercato per investire nelle meme coin e altre criptovalute.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/10\/04143236\/COPERTINE-CN-LOGO-1280-%C3%97-720-23.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/gli-analisti-consigliano-di-puntare-sulle-meme-coin-durante-il-calo-del-mercato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Gli analisti consigliano di puntare sulle meme coin durante il calo del mercato"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/189485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=189485"}],"version-history":[{"count":2,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/189485\/revisions"}],"predecessor-version":[{"id":189514,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/189485\/revisions\/189514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/189513"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=189485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=189485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=189485"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=189485"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=189485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}