{"id":182543,"date":"2024-07-29T10:00:40","date_gmt":"2024-07-29T10:00:40","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=182543"},"modified":"2024-07-29T10:00:40","modified_gmt":"2024-07-29T10:00:40","slug":"chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/","title":{"rendered":"ChatGPT stabilisce il prezzo di SHIB per l&#8217;1 agosto, dopo il furto da 100 milioni di dollari"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-182563\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/07\/1722244112-copertina-altcoin1.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg 1280w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1-300x169.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1-640x360.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1-768x432.jpg 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1-450x253.jpg 450w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><\/p><p>WazirX, uno dei principali exchange di criptovalute in India, &egrave; stato <a href=\"https:\/\/cryptonews.com\/it\/news\/breaking-news-234-milioni-rubati-dallexchange-wazirx-prelievi-sospesi\/\" target=\"_blank\" rel=\"noopener\"><strong>vittima di un enorme hack<\/strong><\/a>, che ha portato al furto di circa 230 milioni di dollari in vari asset digitali.<\/p><p>La violazione, confermata da pi&ugrave; analisti della sicurezza, &egrave; stata dettagliata da Lookonchain, una societ&agrave; di analisi blockchain. Secondo questa analisi, <strong>la perdita maggiore<\/strong> &egrave; stata in token Shiba Inu (SHIB), con un incredibile ammontare di <strong>5,43 trilioni di SHIB<\/strong>, del valore di 102 milioni di dollari, rubati. Questo rende SHIB la criptovaluta pi&ugrave; colpita in questo hack di alto profilo.<\/p><p>Oltre a SHIB, gli hacker sono riusciti a rubare <strong>15.298 Ethereum (ETH)<\/strong> per un valore di 52,5 milioni di dollari, <strong>20,5 milioni di Polygon (MATIC)<\/strong> per un valore di 11,24 milioni di dollari, <strong>640,27 miliardi di Pepe (PEPE)<\/strong> per un valore di 7,6 milioni di dollari, <strong>5,79 milioni di Tether (USDT)<\/strong> e <strong>135 milioni di Gala (GALA)<\/strong> per un valore di 3,5 milioni di dollari.<\/p><figure id=\"attachment_182544\" aria-describedby=\"caption-attachment-182544\" style=\"width: 636px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-182544 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"636\" height=\"1024\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/07\/1722238970-image-87-636x1024-1.png\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074250\/1722238970-image-87-636x1024-1.png 636w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074250\/1722238970-image-87-636x1024-1-186x300.png 186w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074250\/1722238970-image-87-636x1024-1-398x640.png 398w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074250\/1722238970-image-87-636x1024-1-450x725.png 450w\"><figcaption id=\"caption-attachment-182544\" class=\"wp-caption-text\">&#8220;Distribuzione delle criptovalute perse nell&#8217;hack di WazirX. Fonte: Lookonchain&#8221;<\/figcaption><\/figure><p>In risposta alla violazione della sicurezza, l&#8217;exchange ha temporaneamente <strong>sospeso i prelievi di criptovalute e rupie indiane<\/strong>. Inoltre ulteriori analisi hanno indicato che l&#8217;autore del furto ha iniziato a <strong>vendere gli SHIB rubati<\/strong>.<\/p><p>Nel complesso, l&#8217;hack ha sollevato preoccupazioni all&#8217;interno della comunit&agrave; delle criptovalute, considerando che il settore sta tentando <a href=\"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-trump-appoggia-lidea-di-btc-come-riserva-di-valore\/\" target=\"_blank\" rel=\"noopener\"><strong>una ripresa guidata da Bitcoin (BTC)<\/strong><\/a>. Sar&agrave; interessante monitorare come il token pi&ugrave; colpito, SHIB, reagir&agrave; all&#8217;incidente nei prossimi giorni.\n<\/p><h2>Previsione del prezzo di SHIB<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nIn questo contesto, abbiamo deciso di <strong>consultare ChatGPT-4o<\/strong>, l&#8217;ultimo e pi&ugrave; avanzato strumento di intelligenza artificiale di OpenAI, per raccogliere intuizioni su <strong>come SHIB si comporter&agrave; il 1&deg; agosto<\/strong>.<\/p><p>Lo strumento di IA ha <strong>delineato diversi scenari possibili<\/strong> per il prezzo di SHIB entro l&#8217;inizio del prossimo mese, considerando le conseguenze immediate dell&#8217;hack e le dinamiche di mercato pi&ugrave; ampie.<\/p><p>L&#8217;hack potrebbe aver minato la fiducia degli investitori, portando a una svendita e a una diminuzione del prezzo di SHIB. Secondo ChatGPT-4o se <strong>il sentiment negativo<\/strong> dovesse prevalere, il prezzo potrebbe <strong>scendere a circa $0,000015<\/strong> o anche pi&ugrave; basso.<\/p><p>Il valore potrebbe invece stabilizzarsi o riprendersi se il mercato percepisse che le misure di sicurezza vengano rafforzate e che la situazione &egrave; sia controllo. In questo scenario neutro, la piattaforma IA ha previsto che la meme coin potrebbe <strong>oscillare intorno a $0,000017<\/strong>.<\/p><p>Nel contempo, ChatGPT-4o ha riconosciuto che anch le tendenze generali del mercato delle criptovalute, le notizie normative e i fattori macroeconomici giocheranno un ruolo significativo. Se dovessero emergere notizie positive o un forte interesse all&#8217;acquisto, il prezzo potrebbe <strong>salire fino a circa $0,000020 o pi&ugrave;<\/strong>.\n<\/p><h2>Aumento del burning<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nOltre a fare affidamento sulla traiettoria generale del mercato, SHIB sta considerando iniziative guidate dalla comunit&agrave; per mitigare eventuali ripercussioni dall&#8217;exchange. Per esempio, &egrave; aumentata l&#8217;attivit&agrave; di burning.<\/p><p>Secondo i dati condivisi da Shibburn in un post su X del 18 luglio, <strong>il tasso di burning<\/strong> nelle ultime 24 ore &egrave; aumentato dell&#8217;874,74%.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">HOURLY SHIB UPDATE<a href=\"https:\/\/twitter.com\/search?q=%24SHIB&amp;src=ctag&amp;ref_src=twsrc%5Etfw\">$SHIB<\/a> Price: $0.00001735 (1hr -0.79% \u25bc | 24hr -10.32% \u25bc )<br>Market Cap: $10,218,833,108 (-10.66% \u25bc)<br>Total Supply: 589,272,418,885,660<\/p>\n<p>TOKENS BURNT<br>Past 24Hrs: 8,772,074 (874.74% \u25b2)<br>Past 7 Days: 85,943,396 (33.52% \u25b2)<\/p>\n<p>&mdash; Shibburn (@shibburn) <a href=\"https:\/\/twitter.com\/shibburn\/status\/1813876416246694367?ref_src=twsrc%5Etfw\">July 18, 2024<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/p><h2>Analisi del prezzo di SHIB<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nAl momento, SHIB viene scambiato a <strong>$0,00001735<\/strong> con perdite superiori al 10% nell&#8217;arco delle ultime 24 ore. Sul grafico settimanale, per&ograve;, la meme coin &egrave; ancora in aumento di oltre il 4%.<\/p><figure id=\"attachment_182545\" aria-describedby=\"caption-attachment-182545\" style=\"width: 675px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-182545 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"675\" height=\"586\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/07\/1722239101-image-89.png\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074501\/1722239101-image-89.png 675w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074501\/1722239101-image-89-300x260.png 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074501\/1722239101-image-89-640x556.png 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29074501\/1722239101-image-89-450x391.png 450w\"><figcaption id=\"caption-attachment-182545\" class=\"wp-caption-text\">Grafico del prezzo di SHIB su sette giorni. Fonte: Finbold<\/figcaption><\/figure><p>Con SHIB che mostra segni di ribasso a breve termine, gli investitori devono <strong>monitorare diversi livelli chiave<\/strong>, come la resistenza a $0,000018. La perdita del supporto a $0,0000170 potrebbe probabilmente esacerbare i sentimenti ribassisti.\n<\/p><h2>La prevendita di Shiba Shootout si avvicina a $1 milione<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nIn questa situazione di incertezza per SHIB, un nuovo progetto ha iniziato a scuotere il mondo delle meme coin, combinando proprio il popolare tema di Shiba Inu con un pizzico di spirito del Far West.<\/p><p>Parliamo della <strong>prevendita di Shiba Shootout<\/strong> che si avvicina al <strong>traguardo di $1 milione<\/strong>, portando molti a ritenere che potrebbe essere questa la prossima meme coin a esplodere quest&#8217;anno&#8230;<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-182572 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1513\" height=\"693\" sizes=\"auto, (max-width: 1513px) 100vw, 1513px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/07\/1722244440-shiba-shootout-viral.jpg\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29091400\/1722244440-shiba-shootout-viral.jpg 1513w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29091400\/1722244440-shiba-shootout-viral-300x137.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29091400\/1722244440-shiba-shootout-viral-640x293.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29091400\/1722244440-shiba-shootout-viral-768x352.jpg 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29091400\/1722244440-shiba-shootout-viral-450x206.jpg 450w\"><\/p><p>La sua caratteristica principale &egrave; un gioco mobile Play-to-Earn (P2E) attualmente in fase di sviluppo ma di cui &egrave; gi&agrave; disponibile su Google Play e App Store una versione base che consente di cominciare a farsi un&#8217;idea.<\/p><p>La versione completa, prevista per il lancio pi&ugrave; avanti quest&#8217;anno, presenter&agrave; elementi di gameplay pi&ugrave; avanzati ambientati nella citt&agrave; virtuale di Shiba Gulch ma soprattutto permetter&agrave; ai giocatori di <strong>guadagnare SHIBASHOOT<\/strong>.<\/p><p>Si tratta di un token ERC-20 nativo di Shiba Shootout che svolge molteplici funzioni all&#8217;interno dell&#8217;ecosistema. Non &egrave; solo la <strong>valuta in-game per il gioco P2E<\/strong> ma anche la chiave per accedere a varie funzionalit&agrave; e ricompense.<\/p><p>A cominciare dal <strong>Cactus Staking<\/strong>, un sistema che permette agli utenti di mettere in staking i loro SHIBASHOOT e guadagnare token aggiuntivi nel tempo. In alternativa c&#8217;&egrave; anche una funzione chiamata <strong>Lucky Lasso Lotteries<\/strong>, dove i giocatori usano i loro token per avere la possibilit&agrave; di vincere premi crypto.<\/p><p>I possessori di SHIBASHOOT, inoltre, avranno anche diritti di voto nella configurazione di governance del progetto.<\/p><p>Attualmente, gli investitori precoci possono assicurarsi i token <strong>a soli $0,0197 ciascuno<\/strong>. Questo prezzo dovrebbe rappresentare un valore molto pi&ugrave; basso rispetto a quello della quotazione su DEX. Ecco perch&eacute; sarebbe meglio non aspettare a entrare nel progetto.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/ext\/shiba-shootout\/\" rel=\"nofollow noindex\">Scopri Shiba Shootout<\/a><\/div><p><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><h3>Leggi anche:<\/h3><ul>\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/trump-senza-freni-alla-bitcoin-conference-di-nashville-2024\/\" target=\"_blank\" rel=\"noopener\"><strong>Trump senza freni alla Bitcoin Conference di Nashville 2024<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-trump-appoggia-lidea-di-btc-come-riserva-di-valore\/\" target=\"_blank\" rel=\"noopener\"><strong>Previsione Bitcoin: Trump appoggia l&rsquo;idea di BTC come riserva di valore<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/cryptonews.com\/it\/guides\/nuove-criptovalute\/\" target=\"_blank\" rel=\"noopener\"><strong>Tutte le nuove criptovalute da comprare nel 2024<\/strong><\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>L&#8217;hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all&#8217;IA come reagir\u00e0 Shiba Inu&#8230; <\/p>\n","protected":false},"author":298,"featured_media":182563,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[758,6912],"editors":[6140],"sponsored_companies":[],"class_list":["post-182543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin-news","tag-shiba-inu","tag-shiba-shootout","editors-lucio-prosperi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ChatGPT fissa il prezzo di SHIB all&#039;1 agosto. C&#039;\u00e8 aria di ripresa?<\/title>\n<meta name=\"description\" content=\"L&#039;hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all&#039;IA come reagir\u00e0 Shiba Inu...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ChatGPT fissa il prezzo di SHIB all&#039;1 agosto. C&#039;\u00e8 aria di ripresa?\" \/>\n<meta property=\"og:description\" content=\"L&#039;hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all&#039;IA come reagir\u00e0 Shiba Inu...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-29T10:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ChatGPT fissa il prezzo di SHIB all&#039;1 agosto. C&#039;\u00e8 aria di ripresa?\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all&#039;IA come reagir\u00e0 Shiba Inu...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ChatGPT fissa il prezzo di SHIB all'1 agosto. C'\u00e8 aria di ripresa?","description":"L'hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all'IA come reagir\u00e0 Shiba Inu...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/","og_locale":"it_IT","og_type":"article","og_title":"ChatGPT fissa il prezzo di SHIB all'1 agosto. C'\u00e8 aria di ripresa?","og_description":"L'hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all'IA come reagir\u00e0 Shiba Inu...","og_url":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/","og_site_name":"Cryptonews Italia","article_published_time":"2024-07-29T10:00:40+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"ChatGPT fissa il prezzo di SHIB all'1 agosto. C'\u00e8 aria di ripresa?","twitter_description":"L'hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all'IA come reagir\u00e0 Shiba Inu...","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/"},"author":{"name":"lucio","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/5e6d68d2f5fe4e3cd7324728830f89f6"},"headline":"ChatGPT stabilisce il prezzo di SHIB per l&#8217;1 agosto, dopo il furto da 100 milioni di dollari","datePublished":"2024-07-29T10:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/"},"wordCount":992,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg","keywords":["Shiba Inu","Shiba Shootout"],"articleSection":["Altcoin News"],"inLanguage":"it-IT","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/","url":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/","name":"ChatGPT fissa il prezzo di SHIB all'1 agosto. C'\u00e8 aria di ripresa?","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg","datePublished":"2024-07-29T10:00:40+00:00","description":"L'hack di cui \u00e8 stato vittima WazirX ha portato al furto soprattutto di token SHIB. Abbiamo chiesto all'IA come reagir\u00e0 Shiba Inu...","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/07\/29090832\/1722244112-copertina-altcoin1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/chatgpt-stabilisce-il-prezzo-di-shib-per-l1-agosto-dopo-il-furto-da-100-milioni-di-dollari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"ChatGPT stabilisce il prezzo di SHIB per l&#8217;1 agosto, dopo il furto da 100 milioni di dollari"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/182543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/298"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=182543"}],"version-history":[{"count":3,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/182543\/revisions"}],"predecessor-version":[{"id":182573,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/182543\/revisions\/182573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/182563"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=182543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=182543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=182543"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=182543"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=182543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}