{"id":177933,"date":"2024-06-10T11:30:27","date_gmt":"2024-06-10T11:30:27","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=177933"},"modified":"2024-06-10T11:16:21","modified_gmt":"2024-06-10T11:16:21","slug":"arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/","title":{"rendered":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-177954 size-full\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/06\/1718013928-cn-cover-021.jpg\" alt=\"Arbitrum vota un fondo da $215 milioni\" width=\"1280\" height=\"720\" srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg 1280w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021-300x169.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021-640x360.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><\/p><p>Al fine di sostenere i progetti avviati nell&#8217;ecosistema di gioco sulla rete Ethereum Layer 2 di <strong>Arbitrum<\/strong>, la piattaforma di governance della rete ha approvato una proposta di allocazione di 225 milioni di token ARB nell&#8217;arco di tre anni.<\/p><p>La proposta &egrave; stata avanzata dal cofondatore di Vela Exchange, <strong>Dan Peng<\/strong>, e prevede lo stanziamento di 225 milioni di <strong>token ARB<\/strong>, per un valore di circa 215 milioni di dollari ai prezzi attuali, nell&#8217;arco di tre anni, a favore di un <strong>Gaming Catalyst Program (GCP)<\/strong> di nuova creazione, progettato per <em>&#8220;&#8230;espandere immediatamente la consapevolezza e l&#8217;adozione di Arbitrum\/Orbit\/Stylus da parte dei builder e dei player appartenenti alla comunit&agrave; di gioco&#8221;<\/em>.\n<\/p><h2>Un fondo da 225 milioni di dollari stanziato per il settore gaming di Arbitrum<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nPresentata per la prima volta a marzo, la proposta &egrave; passata ufficialmente venerd&igrave; 7 giugno con oltre il 75% dei voti a favore. Tra le organizzazioni che hanno sostenuto in modo significativo la proposta figurano <strong>L2Beat<\/strong>, <strong>Wintermute<\/strong> e <strong>Treasure<\/strong> <strong>DAO<\/strong>, focalizzata sui giochi, mentre <strong>Blockworks Research<\/strong> e <strong>Camelot DAO<\/strong> sono tra coloro che hanno votato contro.<\/p><p>In risposta all&#8217;approvazione della proposta, <strong>Treasure DAO<\/strong> ha commentato su X:\n<\/p><blockquote><p>&#8220;Arbitrum &egrave; la casa del gioco &#8211; questo include tutti i giochi, le catene di gioco e tutti i costruttori all&#8217;interno della sua orbita. Facciamo accadere un po&#8217; di magia&#8221;.<\/p><\/blockquote><p>\nGran parte del fondo &egrave; destinato agli <em>editors<\/em>, con gli sviluppatori nuovi e in fase iniziale che avranno la possibilit&agrave; di richiedere sovvenzioni per un valore massimo di <strong>500.000 ARB<\/strong> (circa 483.000 dollari ai prezzi attuali), mentre gli sviluppatori pi&ugrave; affermati dovranno richiedere investimenti con una componente di condivisione del valore attraverso token, azioni o mezzi simili. Il resto dei fondi sar&agrave; destinato a ricompense legate alle infrastrutture e alle spese operative.<\/p><p>Le operazioni quotidiane saranno gestite da un <strong>team GCP<\/strong> dedicato, anche se il programma sar&agrave; supervisionato da un consiglio di <em>&#8220;5 persone con una profonda esperienza di gioco, di venture, di analisi\/reporting e\/o con competenze di governance DAO&#8221;<\/em>, elette dal <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/whats-store-for-daos-2022-it\/\" target=\"_blank\" rel=\"noopener\"><strong>DAO<\/strong><\/a>.<\/p><p>Il consiglio avr&agrave; la capacit&agrave; di porre il veto sulle decisioni di investimento e sulle nomine dei membri del team. Il budget del <strong>team GCP<\/strong> &egrave; stato fissato a 25 milioni di dollari per le spese operative, e qualsiasi spesa in eccesso dovr&agrave; essere approvata dal <a href=\"https:\/\/cryptonews.com\/it\/exclusives\/the-future-is-dao-how-are-online-communities-evolving-it\/\" target=\"_blank\" rel=\"noopener\"><strong>DAO<\/strong><\/a>.<\/p><figure id=\"attachment_177958\" aria-describedby=\"caption-attachment-177958\" style=\"width: 1495px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-177958 size-full lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1495\" height=\"533\" sizes=\"auto, (max-width: 1495px) 100vw, 1495px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/06\/1718015705-001a.jpg\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103505\/1718015705-001a.jpg 1495w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103505\/1718015705-001a-300x107.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103505\/1718015705-001a-640x228.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103505\/1718015705-001a-768x274.jpg 768w\"><figcaption id=\"caption-attachment-177958\" class=\"wp-caption-text\">Grafico del prezzo di Arbitrum (ARB) a 1 giorno &#8211; Fonte: <strong>CoinMarketCap<\/strong><\/figcaption><\/figure><p>Secondo i dati di <strong>CoinMarketCap<\/strong> aggiornati al momento della stesura di questo articolo, il <strong>token ARB<\/strong> &egrave; scambiato al prezzo di <strong>0,9689 dollari<\/strong>, segnando un calo dello 0,70% nelle ultime 24 ore e del 12% rispetto al valore di scambio di <strong>1,10 dollari<\/strong>, registrato poco tempo prima della conclusione del periodo di votazione.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><strong><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/it\/visit\/etoro-crypto\/\" target=\"_blank\" rel=\"nofollow noindex noopener\">Investi in ARB<\/a><\/strong><\/div><p style=\"text-align: center\"><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><h2>PlayDoge: il Tamagotchi rivive sulla blockchain<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nUn nuovo progetto di memecoin sta facendo rivivere una delle vecchie glorie dei videogames, il classico <strong>Tamagotchi<\/strong>, che ha rinnovato portandolo nel mondo della blockchain.<\/p><p>Il progetto si chiama <a href=\"https:\/\/cryptonews.com\/ext\/playdoge\/\" target=\"_blank\" rel=\"noopener sponsored nofollow\"><strong>PlayDoge (PLAY)<\/strong><\/a> e ha da poco lanciato la sua prevendita, che ha gi&agrave; raccolto pi&ugrave; di 3,5 milioni di dollari.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-177959 size-full lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1470\" height=\"857\" sizes=\"auto, (max-width: 1470px) 100vw, 1470px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/06\/1718015934-002.jpg\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103855\/1718015934-002.jpg 1470w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103855\/1718015934-002-300x175.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103855\/1718015934-002-640x373.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103855\/1718015934-002-768x448.jpg 768w\"><\/p><p>La criptovaluta nativa della piattaforma PlayDoge, il <a href=\"https:\/\/cryptonews.com\/it\/news\/come-comprare-playdoge\/\" target=\"_blank\" rel=\"noopener\"><strong>token PLAY<\/strong><\/a>, &egrave; una memecoin che al momento possiede soltanto un&#8217;utilit&agrave; di staking. Ma al termine della prevendita, gli sviluppatori lanceranno l&#8217;app mobile di gioco <em>Play-to-Earn<\/em> e il token PLAY funger&agrave; da valuta virtuale utilizzabile nel gioco, oltre a poter essere negoziato una volta che sar&agrave; quotato sugli exchange.<\/p><p>Il team di sviluppatori di <strong>PlayDoge<\/strong> sta infatti realizzando un mobile game <strong>P2E<\/strong> ispirato all&#8217;originale Tamagotchi, il cui scopo principale &egrave; quello di prendersi cura di un animale domestico virtuale.<\/p><p>Tutte le azioni finalizzate alla cura e alla crescita del proprio pet: dargli da mangiare quando &egrave; affamato, farlo divertire, farlo dormire quando &egrave; stanco e curarlo quando &egrave; ammalato, saranno ricompensate in <strong>token PLAY<\/strong>. Inoltre, il gioco prevede anche delle classifiche per i migliori giocatori, con relative ricompense extra.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-177960 size-full lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1140\" height=\"781\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2024\/06\/1718015951-003.jpg\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103911\/1718015951-003.jpg 1140w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103911\/1718015951-003-300x206.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103911\/1718015951-003-640x438.jpg 640w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10103911\/1718015951-003-768x526.jpg 768w\"><\/p><p>Per quanto concerne lo <strong>staking<\/strong>, invece, i <strong>token PLAY<\/strong> possono essere bloccati nel relativo pool subito dopo l&#8217;acquisto. Qui iniziano a maturare un sostanziale reddito passivo. Il rate delle ricompense dello staking &egrave; dinamico e dipende dal numero complessivo di token bloccati nel pool. Per il momento, circa 47,8 milioni di token PLAY sono stati bloccati nel pool di staking, con un reddito APY stimato al <strong>394%<\/strong>.<\/p><p>Attualmente, il <strong>token PLAY<\/strong> &egrave; disponibile al prezzo unitario di <strong>0,00505 dollari<\/strong>. Quando la prevendita passer&agrave; alla prossima fase, il prezzo subir&agrave; un ulteriore aumento. Ecco perch&eacute; &egrave; consigliabile partecipare presto alla prevendita. Solo cos&igrave; &egrave; possibile posizionarsi come <em>early adopters<\/em> e assicurarsi il massimo guadagno al momento della quotazione ufficiale del token Play sugli exchange.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><strong><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/ext\/playdoge\/\" target=\"_blank\" rel=\"nofollow noindex noopener\">Scopri la prevendita di PlayDoge<\/a><\/strong><\/div><p style=\"text-align: center\"><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><h3>Leggi anche:<\/h3><ul>\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/segnale-di-acquisto-per-2-criptovalute-ipervendute-questa-settimana\/\" target=\"_blank\" rel=\"noopener\"><strong>Segnale di acquisto per 2 criptovalute ipervendute questa settimana<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/binance-da-record-nuovo-ath-presale-dei-token-di-riserva-di-valore-btn-e-voci-su-un-etf-spot\/\" target=\"_blank\" rel=\"noopener\"><strong>Binance da record: nuovo ATH, presale dei token di Riserva di Valore $BTN e voci su un ETF spot<\/strong><\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete. <\/p>\n","protected":false},"author":181,"featured_media":177954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[659,7096],"editors":[6251],"sponsored_companies":[],"class_list":["post-177933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin-news","tag-dao","tag-playdoge","editors-aniello-raul-barone"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari<\/title>\n<meta name=\"description\" content=\"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari\" \/>\n<meta property=\"og:description\" content=\"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T11:30:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari\" \/>\n<meta name=\"twitter:description\" content=\"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari","description":"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/","og_locale":"it_IT","og_type":"article","og_title":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari","og_description":"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.","og_url":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/","og_site_name":"Cryptonews Italia","article_published_time":"2024-06-10T11:30:27+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari","twitter_description":"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/"},"author":{"name":"raulbaroneind","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/23907e62540ffd34eb7dde1a29418d3c"},"headline":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari","datePublished":"2024-06-10T11:30:27+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/"},"wordCount":866,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg","keywords":["DAO","PlayDoge"],"articleSection":["Altcoin News"],"inLanguage":"it-IT","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/","url":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/","name":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg","datePublished":"2024-06-10T11:30:27+00:00","description":"La DAO di Arbitrum ha approvato una proposta di stanziamento di 225 milioni di ARB per sostenere progetti di gioco sulla rete.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/8\/2024\/06\/10100529\/1718013928-cn-cover-021.jpg","width":1280,"height":720,"caption":"Arbitrum vota un fondo da $215 milioni"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/arbitrum-dao-vota-per-approvare-un-fondo-da-215-milioni-di-dollari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Arbitrum DAO vota per approvare un fondo da 215 milioni di dollari"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/177933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=177933"}],"version-history":[{"count":5,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/177933\/revisions"}],"predecessor-version":[{"id":177970,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/177933\/revisions\/177970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/177954"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=177933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=177933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=177933"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=177933"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=177933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}