{"id":148948,"date":"2023-11-10T17:30:55","date_gmt":"2023-11-10T17:30:55","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=148948"},"modified":"2023-11-10T16:42:12","modified_gmt":"2023-11-10T16:42:12","slug":"cardano-ada-risponde-alla-crescita-del-mercato-crypto","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/","title":{"rendered":"Cardano (ADA) risponde alla crescita del mercato crypto"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-148957\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg\" alt=\"\" width=\"1200\" height=\"700\" srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg 1200w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover-300x175.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover-640x373.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover-768x448.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/p><p>Bitcoin sembra sul punto di esplodere da un momento all&#8217;altro e superare la soglia dei 40.000$, di riflesso molte altcoin stanno godendo di questo nuovo ritorno di interesse. Tra i maggiori vincitori c&#8217;&egrave; anche <strong>Cardano<\/strong> (ADA) che ha guadagnato il 15% dall&#8217;inizio di novembre.<\/p><p>Finora, novembre si &egrave; rivelato un mese molto interessante per il mercato crypto e la cosa sembra confermarsi anche quest&#8217;anno.<\/p><p>A determinare la crescita recente ha contribuito l&#8217;aumentare delle aspettative positive sull&#8217;approvazione degli <strong>ETF spot di Bitcoin<\/strong>.\n<\/p><h2>Analisi tecnica e sentiment di mercato per Cardano<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nSul piano tecnico, i grafici di ADA ispirano ottimismo. In primo luogo, il valore della crypto &egrave; ancora sottostimato se si considera il rapporto tra valore di mercato e valore realizzato (MVRV). Quindi c&#8217;&egrave; ancora spazio sufficiente per continuare a crescere.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-148958 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"2048\" height=\"459\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631362-1699612470-indicatorscardano-2048x459-1.png\" data-srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631362-1699612470-indicatorscardano-2048x459-1.png 2048w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631362-1699612470-indicatorscardano-2048x459-1-300x67.png 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631362-1699612470-indicatorscardano-2048x459-1-640x143.png 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631362-1699612470-indicatorscardano-2048x459-1-768x172.png 768w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631362-1699612470-indicatorscardano-2048x459-1-1536x344.png 1536w\"><\/p><p>Aumenta anche la dominance di<strong> Cardano sui social<\/strong>, il che indica che il token suscita interesse tra i trader e gli sviluppatori visto che ADA continua a essere un argomento seguito sui social media.&nbsp;Di solito questa tendenza si pu&ograve; interpretare come un indicatore rialzista.<\/p><p>Cresce anche il numero di indirizzi attivi su base giornaliera, rivelando un maggiore coinvolgimento della community.\n<\/p><h2>Crescono le funzionalit&agrave; del network di Cardano<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nL&#8217;obiettivo di Cardano &egrave; sempre stato posizionarsi come attore chiave nel settore blockchain. Anche se non hanno giocato in favore di questo obiettivo i continui rinvii degli aggiornamenti, i suoi dirigenti hanno finalmente preso posizione sulla questione.<\/p><p>Durante il Cardano Summit 2023 tenutosi di recente a Dubai, la societ&agrave; promotrice Input Output Global (IOG), ha lanciato il programma Partner Chain.<\/p><p>Questo segna una svolta importante per il network ed &egrave; stato introdotto dallo stesso Charles Hoskinson, volto di Cardano, che ha descritto il programma come un elemento rivoluzionario nel contesto del Web3.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">\ud83d\udd17 Partner chains are the next frontier for <a href=\"https:\/\/twitter.com\/hashtag\/Cardano?src=hash&amp;ref_src=twsrc%5Etfw\">#Cardano<\/a>&#39;s evolution! IOG unveils a revolutionary framework enabling independent, interoperable, layer 1 <a href=\"https:\/\/twitter.com\/hashtag\/blockchain?src=hash&amp;ref_src=twsrc%5Etfw\">#blockchain<\/a> networks to thrive. \ud83d\udca1<a href=\"https:\/\/t.co\/wvHRy7W3CP\">https:\/\/t.co\/wvHRy7W3CP<\/a><\/p>\n<p>&mdash; Input Output (@InputOutputHK) <a href=\"https:\/\/twitter.com\/InputOutputHK\/status\/1720368018679583201?ref_src=twsrc%5Etfw\">November 3, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Il concetto di Partner Chains sviluppa la visione di Cardano in termini di scalabilit&agrave; e interoperabilit&agrave;, i caposaldi dell&#8217;ecosistema.<\/p><p>Secondo IOG le chain partner otterranno un vantaggio grazie all&#8217;accesso al Settlement Layer (CSL) di Cardano, le cui capacit&agrave; di scalabilit&agrave; sono gi&agrave; dimostrate, ma restando liberi di innovare.\n<\/p><h2>Previsione dei prezzi Cardano: vicino a 0,40$<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nIl recente slancio di Cardano (ADA) &egrave; piuttosto incoraggiante e potrebbe segnalare cambiamenti fondamentali per il futuro di questa criptovaluta.<\/p><p>Il breakout oltre il livello di resistenza a 0,37$ &egrave; un punto notevole. Se si manterr&agrave; la pressione d&#8217;acquisto il livello si potrebbe facilmente superare.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-148959 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1716\" height=\"373\" sizes=\"auto, (max-width: 1716px) 100vw, 1716px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631428-1699615129-cardano-7d.png\" data-srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631428-1699615129-cardano-7d.png 1716w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631428-1699615129-cardano-7d-300x65.png 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631428-1699615129-cardano-7d-640x139.png 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631428-1699615129-cardano-7d-768x167.png 768w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631428-1699615129-cardano-7d-1536x334.png 1536w\"><\/p><p>Inoltre, molti analisti scommettono sull&#8217;obiettivo di 0,40$ perch&eacute; le condizioni di mercato sono favorevoli. Il prezzo potrebbe puntare invece a un obiettivo pi&ugrave; ambizioso a 0,45$, cio&egrave; un aumento del 25% rispetto ai livelli attuali.\n<\/p><h2>Alternative da prendere in considerazione: Bitcoin Minetrix<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nBitcoin Minetrix (BTCMTX) &egrave; un progetto crypto che offre un approccio innovativo al mining di Bitcoin. Grazie al<strong> cloud mining<\/strong>, il progetto desidera offrire l&#8217;opportunit&agrave; di minare Bitcoin senza sopportare pesanti investimenti di solito necessari.<\/p><p>Questo approccio ha attirato un gran numero di investitori. La prevendita ha gi&agrave; superato 3,7 milioni di dollari e si avvicina al suo obiettivo di 4,4 milioni di dollari.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Come on board the <a href=\"https:\/\/twitter.com\/hashtag\/BitcoinMinetrix?src=hash&amp;ref_src=twsrc%5Etfw\">#BitcoinMinetrix<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Telegram?src=hash&amp;ref_src=twsrc%5Etfw\">#Telegram<\/a> group! \ud83d\udcbc<\/p>\n<p>1\ufe0f\u20e3 Gain knowledge: Engage with experienced mining experts.<\/p>\n<p>2\ufe0f\u20e3 Stay updated: Get instant notifications on market changes and advancements.<\/p>\n<p>3\ufe0f\u20e3 Connect and exchange: Join a network of <a href=\"https:\/\/twitter.com\/hashtag\/Crypto?src=hash&amp;ref_src=twsrc%5Etfw\">#Crypto<\/a> enthusiasts. <a href=\"https:\/\/t.co\/uQAMryNQRf\">pic.twitter.com\/uQAMryNQRf<\/a><\/p>\n<p>&mdash; Bitcoinminetrix (@bitcoinminetrix) <a href=\"https:\/\/twitter.com\/bitcoinminetrix\/status\/1722901988667425010?ref_src=twsrc%5Etfw\">November 10, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Bitcoin Minetrix ha trovato un modo per rendere il mining di Bitcoin pi&ugrave; accessibile grazie al cloud computing per fornire utilit&agrave; al proprio token BTCMTX.<\/p><p>Inoltre si investe molto sulla trasparenza e la sicurezza del sistema grazie alla completa decentralizzazione.<\/p><p>Per promuovere il lancio del token &egrave; ora disponibile il concorso Gleam che offre ricchi premi per motivare gli investitori a partecipare a questa innovazione dello stake-to-mine.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/it\/visit\/bitcoin-minetrix\/\" target=\"_blank\" rel=\"nofollow noindex noopener\">Prevendita Bitcoin Minetrix<\/a><\/div><p><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Tra i maggiori vincitori dell&#8217;attuale rally del mercato c&#8217;\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall&#8217;inizio di novembre.<\/p>\n","protected":false},"author":162,"featured_media":148957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[431,321],"editors":[2210],"sponsored_companies":[],"class_list":["post-148948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin-news","tag-ada","tag-cardano","editors-marcello-bonti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cardano (ADA) risponde alla crescita del mercato crypto<\/title>\n<meta name=\"description\" content=\"Tra i maggiori vincitori dell&#039;attuale rally del mercato c&#039;\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall&#039;inizio di novembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cardano (ADA) risponde alla crescita del mercato crypto\" \/>\n<meta property=\"og:description\" content=\"Tra i maggiori vincitori dell&#039;attuale rally del mercato c&#039;\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall&#039;inizio di novembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-10T17:30:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Tra i maggiori vincitori dell&#039;attuale rally del mercato c&#039;\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall&#039;inizio di novembre.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cardano (ADA) risponde alla crescita del mercato crypto","description":"Tra i maggiori vincitori dell'attuale rally del mercato c'\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall'inizio di novembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/","og_locale":"it_IT","og_type":"article","og_title":"Cardano (ADA) risponde alla crescita del mercato crypto","og_description":"Tra i maggiori vincitori dell'attuale rally del mercato c'\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall'inizio di novembre.","og_url":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/","og_site_name":"Cryptonews Italia","article_published_time":"2023-11-10T17:30:55+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"Tra i maggiori vincitori dell'attuale rally del mercato c'\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall'inizio di novembre.","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/"},"author":{"name":"lauradimariatnf","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/f301a2fe5b1b74682fd70e7a2502d752"},"headline":"Cardano (ADA) risponde alla crescita del mercato crypto","datePublished":"2023-11-10T17:30:55+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/"},"wordCount":623,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg","keywords":["ada","cardano"],"articleSection":["Altcoin News"],"inLanguage":"it-IT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/","url":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/","name":"Cardano (ADA) risponde alla crescita del mercato crypto","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg","datePublished":"2023-11-10T17:30:55+00:00","description":"Tra i maggiori vincitori dell'attuale rally del mercato c'\u00e8 anche Cardano (ADA) che ha guadagnato il 15% dall'inizio di novembre.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699631291-ada-cover.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/cardano-ada-risponde-alla-crescita-del-mercato-crypto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Cardano (ADA) risponde alla crescita del mercato crypto"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/148948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=148948"}],"version-history":[{"count":4,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/148948\/revisions"}],"predecessor-version":[{"id":148975,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/148948\/revisions\/148975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/148957"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=148948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=148948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=148948"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=148948"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=148948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}