{"id":147464,"date":"2023-11-04T15:24:24","date_gmt":"2023-11-04T15:24:24","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=147464"},"modified":"2023-11-04T16:33:38","modified_gmt":"2023-11-04T16:33:38","slug":"previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/","title":{"rendered":"Previsione Bitcoin: BTC tenta il breakout oltre la resistenza a 36.000$"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-147465\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg\" alt=\"\" width=\"1200\" height=\"700\" srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg 1200w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover-300x175.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover-640x373.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover-768x448.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/p><p>Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l&#8217;attenzione di investitori e analisti. Oggi sabato 4 novembre, BTC registra un guadagno marginale dello 0,04% ed &egrave; scambiato a 34.764$.<\/p><p>Il <strong>prezzo di BTC<\/strong> si muove in un contesto di particolare inasprimento sul piano normativo negli USA. Il settore delle criptovalute &egrave; attualmente oggetto di maggiore controllo.<\/p><p>Su scala globale, invece, cresce l&#8217;apprezzamento per gli <strong>ETF spot di BTC<\/strong> che hanno attirato complessivamente capitali per 4,16 miliardi di dollari, prova del crescente interesse istituzionale per la valuta digitale.<\/p><p>Sorprende che anche in <strong>Cina<\/strong> torna a crescere l&#8217;interesse per la prima crypto. &Egrave; di questi giorni la notizia che una scuola inglese ha potenziato la propria attivit&agrave; di mining crypto con 220 nuove macchine.<\/p><p>Questi segnali sono sufficienti per spingere i prezzi oltre la soglia cruciale dei 36.000$?\n<\/p><h2>Nuova stretta normativa negli USA, nel mirino i dirigenti delle compagnie crypto<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nNuove indagini del governo USA su diverse figure di spicco nel settore crypto potrebbero influenzare il sentimento del mercato.<strong> Sam Bankman-Fried<\/strong>, un tempo leader del settore, &egrave; stato condannato per aver frodato i clienti del suo exchange FTX, rovinosamente fallito.<\/p><p>Proseguono le indagini della Commodities Futures Trading Commission (CFTC) e la Securities and Exchange Commission (SEC) degli Stati Uniti nei confronti del CEO di Binance<strong> Changpeng &#8220;CZ&#8221; Zhao<\/strong>, su cui pendono varie accuse.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">The other crypto bosses in US authorities&#39; crosshairs <a href=\"https:\/\/t.co\/ca816wtG52\">https:\/\/t.co\/ca816wtG52<\/a> <a href=\"https:\/\/t.co\/x7LoAGvzdg\">pic.twitter.com\/x7LoAGvzdg<\/a><\/p>\n<p>&mdash; Reuters (@Reuters) <a href=\"https:\/\/twitter.com\/Reuters\/status\/1720517036789436741?ref_src=twsrc%5Etfw\">November 3, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Do Kwon, cofondatore di <strong>Terraform Labs<\/strong>, &egrave; stato arrestato in Montenegro ed &egrave; accusato di frode. La SEC lo accusa di aver orchestrato una frode multimiliardaria.<\/p><p>Alex Mashinsky, fondatore di <strong>Celsius Network<\/strong>, &egrave; accusato di aver ingannato gli investitori e gonfiato il valore del token della piattaforma. In questo momento si trova sotto il mirino di vari enti governativi.<\/p><p>Questi interventi potrebbero innescare una reazione da parte del legislatore e portare a un inasprimento delle regole per il mercato crypto, impattando sul sentimento del mercato e quindi sul prezzo di Bitcoin.\n<\/p><h2>Il mercato del lavoro USA rallenta, cresce il mercato azionario e calano dollaro e tassi di interesse<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\n&Egrave; in calo il livello di occupazione nel mese si ottobre negli USA dove si registra un rallentamento della creazione di posti di lavoro. Ai minimi in cinque settimane anche i rendimenti dei titoli di stato USA a 10 anni. Anche il dollaro statunitense tocca il minimo in sei settimane.<\/p><p>La Federal Reserve potrebbe decidere di interrompere l&#8217;aumento dei tassi di interesse alla luce di questo rallentamento sul piano occupazionale. Ipotesi avvalorata dalla decisione della Fed di mantenere i tassi fermi all&#8217;inizio della settimana.<\/p><p>Gli analisti stimano solo il 5% di possibilit&agrave; per un aumento a dicembre&nbsp;dei tassi&nbsp;da parte della Fed.<\/p><p>https:\/\/twitter.com\/CryptoverseFeed\/status\/1720014895259783383<\/p><p>Questa prospettiva di solito ha un <strong>effetto favorevole sul prezzo di Bitcoin (BTC)<\/strong>. Infatti, i tassi d&#8217;interesse pi&ugrave; bassi possono rendere gli asset di rischio, come le criptovalute, pi&ugrave; interessanti per gli investitori in cerca di rendimenti migliori. Qualsiasi segnale che lasci intendere una politica monetaria meno falco da parte della Fed si potrebbe considerare rialzista per BTC.<\/p><p>Non sempre, per&ograve;, la relazione tra tassi d&#8217;interesse e prezzi di BTC &egrave; diretta, perch&eacute; il prezzo di BTC &egrave; molto sensibile a una serie di fattori, come l&#8217;umore del mercato e il quadro economico generale.\n<\/p><h2>Nel mondo gli ETF di Bitcoin valgono 4,16 miliardi di dollari<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nGli investimenti globali in ETF legati all&#8217;attuale prezzo del Bitcoin hanno superato i 4,16 miliardi di dollari, secondo l&#8217;aggregatore di dati crypto CoinGecko.<\/p><p>&Egrave; interessante notare che circa due miliardi di questi sono gestiti da sette fondi di Bitcoin istituiti in Canada dal 2021.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Global assets in spot bitcoin ETFs hit $4.16 billion &#8211; CoinGecko <a href=\"https:\/\/t.co\/oVWsPMsuKX\">https:\/\/t.co\/oVWsPMsuKX<\/a> <a href=\"https:\/\/t.co\/I4iobZp0Vt\">pic.twitter.com\/I4iobZp0Vt<\/a><\/p>\n<p>&mdash; Reuters Business (@ReutersBiz) <a href=\"https:\/\/twitter.com\/ReutersBiz\/status\/1720463414332424636?ref_src=twsrc%5Etfw\">November 3, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>In questo momento sono dieci le richieste di approvazione di ETF legati al prezzo spot di Bitcoin al vaglio della SEC negli Stati Uniti. Questi strumenti offrirebbero un canale preferenziale per gli investitori istituzionali che vogliono esporsi a BTC senza possederlo direttamente.\n<\/p><h2>Una scuola cinese acquisisce 220 nuove macchine per il mining<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nBTC Digital, una catena di scuole di inglese in Cina, ha aggiunto altre 220 unit&agrave; di mining al suo portafoglio, portando la sua dotazione di macchine per minare Bitcoin a 2.174, con una potenza di elaborazione di circa 230 (PH\/s).<\/p><p>Le unit&agrave; aggiuntive dovrebbero essere operative entro la fine del mese. L&#8217;operazione &egrave; costata 968.800$ pagate in quote azionarie della compagnia.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">BTC DIGITAL LTD. ANNOUNCES PURCHASE OF 220 UNITS OF ANTMINER S19J PRO BITCOIN MINING MACHINES <a href=\"https:\/\/twitter.com\/hashtag\/News?src=hash&amp;ref_src=twsrc%5Etfw\">#News<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Markets?src=hash&amp;ref_src=twsrc%5Etfw\">#Markets<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/BITCOIN?src=hash&amp;ref_src=twsrc%5Etfw\">#BITCOIN<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/BTC?src=hash&amp;ref_src=twsrc%5Etfw\">#BTC<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/BTC?src=hash&amp;ref_src=twsrc%5Etfw\">#BTC<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/live?src=hash&amp;ref_src=twsrc%5Etfw\">#live<\/a><\/p>\n<p>&mdash; Capital Hungry (@Capital_Hungry) <a href=\"https:\/\/twitter.com\/Capital_Hungry\/status\/1720418312041959448?ref_src=twsrc%5Etfw\">November 3, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Nel 2021, BTC Digital &egrave; passata dal settore dell&#8217;istruzione a quello del mining di Bitcoin, concentrandosi sulle operazioni di mining negli Stati Uniti.\n<\/p><h2>Previsione del prezzo di Bitcoin<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nIl <strong>grafico a 4 ore di Bitcoin<\/strong> evidenzia i livelli critici da tenere sotto controllo. Il punto di riferimento &egrave; 33.965$, che funge da livello chiave per misurare le oscillazioni di prezzo.<\/p><p>La prima resistenza si incontra a 35.255$, e ulteriori sfide sono a 36.040$ e 36.995$. Al contrario, il supporto si trova a 33.095$, 32.400$ e 31.800$.<\/p><p>L&#8217;<strong>indice di forza relativa (RSI)<\/strong> si trova in posizione neutra a 48, mostrando un equilibrio nelle forze di mercato. La media mobile esponenziale a 50 giorni (EMA) a 34.150$ &egrave; un indicatore della tendenza a breve termine. L&#8217;attuale oscillazione di Bitcoin intorno a questa EMA suggerisce il prevalere dell&#8217;indecisione del mercato.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-147466 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"Grafico BTC 4 novembre 2023 - Fonte TradingView\" width=\"1740\" height=\"952\" sizes=\"auto, (max-width: 1740px) 100vw, 1740px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108423-fonte-tradingview.jpg\" data-srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108423-fonte-tradingview.jpg 1740w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108423-fonte-tradingview-300x164.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108423-fonte-tradingview-640x350.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108423-fonte-tradingview-768x420.jpg 768w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108423-fonte-tradingview-1536x840.jpg 1536w\"><\/p><p>I modelli tecnici, come la linea di tendenza al rialzo a 34.200$ e l&#8217;allineamento con l&#8217;EMA a 50 giorni, indicano una tendenza all&#8217;acquisto e un potenziale consolidamento del mercato.<\/p><p>In sintesi, <strong>Bitcoin mostra una leggera inclinazione rialzista<\/strong>, soprattutto se rimane sopra i 34.150$. La combinazione di indicatori e modelli suggerisce un cauto ottimismo, con una possibile spinta verso 35.255$ se l&#8217;attuale supporto regger&agrave;.<\/p><p>Data la volatilit&agrave; intrinseca di BTC, &egrave; fondamentale monitorare questi livelli e indicatori chiave per prendere decisioni di trading e investimento informate.\n<\/p><h2>Crypto da tenere d&#8217;occhio<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nInvestire in un progetto crypto nelle prime fasi potrebbe essere una buona idea per differenziare il portafoglio di investimento. &Egrave; una buona idea tenere d&#8217;occhio i token che si trovano in fase di prevendita.<\/p><p>Il team dedicato agli Approfondimenti su Cryptonews ha curato un elenco delle crypto pi&ugrave; promettenti del 2023, fornendo preziose informazioni su questi progetti.<\/p><p>L&#8217;elenco viene aggiornato ogni settimana per includere nuove altcoin e progetti in prevendita.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/it\/news\/criptovalute-che-esploderanno\/\" rel=\"nofollow noindex\"> Scopri 16 nuove crypto<\/a><\/div><p><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l&#8217;attenzione di investitori e analisti.<\/p>\n","protected":false},"author":162,"featured_media":147465,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[746],"editors":[2210],"sponsored_companies":[],"class_list":["post-147464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","tag-prezzo-bitcoin","editors-marcello-bonti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.<\/title>\n<meta name=\"description\" content=\"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l&#039;attenzione di investitori e analisti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.\" \/>\n<meta property=\"og:description\" content=\"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l&#039;attenzione di investitori e analisti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-04T15:24:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-04T16:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.\" \/>\n<meta name=\"twitter:description\" content=\"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l&#039;attenzione di investitori e analisti.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.","description":"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l'attenzione di investitori e analisti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/","og_locale":"it_IT","og_type":"article","og_title":"Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.","og_description":"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l'attenzione di investitori e analisti.","og_url":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/","og_site_name":"Cryptonews Italia","article_published_time":"2023-11-04T15:24:24+00:00","article_modified_time":"2023-11-04T16:33:38+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.","twitter_description":"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l'attenzione di investitori e analisti.","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/"},"author":{"name":"lauradimariatnf","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/f301a2fe5b1b74682fd70e7a2502d752"},"headline":"Previsione Bitcoin: BTC tenta il breakout oltre la resistenza a 36.000$","datePublished":"2023-11-04T15:24:24+00:00","dateModified":"2023-11-04T16:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/"},"wordCount":1049,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg","keywords":["Prezzo Bitcoin"],"articleSection":["Bitcoin News"],"inLanguage":"it-IT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/","url":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/","name":"Previsione Bitcoin: BTC tenta il breakout oltre 36.000$.","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg","datePublished":"2023-11-04T15:24:24+00:00","dateModified":"2023-11-04T16:33:38+00:00","description":"Bitcoin continua a sfidare la resistenza a 36.000$ tanto da attirare l'attenzione di investitori e analisti.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/11\/1699108092-btc-cover.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-bitcoin-btc-tenta-il-breakout-oltre-la-resistenza-a-36-000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Previsione Bitcoin: BTC tenta il breakout oltre la resistenza a 36.000$"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/147464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=147464"}],"version-history":[{"count":4,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/147464\/revisions"}],"predecessor-version":[{"id":147475,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/147464\/revisions\/147475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/147465"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=147464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=147464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=147464"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=147464"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=147464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}