{"id":134488,"date":"2023-08-11T10:45:37","date_gmt":"2023-08-11T10:45:37","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=134488"},"modified":"2023-08-11T10:51:11","modified_gmt":"2023-08-11T10:51:11","slug":"leuro-digitale-e-morto-in-partenza-per-salvare-le-banche","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/","title":{"rendered":"L&#8217;euro digitale \u00e8 morto in partenza per salvare le banche!"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-134489\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg 1280w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale-300x169.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale-640x360.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><\/p><p>Secondo un <a href=\"https:\/\/cepr.org\/voxeu\/columns\/why-digital-euro-might-be-dead-arrival\"><strong>rapporto<\/strong> <\/a>scritto dagli economisti <strong>Cyril Monnetm<\/strong> e<strong> Dirk Niepel,<\/strong> entrambi dell&#8217;universit&agrave; di Berna<strong>,<\/strong>&nbsp;l&#8217;impegno dell&#8217;Unione europea per sviluppare un euro digitale &egrave; destinato a fallire.<\/p><p>Nell&#8217;articolo i due esperti hanno criticato uno dei principali obiettivi delle <strong>CBDC<\/strong> della Banca Centrale Europea, definendolo un rischio per l&#8217;intero progetto.\n<\/p><blockquote><p>&#8220;Le scelte progettuali sollevano dubbi sugli obiettivi e sulla strategia della BCE e, di conseguenza, l&#8217;euro digitale potrebbe essere morto in partenza&#8221; .<\/p><\/blockquote><h2>Nel mirino la protezione delle banche<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nI due economisti hanno messo in dubbio, nel dettaglio, l&#8217;obiettivo della BCE di &#8220;non danneggiare le banche e proteggere il loro modello di business&#8221;, sollevando preoccupazioni di potenziali<strong> conflitti di interesse<\/strong> nel consentire alle banche intermediarie di essere responsabili della distribuzione dell&#8217;euro digitale.<\/p><p>Gli autori del rapporto aggiungono: &#8220;Le principali opzioni preferite dal Consiglio direttivo riducono l&#8217;attrattiva dell&#8217;euro digitale anzich&eacute; aumentarla. Inoltre prevedono <strong>limiti di detenzione<\/strong> per gli utenti (poche migliaia di euro) e limiti ancora pi&ugrave; bassi per i commercianti (zero)&#8221;.<\/p><p>&#8220;Una parte consistente dei profitti delle banche deriva dall&#8217;offerta di servizi di pagamento. Pertanto, le banche non hanno interesse a vedere l&#8217;euro digitale vivo e vegeto, a meno che i <strong>servizi bancar<\/strong>i legati all&#8217;euro digitale, come l&#8217;onboarding o la gestione dei portafogli, non siano ancora pi&ugrave; redditizi&#8221;, si legge nel rapporto.\n<\/p><h2>Stress finanziario<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nIl documento sottolinea che il piano della BCE di imporre un premio di <strong>interesse negativo<\/strong> sull&#8217;euro digitale in caso di stress finanziario potrebbe ridurne l&#8217;attrattiva per gli intermediari.<\/p><p>L&#8217;euro digitale sar&agrave; cos&igrave; &#8220;inferiore&#8221; in termini di <strong>convenienza<\/strong> e <strong>privacy<\/strong>, fattori chiave per l&#8217;adozione. &#8220;La migliore soluzione disponibile nel settore privato per i pagamenti al dettaglio sar&agrave; superiore all&#8217;euro digitale in termini di convenienza per l&#8217;utente.<\/p><p>E per quanto riguarda la privacy nei confronti del governo e la resistenza alla censura, molti cittadini europei hanno una fiducia limitata nella BCE&#8221;, si legge nel documento.<\/p><p>L&#8217;euro digitale &egrave; attualmente in fase di progettazione e, secondo i funzionari della BCE, la prima emissione possibile &egrave; il 2027.<\/p><p>A fine giugno, il direttore della BCE <strong>Fabio Panetta<\/strong> ha dichiarato che: &#8220;L&#8217;euro digitale &egrave; un passo necessario per garantire che il nostro sistema monetario stia al passo con i progressi digitali. Sar&agrave; ampiamente accessibile e facile da usare, pur preservando la privacy, proprio come il contante&#8221;.<\/p>","protected":false},"excerpt":{"rendered":"<p>Due economisti hanno messo in dubbio l&#8217;obiettivo della BCE di &#8220;non danneggiare le banche e proteggere il loro modello di business&#8221;.<\/p>\n","protected":false},"author":141,"featured_media":134489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,1],"tags":[150],"editors":[3568],"sponsored_companies":[],"class_list":["post-134488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-banche","editors-roberto-migliore"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;euro digitale \u00e8 morto in partenza per salvare le banche!<\/title>\n<meta name=\"description\" content=\"Due economisti hanno messo in dubbio l&#039;obiettivo della BCE di &quot;non danneggiare le banche e proteggere il loro modello di business&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;euro digitale \u00e8 morto in partenza per salvare le banche!\" \/>\n<meta property=\"og:description\" content=\"Due economisti hanno messo in dubbio l&#039;obiettivo della BCE di &quot;non danneggiare le banche e proteggere il loro modello di business&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-11T10:45:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T10:51:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Due economisti hanno messo in dubbio l&#039;obiettivo della BCE di &quot;non danneggiare le banche e proteggere il loro modello di business&quot;.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'euro digitale \u00e8 morto in partenza per salvare le banche!","description":"Due economisti hanno messo in dubbio l'obiettivo della BCE di \"non danneggiare le banche e proteggere il loro modello di business\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/","og_locale":"it_IT","og_type":"article","og_title":"L'euro digitale \u00e8 morto in partenza per salvare le banche!","og_description":"Due economisti hanno messo in dubbio l'obiettivo della BCE di \"non danneggiare le banche e proteggere il loro modello di business\".","og_url":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/","og_site_name":"Cryptonews Italia","article_published_time":"2023-08-11T10:45:37+00:00","article_modified_time":"2023-08-11T10:51:11+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"Due economisti hanno messo in dubbio l'obiettivo della BCE di \"non danneggiare le banche e proteggere il loro modello di business\".","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/"},"author":{"name":"christianboscoloczvh","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/674a071a36e0e74b5de8cab751183e36"},"headline":"L&#8217;euro digitale \u00e8 morto in partenza per salvare le banche!","datePublished":"2023-08-11T10:45:37+00:00","dateModified":"2023-08-11T10:51:11+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/"},"wordCount":413,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg","keywords":["banche"],"articleSection":["Blockchain News","News"],"inLanguage":"it-IT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/","url":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/","name":"L'euro digitale \u00e8 morto in partenza per salvare le banche!","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg","datePublished":"2023-08-11T10:45:37+00:00","dateModified":"2023-08-11T10:51:11+00:00","description":"Due economisti hanno messo in dubbio l'obiettivo della BCE di \"non danneggiare le banche e proteggere il loro modello di business\".","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/08\/euro-digitale.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/leuro-digitale-e-morto-in-partenza-per-salvare-le-banche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;euro digitale \u00e8 morto in partenza per salvare le banche!"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/134488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=134488"}],"version-history":[{"count":10,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/134488\/revisions"}],"predecessor-version":[{"id":134500,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/134488\/revisions\/134500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/134489"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=134488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=134488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=134488"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=134488"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=134488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}