{"id":132345,"date":"2023-07-25T12:16:48","date_gmt":"2023-07-25T12:16:48","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=132345"},"modified":"2023-07-25T12:16:51","modified_gmt":"2023-07-25T12:16:51","slug":"previsioni-bitcoin-binance-e-fed-agitano-il-mercato","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/","title":{"rendered":"Bitcoin sotto pressione, Binance e Fed agitano il mercato"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-132389 aligncenter\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg\" alt=\"Bitcoin\" width=\"1200\" height=\"700\" srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg 1200w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1-300x175.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1-640x373.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1-768x448.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/p><p>Durante la giornata di oggi la crypto di<strong><a href=\"https:\/\/cryptonews.com\/it\/news\/svelato-il-mistero-di-satoshi-nakamoto-indagine-suggerisce-un-gruppo\/\" target=\"_blank\" rel=\"noopener\"> Satoshi Nakamoto<\/a><\/strong> ha subito un calo del 3% ed &egrave; stata scambiata a<strong> 29.171 dollari<\/strong>.<\/p><p>Questo ribasso potrebbe essere stato influenzato dall&#8217;incapacit&agrave; di mantenere livelli di prezzo pi&ugrave; elevati, spingendo alcuni investitori a optare per posizioni allo scoperto, mentre altri decidono di garantirsi i profitti delle posizioni rialziste a breve termine.<\/p><p>Al momento due fattori stanno giocando un ruolo chiave nella performance di BTC, ovvero la causa in corso sull&#8217;<strong><a href=\"https:\/\/cryptonews.com\/it\/news\/migliori-exchange-crypto\/\" target=\"_blank\" rel=\"noopener\">exchange crypto<\/a><\/strong> Binance e le preoccupazioni per un potenziale rialzo dei tassi da parte della Fed.<\/p><p>Data l&#8217;attuale incertezza nel mercato crypto, gli investitori sono sulle spine e stanno monitorando attentamente le dinamiche di mercato prima di <strong><a href=\"https:\/\/cryptonews.com\/it\/guides\/investire-in-criptovalute\/\" target=\"_blank\" rel=\"noopener\">investire in crypto<\/a><\/strong>.\n<\/p><h2>La causa di Binance pesa su BTC<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nIl calo del valore di Bitcoin ha coinciso con la pubblicazione di un rapporto del Wall Street Journal che ha suscitato preoccupazioni tra gli investitori riguardo a <strong>Binance<\/strong>.<\/p><p>Il rapporto ha evidenziato le dichiarazioni rilasciate dal CEO di Binance Changpeng Zhao, conosciuto anche come &#8220;<strong>CZ<\/strong>&#8220;, nel 2019, che hanno suscitato diversi dubbi riguardo a <strong>potenziali attivit&agrave; di &#8220;wash trading&#8221;<\/strong> da parte di affiliati di Binance durante il lancio del suo braccio commerciale statunitense, portando a sospetti di <strong>volumi di trading gonfiati<\/strong>.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Binance US Accused of Wash Trading, Denies Allegations Amid SEC Scrutiny &#8211; <a href=\"https:\/\/t.co\/4PlVxt8pq1\">https:\/\/t.co\/4PlVxt8pq1<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/crypto?src=hash&amp;ref_src=twsrc%5Etfw\">#crypto<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/cryptonews?src=hash&amp;ref_src=twsrc%5Etfw\">#cryptonews<\/a><\/p>\n<p>&mdash; CryptoJobs.co (@CryptoJobs_co) <a href=\"https:\/\/twitter.com\/CryptoJobs_co\/status\/1683694528601944066?ref_src=twsrc%5Etfw\">July 25, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>&nbsp;<\/p><p>Binance &egrave; gi&agrave; alle prese con complesse questioni legali, avendo ricevuto una&nbsp;<strong><a href=\"https:\/\/cryptonews.com\/it\/news\/la-sec-cita-in-giudizio-binance-e-il-mercato-crolla-che-cosa-succede\/\" target=\"_blank\" rel=\"noopener\">citazione in giudizio<\/a><\/strong> da parte della Securities and Exchange Commission (<strong>SEC<\/strong>) il mese scorso.<\/p><p>Al momento l&#8217;exchange crypto &egrave; soggetto a un&#8217;indagine da parte del Dipartimento di Giustizia, il cui esito potrebbe portare a un decreto di consenso o a un accordo.<\/p><p>L&#8217;indagine si focalizza su possibili violazioni relative <strong>all&#8217;antiriciclaggio<\/strong> e<strong> all&#8217;evasione delle sanzioni<\/strong>, aspetti che potrebbero avere implicazioni significative sulle operazioni future di Binance.\n<\/p><h2>Bitcoin attende la Fed<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nGli investitori hanno il fiato sospeso in attesa del verdetto della <strong><a href=\"https:\/\/cryptonews.com\/it\/news\/bitcoin-e-altcoin-iniziano-al-ribasso-la-settimana-critica-della-fed\/\" target=\"_blank\" rel=\"noopener\">riunione della Federal Reserve<\/a><\/strong>, cercando di scorgere indizi riguardo possibili rialzi dei tassi di interesse.<\/p><p>Solitamente gli incrementi dei tassi hanno influito negativamente sul valore di bitcoin, e di conseguenza, gli operatori di mercato rimangono cauti riguardo alle decisioni future della Fed, soprattutto considerando i timori di una possibile recessione in corso.<\/p><p>Al termine della riunione della Federal Reserve, si prevede che il valore di Bitcoin possa continuare a subire fluttuazioni all&#8217;interno di un range ristretto.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">UPDATE:\ud83c\uddfa\ud83c\uddf8Market predicting 99.8% chance of U.S FED rate hike at the next <a href=\"https:\/\/twitter.com\/hashtag\/FOMC?src=hash&amp;ref_src=twsrc%5Etfw\">#FOMC<\/a> meeting Wednesday 26th July. <a href=\"https:\/\/twitter.com\/hashtag\/crypto?src=hash&amp;ref_src=twsrc%5Etfw\">#crypto<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/bitcoin?src=hash&amp;ref_src=twsrc%5Etfw\">#bitcoin<\/a> <a href=\"https:\/\/t.co\/sLYYJjtYoR\">pic.twitter.com\/sLYYJjtYoR<\/a><\/p>\n<p>&mdash; Crypto Macro (@cryptomacro14) <a href=\"https:\/\/twitter.com\/cryptomacro14\/status\/1682336537009344513?ref_src=twsrc%5Etfw\">July 21, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>&nbsp;<\/p><p>Inoltre il mercato prevede un <strong>rialzo dei tassi di 25 punti base<\/strong> da parte della Fed questa settimana e sta monitorando attentamente i segnali sulle possibili mosse.<\/p><p>Fino a quando non ci saranno dati e fiducia sufficienti riguardo all&#8217;andamento dell&#8217;inflazione, le decisioni del FOMC sui tassi di interesse rimarranno probabilmente incerte. Questa incertezza potrebbe influenzare la spinta di Bitcoin nel superare il livello di 31.500 dollari.<\/p><p>&nbsp;\n<\/p><h2>L&#8217;Halving di Bitcoin si avvicina!<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nNella giornata di ieri la rete Bitcoin ha raggiunto un traguardo cruciale, arrivando al blocco 800.000 e segnando cos&igrave; una svolta significativa nella storia della crypto di maggior valore.<\/p><p>Secondo quanto riportato dal media Bitcoinblockhalf.com, questo evento segna <strong>l&#8217;avvicinarsi del prossimo Halving di Bitcoin<\/strong>, previsto al blocco 840.000, che comporter&agrave; una <a href=\"https:\/\/cryptonews.com\/it\/news\/il-prossimo-halving-di-bitcoin-mettera-alla-prova-i-miner\/\" target=\"_blank\" rel=\"noopener\"><strong>riduzione del 50% dei guadagni per i miner<\/strong><\/a>. Questo avverr&agrave; tra meno di nove mesi, corrispondenti a circa 40.000 blocchi.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/Bitcoin?src=hash&amp;ref_src=twsrc%5Etfw\">#Bitcoin<\/a> block 800,000 has been mined! \ud83c\udf89<\/p>\n<p>40,000 blocks (~278 days) until the halving <a href=\"https:\/\/t.co\/ZU5EmL64EQ\">pic.twitter.com\/ZU5EmL64EQ<\/a><\/p>\n<p>&mdash; Mandrik (@Mandrik) <a href=\"https:\/\/twitter.com\/Mandrik\/status\/1683315667951407106?ref_src=twsrc%5Etfw\">July 24, 2023<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>&nbsp;<\/p><p><strong>Storicamente gli Halving di Bitcoin hanno provocato un aumento del valore della crypto<\/strong>. Il mercato crypto, per&ograve;, &egrave; soggetto a numerosi fattori che potrebbero influenzarne la traiettoria.<\/p><p>Quindi l&#8217;effetto dell&#8217;Halving su Bitcoin rimane incerto e pu&ograve; essere influenzato da diversi elementi del mercato.\n<\/p><h2>Previsioni del valore di Bitcoin<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nBitcoin ha subito un forte calo e <strong>si &egrave; avvicinato al livello di 28.850 dollari<\/strong>.&nbsp;Tuttavia, la chiusura di una candela doji appena sopra questa soglia critica suggerisce la possibilit&agrave; di un indebolimento della tendenza ribassista.<\/p><p>Inoltre, la presenza di una candela doji e una candela spinning top intorno al livello di 28.800 dollari, suggeriscono una possibile inversione rialzista.<\/p><p>In aggiunta, l&#8217;indice di forza relativa (RSI) e gli indicatori di divergenza della media mobile convergente (MACD) sono entrambi nella zona di ipervenduto, e ci&ograve; aumenta la probabilit&agrave; di un&#8217;inversione al rialzo.<\/p><p><em><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-132383 aligncenter lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"Bitcoin\" width=\"1177\" height=\"859\" sizes=\"auto, (max-width: 1177px) 100vw, 1177px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1177_859.jpg\" data-srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1177_859.jpg 1177w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1177_859-300x219.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1177_859-640x467.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1177_859-768x561.jpg 768w\">Grafico del valore di Bitcoin &#8211; Fonte: Tradingview<\/em><\/p><p>Bisogna quindi monitorare il livello di 28.850 dollari, poich&eacute; una rottura al di sopra di questa soglia potrebbe spingere Bitcoin verso una <strong>resistenza immediata situata a 29.500 dollari<\/strong>.<\/p><p>Questo livello di resistenza coincide con la media mobile esponenziale a 50 giorni ed &egrave; stato precedentemente un significativo livello di supporto.<\/p><p>Quindi ci si aspetta che agisca come una resistenza. Se Bitcoin dovesse superare con successo il livello di 29.500 dollari, il prossimo obiettivo potrebbe essere intorno ai livelli di 29.900 o 30.300 dollari.<\/p><p>I trader dovrebbero tenere d&#8217;occhio i movimenti di prezzo per valutare le potenziali opportunit&agrave; di un breakout al rialzo o la possibilit&agrave; di ulteriore pressione ribassista sul valore di Bitcoin.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/ext\/etoro-crypto\/\" target=\"_blank\" rel=\"nofollow noindex noopener\"> Investi in BTC<\/a><\/div><p><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><p>&nbsp;\n<\/p><h2>Crypto da tenere d&rsquo;occhio nel 2023<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nSe vuoi investire in un progetto crypto in fase iniziale valuta le migliori prevendite. Il team di Cryptonews ha curato un elenco completo delle crypto pi&ugrave; promettenti del 2023, fornendo informazioni preziose su questi progetti.<\/p><p>L&rsquo;elenco viene aggiornato regolarmente, con <strong>nuove altcoin e progetti ICO<\/strong>, quindi ti consigliamo di tenerlo d&rsquo;occhio.\n<\/p><div style=\"background: #920047;margin: auto;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em;font-size: 16px\"><a style=\"text-decoration: none;color: white\" href=\"https:\/\/cryptonews.com\/it\/news\/criptovalute-che-esploderanno\/\" rel=\"nofollow noindex\"> Scopri le crypto che esploderanno<\/a><\/div><p><em>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/em><\/p><p>&nbsp;\n<\/p><h3>Trova il prezzo migliore per acquistare\/vendere criptovalute<\/h3><p>\n&nbsp;<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-132384 aligncenter lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"Bitcoin\" width=\"1289\" height=\"509\" sizes=\"auto, (max-width: 1289px) 100vw, 1289px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1289_509.jpg\" data-srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1289_509.jpg 1289w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1289_509-300x118.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1289_509-640x253.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/07\/image___media_library_original_1289_509-768x303.jpg 768w\"><\/p><p><em>Tracker dei prezzi crypto. Fonte: <strong><a href=\"https:\/\/cryptonews.com\/it\/price-tracker\/\">Cryptonews<\/a><\/strong><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Bitcoin ha perso il 3% ed \u00e8 stato scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e alle preoccupazioni per i tassi della Fed. <\/p>\n","protected":false},"author":20,"featured_media":132389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[59,45,1049,233,536],"editors":[2171],"sponsored_companies":[],"class_list":["post-132345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","category-news","tag-binance","tag-bitcoin","tag-btc","tag-fed","tag-mercato","editors-gaia-rossi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Previsioni Bitcoin: Binance e Fed agitano il mercato<\/title>\n<meta name=\"description\" content=\"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Previsioni Bitcoin: Binance e Fed agitano il mercato\" \/>\n<meta property=\"og:description\" content=\"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T12:16:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T12:16:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Previsioni Bitcoin: Binance e Fed agitano il mercato\" \/>\n<meta name=\"twitter:description\" content=\"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Previsioni Bitcoin: Binance e Fed agitano il mercato","description":"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/","og_locale":"it_IT","og_type":"article","og_title":"Previsioni Bitcoin: Binance e Fed agitano il mercato","og_description":"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.","og_url":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/","og_site_name":"Cryptonews Italia","article_published_time":"2023-07-25T12:16:48+00:00","article_modified_time":"2023-07-25T12:16:51+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Previsioni Bitcoin: Binance e Fed agitano il mercato","twitter_description":"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"Bitcoin sotto pressione, Binance e Fed agitano il mercato","datePublished":"2023-07-25T12:16:48+00:00","dateModified":"2023-07-25T12:16:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/"},"wordCount":1047,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg","keywords":["Binance","bitcoin","BTC","fed","Mercato"],"articleSection":["Bitcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/","url":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/","name":"Previsioni Bitcoin: Binance e Fed agitano il mercato","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg","datePublished":"2023-07-25T12:16:48+00:00","dateModified":"2023-07-25T12:16:51+00:00","description":"Bitcoin ha perso il 3% ed \u00e8 scambiato a $29.171. Il ribasso potrebbe essere dovuto alla causa su Binance e ai nuovi tassi Fed.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/07\/Copertina-per-Bitcoin-16-1.jpg","width":1200,"height":700,"caption":"Bitcoin"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/previsioni-bitcoin-binance-e-fed-agitano-il-mercato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Bitcoin sotto pressione, Binance e Fed agitano il mercato"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/132345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=132345"}],"version-history":[{"count":15,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/132345\/revisions"}],"predecessor-version":[{"id":132396,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/132345\/revisions\/132396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/132389"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=132345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=132345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=132345"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=132345"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=132345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}