{"id":117015,"date":"2023-04-19T22:00:11","date_gmt":"2023-04-19T22:00:11","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=117015"},"modified":"2023-04-19T15:58:43","modified_gmt":"2023-04-19T15:58:43","slug":"la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/","title":{"rendered":"La Banca centrale russa valuta l&#8217;utilizzo delle crypto per i pagamenti internazionali"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-117064 aligncenter\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg\" alt=\"Russia\" width=\"1200\" height=\"720\" srcset=\"https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg 1200w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1-300x180.jpg 300w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1-640x384.jpg 640w, https:\/\/cryptonews.com\/it\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1-768x461.jpg 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/p><p>Stando a quanto riferito dai media locali la <strong>banca centrale russa<\/strong> sembra che sia pronta a prendere in considerazione l&#8217;utilizzo delle crypto per i pagamenti all&#8217;estero. Si tratta di un grande passo nel tentativo del Paese di regolamentare il mercato crypto.<\/p><p>Il capo della banca ha recentemente parlato dei piani durante un evento con i rappresentanti del partito Nuovo Popolo. La banca centrale, nonostante sia contraria all&#8217;uso delle crypto, rimane aperta riguardo ai <strong>pagamenti internazionali.<\/strong><\/p><p>Il capo della banca centrale ha dichiarato:\n<\/p><blockquote><p>&#8221; Siamo fedeli alla stessa posizione secondo cui all&#8217;interno del Paese le criptovalute&#8230; non dovrebbero essere utilizzate, mentre per i pagamenti esterni presumiamo che ci&ograve; sia possibile sotto forma di esperimento, anche questo disegno di legge &egrave; in fase di elaborazione sotto forma di regime sperimentale.&#8221;<\/p><\/blockquote><h2>La Russia apre le porte agli exchange crypto<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nInoltre sembra che la Russia autorizzer&agrave; gli <strong>exchange crypto<\/strong> a partire dal secondo trimestre del 2023, con una legislazione corrispondente che sar&agrave; adottata a breve.<\/p><p>I funzionari non hanno escluso la borsa di San Pietroburgo in questo processo e sembra che l&#8217;obiettivo generale sia quello di definire le regole relative alle operazioni degli exchange crypto.\n<\/p><h2>Adozione crypto in aumento<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nL&#8217;adozione crypto sembra essere in aumento in <strong>Russia<\/strong>, anche se negli ultimi anni ha cercato di frenare il mercato. Le autorit&agrave; hanno monitorato l&#8217;uso e la crescita degli asset crypto e riferiscono direttamente a Putin.<\/p><p>&Egrave; stato anche riferito che la Russia utilizza gli asset crypto per <strong>aggirare le sanzion<\/strong>i che le sono state imposte. Inoltre il Paese ha approvato una legge sulla blockchain nella prima fase parlamentare. Tale legge prevede che i miner debbano dichiarare&nbsp; i loro guadagni, altrimenti rischiano il carcere.<\/p><p>&nbsp;<\/p><p><strong>Leggi anche:<\/strong>\n<\/p><ul>\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/l\/\">La Russia sfrutta gli exchange crypto per le transazioni in stablecoin verso UK. Ecco come!<\/a><\/li>\n<li><a href=\"https:\/\/cryptonews.com\/it\/news\/aumentano-i-falsi-exchange-di-criptovalute-in-russia-i-truffatori-prendono-di-mira-i-russi\/\">Aumentano i falsi exchange di criptovalute in Russia: i truffatori prendono di mira i russi?<\/a><\/li>\n<\/ul><p>\n&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La banca centrale russa sta considerando l&#8217;utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.<\/p>\n","protected":false},"author":20,"featured_media":117064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,1],"tags":[757,46,206],"editors":[3235],"sponsored_companies":[],"class_list":["post-117015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blockchain-news","category-news","tag-crypto","tag-pagamenti","tag-russia","editors-massimo-de-vincenti2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Russia valuta le crypto per i pagamenti internazionali<\/title>\n<meta name=\"description\" content=\"La banca centrale russa sta considerando l&#039;utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Russia valuta le crypto per i pagamenti internazionali\" \/>\n<meta property=\"og:description\" content=\"La banca centrale russa sta considerando l&#039;utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-19T22:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La Russia valuta le crypto per i pagamenti internazionali\" \/>\n<meta name=\"twitter:description\" content=\"La banca centrale russa sta considerando l&#039;utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Russia valuta le crypto per i pagamenti internazionali","description":"La banca centrale russa sta considerando l'utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/","og_locale":"it_IT","og_type":"article","og_title":"La Russia valuta le crypto per i pagamenti internazionali","og_description":"La banca centrale russa sta considerando l'utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.","og_url":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/","og_site_name":"Cryptonews Italia","article_published_time":"2023-04-19T22:00:11+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"La Russia valuta le crypto per i pagamenti internazionali","twitter_description":"La banca centrale russa sta considerando l'utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/"},"author":{"name":"gaiatommasiucwz","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/57844a77e1df1510b6011133fc006537"},"headline":"La Banca centrale russa valuta l&#8217;utilizzo delle crypto per i pagamenti internazionali","datePublished":"2023-04-19T22:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/"},"wordCount":335,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg","keywords":["CRYPTO","pagamenti","russia"],"articleSection":["Blockchain News","News"],"inLanguage":"it-IT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/","url":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/","name":"La Russia valuta le crypto per i pagamenti internazionali","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg","datePublished":"2023-04-19T22:00:11+00:00","description":"La banca centrale russa sta considerando l'utilizzo delle crypto per i pagamenti internazionali, un passo importante verso la regolamentazione del mercato crypto.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/04\/CN-COVER-1200x720-18-1.jpg","width":1200,"height":720,"caption":"Russia"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/la-banca-centrale-russa-valuta-lutilizzo-delle-crypto-per-i-pagamenti-internazionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Banca centrale russa valuta l&#8217;utilizzo delle crypto per i pagamenti internazionali"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/117015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=117015"}],"version-history":[{"count":7,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/117015\/revisions"}],"predecessor-version":[{"id":117069,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/117015\/revisions\/117069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media\/117064"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=117015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=117015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=117015"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=117015"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=117015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}