{"id":102681,"date":"2023-01-26T16:32:00","date_gmt":"2023-01-26T16:32:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=102681"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/","title":{"rendered":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg\" alt=\"Fonte: TradingView\" srcset=\"https:\/\/cimg.co\/news\/102637\/253155\/responsive-images\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_3706_2292.jpg 3706w, https:\/\/cimg.co\/news\/102637\/253155\/responsive-images\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_1200_742.jpg 1200w, https:\/\/cimg.co\/news\/102637\/253155\/responsive-images\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_900_557.jpg 900w, https:\/\/cimg.co\/news\/102637\/253155\/responsive-images\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_720_445.jpg 720w, https:\/\/cimg.co\/news\/102637\/253155\/responsive-images\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_600_371.jpg 600w, https:\/\/cimg.co\/news\/102637\/253155\/responsive-images\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_300_186.jpg 300w\" sizes=\"100vw\" width=\"3706\" class=\"content-img\"><figcaption><i>Fonte: TradingView<\/i><\/figcaption><\/figure><p class=\"wp-block-paragraph\">Il prezzo di XRP &egrave; salito dell&#8217;1% nelle ultime 24 ore e raggiunge quota 0,412239$ mentre il mercato delle criptovalute ha registrato un guadagno di quasi il 2% nello stesso arco di tempo. Al prezzo attuale si registra un guadagno dell&#8217;8% in una settimana e del 12% negli ultimi 30 giorni. Finalmente l&#8217;altcoin si libera dalla tendenza al ribasso di lungo termine che ne caratterizzava l&#8217;andamento da fine di ottobre.<\/p><p>Chi possiede XRP sta ancora aspettando la fine del caso Ripple-SEC che dovrebbe avvenire nei prossimi mesi. L&#8217;andamento dell&#8217;altcoin nell&#8217;ultima settimana potrebbe segnare l&#8217;inizio di un nuovo periodo di crescita sostenuta.<\/p><h2>Previsione valore XRP: Rotto il modello di trading di lungo termine &egrave; il momento di puntare a 1$?<\/h2><span class=\"replacer\"><\/span><p>Il grafico di XRP mostra che l&#8217;indice di forza relativa (viola) &egrave; salito vicino a 70 negli ultimi giorni, con un&#8217;inversione di tendenza rispetto all&#8217;andamento negli ultimi due mesi del 2022 e all&#8217;inizio di gennaio. Altro segnale incoraggiante, la media mobile a 30 giorni (rosso) sta per superare quella a 200 giorni (blu), formando il cosiddetto &#8220;golden cross&#8221; che di solito &egrave; segno di un sostanziale breakout.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"Andamento XRP - Fonte: TradingView\" sizes=\"100vw\" width=\"3772\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/102637\/253145\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/102637\/253145\/responsive-images\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_3772_2236.jpg 3772w, https:\/\/cimg.co\/news\/102637\/253145\/responsive-images\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_1200_711.jpg 1200w, https:\/\/cimg.co\/news\/102637\/253145\/responsive-images\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_900_534.jpg 900w, https:\/\/cimg.co\/news\/102637\/253145\/responsive-images\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_720_427.jpg 720w, https:\/\/cimg.co\/news\/102637\/253145\/responsive-images\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_600_356.jpg 600w, https:\/\/cimg.co\/news\/102637\/253145\/responsive-images\/chart-xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming___media_library_original_300_178.jpg 300w\"><figcaption><i>Andamento XRP &#8211; Fonte: TradingView<\/i><\/figcaption><\/figure><p>Insomma, XRP mostra tutti i segnali di una prossima ripresa in grande stile che promette di smarcarsi dalle tristi performance di fine anno. Oltre a beneficiare di un generale miglioramento delle condizioni di mercato, la ripresa si deve anche all&#8217;avvicinarsi della fase conclusiva del caso che vede contrapposte Ripple e SEC.<\/p><p>Il <a href=\"https:\/\/www.cnbc.com\/2023\/01\/18\/ripple-ceo-optimistic-crypto-firm-will-get-sec-xrp-lawsuit-ruling-soon.html\"><strong>CEO Brad Garlinghouse in un&#8217;intervista alla CNBC<\/strong><\/a> la scorsa settimana si &egrave; detto ottimista e che la controversia dovrebbe concludersi entro met&agrave; anno o al massimo entro la fine dell&#8217;anno.<\/p><p>Si &egrave; detto fiducioso riguardo la prospettiva di una soluzione favorevole nei confronti di Ripple cos&igrave; come lo &egrave; il legale statunitense James K. Filan che ha condiviso la sua posizione con un tweet il 20 gennaio.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/FilanLaw\/status\/1616263942892064769\"><\/oembed><\/figure><p>In pratica, tutto quello che si poteva aggiungere per supportare la tesi di XRP &egrave; stato detto, ora il Giudice Torres ha tutti gli elementi per esprimersi. Insomma, l&#8217;atmosfera intorno a Ripple &egrave; di piena fiducia e sembra arrivato il momento di lasciarsi alle spalle le cattive performance che hanno caratterizzato il 2022.<\/p><p>La community crypto sembra coesa nel credere che le argomentazioni che Ripple ha presentato in propria difesa siano pi&ugrave; solide delle accuse formalizzate dalla SEC.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/Belisarius2020\/status\/1616457897428545536\"><\/oembed><\/figure><h2>Ripple al centro di una nuova truffa<\/h2><span class=\"replacer\"><\/span><p>Insomma, le cose sembrano mettersi cos&igrave; bene per XRP che qualcuno ha pensato di sfruttarne la crescente popolarit&agrave; per organizzare una nuova truffa che prende di mira i meno esperti.<\/p><p>Infatti i truffatori sono riusciti a creare una copia molto verosimile del sito di Ripple proponendo un improbabile piano di staking della moneta con ritorni alquanto sospetti.&nbsp;<\/p><p>Di fatto il sistema di convalida delle transazioni su Ripple non &egrave; di tipo Proof of Stake, quindi i truffatori che promettevano profitti fino al 26% sfruttavano la credulit&agrave; dei trader meno esperti.&nbsp;<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"948\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/102681\/253239\/staking-xrp.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/102681\/253239\/responsive-images\/staking-xrp___media_library_original_948_496.jpg 948w, https:\/\/cimg.co\/news\/102681\/253239\/responsive-images\/staking-xrp___media_library_original_900_471.jpg 900w, https:\/\/cimg.co\/news\/102681\/253239\/responsive-images\/staking-xrp___media_library_original_720_377.jpg 720w, https:\/\/cimg.co\/news\/102681\/253239\/responsive-images\/staking-xrp___media_library_original_600_314.jpg 600w, https:\/\/cimg.co\/news\/102681\/253239\/responsive-images\/staking-xrp___media_library_original_300_157.jpg 300w\"><\/figure><p>Viste le premesse, gli investitori pi&ugrave; prudenti sono propensi a orientare le previsioni all&#8217;interno della finestra di 1,30$, altri si aspettano performance pi&ugrave; entusiasmanti a 10$ nel lungo termine.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/RippleLordz\/status\/1617442162358251520\"><\/oembed><\/figure><p>Dato che XRP si trova al momento a circa 0,41$, pare ragionevole credere che dopo la risoluzione della controversia con la SEC si possa raggiungere l&#8217;obiettivo di 1$ o poco pi&ugrave;. Questo dipender&agrave; direttamente da come si comporteranno il mercato crypto e l&#8217;economia globale, ma pare ragionevole credere che XRP riuscir&agrave; a raggiungere la cifra intera.<\/p><p><a href=\"https:\/\/cryptonews.com\/ext\/etoro-crypto\/\" rel=\" sponsored nofollow\"><strong>Investi in XRP<\/strong><\/a><\/p><p><i>Le criptovalute sono altamente volatili e non regolamentate. Nessuna tutela del consumatore. Potrebbe essere applicata una tassa sugli utili.<\/i><\/p><h2><strong>Alternative a XRP<\/strong><\/h2><span class=\"replacer\"><\/span><p>Se sei alla ricerca di progetti crypto con alto potenziale, allora potrai apprezzare<a href=\"https:\/\/cryptonews.com\/it\/news\/criptovalute-che-esploderanno\/\"> la selezione delle migliori 15 crypto nel 2023<\/a>, recensite dal nostro team di <i>CryptoNews<\/i> Industry Talk.<br><br>L&#8217;elenco &egrave; aggiornato ogni settimana con nuove ICO e progetti crypto.<\/p><div class=\"raw-html-embed\"><div style=\"background: #920047;margin-bottom: 20px;width: 50%;text-align: center;padding: 8px;border-radius: 5px;background-image: linear-gradient(107deg,#930046,#59008a);color: white;padding-left: 1em;padding-right: 1em; font-size: 16px;\"><a style=\"text-decoration:none;color:white\" href=\"https:\/\/cryptonews.com\/it\/news\/criptovalute-che-esploderanno\/\" target=\"_blank\" rel=\"nofollow noindex\">Scopri 15 nuove crypto<\/a><\/div><\/div><p><i><sup>Disclaimer: La sezione Industry Talk presenta approfondimenti di operatori del settore crittografico e non fa parte dei contenuti editoriali di Cryptonews.com.<\/sup><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Fonte: TradingViewIl prezzo di XRP &egrave; salito dell&#8217;1% nelle ultime 24 ore e raggiunge quota 0,412239$ mentre il mercato delle criptovalute ha registrato un guadagno di quasi il 2% nello stesso arco di tempo. Al prezzo attuale si registra un guadagno dell&#8217;8% in una settimana e del 12% negli ultimi 30 giorni. Finalmente l&#8217;altcoin si [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[581,184,58,244],"editors":[2210],"sponsored_companies":[],"class_list":["post-102681","post","type-post","status-publish","format-standard","hentry","category-altcoin-news","category-news","tag-previsioni","tag-ripple","tag-sec","tag-xrp","editors-marcello-bonti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?<\/title>\n<meta name=\"description\" content=\"Il prezzo di XRP \u00e8 salito dell&#039;1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?\" \/>\n<meta property=\"og:description\" content=\"Il prezzo di XRP \u00e8 salito dell&#039;1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T16:32:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?\" \/>\n<meta name=\"twitter:description\" content=\"Il prezzo di XRP \u00e8 salito dell&#039;1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/102681\/253240\/cn-cover-8.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?","description":"Il prezzo di XRP \u00e8 salito dell'1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/","og_locale":"it_IT","og_type":"article","og_title":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?","og_description":"Il prezzo di XRP \u00e8 salito dell'1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.","og_url":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/","og_site_name":"Cryptonews Italia","article_published_time":"2023-01-26T16:32:00+00:00","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?","twitter_description":"Il prezzo di XRP \u00e8 salito dell'1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.","twitter_image":"https:\/\/cimg.co\/news\/102681\/253240\/cn-cover-8.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/"},"author":{"name":"lauradimariatnf","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/person\/f301a2fe5b1b74682fd70e7a2502d752"},"headline":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?","datePublished":"2023-01-26T16:32:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/"},"wordCount":691,"publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg","keywords":["Previsioni","ripple","sec","xrp"],"articleSection":["Altcoin News","News"],"inLanguage":"it-IT","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/","url":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/","name":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg","datePublished":"2023-01-26T16:32:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Il prezzo di XRP \u00e8 salito dell'1% nelle ultime 24 ore, e raggiunge 0,412239$, mentre il mercato crypto guadagna quasi il 2% nello stesso arco di tempo.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#primaryimage","url":"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg","contentUrl":"https:\/\/cimg.co\/news\/102637\/253155\/xrp-price-prediction-as-xrp-breaks-out-of-long-term-trading-pattern-1-incoming.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/previsione-valore-xrp-rotto-il-modello-di-trading-di-lungo-termine-e-il-momento-di-puntare-a-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Previsione valore XRP: Rotto il modello di trading di lungo termine \u00e8 il momento di puntare a 1$?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/102681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=102681"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts\/102681\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=102681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=102681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=102681"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=102681"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/sponsored_companies?post=102681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}