{"id":44789,"date":"2021-01-01T01:01:00","date_gmt":"2021-01-01T01:01:00","guid":{"rendered":"https:\/\/cryptonews.com\/it\/?p=44789"},"modified":"2023-02-08T10:44:24","modified_gmt":"2023-02-08T10:44:24","slug":"monero","status":"publish","type":"coins","link":"https:\/\/cryptonews.com\/it\/coins\/monero\/","title":{"rendered":"Monero (XMR)"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Monero<\/strong> &egrave; una criptovaluta decentralizzata e orientata alla privacy dedicata alla protezione dell&#8217;anonimato dei suoi utenti offuscando le informazioni su mittenti, destinatari e gli importi presenti nelle transazioni.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/coin\/44789\/21287\/monero-xmr.png\" alt=\"monero xmr\"><\/figure><p>&nbsp;<\/p><h2>Cos&#8217;&egrave; Monero?<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>La <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/web.getmonero.org\/it\/index.html\">piattaforma Monero<\/a> e il suo token <strong>XMR<\/strong> sono stati progettati pensando a una missione: consentire a ciascun utente di controllare il livello di visibilit&agrave; dei loro dati personali online. &Egrave; nata nel 2012 con il lancio di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/coins\/bytecoin-bcn\/\">Bytecoin<\/a>, una criptovaluta incentrata sull&#8217;anonimato da cui Monero &egrave; stato lanciato come fork nel luglio 2014. L&#8217;idea per il progetto &egrave; nata dalla percezione che la reputazione del Bytecoin ha avuto un colpo dopo che il pubblico ha appreso che la maggior parte delle sue monete apparentemente estraibili erano gi&agrave; esistenti. Nonostante il fatto che la rete madre Bytecoin sia stata costruita da zero utilizzando <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonote.org\/\">CryptoNote<\/a>, un potente protocollo di livello applicativo open source orientato alla privacy, i futuri designer di Monero hanno continuato per la propria strada.<\/p><p>Due di questi, David Latapie e Riccardo Spagni, hanno chiamato il loro cripto-pet in onore del termine &#8220;moneta&#8221; in Esperanto. Il team Monero ha mantenuto il protocollo Cryptonote da Bytecoin, abbinandolo a ring signature, ring transaction riservate (RCT) e tecnologie di indirizzo invisibile. L&#8217;obiettivo era quello di creare la prima criptovaluta completamente non rintracciabile e sicura, che avanza la protezione della privacy come principale punto di vendita.<\/p><p>&nbsp;<\/p><h2>Cosa cerca di realizzare?<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>La missione di Monero non si limita a fare meglio di altre <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/exclusives\/top-5-privacy-coins-features-and-differences-2725\/\">monete orientate alla privacy<\/a>; i suoi obiettivi sono estesi alla correzione di ci&ograve; che i suoi sviluppatori vedono come i punti deboli delle criptovalute tradizionali, come Bitcoin:<\/p><ul><li><u>Monero considera la privacy e l&#8217;anonimato come aree chiave da prevedere se le criptovalute devono diventare autentici contanti elettronici<\/u>. Agli occhi degli sviluppatori Monero, la tracciabilit&agrave; delle transazioni rimane un peccato originale della maggior parte dei cryptos, in quanto ci&ograve; non consente loro di allontanarsi dagli standard del tradizionale sistema bancario basato su fiat. Queste transazioni possono essere facilmente rintracciate nei loro punti di origine e destinatari poich&eacute; la maggior parte di quelle che avvengono tra gli utenti della rete rimangono pubbliche. Monero si allontana da questo modello facendo s&igrave; che tutte le transazioni in entrata possano provenire da quante pi&ugrave; fonti possibili con uguale probabilit&agrave;. Comprendendo che i pagamenti peer-to-peer non dovrebbero n&eacute; coinvolgere n&eacute; interessare terze parti, Monero fa un ulteriore sforzo per proteggere il rapporto tra i suoi utenti e le cose con cui acquistano o negoziano, che &egrave; il fondamento ideale del loro contante elettronico.<\/li><li><u>La protezione della privacy non &egrave; limitata alle transazioni delle parti, in quanto riguarda ugualmente la natura di una transazione stessa<\/u>. Sulla base di questo obiettivo, i registri nascosti e pubblici di Monero offrono supporto per le transazioni private non solo per quanto riguarda il mittente, ma anche per le destinazioni della transazione. Lo stesso vale per offuscare le informazioni sugli importi delle transazioni. Si suppone che Monero corregga la &#8220;pseudonimia&#8221; di Bitcoin che viene spesso scambiata per vero anonimato. Promette anche la fungibilit&agrave;, il che significa che le sue monete sono intercambiabili e resistenti all&#8217;essere contaminate da coinvolgimenti in pirateria informatica o furto. Il team di Monero ha sviluppato Kovri come un livello anonimo decentralizzato costruito attorno a <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/it.wikipedia.org\/wiki\/I2P\">l&#8217;architettura I2P (the Invisible Internet Project)<\/a>, che assomiglia a <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/it.wikipedia.org\/wiki\/Tor_(software)\">Tor<\/a>.<\/li><li><u>L&#8217;attenzione di Monero alla privacy vuole cambiare le regole del gioco oltre lo scopo della privacy &#8220;virtuale&#8221;<\/u>. Per il team Monero, promuovere la fiducia degli utenti con funzionalit&agrave; avanzate di privacy si estende per proteggere il loro interesse al di fuori del dominio della tracciabilit&agrave; e della collegabilit&agrave; delle transazioni. Monero vuole impedire l&#8217;estrazione di informazioni nascoste dai database pubblici al fine di diventare una criptovaluta in grado di proteggere i suoi utenti dinanzi ai tribunali e istituzioni giudiziarie simili, anche da punizioni come la <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/web.getmonero.org\/it\/resources\/about\/index.html\">pena di morte<\/a>. Allo stesso tempo, gli sviluppatori non vogliono limitare l&#8217;accesso ai vantaggi della privacy di Monero richiedendo ai propri utenti di conoscerne il funzionamento interno. Il team promette di sottoporre al pubblico tutte le decisioni sullo sviluppo per la discussione pubblica.<\/li><li><u>Il modello di prova del lavoro di Monero &egrave; considerato pi&ugrave; democratico rispetto a quello trovato in Bitcoin, a sostegno dell&#8217;offerta di Monero per un pi&ugrave; alto livello di decentralizzazione<\/u>. Il modello Proof-of-Work di Monero prevede l&#8217;implementazione dell&#8217;algoritmo di hashing <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/www.mycryptopedia.com\/cryptonight-cryptonote-explained\/\">CryptoNight<\/a>, utilizzato per i token di mining XMR. Si suppone che questa tecnologia offra un approccio pi&ugrave; egualitario al mining, poich&eacute; pu&ograve; essere calcolato da CPU e GPU, pur essendo meno amichevole con coloro che usano circuiti integrati specifici dell&#8217;applicazione (ASIC).<\/li><\/ul><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"cos'&egrave; monero xmr\" class=\" lazyload\" data-src=\"https:\/\/cimg.co\/coin\/44789\/21288\/cose-monero-xmr.png\" data-srcset=\"\"><\/figure><p>&nbsp;<\/p><h2>Come funziona?<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>Per ottenere gli effetti desiderati sul processo di transazione, il flusso di lavoro di Monero segue un percorso specifico basato sulla sua implementazione della tecnologia CryptoNote:<\/p><ul><li>Alla creazione di un account Monero, a un utente verranno fornite una chiave di visualizzazione privata e chiavi di spesa privata, insieme a un indirizzo pubblico. La chiave di spesa pu&ograve; essere utilizzata per spendere pagamenti, mentre la chiave di visualizzazione fornisce informazioni dettagliate sulle transazioni in entrata. Infine, l&#8217;indirizzo pubblico viene utilizzato per ricevere fondi. Questi sono usati per creare l&#8217;indirizzo Monero dell&#8217;utente.<\/li><li>A questo punto, immaginiamo che esista un output che un utente desidera spendere dopo che &egrave; stato inviato alla chiave pubblica unica.<\/li><li>Con l&#8217;aiuto di un Extra, un TxOutNumber e la chiave dell&#8217;account privato, l&#8217;utente pu&ograve; recuperare la propria chiave privata unica.<\/li><li>Il valore Extra per l&#8217;invio di una transazione a un altro utente viene generato in modo casuale.<\/li><li>L&#8217;Extra, il TxOutNumber e la chiave pubblica dell&#8217;account di un destinatario vengono utilizzati per creare l&#8217;output della chiave pubblica del destinatario.<\/li><li>Il mittente pu&ograve; nascondere il collegamento al proprio output tra le chiavi esterne nell&#8217;input.<\/li><li>La doppia spesa &egrave; evitata includendo la chiave immagine, un marcatore speciale creato dalla chiave privata unica del mittente. C&#8217;&egrave; una sola immagine chiave per ogni spesa sulla blockchain.<\/li><li>I mittenti firmano le transazioni con la propria chiave privata unica, tutte le chiavi pubbliche e la chiave immagine, e aggiunge la ring singature (vedi sotto) alla fine della transazione in questione.<\/li><\/ul><p>&nbsp;<\/p><h2>Come funzionano le ring signature?<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>Oltre al protocollo CryptoNote, i designer di Monero hanno aggiunto a Monero la tecnologia della ring signature per consentire transazioni pi&ugrave; sicure e non rintracciabili. Le ring signature sono firme digitali e coinvolgono pi&ugrave; firmatari che devono firmare una transazione. Ci&ograve; accade senza che una parte esterna possa rilevare un mittente &#8220;autentico&#8221;. In linea con il flusso di lavoro transazionale di Monero, un mittente crea una chiave di spesa unica, e solo il destinatario &egrave; in grado di trovare e spendere i fondi distribuiti con l&#8217;aiuto di tale chiave.<\/p><p>Il &#8220;ring&#8221; nel nome della tecnologia di firma si riferisce al ring (anello) dei potenziali firmatari che viene creato con l&#8217;aiuto dell&#8217;account dell&#8217;utente e seleziona le chiavi pubbliche. Questo rende quasi impossibile determinare quale tra i membri di un particolare gruppo (o un anello) abbia creato una firma, rendendo cos&igrave; le uscite resistenti alla tracciabilit&agrave;.<\/p><p>&nbsp;<\/p><h2>Cosa sono le ring transaction riservate?<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>Allo stesso tempo, alla rete Monero viene impedito di &#8220;apprendere&#8221; informazioni sugli importi che vengono spesi. Gli utenti che desiderano inviare fondi possono divulgare solo il minimo di informazioni di cui i miners hanno bisogno per convalidare la transazione, senza rivelare alcuna informazione sugli importi spesi in pubblico. Ci&ograve; &egrave; garantito con l&#8217;uso della tecnologia Ring Confidential Transactions (RCT).<\/p><p>Oltre a impegnare gli importi da spendere, RCT crittografer&agrave; le informazioni sull&#8217;importo per ciascuna spesa e le render&agrave; parte della transazione. Queste informazioni saranno combinate con il segreto condiviso incluso nella transazione. Infine, l&#8217;importo viene calcolato combinando la chiave privata del destinatario con la chiave di visualizzazione pubblica transazionale.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"monero xmr addresses\" sizes=\"100vw\" class=\" lazyload\" data-src=\"https:\/\/cimg.co\/w\/coins-attachments\/1\/5ce\/d4fa81fdad.jpg\" data-srcset=\"https:\/\/cimg.co\/w\/coins-attachments\/1\/5ce\/d4fa81fdad.jpg 300w, https:\/\/cimg.co\/w\/coins-attachments\/2\/5ce\/d4fa81fdad.jpg 600w, https:\/\/cimg.co\/w\/coins-attachments\/3\/5ce\/d4fa81fdad.jpg 720w, https:\/\/cimg.co\/w\/coins-attachments\/4\/5ce\/d4fa81fdad.jpg 900w\"><\/figure><p>&nbsp;<\/p><h2>Indirizzi Stealth di XMR<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>Gli indirizzi Stealth (invisibili) presenti sulla piattaforma Monero fanno parte del pacchetto di protezione della privacy con il quale la piattaforma mira a proteggere entrambe le parti di una transazione. Questo viene fatto obbligando il mittente a creare indirizzi una tantum casuali per ogni transazione. In questo modo, solo gli utenti coinvolti nella transazione conoscono la destinazione finale di un pagamento.<\/p><p>Mentre gli indirizzi invisibili rendono pi&ugrave; difficile collegare i fondi del destinatario con il loro portafoglio, &egrave; comunque possibile verificare che una transazione abbia raggiunto un determinato indirizzo se il mittente decide di dare accesso alla propria chiave di visualizzazione pubblica.<\/p><p>Sulla base di ci&ograve;, gli utenti possono godere dei vantaggi della trasparenza selettiva, il che significa che alcune transazioni possono essere rese visibili e altre non rintracciabili. Ci&ograve; &egrave; reso ancora pi&ugrave; semplice grazie alla maggiore flessibilit&agrave; di CryptoNote con scalabilit&agrave; e gestione delle dimensioni dei blocchi, il che significa che le transazioni con Monero richiedono pi&ugrave; dati e input crittografici. Infine, tutte queste caratteristiche hanno sollevato alcune preoccupazioni sul fatto che Monero potrebbe diventare popolare tra i cyber criminali.<\/p><p>&nbsp;<\/p><h2>Disponibilit&agrave; token XMR<\/h2><span class=\"replacer\"><\/span><p>&nbsp;<\/p><p>La quantit&agrave; di monete Monero in dotazione non &egrave; limitata. Inizialmente verranno rilasciati 18,4 milioni di XMR, con una produzione fissa di 0,3 XMR al minuto prevista per un periodo indefinito. La capitalizzazione di mercato della moneta a maggio 2019 era di 1,6 miliardi di dollari, in calo rispetto al picco storico raggiunto all&#8217;inizio del 2018.<\/p><p>Poich&eacute; il mining &egrave; basato sull&#8217;attenzione della piattaforma al decentramento, viene effettuato principalmente con GPU, essendo le CPU un&#8217;opzione meno efficiente. Per combattere il mining basato su ASIC, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/monero.org\/forks\/\">Monero ha sub&igrave;to un fork<\/a> in diversi token: Monero 0 (ZMR), Monero Classic (XMC), Monero Original (XMO), MoneroV (XMV) e altri. Oltre al mining, si pu&ograve; facilmente acquistare XMR direttamente dagli exchange di criptovaluta, come <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/reviews\/kraken\/\">Kraken<\/a>, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/it\/reviews\/binance\/\">Binance<\/a> e altri. Una volta acquisite, le monete possono essere spese con l&#8217;aiuto dell&#8217;elenco di <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/web.getmonero.org\/it\/community\/merchants\/index.html\">commercianti Monero<\/a> o conservate in vari <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/web.getmonero.org\/downloads\/\">portafogli<\/a> desktop.<\/p><p>Nel marzo 2019, <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/news\/monero-dips-following-hard-fork-that-made-it-more-secure-3501\/\">Monero ha sub&igrave;to un hard fork<\/a> che avrebbe dovuto migliorare la sua privacy, sicurezza e resistenza ASIC. Non sono emerse nuove monete da questa modifica al protocollo, il che significa che solo i miners dovevano aggiornare il loro software di mining, mentre i possessori di XMR dovevano aggiornare i loro portafogli all&#8217;ultima versione per rimanere funzionali.<\/p><p>Finora il progetto Monero ha visto la partecipazione di oltre 500 collaboratori, che comprende per la maggior parte il suo team di sviluppatori.<\/p><p>____<\/p><p><i>Seguici sui nostri canali social:<\/i><\/p><p>Telegram:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/t.me\/ItaliaCryptonews\">https:\/\/t.me\/ItaliaCryptonews<\/a><\/p><p>Twitter:&nbsp;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/twitter.com\/cryptonews_IT\">https:\/\/twitter.com\/cryptonews_IT<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Monero &egrave; una criptovaluta decentralizzata e orientata alla privacy dedicata alla protezione dell&#8217;anonimato dei suoi utenti offuscando le informazioni su mittenti, destinatari e gli importi presenti nelle transazioni.&nbsp;Cos&#8217;&egrave; Monero?&nbsp;La piattaforma Monero e il suo token XMR sono stati progettati pensando a una missione: consentire a ciascun utente di controllare il livello di visibilit&agrave; dei loro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","categories":[],"tags":[],"editors":[],"class_list":["post-44789","coins","type-coins","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monero (XMR) cos&#039;\u00e8 e come funziona?<\/title>\n<meta name=\"description\" content=\"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monero (XMR) cos&#039;\u00e8 e come funziona?\" \/>\n<meta property=\"og:description\" content=\"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/coins\/monero\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/coin\/44789\/21287\/monero-xmr.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Monero (XMR) cos&#039;\u00e8 e come funziona?\" \/>\n<meta name=\"twitter:description\" content=\"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/w\/coins-attachments\/1\/5ce\/d4fa81fdad.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monero (XMR) cos'\u00e8 e come funziona?","description":"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Monero (XMR) cos'\u00e8 e come funziona?","og_description":"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.","og_url":"https:\/\/cryptonews.com\/it\/coins\/monero\/","og_site_name":"Cryptonews Italia","article_modified_time":"2023-02-08T10:44:24+00:00","og_image":[{"url":"https:\/\/cimg.co\/coin\/44789\/21287\/monero-xmr.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Monero (XMR) cos'\u00e8 e come funziona?","twitter_description":"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.","twitter_image":"https:\/\/cimg.co\/w\/coins-attachments\/1\/5ce\/d4fa81fdad.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/it\/coins\/monero\/","url":"https:\/\/cryptonews.com\/it\/coins\/monero\/","name":"Monero (XMR) cos'\u00e8 e come funziona?","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/it\/coins\/monero\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/it\/coins\/monero\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/coin\/44789\/21287\/monero-xmr.png","datePublished":"2021-01-01T01:01:00+00:00","dateModified":"2023-02-08T10:44:24+00:00","description":"Monero e il suo token XMR sono stati progettati per consentire a ciascun utente di controllare il livello di visibilit\u00e0 dei loro dati personali online.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/coins\/monero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/it\/coins\/monero\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/coins\/monero\/#primaryimage","url":"https:\/\/cimg.co\/coin\/44789\/21287\/monero-xmr.png","contentUrl":"https:\/\/cimg.co\/coin\/44789\/21287\/monero-xmr.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/coins\/monero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Coins","item":"https:\/\/cryptonews.com\/it\/coins"},{"@type":"ListItem","position":3,"name":"Monero (XMR)"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/coins\/44789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/coins"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/types\/coins"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/comments?post=44789"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/coins\/44789\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/media?parent=44789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories?post=44789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/tags?post=44789"},{"taxonomy":"type","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/1?post=44789"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/editors?post=44789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}