{"id":91364,"date":"2022-10-18T17:21:00","date_gmt":"2022-10-18T17:21:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=91364"},"modified":"2023-06-26T11:06:47","modified_gmt":"2023-06-26T11:06:47","slug":"tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/","title":{"rendered":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/91364\/228641\/responsive-images\/tron___media_library_original_1032_614.jpg 1032w, https:\/\/cimg.co\/news\/91364\/228641\/responsive-images\/tron___media_library_original_900_535.jpg 900w, https:\/\/cimg.co\/news\/91364\/228641\/responsive-images\/tron___media_library_original_720_428.jpg 720w, https:\/\/cimg.co\/news\/91364\/228641\/responsive-images\/tron___media_library_original_600_356.jpg 600w, https:\/\/cimg.co\/news\/91364\/228641\/responsive-images\/tron___media_library_original_300_178.jpg 300w\" sizes=\"100vw\" width=\"1032\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">TRON (TRX) est la <strong>premi&egrave;re crypto-monnaie au monde &agrave; devenir d&eacute;flationniste<\/strong>, ce qui a &eacute;tabli sa popularit&eacute;. Sa communaut&eacute; avait vot&eacute; en faveur de l&rsquo;&eacute;tablissement de ce m&eacute;canisme permettant de r&eacute;duire son offre par combustion.<\/p><p>La crypto-monnaie a encha&icirc;n&eacute; <strong>50 semaines dans un &eacute;tat d&eacute;flationniste<\/strong> ce qui est une premi&egrave;re dans l&rsquo;univers cryptographique. D&eacute;sormais, l&rsquo;&eacute;quipe derri&egrave;re le projet a annonc&eacute; r&eacute;cemment que ce processus prenait fin. Il serait int&eacute;ressant de voir quel impact ce processus a eu sur le cours de la crypto selon les experts.<\/p><h2>Tron (TRX) a consid&eacute;rablement r&eacute;duit son offre<\/h2><span class=\"replacer\"><\/span><p>Ce n&rsquo;est peut-&ecirc;tre pas l&rsquo;une des crypto-monnaies les plus populaires, mais Tron (TRX) est entr&eacute; dans l&rsquo;histoire. <strong>Son m&eacute;canisme de d&eacute;flation introduit le 28 octobre 2021 a fonctionn&eacute; pendant 50 semaines<\/strong> sans arr&ecirc;t.<\/p><p>Il faut rappeler qu&rsquo;une <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/fr\/news\/binance-a-brule-plus-de-500-millions-de-dollars-de-bnb-une-hausse-en-preparation\/\">crypto d&eacute;flationniste<\/a> est celle qui <strong>diminue son nombre de jetons au fil du temps par le syst&egrave;me de combustion<\/strong>. Des jetons sont retir&eacute;s de la circulation et envoy&eacute;s dans un portefeuille n&rsquo;appartenant &agrave; personne. Cette adresse re&ccedil;oit uniquement et ne peut pas envoyer des jetons. Le but de ce m&eacute;canisme est de cr&eacute;er le manque et augmenter la valeur du token.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/TRONSCAN_ORG\/status\/1581924371576209409?s=20&amp;t=R8vZqYwVWDXf9ZhAjntcWA\"><\/oembed><\/figure><p>Cette exp&eacute;rience a permis de <strong>r&eacute;duire l&rsquo;offre de jetons TRX disponibles<\/strong>. Selon l&rsquo;explorateur officiel de la blockchain TRON, TRONSCAN, le montant total de jetons a atteint <strong>9,6 milliards de TRX<\/strong>. La d&eacute;flation a permis d&rsquo;&eacute;liminer <strong>1&nbsp;106&nbsp;056&nbsp;407 TRX<\/strong> au 22 mai 2022 tandis que <strong>5&nbsp;273&nbsp;312<\/strong> TRX ont &eacute;t&eacute; frapp&eacute;s au 14 ao&ucirc;t 2021.<\/p><h2>Que signifie la fin du m&eacute;canisme de combustion pour Tron&nbsp;?<\/h2><span class=\"replacer\"><\/span><p>La fin annonc&eacute;e du m&eacute;canisme de combustion des jetons TRX pourrait avoir un effet positif sur le prix de la crypto-monnaie. Par exemple, sur les 7 derniers jours, CoinMarketCap affiche un graphique dans le vert. Son prix actuel est de <strong>0,063 $,<\/strong> ce qui repr&eacute;sente toutefois une l&eacute;g&egrave;re baisse de 0,17 % sur les derni&egrave;res 24 heures.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1161\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91364\/228639\/trx-7d-graph-coinmarketcap.jfif\" data-srcset=\"https:\/\/cimg.co\/news\/91364\/228639\/responsive-images\/trx-7d-graph-coinmarketcap___media_library_original_1161_500.jfif 1161w, https:\/\/cimg.co\/news\/91364\/228639\/responsive-images\/trx-7d-graph-coinmarketcap___media_library_original_900_387.jfif 900w, https:\/\/cimg.co\/news\/91364\/228639\/responsive-images\/trx-7d-graph-coinmarketcap___media_library_original_720_310.jfif 720w, https:\/\/cimg.co\/news\/91364\/228639\/responsive-images\/trx-7d-graph-coinmarketcap___media_library_original_600_258.jfif 600w, https:\/\/cimg.co\/news\/91364\/228639\/responsive-images\/trx-7d-graph-coinmarketcap___media_library_original_300_129.jfif 300w\"><figcaption>Graphique sur sept jours de TRX &#8211; source : CoinMarketCap<\/figcaption><\/figure><p>Certains analystes veulent rester positifs par rapport &agrave; l&rsquo;avenir de Tron par rapport aux r&eacute;centes actualit&eacute;s qui entourent le projet. D&rsquo;abord, le r&eacute;seau a r&eacute;cemment enregistr&eacute; <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/TRONSCAN_ORG\/status\/1579360848434573316?s=20&amp;t=R8vZqYwVWDXf9ZhAjntcWA\"><strong>4 milliards de transactions en 24 heures<\/strong><\/a> suite aux rumeurs du rachat de la plateforme d&rsquo;&eacute;change Huobi par le fondateur de Tron.<\/p><p>En outre, Tron est &agrave; ce jour la <strong>deuxi&egrave;me plus grande cha&icirc;ne publique par capitalisation boursi&egrave;re<\/strong>. Aussi, le r&eacute;seau a atteint <strong>plus de 116 millions de comptes cr&eacute;&eacute;s<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>TRON (TRX) est la premi&egrave;re crypto-monnaie au monde &agrave; devenir d&eacute;flationniste, ce qui a &eacute;tabli sa popularit&eacute;. Sa communaut&eacute; avait vot&eacute; en faveur de l&rsquo;&eacute;tablissement de ce m&eacute;canisme permettant de r&eacute;duire son offre par combustion.La crypto-monnaie a encha&icirc;n&eacute; 50 semaines dans un &eacute;tat d&eacute;flationniste ce qui est une premi&egrave;re dans l&rsquo;univers cryptographique. D&eacute;sormais, l&rsquo;&eacute;quipe derri&egrave;re [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2032],"sponsored_companies":[],"class_list":["post-91364","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-pauline-eyebe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste<\/title>\n<meta name=\"description\" content=\"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste\" \/>\n<meta property=\"og:description\" content=\"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-18T17:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste\" \/>\n<meta name=\"twitter:description\" content=\"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste","description":"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/","og_locale":"fr_FR","og_type":"article","og_title":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste","og_description":"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/","og_site_name":"Cryptonews France","article_published_time":"2022-10-18T17:21:00+00:00","article_modified_time":"2023-06-26T11:06:47+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste","twitter_description":"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.","twitter_image":"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/"},"author":{"name":"upeyebeqsk","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/9c70beb09a257825283d4ed565f77da5"},"headline":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste","datePublished":"2022-10-18T17:21:00+00:00","dateModified":"2023-06-26T11:06:47+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/"},"wordCount":531,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/","name":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg","datePublished":"2022-10-18T17:21:00+00:00","dateModified":"2023-06-26T11:06:47+00:00","description":"TRON a pass\u00e9 plus de 50 semaines sans arr\u00eat dans un \u00e9tat d\u00e9flationniste ce qui est un record dans le milieu de la cryptographie.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#primaryimage","url":"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg","contentUrl":"https:\/\/cimg.co\/news\/91364\/228641\/tron.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/tron-enregistre-un-record-pour-la-periode-passee-dans-un-etat-deflationniste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"TRON enregistre un record pour la p\u00e9riode pass\u00e9e dans un \u00e9tat d\u00e9flationniste"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/91364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=91364"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/91364\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=91364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=91364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=91364"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=91364"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=91364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}