{"id":87793,"date":"2022-09-16T10:07:00","date_gmt":"2022-09-16T10:07:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=87793"},"modified":"2023-06-26T11:06:48","modified_gmt":"2023-06-26T11:06:48","slug":"leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/","title":{"rendered":"L&rsquo;ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg\" srcset=\"https:\/\/cimg.co\/news\/87793\/220692\/responsive-images\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms___media_library_original_1920_1080.jpg 1920w, https:\/\/cimg.co\/news\/87793\/220692\/responsive-images\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms___media_library_original_1200_675.jpg 1200w, https:\/\/cimg.co\/news\/87793\/220692\/responsive-images\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms___media_library_original_900_506.jpg 900w, https:\/\/cimg.co\/news\/87793\/220692\/responsive-images\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms___media_library_original_720_405.jpg 720w, https:\/\/cimg.co\/news\/87793\/220692\/responsive-images\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms___media_library_original_600_337.jpg 600w, https:\/\/cimg.co\/news\/87793\/220692\/responsive-images\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms___media_library_original_300_168.jpg 300w\" width=\"1920\" class=\"content-img\" alt=\"\"><figcaption>ETH Coins<\/figcaption><\/figure><p class=\"wp-block-paragraph\">Les gains enregistr&eacute;s par Ethereum apr&egrave;s la fusion ont &eacute;t&eacute; an&eacute;antis &agrave; cause d&rsquo;une forte liquidation. Dans les derni&egrave;res 24 heures qui ont suivi la mise en service du nouveau protocole, plus de 150 millions de dollars en ETH ont &eacute;t&eacute; liquid&eacute;s, cr&eacute;ant une baisse du prix de l&rsquo;ETH.<\/p><p>Ethereum a enregistr&eacute; sa premi&egrave;re baisse apr&egrave;s la mise en service de The Merge (la fusion). Le nouveau protocole fait passer le r&eacute;seau Ethereum d&rsquo;un consensus de preuve de travail &agrave; un processus de preuve d&rsquo;enjeu.&nbsp;<\/p><p>Comme il fallait s&rsquo;y attendre, ce changement a apport&eacute; son lot de cons&eacute;quences. En effet, on a assist&eacute; &agrave; la plus grande bougie de liquidation sur une p&eacute;riode d&rsquo;un mois entra&icirc;nant ainsi un effondrement du prix d&rsquo;Ethereum.<\/p><h2>Ethereum se portait pourtant bien<\/h2><span class=\"replacer\"><\/span><p>Tout semblait pourtant aller dans le bon sens pour Ethereum. Apr&egrave;s que la fusion soit effective, le prix d&rsquo;ETH s&rsquo;est dans une bonne dynamique. En quelques heures, il a atteint 1&nbsp;640 $ et plusieurs personnes se sont esp&eacute;raient que ce soit le d&eacute;but d&rsquo;un bull run.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" width=\"1280\" class=\"content-img lazyload\" alt=\"\" data-src=\"https:\/\/cimg.co\/news\/87727\/220605\/cryptocurrency-ga8707d1c1-1280.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/87727\/220605\/responsive-images\/cryptocurrency-ga8707d1c1-1280___media_library_original_1280_746.jpg 1280w, https:\/\/cimg.co\/news\/87727\/220605\/responsive-images\/cryptocurrency-ga8707d1c1-1280___media_library_original_1200_699.jpg 1200w, https:\/\/cimg.co\/news\/87727\/220605\/responsive-images\/cryptocurrency-ga8707d1c1-1280___media_library_original_900_524.jpg 900w, https:\/\/cimg.co\/news\/87727\/220605\/responsive-images\/cryptocurrency-ga8707d1c1-1280___media_library_original_720_419.jpg 720w, https:\/\/cimg.co\/news\/87727\/220605\/responsive-images\/cryptocurrency-ga8707d1c1-1280___media_library_original_600_349.jpg 600w, https:\/\/cimg.co\/news\/87727\/220605\/responsive-images\/cryptocurrency-ga8707d1c1-1280___media_library_original_300_174.jpg 300w\"><\/figure><p>Cependant, Ethereum a subi les cons&eacute;quences d&rsquo;une liquidation excessive. En moins d&rsquo;une heure, la crypto-monnaie a enregistr&eacute; plus de 60 millions de dollars de liquidations. Cela a entra&icirc;n&eacute; une forte pression &agrave; la baisse de son prix et de l&rsquo;ensemble du march&eacute;. En tout, on a enregistr&eacute; plus de 150 millions de dollars de liquidations dans les 24 derni&egrave;res heures.<\/p><p>CoinAnalyze &eacute;value les liquidations &agrave; environ 77 millions de dollars pour OKEx et 40 millions de dollars pour FTX sur les 24 derni&egrave;res heures. D&rsquo;apr&egrave;s une analyse du march&eacute;, environ 98,6 millions de dollars de liquidations enregistr&eacute;es &eacute;taient longues. En revanche, 48,3 million de dollars de liquidations &eacute;taient shorts.<\/p><p>Comme on pouvait s&rsquo;y attendre avec de pareils &eacute;v&eacute;nements, le prix d&rsquo;Ethereum a connu une premi&egrave;re baisse apr&egrave;s la fusion. Il est pass&eacute; en dessous de 1&nbsp;500 $, se vendant aux alentour de 1&nbsp;480 $.<\/p><h2>Les pertes se sont r&eacute;percut&eacute;es sur le reste du march&eacute;<\/h2><span class=\"replacer\"><\/span><p>Ethereum n&rsquo;est pas la seule crypto-monnaie a avoir enregistr&eacute; des pertes suite aux liquidations massives. Plusieurs actifs &agrave; forte capitalisation sont pass&eacute;es dans le rouge &agrave; cause de cet &eacute;v&eacute;nement.&nbsp;<\/p><p>&nbsp;<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" width=\"1282\" class=\"content-img lazyload\" alt=\"\" data-src=\"https:\/\/cimg.co\/news\/87778\/220682\/ethereum-chart-post-merge.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/87778\/220682\/responsive-images\/ethereum-chart-post-merge___media_library_original_1282_784.jpg 1282w, https:\/\/cimg.co\/news\/87778\/220682\/responsive-images\/ethereum-chart-post-merge___media_library_original_1200_733.jpg 1200w, https:\/\/cimg.co\/news\/87778\/220682\/responsive-images\/ethereum-chart-post-merge___media_library_original_900_550.jpg 900w, https:\/\/cimg.co\/news\/87778\/220682\/responsive-images\/ethereum-chart-post-merge___media_library_original_720_440.jpg 720w, https:\/\/cimg.co\/news\/87778\/220682\/responsive-images\/ethereum-chart-post-merge___media_library_original_600_366.jpg 600w, https:\/\/cimg.co\/news\/87778\/220682\/responsive-images\/ethereum-chart-post-merge___media_library_original_300_183.jpg 300w\"><\/figure><p>Toutefois, il faut noter que seul Ethereum a subi une baisse importante de son prix. Les autres actifs sur le march&eacute; de la cryptographie n&rsquo;ont perdu que quelques pour cent. En revanche, la perte de l&rsquo;Ether est plus importante &agrave; 7,5% sur 24 heures.&nbsp;<\/p><p>Alors que les sp&eacute;culations pour savoir la raison de la liquidation massive d&rsquo;Ethereum vont bon train, plusieurs experts pointent du doigt les inqui&eacute;tudes entourant la fusion. Pour d&rsquo;autres, il s&rsquo;agit d&rsquo;un probl&egrave;me plus g&eacute;n&eacute;ral du march&eacute; de la cryptographie qui est volatile.<\/p><p>Ethereum connait des moments difficiles avec des difficult&eacute;s &agrave; se relever de la chute de son prix sur le march&eacute;. Contrairement &agrave; cette crypto-monnaie, les autres altcoins ont connu une certaine stabilit&eacute; ces derniers jours. De ce fait, les derni&egrave;res 24 heures viennent mettre &agrave; mal les performances enregistr&eacute;es pendant plusieurs jours.<\/p><p>En parall&egrave;le du march&eacute; cryptographique, le march&eacute; traditionnel a &eacute;galement subi un r&eacute;cent crash avec des actions et des indices qui essayaient de se stabiliser. Des analystes mettent cela sur le compte de l&rsquo;&eacute;v&eacute;nement politique r&eacute;cent, la rencontre entre les pr&eacute;sidents russe et chinois. Elle s&rsquo;est d&eacute;roul&eacute;e en Ouzb&eacute;kistan et portait sur la \u00ab\u00a0stabilit&eacute; mondiale et r&eacute;gionale\u00a0\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>ETH CoinsLes gains enregistr&eacute;s par Ethereum apr&egrave;s la fusion ont &eacute;t&eacute; an&eacute;antis &agrave; cause d&rsquo;une forte liquidation. Dans les derni&egrave;res 24 heures qui ont suivi la mise en service du nouveau protocole, plus de 150 millions de dollars en ETH ont &eacute;t&eacute; liquid&eacute;s, cr&eacute;ant une baisse du prix de l&rsquo;ETH.Ethereum a enregistr&eacute; sa premi&egrave;re baisse [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2032],"sponsored_companies":[],"class_list":["post-87793","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-pauline-eyebe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures<\/title>\n<meta name=\"description\" content=\"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L&#039;effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures\" \/>\n<meta property=\"og:description\" content=\"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L&#039;effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-16T10:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures\" \/>\n<meta name=\"twitter:description\" content=\"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L&#039;effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/87793\/220694\/eth.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures","description":"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L'effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures","og_description":"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L'effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/","og_site_name":"Cryptonews France","article_published_time":"2022-09-16T10:07:00+00:00","article_modified_time":"2023-06-26T11:06:48+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"L'ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures","twitter_description":"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L'effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.","twitter_image":"https:\/\/cimg.co\/news\/87793\/220694\/eth.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/"},"author":{"name":"upeyebeqsk","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/9c70beb09a257825283d4ed565f77da5"},"headline":"L&rsquo;ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures","datePublished":"2022-09-16T10:07:00+00:00","dateModified":"2023-06-26T11:06:48+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/"},"wordCount":721,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/","name":"L'ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg","datePublished":"2022-09-16T10:07:00+00:00","dateModified":"2023-06-26T11:06:48+00:00","description":"ETH connait sa premi\u00e8re chute apr\u00e8s la fusion, passant en dessous de 1 500 $. L'effondrement a \u00e9t\u00e9 caus\u00e9 par une forte liquidation \u00e9valu\u00e9e \u00e0 plus de 150 millions de dollars des jetons ETH.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#primaryimage","url":"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg","contentUrl":"https:\/\/cimg.co\/news\/87793\/220692\/ethereum-merge-buyers-turn-into-sellers-as-trouble-free-upgrade-underwhelms.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/leth-chute-en-dessous-de-1-500-bien-que-plus-de-150-millions-de-dollars-ont-ete-liquides-en-24-heures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;ETH chute en dessous de 1 500 $ bien que plus de 150 millions de dollars ont \u00e9t\u00e9 liquid\u00e9s en 24 heures"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/87793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=87793"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/87793\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=87793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=87793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=87793"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=87793"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=87793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}