{"id":32220,"date":"2019-12-17T05:10:00","date_gmt":"2019-12-17T05:10:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=32220"},"modified":"2023-06-26T11:06:29","modified_gmt":"2023-06-26T11:06:29","slug":"south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/","title":{"rendered":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Les procureurs sud-cor&eacute;ens de la ville de <b>Daejeon<\/b> ont d&eacute;mantel&eacute; ce qui semble &ecirc;tre un syst&egrave;me pyramidal &agrave; plusieurs niveaux de 18,4 millions de dollars US centr&eacute; sur un faux jeton.<\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5df\/7c38a61506.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5df\/7c38a61506.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5df\/7c38a61506.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5df\/7c38a61506.jpg 1254w\" alt=\"\" class=\"content-img\"><figcaption>Source: iStock\/tongpatong<\/figcaption><\/figure><p><a href=\"https:\/\/www.yna.co.kr\/view\/AKR20191216115200063?input=1195m\" target=\"_blank\" rel=\"noopener\">Selon l&rsquo;agence de presse Yonhap<\/a>, la police affirme que les dirigeants d&rsquo;au moins une soci&eacute;t&eacute; anonyme ont convaincu \u00ab\u00a0un grand nombre d&rsquo;investisseurs\u00a0\u00bb d&rsquo;investir dans un jeton qui n&rsquo;a pas &eacute;t&eacute; nomm&eacute; et qu&rsquo;on appellera \u00ab\u00a0crypto H\u00a0\u00bb. Ni le nom de l&rsquo;entreprise ni le jeton en question n&rsquo;ont &eacute;t&eacute; communiqu&eacute;s aux m&eacute;dias pour des raisons juridiques.<\/p><p><b>Lire aussi: <a href=\"https:\/\/cryptonews.com\/fr\/news\/exit-scam-fears-as-major-darknet-site-ico-promises-700-growt-5092\/\">Une ICO promet une croissance de 700% en 6 mois&#8230; &ccedil;a sent la fraude en Bitcoin<\/a>.<\/b><\/p><p>Il a &eacute;t&eacute; promis aux investisseurs que le jeton d&rsquo;une valeur initiale de 0,0034 USD monterait en fl&egrave;che une fois qu&rsquo;il serait list&eacute; sur les principaux exchanges, pour atteindre 4,3 USD chacun.<\/p><p>Comme c&rsquo;est le cas dans les arnaques pyramidales, les investisseurs &eacute;taient &eacute;galement encourag&eacute;s &agrave; recruter plus d&rsquo;acheteurs en leur promettant qu&rsquo;ils recevraient une plus grande part des b&eacute;n&eacute;fices futurs s&rsquo;ils investissaient davantage.<\/p><p>On a dit aux investisseurs que la crypto H &eacute;tait l&rsquo;id&eacute;e d&rsquo;une soci&eacute;t&eacute; tha&iuml;landaise de haute technologie et on leur a montr&eacute; du mat&eacute;riel promotionnel convaincant mettant en vedette des acteurs &eacute;trangers. De fausses donn&eacute;es sur le prix de la cryptomonnaie H, sur les transactions ont &eacute;galement &eacute;t&eacute; produites dans le but de tromper les investisseurs.<\/p><p>Un tribunal de la ville a appris que le livre blanc sur la cryptomonnaie H existe toujours et peut &ecirc;tre consult&eacute; en ligne. Cependant, les procureurs ont depuis d&eacute;couvert que la soci&eacute;t&eacute; en question n&rsquo;&eacute;tait rien d&rsquo;autre qu&rsquo;une coquille et qu&rsquo;aucune crypto H n&rsquo;avait en r&eacute;alit&eacute; jamais &eacute;t&eacute; &eacute;mise.<\/p><p>Le syst&egrave;me semble avoir &eacute;t&eacute; exceptionnellement sophistiqu&eacute; et ses op&eacute;rateurs ont men&eacute; leur campagne d&rsquo;ao&ucirc;t 2017 &agrave; juillet de l&rsquo;ann&eacute;e derni&egrave;re.<\/p><p>Suivez nos liens d&rsquo;affili&eacute;s pour:<\/p><p><b>Acheter des cryptomonnaies<\/b><\/p><ul><li>Sur <a href=\"https:\/\/www.coinhouse.com\/r\/179207\" target=\"_blank\" rel=\"noopener\">Coinhouse<\/a> (Zone SEPA Europe et citoyens fran&ccedil;ais).<\/li><li>Sur <a href=\"https:\/\/rapi.cryptonews.com\/ext\/bitbuy\/fr\" target=\"_blank\" rel=\"noopener sponsored nofollow\">BitBuy<\/a> (Uniquement au Canada).<\/li><li>Sur <a href=\"https:\/\/www.bcbitcoin.co.uk\/?ref=CryptoNewsFR\" target=\"_blank\" rel=\"noopener\">BC Bitcoin<\/a> (Europe, Canada).<\/li><li>Sur <a href=\"https:\/\/content.etoro.com\/lp\/new-crypto\/?dl=30002065&amp;culture=fr-fr&amp;utm_medium=Affiliate&amp;utm_source=80205&amp;utm_content=10545&amp;utm_serial=cn-fr&amp;utm_campaign=cn-fr&amp;utm_term=\" target=\"_blank\" rel=\"noopener\">eToro<\/a> (Sauf au Canada).<\/li><\/ul><p><b>S&eacute;curiser vos cryptomonnaies<\/b><\/p><ul><li>Portefeuille <a href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0&amp;tracker=CN-FR\" target=\"_blank\" rel=\"noopener\">Ledger<\/a>.<\/li><li>Portefeuille <a href=\"https:\/\/cryptonews.com\/ext\/trezor\/\" target=\"_blank\" rel=\"nofollow noopener\">Trezor<\/a>.<\/li><\/ul><p><b>Payer toutes vos factures ou envoyer de l&rsquo;argent vers votre banque<\/b><\/p><ul><li><a href=\"https:\/\/bylls.com\/signup?referralcode=4e4538be3e456adefeeb9544f1d5dbb9de98154111\" target=\"_blank\" rel=\"noopener\">Bylls<\/a> (Disponible uniquement au Canada).<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Les procureurs sud-cor&eacute;ens de la ville de Daejeon ont d&eacute;mantel&eacute; ce qui semble &ecirc;tre un syst&egrave;me pyramidal &agrave; plusieurs niveaux de 18,4 millions de dollars US centr&eacute; sur un faux jeton.Source: iStock\/tongpatongSelon l&rsquo;agence de presse Yonhap, la police affirme que les dirigeants d&rsquo;au moins une soci&eacute;t&eacute; anonyme ont convaincu \u00ab\u00a0un grand nombre d&rsquo;investisseurs\u00a0\u00bb d&rsquo;investir dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3],"tags":[72],"editors":[2550],"sponsored_companies":[],"class_list":["post-32220","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-people","tag-cryptomonnaie","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande<\/title>\n<meta name=\"description\" content=\"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande\" \/>\n<meta property=\"og:description\" content=\"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-17T05:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande\" \/>\n<meta name=\"twitter:description\" content=\"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/26178\/8427\/5df7c39f71e94.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","description":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","og_description":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/","og_site_name":"Cryptonews France","article_published_time":"2019-12-17T05:10:00+00:00","article_modified_time":"2023-06-26T11:06:29+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","twitter_description":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","twitter_image":"https:\/\/cimg.co\/news\/26178\/8427\/5df7c39f71e94.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","datePublished":"2019-12-17T05:10:00+00:00","dateModified":"2023-06-26T11:06:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/"},"wordCount":469,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg","keywords":["Cryptomonnaie"],"articleSection":["Exclusives","Personnalit\u00e9s Crypto"],"inLanguage":"fr-FR","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/","name":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg","datePublished":"2019-12-17T05:10:00+00:00","dateModified":"2023-06-26T11:06:29+00:00","description":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5df\/7c38a61506.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/south-korean-police-charge-operators-of-usd-18m-bogus-thai-c-5113\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Une fraude pyramidale \u00e0 la cryptomonnaie de 18 millions de dollars en Tha\u00eflande"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/32220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=32220"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/32220\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=32220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=32220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=32220"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=32220"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=32220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}