{"id":32177,"date":"2019-12-04T14:00:00","date_gmt":"2019-12-04T14:00:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=32177"},"modified":"2023-06-26T11:07:28","modified_gmt":"2023-06-26T11:07:28","slug":"nordea-employees-banned-from-buying-bitcoin-more-news-4990","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/","title":{"rendered":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies"},"content":{"rendered":"<ul><li><b>Nordea Bank<\/b> peut emp&ecirc;cher ses employ&eacute;s d&rsquo;investir dans le Bitcoin (BTC) et d&rsquo;autres cryptomonnaies sur leur temps libre, a rapport&eacute; <b><a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2019-12-03\/nordea-wins-danish-court-battle-to-ban-staff-trading-in-bitcoin\" target=\"_blank\" rel=\"noopener\">Bloomberg<\/a><\/b>, citant un <a href=\"https:\/\/www.arbejdsretten.dk\/media\/1233477\/dom%20-%20nordea.pdf\" target=\"_blank\" rel=\"noopener\">verdict<\/a> d&rsquo;un tribunal danois. Les risques associ&eacute;s aux cryptomonnaies justifient cette restriction, a d&eacute;clar&eacute; le tribunal, bien que le syndicat danois des employ&eacute;s du secteur financier ait d&eacute;clar&eacute; que l&rsquo;interdiction portait atteinte &agrave; la vie priv&eacute;e des employ&eacute;s. Toutefois, la restriction ne s&rsquo;appliquait pas aux instruments financiers li&eacute;s aux cryptomonnaies que Nordea avait vendues &agrave; ses clients, ni aux cryptomonnaies que les employ&eacute;s pouvaient avoir d&eacute;tenues avant l&rsquo;interdiction.<\/li><li><b>La Crypto Valley Association<\/b> (CVA), un &eacute;cosyst&egrave;me mondial concernant la blockchain et la technologie cryptographique, a d&eacute;clar&eacute; avoir publi&eacute; son <a href=\"https:\/\/cryptovalley.swiss\/wp-content\/uploads\/CVA-Asset-Tokenization-Paper-final-version-FDU.pdf\" target=\"_blank\" rel=\"noopener\">Asset Tokenization Paper<\/a>, un document qui d&eacute;finit le processus de tokenisation pour les entreprises suisses, aborde les questions juridiques et techniques relatives &agrave; la tokenisation des actifs, et fournit des conseils &agrave; ceux qui s&rsquo;occupent des security tokens.<\/li><li>Le Venezuela dit qu&rsquo;il d&eacute;veloppe des liens plus &eacute;troits avec la Russie dans le domaine des cryptomonnaies. Dans un <a href=\"https:\/\/vicepresidencia.gob.ve\/relacion-entre-rusia-y-venezuela-es-ejemplar-profunda-e-historica\/\" target=\"_blank\" rel=\"noopener\">communiqu&eacute; officiel<\/a> de la vice-pr&eacute;sidence, Caracas affirme qu&rsquo;elle noue des liens de plus en plus forts avec Moscou et mentionne en particulier ce qu&rsquo;elle appelle les \u00ab\u00a0relations financi&egrave;res de plus en plus &eacute;troites\u00a0\u00bb dans \u00ab\u00a0le secteur des monnaies fiats et crypto-devises internationales\u00a0\u00bb.<\/li><\/ul><p class=\"wp-block-paragraph\"><b>Lire aussi: <a href=\"https:\/\/cryptonews.com\/fr\/news\/south-korea-to-make-government-led-usd-383m-blockchain-r-d-d-4896\/\">Le gouvernement sud-cor&eacute;en investit 383 millions de dollars dans la blockchain (R&amp;D)<\/a>.<\/b><\/p><figure><img decoding=\"async\" src=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg\" sizes=\"(min-width: 640px) 720px, 100vw\" srcset=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg 300w, https:\/\/cimg.co\/w\/articles-attachments\/2\/5de\/67056544f4.jpg 600w, https:\/\/cimg.co\/w\/articles-attachments\/3\/5de\/67056544f4.jpg 720w, https:\/\/cimg.co\/w\/articles-attachments\/4\/5de\/67056544f4.jpg 900w, https:\/\/cimg.co\/w\/articles-attachments\/0\/5de\/67056544f4.jpg 1254w\" alt=\"\" class=\"content-img\"><figcaption>Source: iStock\/Reimphoto<\/figcaption><\/figure><ul><li>La ville de Murcie, en Espagne, sera l&rsquo;h&ocirc;te en fin d&rsquo;ann&eacute;e d&rsquo;une c&eacute;r&eacute;monie de remise des prix concernant la blockchain et les cryptomonnaies, <a href=\"https:\/\/www.extradigital.es\/murcia-sera-la-sede-de-los-i-premios-nacionales-de-blockchain-en-2020\/\" target=\"_blank\" rel=\"noopener\">rapporte<\/a> le m&eacute;dia Extra Digital.es. Cet &eacute;v&eacute;nement, le premier du genre dans le pays, est le fruit de la cr&eacute;ation d&rsquo;une association locale regroupant des entreprises sp&eacute;cialis&eacute;es dans la cha&icirc;ne de blocs et les cryptos, et verra des personnes et des projets r&eacute;compens&eacute;s dans trois cat&eacute;gories: meilleure startup, meilleur projet et personne la plus influente.<\/li><li>Un consortium d&rsquo;entreprises technologiques japonaises s&rsquo;est associ&eacute; au <b>Muroran Institute of Technology<\/b> du Japon et &agrave; quatre autres universit&eacute;s dans le cadre d&rsquo;un projet qui permettra aux dipl&ocirc;m&eacute;s d&rsquo;obtenir une preuve de leurs dipl&ocirc;mes dans des magasins de proximit&eacute;. Les demandeurs d&#8217;emploi pourront utiliser la plateforme dans le cadre de leur processus d&#8217;emploi. Le projet se d&eacute;roulera au cours de l&rsquo;ann&eacute;e fiscale 2020, <a href=\"https:\/\/asia.nikkei.com\/Business\/Technology\/Japan-to-use-blockchain-to-prevent-resume-fraud\" target=\"_blank\" rel=\"noopener\">rapporte le m&eacute;dia Nikkei<\/a>.<\/li><\/ul><p>Suivez nos liens d&rsquo;affili&eacute;s pour:<\/p><p><b>Acheter des cryptomonnaies<\/b><\/p><ul><li>Sur <a href=\"https:\/\/www.coinhouse.com\/r\/179207\" target=\"_blank\" rel=\"noopener\">Coinhouse<\/a> (Zone SEPA Europe et citoyens fran&ccedil;ais).<\/li><li>Sur <a href=\"https:\/\/rapi.cryptonews.com\/ext\/bitbuy\/fr\" target=\"_blank\" rel=\"noopener sponsored nofollow\">BitBuy<\/a> (Uniquement au Canada).<\/li><li>Sur <a href=\"https:\/\/www.bcbitcoin.co.uk\/?ref=CryptoNewsFR\" target=\"_blank\" rel=\"noopener\">BC Bitcoin<\/a> (Europe, Canada).<\/li><li>Sur <a href=\"https:\/\/content.etoro.com\/lp\/new-crypto\/?dl=30002065&amp;culture=fr-fr&amp;utm_medium=Affiliate&amp;utm_source=80205&amp;utm_content=10545&amp;utm_serial=cn-fr&amp;utm_campaign=cn-fr&amp;utm_term=\" target=\"_blank\" rel=\"noopener\">eToro<\/a> (Sauf au Canada).<\/li><\/ul><p><b>S&eacute;curiser vos cryptomonnaies<\/b><\/p><ul><li>Portefeuille <a href=\"https:\/\/shop.ledger.com\/?r=12b53b98a1c0&amp;tracker=CN-FR\" target=\"_blank\" rel=\"noopener\">Ledger<\/a>.<\/li><li>Portefeuille <a href=\"https:\/\/cryptonews.com\/ext\/trezor\/\" target=\"_blank\" rel=\"nofollow noopener\">Trezor<\/a>.<\/li><\/ul><p><b>Payer toutes vos factures ou envoyer de l&rsquo;argent vers votre banque<\/b><\/p><ul><li><a href=\"https:\/\/bylls.com\/signup?referralcode=4e4538be3e456adefeeb9544f1d5dbb9de98154111\" target=\"_blank\" rel=\"noopener\">Bylls<\/a> (Disponible uniquement au Canada).<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Nordea Bank peut emp&ecirc;cher ses employ&eacute;s d&rsquo;investir dans le Bitcoin (BTC) et d&rsquo;autres cryptomonnaies sur leur temps libre, a rapport&eacute; Bloomberg, citant un verdict d&rsquo;un tribunal danois. Les risques associ&eacute;s aux cryptomonnaies justifient cette restriction, a d&eacute;clar&eacute; le tribunal, bien que le syndicat danois des employ&eacute;s du secteur financier ait d&eacute;clar&eacute; que l&rsquo;interdiction portait atteinte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[85,74,348],"editors":[2550],"sponsored_companies":[],"class_list":["post-32177","post","type-post","status-publish","format-standard","hentry","category-bitcoin-news","category-news","tag-blockchain","tag-crypto","tag-japon","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies<\/title>\n<meta name=\"description\" content=\"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies\" \/>\n<meta property=\"og:description\" content=\"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-04T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies\" \/>\n<meta name=\"twitter:description\" content=\"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/26070\/8328\/5de6705e49eab.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","description":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/","og_locale":"fr_FR","og_type":"article","og_title":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","og_description":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","og_url":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/","og_site_name":"Cryptonews France","article_published_time":"2019-12-04T14:00:00+00:00","article_modified_time":"2023-06-26T11:07:28+00:00","og_image":[{"url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","twitter_description":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","twitter_image":"https:\/\/cimg.co\/news\/26070\/8328\/5de6705e49eab.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","datePublished":"2019-12-04T14:00:00+00:00","dateModified":"2023-06-26T11:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/"},"wordCount":554,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg","keywords":["Blockchain","Crypto","Japon"],"articleSection":["Actualit\u00e9s Bitcoin","News"],"inLanguage":"fr-FR","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/","url":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/","name":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg","datePublished":"2019-12-04T14:00:00+00:00","dateModified":"2023-06-26T11:07:28+00:00","description":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#primaryimage","url":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg","contentUrl":"https:\/\/cimg.co\/w\/articles-attachments\/1\/5de\/67056544f4.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/news\/nordea-employees-banned-from-buying-bitcoin-more-news-4990\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"5 nouvelles concernant l\u2019adoption et la r\u00e9gulation des cryptomonnaies"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/32177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=32177"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/32177\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=32177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=32177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=32177"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=32177"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=32177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}