{"id":130384,"date":"2024-01-23T10:49:54","date_gmt":"2024-01-23T10:49:54","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=130384"},"modified":"2024-01-23T10:13:25","modified_gmt":"2024-01-23T10:13:25","slug":"interview-exclusive-sam-macpherson-phoenix-labs-makerdao","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/","title":{"rendered":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-130720 size-full\" src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg\" alt=\"\" width=\"1260\" height=\"630\" srcset=\"https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg 1260w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions--300x150.jpg 300w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions--1024x512.jpg 1024w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions--768x384.jpg 768w\" sizes=\"auto, (max-width: 1260px) 100vw, 1260px\"><\/p><p>\nContributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les &eacute;volutions &agrave; venir sur l&rsquo;un des principaux protocoles DeFi sur Ethereum.\n<\/p><h3>Dans un r&eacute;cent post sur X, vous avez partag&eacute; vos r&eacute;flexions sur le futur de MakerDAO et son &eacute;cosyst&egrave;me. Pourquoi &eacute;tait-ce important de prendre la parole &agrave; ce moment-l&agrave; ?<\/h3><p>\nLa raison pour laquelle j&rsquo;ai &eacute;crit ce tweet, c&rsquo;est que beaucoup de gens utilisent le DAI comme une infrastructure de fond, mais ils ne font pas attention aux d&eacute;tails. J&rsquo;ai voulu souligner les changements majeurs des ann&eacute;es &agrave; venir. J&rsquo;ai vu aussi beaucoup de memes sur le Crypto Twitter de gens disant que les revenus sont &eacute;lev&eacute;s juste parce que les taux d&rsquo;int&eacute;r&ecirc;ts sont &eacute;lev&eacute;s.<\/p><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">I want to kick off 2024 with an educational post about the Maker\/DAI ecosystem. Memes have a strong influence in crypto and can persist even when no longer accurate. I\u2019ll address the state of some of the larger ones.<\/p>\n<p>1. \u201cDAI is just wrapped USDC\u201d<\/p>\n<p>This hasn\u2019t been true for about\u2026 <a href=\"https:\/\/t.co\/9P5WnqVVdF\">pic.twitter.com\/9P5WnqVVdF<\/a><\/p>\n<p>&mdash; Sam MacPherson (@hexonaut) <a href=\"https:\/\/twitter.com\/hexonaut\/status\/1742252791211459043?ref_src=twsrc%5Etfw\">January 2, 2024<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/p><h2>Comment est structur&eacute; MakerDAO ?<\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nAvant &#8211; et encore un peu aujourd&rsquo;hui &#8211; les &eacute;quipes fonctionnaient avec un noyau dur de personnes (Maker Core), r&eacute;parties en fonction de leurs sp&eacute;cialit&eacute;s : d&eacute;velopper des smart contracts, le marketing, la gestion des risques&hellip; Chaque projet remontait au niveau de la gouvernance et donnait lieu &agrave; un vote des holders. Cela a bien fonctionn&eacute; pendant un certain temps, mais cela posait des questions de passage &agrave; l&rsquo;&eacute;chelle. Une nouvelle proposition a &eacute;t&eacute; faite pour imaginer ce que pouvait &ecirc;tre la nouvelle organisation. D&eacute;sormais, il y a six &ldquo;sous DAOs&rdquo;,&nbsp; dont deux sont li&eacute;es aux questions de gouvernance.\n<\/p><h3>Vous avez annonc&eacute; le lancement d&rsquo;un futur nouveau token, le New Governance Token (NGT), qui devrait remplacer le MKR. Est-ce un nom de code ou le vrai nom ?<\/h3><p>\nC&rsquo;est un nom de code.\n<\/p><h3>Quelle est l&rsquo;id&eacute;e de ce changement de nom ?<\/h3><p>\nL&rsquo;id&eacute;e de cette nouvelle marque est de simplifier et unifier. Beaucoup de gens ne savent m&ecirc;me pas que Maker est li&eacute; au DAI. L&rsquo;autre point est que les marques vont &ecirc;tre rafraichies par une grande compagnie de branding. Cela va permettre de cibler la nouvelle vague d&rsquo;utilisateurs et les impliquer davantage dans la DeFi, avec plus de fun. Enfin, les tokens de sous DAOs vont faire l&rsquo;objet d&rsquo;une grande redistribution. Je m&rsquo;attends &agrave; ce que cela soit un boom massif dans la DeFi au sens large, notamment par le fait que les rendements seront tr&egrave;s &eacute;lev&eacute;s et engageants.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-130722 lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1920\" height=\"1281\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" data-src=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/1706265367-genesis-event-050.jpeg\" data-srcset=\"https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/1706265367-genesis-event-050.jpeg 1920w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/1706265367-genesis-event-050-300x200.jpeg 300w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/1706265367-genesis-event-050-1024x683.jpeg 1024w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/1706265367-genesis-event-050-768x512.jpeg 768w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2024\/01\/1706265367-genesis-event-050-1536x1025.jpeg 1536w\">\n<\/p><h3>Ce que l&rsquo;on appelle la &ldquo;DeFi 2.0&rdquo; gagne du terrain avec des protocoles qui utilisent la gamification pour motiver les utilisateurs. Comptez-vous vous en inspirer ?<\/h3><p>\nIl est important d&rsquo;avoir un &eacute;cosyst&egrave;me qui utilise une monnaie qui soit r&eacute;ellement d&eacute;centralis&eacute;e. Ajouter ces nouveaux produits qui attirent des utilisateurs, comme la gamification, est une excellente chose. J&rsquo;esp&egrave;re qu&rsquo;ils utiliseront un stablecoin d&eacute;centralis&eacute; pour cela.\n<\/p><h3>Pourquoi ?<\/h3><p>\nLes raisons de la d&eacute;centralisation sont nombreuses : la protection contre l&rsquo;autoritarisme, contre des gouvernements corrompus, la protection des droits humains &agrave; travers le monde, la possibilit&eacute; de bancariser les non bancaris&eacute;s. En Am&eacute;rique du Sud, ils utilisent la cryptomonnaie comme un moyen d&rsquo;acc&eacute;der au dollar am&eacute;ricain, par exemple.\n<\/p><h3>La th&eacute;matique des actifs du monde r&eacute;el (RWA, pour Real World Assets) a &eacute;merg&eacute; ces six derniers mois. Pourtant l&rsquo;USDT adoss&eacute; au dollar est un cas d&rsquo;usage depuis plusieurs ann&eacute;es. Croyez-vous que cette tendance va durer ?<\/h3><p>\nLe RWA est l&agrave; pour durer, et ne fait que commencer. Les stablecoins sont le meilleur cas d&rsquo;usage, et dominent massivement compte tenu du montant de transactions &eacute;chang&eacute;es. Je ne les vois pas s&rsquo;arr&ecirc;ter. Sans les RWA, la crypto serait probablement une industrie vou&eacute;e &agrave; dispara&icirc;tre.<\/p><hr><p>Sur le m&ecirc;me sujet :\n<\/p><ul>\n<li><a href=\"https:\/\/cryptonews.com\/fr\/news\/makerdao-nouveau-token-ngt-2024-mkr\/\">MakerDAO annonce un nouveau nom de token (NGT) pour 2024 : le prix du MKR explose<\/a><\/li>\n<li><a href=\"https:\/\/cryptonews.com\/fr\/news\/selon-fondateur-makerdao-stablecoins-decentralises-pourraient-regner-marche\/\">Selon le fondateur de MakerDAO, les stablecoins d&eacute;centralis&eacute;s pourraient r&eacute;gner sur le march&eacute;<\/a><\/li>\n<li><a href=\"https:\/\/cryptonews.com\/fr\/exclusives\/makerdao-annonce-phase-finale-endgamee-lancement-nouvelle-blockchain\/\">MakerDAO annonce la phase finale de &ldquo;Endgame&rdquo; avec le lancement d&rsquo;une nouvelle blockchain<\/a><\/li>\n<\/ul><p><!-- notionvc: feaa042b-6a23-4832-a2be-04e1ddfa3d95 --><\/p>","protected":false},"excerpt":{"rendered":"<p>Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les &eacute;volutions &agrave; venir sur l&rsquo;un des principaux protocoles DeFi sur Ethereum. Dans un r&eacute;cent post sur X, vous avez partag&eacute; vos r&eacute;flexions sur le futur de MakerDAO et son &eacute;cosyst&egrave;me. Pourquoi &eacute;tait-ce important de prendre la parole &agrave; ce moment-l&agrave; ? La raison [&hellip;]<\/p>\n","protected":false},"author":279,"featured_media":130720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,1,3],"tags":[266],"editors":[2550],"sponsored_companies":[],"class_list":["post-130384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-defi-news","category-news","category-people","tag-defi","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO<\/title>\n<meta name=\"description\" content=\"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO\" \/>\n<meta property=\"og:description\" content=\"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T10:49:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO\" \/>\n<meta name=\"twitter:description\" content=\"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO","description":"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/","og_locale":"fr_FR","og_type":"article","og_title":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO","og_description":"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/","og_site_name":"Cryptonews France","article_published_time":"2024-01-23T10:49:54+00:00","og_image":[{"width":1260,"height":630,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO","twitter_description":"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/"},"author":{"name":"Yann-Olivier Bricombert","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/44dc5126382375a9b8e8702dfcff8c1c"},"headline":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO","datePublished":"2024-01-23T10:49:54+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/"},"wordCount":791,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg","keywords":["DeFi"],"articleSection":["Actualit\u00e9s DeFi","News","Personnalit\u00e9s Crypto"],"inLanguage":"fr-FR","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/","name":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg","datePublished":"2024-01-23T10:49:54+00:00","description":"Contributeur actif de MakerDAO, le co-fondateur de Phoenix Labs revient sur les \u00e9volutions \u00e0 venir sur l\u2019un des principaux protocoles DeFi sur Ethereum.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2024\/01\/Interview-Entretien-Rencontre-Questions-.jpg","width":1260,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/interview-exclusive-sam-macpherson-phoenix-labs-makerdao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Interview exclusive avec Sam MacPherson, co-fondateur de Phoenix Labs, l\u2019un des leaders de MakerDAO"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/130384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/279"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=130384"}],"version-history":[{"count":12,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/130384\/revisions"}],"predecessor-version":[{"id":132385,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/130384\/revisions\/132385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media\/130720"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=130384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=130384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=130384"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=130384"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=130384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}