{"id":129971,"date":"2024-01-16T12:35:50","date_gmt":"2024-01-16T12:35:50","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=129971"},"modified":"2024-02-07T13:10:29","modified_gmt":"2024-02-07T13:10:29","slug":"trueusd-perd-ancrage-dollar","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/","title":{"rendered":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?"},"content":{"rendered":"<p><img decoding=\"async\" class='\"wp-image-127852' src=\"\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg%5C%22\" alt='\"\"' width='\"1260\"' height='\"630\"' srcset=\"https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg 1260w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute--300x150.jpg 300w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute--1024x512.jpg 1024w, https:\/\/cryptonews.com\/fr\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute--768x384.jpg 768w\" sizes=\"(max-width: 1260px) 100vw, 1260px\"><\/p><p>Le stablecoin TUSD chute de 1,5% par rapport &agrave; son prix r&eacute;f&eacute;rence de 1 dollar. Il s&rsquo;&eacute;change actuellement au prix <strong>de 0,966 dollar.<\/strong>\n<\/p><h2><b>Le Stablecoin TrueUSD (TUSD) dans le rouge<\/b><\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nLe stablecoin<strong> TrueUSD (TUSD)<\/strong>, cr&eacute;&eacute; par <a href=\"https:\/\/cryptonews.com\/fr\/news\/exchange-htx-recupere-8-millions-voles-mais-quel-prix\/\"><strong>Justin Sun<\/strong><\/a>, vient de passer dans la zone rouge, alors que des <strong>retraits massifs sont survenus <a href=\"https:\/\/cryptonews.com\/fr\/news\/pourquoi-lusdc-temporairement-decroche-dollar-binance\/\">sur Binance.<\/a><\/strong><\/p><p>En effet, la paire<strong> TUSD-USDT<\/strong> sur Binance a enregistr&eacute;e un volume de vente total d&rsquo;environ <strong>435,4 millions de dollars,<\/strong> dans les 24 derni&egrave;res heures. Avec <strong>369 millions de dollars<\/strong> d&rsquo;achats, le flux du TUSD est donc dans le n&eacute;gatif, avec une perte d&rsquo;environ <strong>66 millions de dollars.<\/strong><\/p><p>D&rsquo;apr&egrave;s les <a href=\"\/\/protos.com\/trueusd-attestations-paused-again-this-time-for-improper-balances\/%5C%22\" rel=\"sponsored\">analyses <strong>de Protos<\/strong><\/a>, ce &ldquo;depeg&rdquo; serait d&ucirc; &agrave; un effet de panique chez les investisseurs alors que <strong>les r&eacute;serves et la confiance envers Poloniex<\/strong> ont &eacute;t&eacute; remises en cause.\n<\/p><blockquote><p>&laquo; La vente massive du TUSD r&eacute;v&egrave;le la panique de ses d&eacute;tenteurs face aux incertitudes de ses ressources et &agrave; l&rsquo;instabilit&eacute; de Poloniex. Apr&egrave;s un incident de piratage qui a &eacute;t&eacute; d&eacute;tect&eacute; sur Poloniex, les d&eacute;tenteurs des TUSD se retrouvent dans une situation de plus en plus difficile pour trouver de la stabilit&eacute; avec le stablecoin index&eacute; sur l&rsquo;USD &raquo;, <b>d&eacute;clare Nick Ruck, directeur op&eacute;rationnel de ContentFi Labs, &agrave;<\/b><a href=\"\/\/www.theblock.co\/post\/272736\/trueusd-drops-below-1-peg-to-0-985-amid-selloff%5C%22\" rel=\"sponsored\"><b> The Block.<\/b><\/a><\/p><\/blockquote><blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">The realtime attests of TUSD stopped working since yesterday, which potentialy means that it was reported as undercollatelised. (see status description in the pic)<a href=\"https:\/\/twitter.com\/tusdio?ref_src=twsrc%5Etfw\">@tusdio<\/a> <a href=\"https:\/\/twitter.com\/The_NetworkFirm?ref_src=twsrc%5Etfw\">@The_NetworkFirm<\/a> any comments? <a href=\"https:\/\/t.co\/s4vsa7Gz4o\">pic.twitter.com\/s4vsa7Gz4o<\/a><\/p>\n<p>&mdash; Symbio (@NoCryptFish) <a href=\"https:\/\/twitter.com\/NoCryptFish\/status\/1745081696930660483?ref_src=twsrc%5Etfw\">January 10, 2024<\/a><\/p><\/blockquote><p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p><p>Pour rappel, l&rsquo;exchange Poloniex a subit de nombreux hacks l&rsquo;ann&eacute;e derni&egrave;re. Dont un &agrave; plus <a href=\"\/\/cryptonews.com\/fr\/news\/alerte-exchange-crypto-poloniex-hacke-100-millions-dollars\/\">de <b>100 millions de dollars,<\/b><\/a><b> en novembre dernier.<\/b><\/p><p>D&rsquo;apr&egrave;s les donn&eacute;es du syst&egrave;me d&rsquo;attestation, &ldquo;les soldes ripcord peuvent &ecirc;tre d&eacute;clench&eacute;es en raison d&rsquo;un d&eacute;s&eacute;quilibre effectif des passifs et des actifs correspondants.&rdquo; En somme, le TUSD a donc &eacute;tait attest&eacute; <strong>comme &ldquo;sous-collat&eacute;ralis&eacute;&rdquo;<\/strong>, t&eacute;moignant d&rsquo;un manque d&rsquo;actifs.\n<\/p><h2><b>D&rsquo;autres facteurs ont jou&eacute; leur r&ocirc;le ?<\/b><\/h2><p><span class=\"replacer\"><\/span><\/p><p>\nD&rsquo;apr&egrave;s <strong>Justin d&rsquo;Anethan,<\/strong> responsable du d&eacute;veloppement commercial chez <strong>Keyrock,<\/strong> le lancement <strong>du projet MANTA<\/strong> sur <a href=\"\/\/www.binance.com\/en\/support\/announcement\/introducing-manta-manta-on-binance-launchpool-farm-manta-by-staking-bnb-and-fdusd-d408406a0b594b2d82206f7ea9ca60bc%5C%22\" rel=\"sponsored\">le Binance Launchpool<\/a> aurait pouss&eacute; de nombreux investisseurs &agrave; retirer leurs actifs en TUSD pour investir dans le projet.\n<\/p><blockquote><p>&laquo; C&rsquo;est peut-&ecirc;tre un petit catalyseur, mais avec l&rsquo;annonce r&eacute;cente de MANTA dans le programme de lancement de Binance et la n&eacute;cessit&eacute; de parier du BNB ou du FDUSD &ndash; au d&eacute;triment d&rsquo;autres stablecoins comme le TUSD qui aurait pu &ecirc;tre utilis&eacute; dans le pass&eacute; pour le staking de lancement &ndash; une horde d&rsquo;investisseurs aurait vendu ce dernier pour le premier. &raquo;<b>, a d&eacute;clar&eacute; Justin d&rsquo;Anethan.<\/b><\/p><\/blockquote><hr><p>Source : <a href=\"\/\/www.theblock.co\/post\/272736\/trueusd-drops-below-1-peg-to-0-985-amid-selloff%5C%22\" rel=\"sponsored\">TheBlock<\/a>, <a href=\"\/\/protos.com\/trueusd-attestations-paused-again-this-time-for-improper-balances\/%5C%22\" rel=\"sponsored\">Protos<\/a><\/p><hr><p>Sur le m&ecirc;me sujet :\n<\/p><ul>\n<li>\n<p class=\"mb-10\"><a href=\"https:\/\/cryptonews.com\/fr\/news\/les-dernieres-nouvelles-sur-laffaire-autour-de-terra-et-do-kwon-on-fait-le-point\/\">Les derni&egrave;res nouvelles sur l&rsquo;affaire autour de Terra et Do Kwon : On fait le point<\/a><\/p>\n<\/li>\n<li>\n<p class='\"mb-10\"'><a href=\"\/\/cryptonews.com\/fr\/news\/etf-ethereum-comptant-mai-2024-jpmorgan-donne-son-avis\/\">Des ETF Ethereum au comptant d&egrave;s mai 2024 ? JPMorgan donne son avis<\/a><\/p>\n<\/li>\n<li>\n<p class=\"mb-10\"><a href=\"https:\/\/cryptonews.com\/fr\/news\/lexchange-hashkey-leve-somme-astronomique-100-millions-dollars\/\">L&rsquo;exchange HashKey l&egrave;ve la somme astronomique de 100 millions de dollars<\/a><\/p>\n<div class=\"row mb-20\"><\/div>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Le stablecoin TUSD chute de 1,5% par rapport &agrave; son prix r&eacute;f&eacute;rence de 1 dollar. Il s&rsquo;&eacute;change actuellement au prix de 0,966 dollar. Le Stablecoin TrueUSD (TUSD) dans le rouge Le stablecoin TrueUSD (TUSD), cr&eacute;&eacute; par Justin Sun, vient de passer dans la zone rouge, alors que des retraits massifs sont survenus sur Binance.En effet, [&hellip;]<\/p>\n","protected":false},"author":356,"featured_media":127852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,9,42],"tags":[],"editors":[2550],"sponsored_companies":[],"class_list":["post-129971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin-news","category-blockchain-news","category-finance-news","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?<\/title>\n<meta name=\"description\" content=\"Le stablecoin TUSD a chut\u00e9 jusqu&#039;au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?\" \/>\n<meta property=\"og:description\" content=\"Le stablecoin TUSD a chut\u00e9 jusqu&#039;au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-16T12:35:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T13:10:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1260\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?\" \/>\n<meta name=\"twitter:description\" content=\"Le stablecoin TUSD a chut\u00e9 jusqu&#039;au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@charl3li\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?","description":"Le stablecoin TUSD a chut\u00e9 jusqu'au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/","og_locale":"fr_FR","og_type":"article","og_title":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?","og_description":"Le stablecoin TUSD a chut\u00e9 jusqu'au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.","og_url":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/","og_site_name":"Cryptonews France","article_published_time":"2024-01-16T12:35:50+00:00","article_modified_time":"2024-02-07T13:10:29+00:00","og_image":[{"width":1260,"height":630,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?","twitter_description":"Le stablecoin TUSD a chut\u00e9 jusqu'au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.","twitter_image":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg","twitter_creator":"@charl3li","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/"},"author":{"name":"charlesledoux","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/6c8832201aa740c692c16649f8406986"},"headline":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?","datePublished":"2024-01-16T12:35:50+00:00","dateModified":"2024-02-07T13:10:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/"},"wordCount":595,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg","articleSection":["Actualit\u00e9s Altcoin","Actualit\u00e9s Blockchain","Actualit\u00e9s Finance"],"inLanguage":"fr-FR","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/","url":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/","name":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#primaryimage"},"thumbnailUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg","datePublished":"2024-01-16T12:35:50+00:00","dateModified":"2024-02-07T13:10:29+00:00","description":"Le stablecoin TUSD a chut\u00e9 jusqu'au 0,966 dollar alors que les investisseurs craignent un manque de r\u00e9serve.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#primaryimage","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/12\/Faillite-Bankrupt-chute-.jpg","width":1260,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/news\/trueusd-perd-ancrage-dollar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le TrueUSD perd son ancrage au dollar : Que s\u2019est-il pass\u00e9 ?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/129971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/356"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=129971"}],"version-history":[{"count":10,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/129971\/revisions"}],"predecessor-version":[{"id":131926,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/129971\/revisions\/131926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media\/127852"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=129971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=129971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=129971"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=129971"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=129971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}