{"id":107757,"date":"2023-09-04T10:41:00","date_gmt":"2023-09-04T10:41:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=124064"},"modified":"2023-09-04T10:44:15","modified_gmt":"2023-09-04T10:44:15","slug":"pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/","title":{"rendered":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg\" srcset=\"https:\/\/cimg.co\/news\/124064\/327712\/responsive-images\/pdg-gala-games___media_library_original_1260_630.jpg 1260w, https:\/\/cimg.co\/news\/124064\/327712\/responsive-images\/pdg-gala-games___media_library_original_1200_600.jpg 1200w, https:\/\/cimg.co\/news\/124064\/327712\/responsive-images\/pdg-gala-games___media_library_original_900_450.jpg 900w, https:\/\/cimg.co\/news\/124064\/327712\/responsive-images\/pdg-gala-games___media_library_original_720_360.jpg 720w, https:\/\/cimg.co\/news\/124064\/327712\/responsive-images\/pdg-gala-games___media_library_original_600_300.jpg 600w, https:\/\/cimg.co\/news\/124064\/327712\/responsive-images\/pdg-gala-games___media_library_original_300_150.jpg 300w\" width=\"1260\" class=\"content-img\" alt=\"\">C&rsquo;est une histoire qui pourrait faire sourire mais qui ne va certainement pas redorer le blason du monde des cryptos. Le <strong>PDG de Gala Games<\/strong> (une plateforme de jeux Web3 tr&egrave;s ax&eacute;e RPG), Eric Schiermeyer, <strong>a port&eacute; plainte contre son cofondateur Wright Thurston, l&rsquo;accusant d&rsquo;avoir vol&eacute; 8,6 milliards de jetons GALA<\/strong> d&eacute;but 2021 pour les revendre et se faire un <strong>pactole de 130 millions de dollars<\/strong>. Un <strong>cofondateur <\/strong>qui, quant &agrave; lui, v<strong>ient &eacute;galement de porter plainte contre son ancien associ&eacute;<\/strong>, lui reprochant d&rsquo;avoir utilis&eacute; les fonds de l&rsquo;entreprise pour des achats personnels, notamment un jet priv&eacute;. Ambiance&hellip;&nbsp;<\/p><h2>Une soci&eacute;t&eacute; fond&eacute;e en 2019&nbsp;<\/h2><span class=\"replacer\"><\/span><p>La <a href=\"https:\/\/cryptonews.com\/fr\/news\/prediction-prix-gala-pourquoi-jeton-de-la-plateforme-a-grimpe-de-65-fr\/\"><strong><u>valeur du token GALA<\/u><\/strong><\/a><strong> a chut&eacute; de 13% depuis l&rsquo;annonce<\/strong> de ces poursuites judiciaires. Une cons&eacute;quence assez courante des affaires de fraude comme celle-ci. Gala Games a &eacute;t&eacute; cofond&eacute;e par Thurston et Schiermeyer d&eacute;but 2019, chacun recevant une participation de 50 %. Michael McCarthy, qui est r&eacute;pertori&eacute; par certaines publications comme le troisi&egrave;me co-fondateur de la soci&eacute;t&eacute;, n&rsquo;est mentionn&eacute; dans aucun des 2 proc&egrave;s. La soci&eacute;t&eacute;, outre l&rsquo;&eacute;dition de RPG, a &eacute;galement des activit&eacute;s dans la musique, les films et les objets de collection num&eacute;riques bas&eacute;s sur la blockchain.<\/p><h2>Les accusations de Eric Schiermeyer&hellip;&nbsp;<\/h2><span class=\"replacer\"><\/span><p>Schiermeyer accuse donc <strong>Thurston d&rsquo;avoir vol&eacute; 8,6 milliards de jetons GALA en f&eacute;vrier 2021, soit plus de 100 % des tokens en circulation &agrave; l&rsquo;&eacute;poque<\/strong>, comme le rapportent les agr&eacute;gateurs de march&eacute;. Pour lui, cela consistait <strong>&agrave; prendre l&rsquo;entreprise en otage<\/strong>, car <strong>r&eacute;v&eacute;ler le vol de jetons l&rsquo;am&egrave;nerait &agrave; liquider ses avoirs<\/strong>, faisant ainsi s&rsquo;effondrer l&rsquo;&eacute;cosyst&egrave;me GALA. En mai 2023, en guise de solution partielle, <strong>la soci&eacute;t&eacute; a &eacute;mis <\/strong><a href=\"https:\/\/cryptonews.com\/fr\/news\/gala-games-un-airdrop-pour-la-deuxieme-version-du-gala\/\"><strong><u>des jetons Gala v2<\/u><\/strong><\/a> qui ont &eacute;t&eacute; annonc&eacute;s comme apportant &ldquo;une multitude d&rsquo;am&eacute;liorations&rdquo;. Schiermeyer<strong> affirme que le v&eacute;ritable objectif des nouveaux jetons &eacute;tait de rendre obsol&egrave;tes les jetons GALA dans les portefeuilles contr&ocirc;l&eacute;s par Thurston<\/strong> tout en laissant le reste de l&rsquo;&eacute;cosyst&egrave;me inchang&eacute;.<\/p><p>Enfin, dans sa plainte, Schiermeyer affirme &eacute;galement que <strong>Thurston &ldquo;a fond&eacute; de nombreuses soci&eacute;t&eacute;s, dont la plupart se sont retrouv&eacute;es en litige, insolvables, en faillite et\/ou poursuivies par la SEC<\/strong>&rdquo;, et affirme que Gala Games est la seule entreprise l&eacute;gitime dans laquelle Thurston a un int&eacute;r&ecirc;t. Ce dernier, qui ne compte pas se laisser faire, a &eacute;galement port&eacute; plainte contre son ancien associ&eacute;.&nbsp;<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" width=\"1200\" class=\"content-img lazyload\" alt=\"\" data-src=\"https:\/\/cimg.co\/news\/124064\/327713\/gala.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/124064\/327713\/responsive-images\/gala___media_library_original_1200_716.jpg 1200w, https:\/\/cimg.co\/news\/124064\/327713\/responsive-images\/gala___media_library_original_900_537.jpg 900w, https:\/\/cimg.co\/news\/124064\/327713\/responsive-images\/gala___media_library_original_720_430.jpg 720w, https:\/\/cimg.co\/news\/124064\/327713\/responsive-images\/gala___media_library_original_600_358.jpg 600w, https:\/\/cimg.co\/news\/124064\/327713\/responsive-images\/gala___media_library_original_300_179.jpg 300w\"><\/figure><h2>&hellip; Et celles de Wright Thurston<\/h2><span class=\"replacer\"><\/span><p>S&rsquo;il reconna&icirc;t dans sa plainte qu&rsquo;il n&rsquo;a pas r&eacute;ellement dirig&eacute; l&rsquo;entreprise, <strong>Wright Thurston accuse Schiermeyer d&rsquo;avoir \u00ab\u00a0fait fonctionner Gala sans sa contribution, l&#8217;emp&ecirc;chant ainsi d&rsquo;aider l&rsquo;entreprise &agrave; engranger des b&eacute;n&eacute;fices\u00a0\u00bb<\/strong>. Il affirme &eacute;galement que &ldquo;<strong>les malversations, la mauvaise gestion et les transactions int&eacute;ress&eacute;es de Schiermeyer ont entra&icirc;n&eacute; des centaines de millions de dollars de dommages &agrave; la r&eacute;putation de Gala et aux actifs de l&rsquo;entreprise et des actionnaires<\/strong>&rdquo;. Des actifs qui auraient notamment financ&eacute; l&rsquo;achat d&rsquo;un jet priv&eacute;.&nbsp;<\/p><p>La justice n&rsquo;a pour l&rsquo;instant pas communiqu&eacute; de calendrier concernant ces 2 plaintes mutuelles. Notons que <strong>Thurston a &eacute;galement &eacute;t&eacute; poursuivi par la SEC<\/strong> cette ann&eacute;e concernant <strong>une autre soci&eacute;t&eacute; qu&rsquo;il a fond&eacute;e, Green United LLC<\/strong>, qui, selon le gendarme financier am&eacute;ricain, a induit les investisseurs en erreur en investissant 18 millions de dollars dans une entreprise frauduleuse de crypto verte. Pas la meilleure des publicit&eacute;s en attendant le r&egrave;glement de ce litige.&nbsp;<\/p><p>Sources: <a href=\"https:\/\/www.theblock.co\/post\/248897\/gala-games-ceo-sues-co-founder-alleging-130-million-theft-pattern-of-deception\"><u>Theblock<\/u><\/a>, <a href=\"https:\/\/cointelegraph.com\/news\/gala-games-founders-sue-court-token-theft-corporate-waste\"><u>Cointelegraph<\/u><\/a>, <a href=\"https:\/\/beincrypto.com\/gala-games-legal-dispute\/\"><u>Beincrypto<\/u><\/a>&nbsp;<\/p><p><br>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est une histoire qui pourrait faire sourire mais qui ne va certainement pas redorer le blason du monde des cryptos. Le PDG de Gala Games (une plateforme de jeux Web3 tr&egrave;s ax&eacute;e RPG), Eric Schiermeyer, a port&eacute; plainte contre son cofondateur Wright Thurston, l&rsquo;accusant d&rsquo;avoir vol&eacute; 8,6 milliards de jetons GALA d&eacute;but 2021 pour les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3],"tags":[],"editors":[],"sponsored_companies":[],"class_list":["post-107757","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-people"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars<\/title>\n<meta name=\"description\" content=\"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars\" \/>\n<meta property=\"og:description\" content=\"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-04T10:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-04T10:44:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars\" \/>\n<meta name=\"twitter:description\" content=\"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars","description":"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/","og_locale":"fr_FR","og_type":"article","og_title":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars","og_description":"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/","og_site_name":"Cryptonews France","article_published_time":"2023-09-04T10:41:00+00:00","article_modified_time":"2023-09-04T10:44:15+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars","twitter_description":"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA","twitter_image":"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars","datePublished":"2023-09-04T10:41:00+00:00","dateModified":"2023-09-04T10:44:15+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/"},"wordCount":740,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg","articleSection":["Exclusives","Personnalit\u00e9s Crypto"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/","name":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg","datePublished":"2023-09-04T10:41:00+00:00","dateModified":"2023-09-04T10:44:15+00:00","description":"Eric Schiermeyer, PDG de Gala Games, accuse le cofondateur Wright Thurston d\u2019avoir vol\u00e9 8,6 milliards de jetons GALA","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#primaryimage","url":"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg","contentUrl":"https:\/\/cimg.co\/news\/124064\/327712\/pdg-gala-games.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/pdg-gala-games-accuse-son-cofondateur-davoir-vole-130-millions-de-dollars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Le PDG de Gala Games accuse son cofondateur d\u2019avoir vol\u00e9 130 millions de dollars"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/107757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=107757"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/107757\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=107757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=107757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=107757"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=107757"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=107757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}