{"id":107720,"date":"2023-09-01T10:25:00","date_gmt":"2023-09-01T10:25:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=123937"},"modified":"2023-09-01T10:34:04","modified_gmt":"2023-09-01T10:34:04","slug":"star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/","title":{"rendered":"La star du football Ronaldinho d\u00e9ment son implication dans une escroquerie crypto de plus de 60 millions $"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg\" alt=\"Ronaldinho d&eacute;ment toute implication dans une escroquerie crypto de 60 millions $\" srcset=\"https:\/\/cimg.co\/news\/123937\/327433\/responsive-images\/ronaldinho-escroquerie-crypto___media_library_original_1260_630.jpg 1260w, https:\/\/cimg.co\/news\/123937\/327433\/responsive-images\/ronaldinho-escroquerie-crypto___media_library_original_1200_600.jpg 1200w, https:\/\/cimg.co\/news\/123937\/327433\/responsive-images\/ronaldinho-escroquerie-crypto___media_library_original_900_450.jpg 900w, https:\/\/cimg.co\/news\/123937\/327433\/responsive-images\/ronaldinho-escroquerie-crypto___media_library_original_720_360.jpg 720w, https:\/\/cimg.co\/news\/123937\/327433\/responsive-images\/ronaldinho-escroquerie-crypto___media_library_original_600_300.jpg 600w, https:\/\/cimg.co\/news\/123937\/327433\/responsive-images\/ronaldinho-escroquerie-crypto___media_library_original_300_150.jpg 300w\" width=\"1260\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">La l&eacute;gende du football, <strong>Ronaldinho, a r&eacute;cemment d&eacute;menti toute implication<\/strong> dans une affaire d&rsquo;escroquerie aux cryptomonnaies estim&eacute;e &agrave; plus de 60 millions de dollars. Lors d&rsquo;une audience au Congr&egrave;s, l&rsquo;ancien joueur professionnel a affirm&eacute; que son image avait &eacute;t&eacute; utilis&eacute;e &agrave; mauvais escient pour promouvoir un programme en crypto suppos&eacute;ment frauduleux.<\/p><h2>Le t&eacute;moignage de Ronaldinho devant le Congr&egrave;s br&eacute;silien<\/h2><span class=\"replacer\"><\/span><p>Ronaldinho, la star &agrave; la retraite du football professionnel, s&rsquo;est r&eacute;cemment exprim&eacute; <a href=\"https:\/\/www.youtube.com\/live\/YO0xjCZcdOA?si=AfJg3-lj3Z1Hf-MI\">devant une commission d&rsquo;enqu&ecirc;te<\/a> parlementaire au Br&eacute;sil. <strong>Il a fermement ni&eacute; toute implication dans le pr&eacute;tendu sch&eacute;ma de pyramide en crypto<\/strong>, <strong>nomm&eacute; \u00ab\u00a018kRonaldinho\u00a0\u00bb<\/strong>, qui promettait aux investisseurs un rendement quotidien de 2&thinsp;% sur leurs investissements en cryptomonnaie.<\/p><p>Suite &agrave; ces all&eacute;gations, une action en justice a &eacute;t&eacute; intent&eacute;e contre la soci&eacute;t&eacute;,<strong> r&eacute;clamant pas moins de 61 millions de dollars<\/strong> de dommages et int&eacute;r&ecirc;ts.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" width=\"1024\" class=\"content-img lazyload\" alt=\"\" data-src=\"https:\/\/cimg.co\/news\/123937\/327429\/ronaldinho-18k-escroqueri.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/123937\/327429\/responsive-images\/ronaldinho-18k-escroqueri___media_library_original_1024_618.jpg 1024w, https:\/\/cimg.co\/news\/123937\/327429\/responsive-images\/ronaldinho-18k-escroqueri___media_library_original_900_543.jpg 900w, https:\/\/cimg.co\/news\/123937\/327429\/responsive-images\/ronaldinho-18k-escroqueri___media_library_original_720_435.jpg 720w, https:\/\/cimg.co\/news\/123937\/327429\/responsive-images\/ronaldinho-18k-escroqueri___media_library_original_600_362.jpg 600w, https:\/\/cimg.co\/news\/123937\/327429\/responsive-images\/ronaldinho-18k-escroqueri___media_library_original_300_181.jpg 300w\"><figcaption><i>Source : Criptoeconomia<\/i><\/figcaption><\/figure><h2>L&rsquo;utilisation non autoris&eacute;e de son image<\/h2><span class=\"replacer\"><\/span><p>L&rsquo;ancien joueur de football a exprim&eacute; que <strong>son nom et son image avaient &eacute;t&eacute; utilis&eacute;s sans son autorisation<\/strong>. Selon lui, les photos utilis&eacute;es dans les supports marketing de \u00ab\u00a018kRonaldinho\u00a0\u00bb &eacute;taient issues d&rsquo;un contrat qu&rsquo;il avait sign&eacute; en juillet 2019 avec une filiale de la soci&eacute;t&eacute; en question.<\/p><p>Cependant, ce contrat, qui portait <strong>sur la vente de montres<\/strong>, a &eacute;t&eacute; r&eacute;sili&eacute; en octobre de la m&ecirc;me ann&eacute;e et n&rsquo;a jamais &eacute;t&eacute; mis en &oelig;uvre. Ronaldinho se positionne donc &eacute;galement <strong>comme une victime<\/strong> de cette pr&eacute;sum&eacute;e escroquerie.<\/p><h2>Le silence sur les remboursements et les cons&eacute;quences l&eacute;gales<\/h2><span class=\"replacer\"><\/span><p>Lors de l&rsquo;audience, Aureo Ribeiro, pr&eacute;sident de la commission d&rsquo;enqu&ecirc;te, a pos&eacute; &agrave; Ronaldinho la question sensible du remboursement potentiel des investisseurs l&eacute;s&eacute;s. &Agrave; cela, <strong>Ronaldinho a choisi de garder le silence<\/strong>.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"Aureo Ribeiro : &amp;quot;La commission d&amp;#039;enqu&ecirc;te n&amp;#039;a pas l&amp;#039;intention d&amp;#039;&eacute;touffer le march&eacute; des actifs cryptographiques&amp;quot;\" width=\"768\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/123937\/327430\/aureo-ribeiro-ronaldinho.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/123937\/327430\/responsive-images\/aureo-ribeiro-ronaldinho___media_library_original_768_512.jpg 768w, https:\/\/cimg.co\/news\/123937\/327430\/responsive-images\/aureo-ribeiro-ronaldinho___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/123937\/327430\/responsive-images\/aureo-ribeiro-ronaldinho___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/123937\/327430\/responsive-images\/aureo-ribeiro-ronaldinho___media_library_original_300_200.jpg 300w\"><figcaption>Aureo Ribeiro : \u00ab\u00a0La commission d&rsquo;enqu&ecirc;te n&rsquo;a pas l&rsquo;intention d&rsquo;&eacute;touffer le march&eacute; des actifs cryptographiques\u00a0\u00bb. <i>Source : <\/i><a href=\"https:\/\/www.camara.leg.br\/noticias\/971028-INSTALADA-NA-CAMARA-A-CPI-DAS-PIRAMIDES-FINANCEIRAS,-QUE-VAI-INVESTIGAR-O-MERCADO-DE-CRIPTOMOEDAS\"><i>Camara<\/i><\/a><i>&nbsp;<\/i><\/figcaption><\/figure><p>Il est &eacute;galement rest&eacute; muet sur la question de <strong>l&rsquo;action en justice de 61 millions de dollars intent&eacute;e contre lui<\/strong>. Avant cette audience, Ronaldinho avait d&eacute;j&agrave; manqu&eacute; deux convocations ant&eacute;rieures, invoquant des conditions m&eacute;t&eacute;orologiques d&eacute;favorables comme raison de son absence.<\/p><h2>Une enqu&ecirc;te plus large sur les escroqueries en cryptomonnaies<\/h2><span class=\"replacer\"><\/span><p>Il convient de noter que cette audience s&rsquo;inscrit dans le cadre d&rsquo;une enqu&ecirc;te plus large lanc&eacute;e en juin par la Chambre des d&eacute;put&eacute;s du Br&eacute;sil. L&rsquo;enqu&ecirc;te vise &agrave; &eacute;claircir <strong>les activit&eacute;s de 11 entreprises<\/strong>, toutes suspect&eacute;es par la Commission des valeurs mobili&egrave;res du pays d&rsquo;avoir promis faussement <strong>des rendements &eacute;lev&eacute;s<\/strong> gr&acirc;ce &agrave; des investissements en cryptomonnaies.<\/p><p>Ce n&rsquo;est pas la premi&egrave;re fois que le Br&eacute;sil est confront&eacute; &agrave; des affaires de fraudes en cryptomonnaie impliquant des figures publiques. En 2022, la police br&eacute;silienne a d&eacute;mantel&eacute; <a href=\"https:\/\/cryptonews.com\/fr\/news\/bresil-la-police-met-fin-a-une-pyramide-crypto-de-769-millions-de-dollars-qui-attirait-des-celebrites\/\">un sch&eacute;ma de pyramide en crypto<\/a> qui aurait <strong>attir&eacute; non seulement des joueurs de football, mais aussi des mannequins de haut niveau<\/strong>, le tout pour un montant &eacute;tonnant de 769 millions de dollars.<\/p><p><i>Source : <\/i><a href=\"https:\/\/cointelegraph.com\/news\/ronaldinho-refutes-role-crypto-pyramid-scheme\"><i>Cointelegraph<\/i><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>La l&eacute;gende du football, Ronaldinho, a r&eacute;cemment d&eacute;menti toute implication dans une affaire d&rsquo;escroquerie aux cryptomonnaies estim&eacute;e &agrave; plus de 60 millions de dollars. Lors d&rsquo;une audience au Congr&egrave;s, l&rsquo;ancien joueur professionnel a affirm&eacute; que son image avait &eacute;t&eacute; utilis&eacute;e &agrave; mauvais escient pour promouvoir un programme en crypto suppos&eacute;ment frauduleux.Le t&eacute;moignage de Ronaldinho devant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2,3],"tags":[],"editors":[2550],"sponsored_companies":[],"class_list":["post-107720","post","type-post","status-publish","format-standard","hentry","category-exclusives","category-people","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $<\/title>\n<meta name=\"description\" content=\"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d&#039;une audience parlementaire au Br\u00e9sil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $\" \/>\n<meta property=\"og:description\" content=\"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d&#039;une audience parlementaire au Br\u00e9sil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T10:25:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T10:34:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $\" \/>\n<meta name=\"twitter:description\" content=\"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d&#039;une audience parlementaire au Br\u00e9sil.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/123937\/327429\/ronaldinho-18k-escroqueri.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $","description":"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d'une audience parlementaire au Br\u00e9sil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/","og_locale":"fr_FR","og_type":"article","og_title":"Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $","og_description":"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d'une audience parlementaire au Br\u00e9sil.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/","og_site_name":"Cryptonews France","article_published_time":"2023-09-01T10:25:00+00:00","article_modified_time":"2023-09-01T10:34:04+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $","twitter_description":"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d'une audience parlementaire au Br\u00e9sil.","twitter_image":"https:\/\/cimg.co\/news\/123937\/327429\/ronaldinho-18k-escroqueri.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/"},"author":{"name":"giedrius","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/5d79e712f570715212460260f4f9cc0f"},"headline":"La star du football Ronaldinho d\u00e9ment son implication dans une escroquerie crypto de plus de 60 millions $","datePublished":"2023-09-01T10:25:00+00:00","dateModified":"2023-09-01T10:34:04+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/"},"wordCount":641,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg","articleSection":["Exclusives","Personnalit\u00e9s Crypto"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/","name":"Ronaldinho d\u00e9ment toute implication dans une escroquerie crypto de 60 millions $","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg","datePublished":"2023-09-01T10:25:00+00:00","dateModified":"2023-09-01T10:34:04+00:00","description":"La star du football Ronaldinho d\u00e9ment toute implication dans une pr\u00e9tendue escroquerie en cryptomonnaie de plus de 60 millions de dollars lors d'une audience parlementaire au Br\u00e9sil.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#primaryimage","url":"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg","contentUrl":"https:\/\/cimg.co\/news\/123937\/327433\/ronaldinho-escroquerie-crypto.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/star-football-ronaldinho-dement-implication-escroquerie-crypto-plus-60-millions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La star du football Ronaldinho d\u00e9ment son implication dans une escroquerie crypto de plus de 60 millions $"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/107720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=107720"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/107720\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=107720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=107720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=107720"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=107720"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=107720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}