{"id":105535,"date":"2023-04-18T04:52:00","date_gmt":"2023-04-18T04:52:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=110601"},"modified":"2023-06-26T11:06:43","modified_gmt":"2023-06-26T11:06:43","slug":"kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/","title":{"rendered":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg\" srcset=\"https:\/\/cimg.co\/news\/110601\/267769\/responsive-images\/1500x500-2___media_library_original_1500_500.jpeg 1500w, https:\/\/cimg.co\/news\/110601\/267769\/responsive-images\/1500x500-2___media_library_original_1200_400.jpeg 1200w, https:\/\/cimg.co\/news\/110601\/267769\/responsive-images\/1500x500-2___media_library_original_900_300.jpeg 900w, https:\/\/cimg.co\/news\/110601\/267769\/responsive-images\/1500x500-2___media_library_original_720_240.jpeg 720w, https:\/\/cimg.co\/news\/110601\/267769\/responsive-images\/1500x500-2___media_library_original_600_200.jpeg 600w, https:\/\/cimg.co\/news\/110601\/267769\/responsive-images\/1500x500-2___media_library_original_300_100.jpeg 300w\" width=\"1500\" class=\"content-img\" alt=\"\"><figcaption>Source : Twitter\/Kyber Network<\/figcaption><\/figure><p class=\"wp-block-paragraph\">Lundi, le 17 avril, Kyber Network, le promoteur de Kyberswap Elastic, la plateforme d&rsquo;&eacute;change de crypto-monnaie d&eacute;centralis&eacute;e, a annonc&eacute; une <a href=\"https:\/\/cryptonews.com\/fr\/exclusives\/etherscan-explorateur-blockchain-prevenir-eventuelles-escroqueries\/\"><strong>potentielle faille <\/strong><\/a>dans les contrats de la plateforme. En cons&eacute;quence, Kyber Network a conseill&eacute; &agrave; tous les investisseurs de retirer leurs fonds le plus rapidement possible.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/KyberNetwork\/status\/1647920799557505028?s=20\"><\/oembed><\/figure><p>Selon le d&eacute;veloppeur, aucune perte de fonds n&rsquo;est &agrave; d&eacute;plorer. Toutefois, par mesure de pr&eacute;caution, il a recommand&eacute; aux <strong>fournisseurs de liquidit&eacute;s<\/strong> (LPs) de retirer leurs fonds. Par ailleurs, le risque ne concerne que les fonds de Kyberswap Elastic. Selon l&rsquo;&eacute;quipe, la faille ne concerne pas les contrats intelligents Kyberswap Classic.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/KyberNetwork\/status\/1648000584145055744?s=20\"><\/oembed><\/figure><p>Dans un message s&eacute;par&eacute;, l&rsquo;&eacute;quipe de Kyber Network a fait savoir que les r&eacute;compenses du <strong>programme Farming <\/strong>seront temporairement suspendues jusqu&rsquo;au d&eacute;ploiement d&rsquo;un nouveau contrat intelligent. Toutes les r&eacute;compenses obtenues avant le 18 avril 2023, 23 h (GMT+7) ont fait l&rsquo;objet d&rsquo;une r&eacute;partition et ne sont pas affect&eacute;es par cette pause.<\/p><p><strong>Le d&eacute;veloppeur de la plateforme<\/strong> a indiqu&eacute; que la communaut&eacute; sera bient&ocirc;t inform&eacute;e de la date &agrave; laquelle les fonds pourront &ecirc;tre &agrave; nouveau d&eacute;pos&eacute;s en toute s&eacute;curit&eacute; dans le protocole.<\/p><p>Selon ses documents officiels, <strong>KyberSwap Elastic <\/strong>est une plateforme d&rsquo;&eacute;change d&eacute;centralis&eacute;e (DEX) gr&acirc;ce &agrave; laquelle les LPs peuvent fournir une \u00ab\u00a0liquidit&eacute; concentr&eacute;e.\u00a0\u00bb L&rsquo;id&eacute;e n&rsquo;est pas de les obliger &agrave; fournir de la liquidit&eacute; &agrave; n&rsquo;importe quel prix, mais de leur permettre de fixer un prix plafond et un prix plancher pour les jetons qu&rsquo;ils d&eacute;posent dans le pool.<\/p><p>Si le prix passe en dessous du plancher ou au-dessus du plafond, les LP ne per&ccedil;oivent plus de frais. En revanche, si le prix reste dans la fourchette qu&rsquo;ils ont fix&eacute;e, ils toucheront des commissions plus &eacute;lev&eacute;es. Ce syst&egrave;me est &agrave; l&rsquo;oppos&eacute; de la <strong>pr&eacute;c&eacute;dente version du DEX<\/strong>, KyberSwap Classic. En effet, ce dernier ne permettait pas de concentrer les liquidit&eacute;s.<\/p><h2>Un piratage de KyberSwap op&eacute;r&eacute; en septembre 2022<\/h2><span class=\"replacer\"><\/span><p>En septembre dernier, l&rsquo;interface utilisateur de KyberSwap a &eacute;t&eacute; pirat&eacute;e, et un hacker s&rsquo;&eacute;tait empar&eacute; de la somme de 265 000 dollars en crypto-monnaie. Apr&egrave;s avoir ouvert une enqu&ecirc;te, la plateforme a offert au pirate, <strong>une prime de 10 % des fonds vol&eacute;s<\/strong>, soit environ 40 000 dollars pour restituer les fonds.<\/p><p>Apr&egrave;s deux heures d&rsquo;investigation, l&rsquo;attaque avait &eacute;t&eacute; identifi&eacute;e et neutralis&eacute;e. Elle portait sur un FE et n&rsquo;avait pas affect&eacute; les contrats intelligents. De m&ecirc;me qu&rsquo;aujourd&rsquo;hui, KyberSwap avait appel&eacute; les utilisateurs &agrave; la prudence dans leurs &eacute;changes avec la plateforme. M&ecirc;me si elle soutenait qu&rsquo;elle &eacute;tait s&ucirc;re, elle conseillait de v&eacute;rifier les <strong>informations du destinataire<\/strong> et l&rsquo;adresse du contrat en cas de transaction.<\/p><p>De son c&ocirc;t&eacute;, <a href=\"https:\/\/cryptonews.com\/fr\/news\/les-difficultes-bancaires-de-binanceus-pourraient-ralentir-ses-activites\/\"><strong>Binance<\/strong><\/a> avait aussi ouvert une enqu&ecirc;te ind&eacute;pendante pour attraper le pirate et restituer les fonds de KyberSwap. Dans son enqu&ecirc;te, l&rsquo;&eacute;quipe de s&eacute;curit&eacute; de Binance a r&eacute;ussi &agrave; r&eacute;duire le nombre de suspects &agrave; deux individus. Par la suite, elle a envoy&eacute; les informations recueillies sur ces suspects &agrave; <strong>l&rsquo;&eacute;quipe de KyberSwap<\/strong>.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/cz_binance\/status\/1565976776710430721?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1565976776710430721%7Ctwgr%5Ef7df9e5484217464248ecdf6fd65d40443dd667a%7Ctwcon%5Es1_c10&amp;ref_url=https%3A%2F%2Ffr.cointelegraph.com%2Fnews%2Fbinance-identifies-kyberswap-hack-suspects-involves-law-enforcement\"><\/oembed><\/figure><p>Toujours dans le cadre de son enqu&ecirc;te personnelle, Binance s&rsquo;est associ&eacute;e aux forces de l&rsquo;ordre pour mener une chasse &agrave; l&rsquo;homme contre ce cybercriminel. Il faut noter que <strong>l&rsquo;action de Binance<\/strong> &eacute;tait tout &agrave; fait d&eacute;sint&eacute;ress&eacute;e et ne visait qu&rsquo;&agrave; venir en aide &agrave; une autre plateforme de crypto en difficult&eacute;.<\/p><p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Source : Twitter\/Kyber NetworkLundi, le 17 avril, Kyber Network, le promoteur de Kyberswap Elastic, la plateforme d&rsquo;&eacute;change de crypto-monnaie d&eacute;centralis&eacute;e, a annonc&eacute; une potentielle faille dans les contrats de la plateforme. En cons&eacute;quence, Kyber Network a conseill&eacute; &agrave; tous les investisseurs de retirer leurs fonds le plus rapidement possible.Selon le d&eacute;veloppeur, aucune perte de fonds [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2032],"sponsored_companies":[],"class_list":["post-105535","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-pauline-eyebe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible<\/title>\n<meta name=\"description\" content=\"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible\" \/>\n<meta property=\"og:description\" content=\"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-18T04:52:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible\" \/>\n<meta name=\"twitter:description\" content=\"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible","description":"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/","og_locale":"fr_FR","og_type":"article","og_title":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible","og_description":"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/","og_site_name":"Cryptonews France","article_published_time":"2023-04-18T04:52:00+00:00","article_modified_time":"2023-06-26T11:06:43+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible","twitter_description":"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.","twitter_image":"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/"},"author":{"name":"upeyebeqsk","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/9c70beb09a257825283d4ed565f77da5"},"headline":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible","datePublished":"2023-04-18T04:52:00+00:00","dateModified":"2023-06-26T11:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/"},"wordCount":712,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/","name":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg","datePublished":"2023-04-18T04:52:00+00:00","dateModified":"2023-06-26T11:06:43+00:00","description":"KyberSwap signale une vuln\u00e9rabilit\u00e9 potentielle et demande aux LPs de se retirer le plus rapidement possible.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#primaryimage","url":"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg","contentUrl":"https:\/\/cimg.co\/news\/110601\/267769\/1500x500-2.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/kyberswap-potentiellement-vulnerable-investisseurs-retirer-fonds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"KyberSwap est potentiellement vuln\u00e9rable : les investisseurs doivent retirer leur fonds le plus rapidement possible"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=105535"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105535\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=105535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=105535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=105535"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=105535"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=105535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}