{"id":105525,"date":"2023-04-17T16:53:00","date_gmt":"2023-04-17T16:53:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=110557"},"modified":"2023-06-26T11:06:43","modified_gmt":"2023-06-26T11:06:43","slug":"recours-collectif-ftx-shaquille-oneal-notifie-proces","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/","title":{"rendered":"Recours collectif FTX : Shaquille O&rsquo;Neal finalement notifi\u00e9"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/110557\/267642\/responsive-images\/fkm0krmwiamnarf___media_library_original_680_383.jpeg 680w, https:\/\/cimg.co\/news\/110557\/267642\/responsive-images\/fkm0krmwiamnarf___media_library_original_600_338.jpeg 600w, https:\/\/cimg.co\/news\/110557\/267642\/responsive-images\/fkm0krmwiamnarf___media_library_original_300_169.jpeg 300w\" sizes=\"100vw\" width=\"680\" class=\"content-img\"><figcaption>Shaquille Oneal. Source : Twitter\/BitcoinAgile<\/figcaption><\/figure><p class=\"wp-block-paragraph\"><strong>Shaquille Oneal<\/strong>, la star du basket-ball, a finalement fait l&rsquo;objet d&rsquo;une assignation en justice. Les avocats en charge d&rsquo;un recours collectif dans l&rsquo;affaire FTX ont notifi&eacute; &agrave; Shaquille O&rsquo;Neal. La star du basket et ancien promoteur de <a href=\"https:\/\/cryptonews.com\/fr\/news\/ftx-recupere-73-milliards-de-dollars-dactifs-redemarrage-exchange-deuxieme-trimestre-de-cette-annee\/\"><strong>FTX<\/strong><\/a> a re&ccedil;u une assignation &agrave; compara&icirc;tre ce dimanche devant son domicile &agrave; Atlanta.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/effect2domino\/status\/1647837107090599936?s=20\"><\/oembed><\/figure><p>En compagnie de plus d&rsquo;une douzaine de c&eacute;l&eacute;brit&eacute;s et d&rsquo;&eacute;quipes sportives, O&rsquo;Neal est poursuivi en justice pour <strong>la promotion de FTX<\/strong>, la plateforme d&rsquo;&eacute;change de crypto-monnaie aujourd&rsquo;hui en faillite. Son soutien pour la plateforme FTX a &eacute;t&eacute; tel que la soci&eacute;t&eacute; l&rsquo;a surnomm&eacute; \u00ab\u00a0Shaqtoshi\u00a0\u00bb, en r&eacute;f&eacute;rence &agrave; Satoshi Nakamoto, le nom de l&rsquo;auteur pr&eacute;sum&eacute; du livre blanc sur le bitcoin.<\/p><h2>Une notification en suspens depuis pr&egrave;s de trois mois<\/h2><span class=\"replacer\"><\/span><p>Depuis trois mois, des avocats le traquent, O&rsquo;Neal se dissimule au vu et au su de tous. En effet, il fait r&eacute;guli&egrave;rement des apparitions &agrave; la t&eacute;l&eacute;vision, poss&egrave;de son propre podcast et est un DJ itin&eacute;rant sous le nom de \u00ab\u00a0<strong>DJ Diesel<\/strong>\u00ab\u00a0. Pourtant, malgr&eacute; tout, les huissiers de justice ont eu bien du mal &agrave; faire savoir &agrave; O&rsquo;Neal qu&rsquo;il &eacute;tait la cible d&rsquo;un proc&egrave;s.<\/p><p>Apr&egrave;s plusieurs tentatives, O&rsquo;Neal a finalement re&ccedil;u une notification &agrave; son domicile, dimanche apr&egrave;s-midi, et les avocats affirment que l&rsquo;&eacute;change a &eacute;t&eacute; enregistr&eacute; sur une vid&eacute;o. C&rsquo;est Edwin Garrison, <strong>un client de FTX<\/strong> de l&rsquo;Oklahoma, qui est &agrave; l&rsquo;origine de la plainte. Le dossier est trait&eacute; par les avocats Adam Moskowitz et David Boies. The Block a &eacute;t&eacute; le premier &agrave; &ecirc;tre inform&eacute; de la nouvelle.<\/p><p><strong>Ma&icirc;tre Moskowitz <\/strong>a d&eacute;clar&eacute; dans un courriel :&nbsp;<\/p><blockquote><p>\u00a0\u00bb Nous avons personnellement remis &agrave; Shaquille O&rsquo;Neal, devant sa r&eacute;sidence, &agrave; 16 heures, une copie de notre plainte \u00ab\u00a0. \u00a0\u00bb Les instructions du juge Moore ont &eacute;t&eacute; prises tr&egrave;s au s&eacute;rieux et nous sommes heureux de mettre enfin un terme &agrave; ce cirque stupide. \u00ab\u00a0<\/p><\/blockquote><h2>La chasse &agrave; O&rsquo;Neal a tourn&eacute; au d&eacute;sespoir<\/h2><span class=\"replacer\"><\/span><p>&Agrave; la veille de la date butoir de lundi, les avocats manquaient de temps pour notifier <a href=\"https:\/\/cryptonews.com\/fr\/exclusives\/shaq-says-he-wont-invest-in-crypto-until-he-understands-it-fr\/\"><strong>l&rsquo;ex-joueur de basketball<\/strong><\/a>. Dans leur d&eacute;sespoir, ils ont saisi un juge pour obtenir l&rsquo;autorisation de notifier le chroniqueur sportif via Twitter, Instagram et par courriel.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/UPresss\/status\/1646340227328536577?s=20\"><\/oembed><\/figure><p>Mais leur demande a essuy&eacute; un &eacute;chec et par la suite, le cabinet de Moskowitz a d&eacute;cid&eacute; d&rsquo;envoyer un tweet &agrave; O&rsquo;Neal depuis l&rsquo;ext&eacute;rieur des studios de TNT &agrave; Atlanta, o&ugrave; O&rsquo;Neal participe &agrave; l&rsquo;&eacute;mission \u00ab\u00a0<strong>The NBA on TNT<\/strong>\u00ab\u00a0.<\/p><p>Selon les avocats, l&rsquo;&eacute;change entre <strong>O&rsquo;Neal et un huissier <\/strong>de justice a &eacute;t&eacute; enregistr&eacute; sur une vid&eacute;o, qui n&rsquo;a toutefois pas encore &eacute;t&eacute; diffus&eacute;e. De son c&ocirc;t&eacute;, O&rsquo;Neal ne s&rsquo;est pas encore exprim&eacute; sur le sujet et a d&eacute;clin&eacute; toute demande de commentaire.<\/p><p>Pour sa part, Ma&icirc;tre Moskowitz a d&eacute;clar&eacute; :&nbsp;<\/p><blockquote><p>\u00ab\u00a0Les cam&eacute;ras de surveillance du domicile de M. O&rsquo;Neal ont enregistr&eacute; notre pr&eacute;sence. Ce dernier n&rsquo;a pas autorit&eacute; &agrave; d&eacute;truire ou &agrave; effacer ces enregistrements, car ils sont indispensables &agrave; la poursuite de notre action en justice. \u00ab\u00a0<\/p><\/blockquote><p>D&eacute;sormais, il reste &agrave; Superman de se pr&eacute;senter devant un tribunal f&eacute;d&eacute;ral o&ugrave; il devra expliquer &agrave; ses millions de fans les raisons de sa campagne de <strong>publicit&eacute; mensong&egrave;re \u00ab\u00a0FTX<\/strong> : I Am All In\u00a0\u00bb (FTX : je suis &agrave; fond).<\/p><p><strong>\u00ab\u00a0Shaq Diesel\u00a0\u00bb<\/strong> n&rsquo;est pas la seule c&eacute;l&eacute;brit&eacute; embourb&eacute;e dans ce recours collectif contre FTX. En effet, dans cette affaire, on retrouve &eacute;galement la star du football Tom Brady, Naomi Osaka, la joueuse de tennis et Larry David, le cr&eacute;ateur de l&rsquo;&eacute;mission Seinfeld.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/DGRCoin\/status\/1635677582015483909?s=20\"><\/oembed><\/figure><p>\u00ab\u00a0DJ Diesel\u00a0\u00bb, qui, selon M. Moskowitz, \u00ab\u00a0se cache de nos huissiers de justice depuis trois mois\u00a0\u00bb, a &eacute;t&eacute; la derni&egrave;re personnalit&eacute; &agrave; recevoir une <strong>signification<\/strong> dimanche. L&rsquo;affaire sera jug&eacute;e par le tribunal de premi&egrave;re instance du district sud de la Floride.<\/p><h2>De nombreuses difficult&eacute;s pour notifier les c&eacute;l&eacute;brit&eacute;s dans le cadre d&rsquo;une proc&eacute;dure judiciaire<\/h2><span class=\"replacer\"><\/span><p>Selon les avocats, <strong>notifier Shaq<\/strong> a &eacute;t&eacute; si difficile qu&rsquo;un huissier de justice a renonc&eacute; apr&egrave;s avoir re&ccedil;u un message textuel mena&ccedil;ant apparemment sa femme, Beth Shaw.<\/p><p>Selon des <strong>conclusions du tribunal<\/strong>, le message disait : \u00ab\u00a0Shaq vit aux Bahamas, putain d&rsquo;idiot, transmettez mes salutations &agrave; Beth Shaw\u00a0\u00bb. L&rsquo;identit&eacute; de l&rsquo;exp&eacute;diteur du message reste incertaine.<\/p><p>La notification de \u00ab\u00a0<strong>Shaq Fu<\/strong>\u00a0\u00bb est un exemple flagrant de la difficult&eacute; qu&rsquo;il y a &agrave; notifier une c&eacute;l&eacute;brit&eacute;, m&ecirc;me si elle appara&icirc;t souvent en public. Selon les documents d&eacute;pos&eacute;s au tribunal, il appara&icirc;t que Shaquille O&rsquo;Neal poss&egrave;de des r&eacute;sidences en Floride, en G&eacute;orgie, au Nevada, en Californie et aux Bahamas. Les avocats s&rsquo;&eacute;taient concentr&eacute;s sur sa r&eacute;sidence au Texas parce qu&rsquo;il y d&eacute;veloppe sa franchise de restaurant<strong> Big Chicken<\/strong>.<\/p><p><strong>Suite &agrave; la faillite de la plateforme d&rsquo;&eacute;change de crypto<\/strong>, O&rsquo;Neal a cherch&eacute; &agrave; prendre ses distances avec FTX. C&rsquo;est ainsi qu&rsquo;apr&egrave;s la faillite de la plateforme de SBF, il a d&eacute;clar&eacute; :&nbsp;<\/p><blockquote><p>\u00ab\u00a0Je n&rsquo;&eacute;tais qu&rsquo;un porte-parole r&eacute;mun&eacute;r&eacute; pour une publicit&eacute;\u00a0\u00bb.<\/p><\/blockquote><p>De son c&ocirc;t&eacute;, <a href=\"https:\/\/cryptonews.com\/fr\/news\/citations-a-comparaitre-sbf-caroline-ellison-employes-ftx\/\"><strong>Sam Bankman-Fried<\/strong><\/a>, l&rsquo;ancien PDG de FTX, a plaid&eacute; non coupable de plusieurs chefs d&rsquo;accusations de fraude criminelle. Cependant, trois autres cadres de la plateforme ont plaid&eacute; coupable devant un tribunal f&eacute;d&eacute;ral.<\/p>","protected":false},"excerpt":{"rendered":"<p>Shaquille Oneal. Source : Twitter\/BitcoinAgileShaquille Oneal, la star du basket-ball, a finalement fait l&rsquo;objet d&rsquo;une assignation en justice. Les avocats en charge d&rsquo;un recours collectif dans l&rsquo;affaire FTX ont notifi&eacute; &agrave; Shaquille O&rsquo;Neal. La star du basket et ancien promoteur de FTX a re&ccedil;u une assignation &agrave; compara&icirc;tre ce dimanche devant son domicile &agrave; Atlanta.En [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2032],"sponsored_companies":[],"class_list":["post-105525","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-pauline-eyebe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recours collectif FTX : Shaquille O&#039;Neal finalement notifi\u00e9<\/title>\n<meta name=\"description\" content=\"Le Shaquille O&#039;Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d&#039;un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recours collectif FTX : Shaquille O&#039;Neal finalement notifi\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le Shaquille O&#039;Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d&#039;un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-17T16:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Recours collectif FTX : Shaquille O&#039;Neal finalement notifi\u00e9\" \/>\n<meta name=\"twitter:description\" content=\"Le Shaquille O&#039;Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d&#039;un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recours collectif FTX : Shaquille O'Neal finalement notifi\u00e9","description":"Le Shaquille O'Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d'un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/","og_locale":"fr_FR","og_type":"article","og_title":"Recours collectif FTX : Shaquille O'Neal finalement notifi\u00e9","og_description":"Le Shaquille O'Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d'un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/","og_site_name":"Cryptonews France","article_published_time":"2023-04-17T16:53:00+00:00","article_modified_time":"2023-06-26T11:06:43+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Recours collectif FTX : Shaquille O'Neal finalement notifi\u00e9","twitter_description":"Le Shaquille O'Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d'un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.","twitter_image":"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/"},"author":{"name":"upeyebeqsk","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/9c70beb09a257825283d4ed565f77da5"},"headline":"Recours collectif FTX : Shaquille O&rsquo;Neal finalement notifi\u00e9","datePublished":"2023-04-17T16:53:00+00:00","dateModified":"2023-06-26T11:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/"},"wordCount":1106,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/","name":"Recours collectif FTX : Shaquille O'Neal finalement notifi\u00e9","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg","datePublished":"2023-04-17T16:53:00+00:00","dateModified":"2023-06-26T11:06:43+00:00","description":"Le Shaquille O'Neal a finalement \u00e9t\u00e9 notifi\u00e9 en justice dans le cadre d'un recours collectif FTX, apr\u00e8s trois mois de proc\u00e9dure.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#primaryimage","url":"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg","contentUrl":"https:\/\/cimg.co\/news\/110557\/267642\/fkm0krmwiamnarf.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/recours-collectif-ftx-shaquille-oneal-notifie-proces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Recours collectif FTX : Shaquille O&#8217;Neal finalement notifi\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=105525"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105525\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=105525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=105525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=105525"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=105525"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=105525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}