{"id":105498,"date":"2023-04-15T20:11:00","date_gmt":"2023-04-15T20:11:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=110448"},"modified":"2023-07-20T16:40:25","modified_gmt":"2023-07-20T16:40:25","slug":"previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/","title":{"rendered":"Pr\u00e9visions de prix pour ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/110328\/267263\/responsive-images\/cardano-price-forecast-as___media_library_original_3706_2292.jpg 3706w, https:\/\/cimg.co\/news\/110328\/267263\/responsive-images\/cardano-price-forecast-as___media_library_original_1200_742.jpg 1200w, https:\/\/cimg.co\/news\/110328\/267263\/responsive-images\/cardano-price-forecast-as___media_library_original_900_557.jpg 900w, https:\/\/cimg.co\/news\/110328\/267263\/responsive-images\/cardano-price-forecast-as___media_library_original_720_445.jpg 720w, https:\/\/cimg.co\/news\/110328\/267263\/responsive-images\/cardano-price-forecast-as___media_library_original_600_371.jpg 600w, https:\/\/cimg.co\/news\/110328\/267263\/responsive-images\/cardano-price-forecast-as___media_library_original_300_186.jpg 300w\" sizes=\"100vw\" width=\"3706\" class=\"content-img\"><figcaption>Source : TradingView<\/figcaption><\/figure><p class=\"wp-block-paragraph\">Le prix de Cardano a grimp&eacute; de <strong>8 % dans les derni&egrave;res 24 heures<\/strong>, atteignant un point haut de <strong>0,437258 dollar<\/strong> apr&egrave;s la mise &agrave; jour r&eacute;ussie d&rsquo;Ethereum vers Shanghai, ce qui a stimul&eacute; l&rsquo;ensemble du march&eacute; crypto.&nbsp;<\/p><p>Le prix actuel d&rsquo;ADA implique qu&rsquo;il a gagn&eacute; <strong>14 %<\/strong> en une semaine et <strong>27 %<\/strong> au cours des 30 derniers jours, tandis que l&rsquo;altcoin a augment&eacute; de <strong>77 %<\/strong> depuis le d&eacute;but de l&rsquo;ann&eacute;e 2023.<\/p><p>En outre, le volume d&rsquo;&eacute;changes sur 24 heures ayant d&eacute;pass&eacute; les <strong>500 milliards de dollars<\/strong> au cours de la derni&egrave;re journ&eacute;e, il semble que suffisamment de liquidit&eacute;s entrent sur le march&eacute; des altcoins pour faire grimper son prix encore davantage.<\/p><p>Cardano continue par ailleurs de se d&eacute;velopper en tant que plateforme, sa valeur totale bloqu&eacute;e augmentant r&eacute;guli&egrave;rement et 1 200 autres projets s&rsquo;appuyant d&eacute;sormais sur son r&eacute;seau, ce qui laisse pr&eacute;sager une hausse cons&eacute;quente du prix de l&rsquo;ADA sur le long terme.<\/p><h2><strong>Pr&eacute;visions de prix pour ADA : une dynamique &agrave; la hausse tir&eacute;e par les whales<\/strong><\/h2><span class=\"replacer\"><\/span><p>Les indicateurs affich&eacute;s sur le graphique de l&rsquo;ADA sont particuli&egrave;rement encourageants, car ils t&eacute;moignent d&rsquo;une excellente dynamique &agrave; l&rsquo;heure actuelle.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"3772\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/110328\/267258\/ada-price-chart.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/110328\/267258\/responsive-images\/ada-price-chart___media_library_original_3772_2236.jpg 3772w, https:\/\/cimg.co\/news\/110328\/267258\/responsive-images\/ada-price-chart___media_library_original_1200_711.jpg 1200w, https:\/\/cimg.co\/news\/110328\/267258\/responsive-images\/ada-price-chart___media_library_original_900_534.jpg 900w, https:\/\/cimg.co\/news\/110328\/267258\/responsive-images\/ada-price-chart___media_library_original_720_427.jpg 720w, https:\/\/cimg.co\/news\/110328\/267258\/responsive-images\/ada-price-chart___media_library_original_600_356.jpg 600w, https:\/\/cimg.co\/news\/110328\/267258\/responsive-images\/ada-price-chart___media_library_original_300_178.jpg 300w\"><figcaption>Source : TradingView<\/figcaption><\/figure><p>Son indice de force relative (en violet) a d&eacute;pass&eacute; le seuil de 70, ce niveau correspondant &agrave; un rallye de rupture.<\/p><p>Simultan&eacute;ment, sa moyenne mobile &agrave; 30 jours (en jaune) poursuit son augmentation au-del&agrave; de sa moyenne &agrave; 200 jours (en bleu), ce qui renforce l&rsquo;id&eacute;e qu&rsquo;une rupture est en train de se produire.<\/p><p>Si l&rsquo;ADA peut d&eacute;passer le plafond de r&eacute;sistance de 0,44 dollar, cette reprise pourrait se poursuivre pendant un certain temps encore, permettant &agrave; l&rsquo;altcoin d&rsquo;atteindre 0,45 dollar, voire un peu plus, avant de manquer de dynamisme.<\/p><p>Les raisons qui expliquent la hausse du jeton sont li&eacute;es &agrave; la nouvelle extr&ecirc;mement bullish selon laquelle la blockchain Ethereum a r&eacute;ussi la mise &agrave; niveau de son protocole vers Shanghai, cette derni&egrave;re permettant le retrait des ETH plac&eacute;s en staking.<\/p><p>Bien que cette nouvelle n&rsquo;ait &eacute;videmment aucune incidence directe sur Cardano, elle a n&eacute;anmoins provoqu&eacute; un rallye sur le march&eacute; des altcoins. En cons&eacute;quence, la plupart des principales cryptomonnaies de Layer 1 ont enregistr&eacute; aujourd&rsquo;hui des gains sur 24 heures sup&eacute;rieurs &agrave; ceux du Bitcoin (BTC).<\/p><p>De fa&ccedil;on plus globale, les donn&eacute;es sur l&rsquo;inflation publi&eacute;es cette semaine ont l&eacute;g&egrave;rement am&eacute;lior&eacute; les perspectives macro&eacute;conomique, ce qui laisse pr&eacute;sager une am&eacute;lioration de l&rsquo;&eacute;conomie mondiale ainsi que la fin des hausses de taux d&rsquo;int&eacute;r&ecirc;t.<\/p><p>De son c&ocirc;t&eacute;, l&rsquo;ADA continue de b&eacute;n&eacute;ficier du d&eacute;veloppement progressif de Cardano en tant que plateforme de contrats intelligents de Layer 1. La valeur totale de Cardano verrouill&eacute;e est pass&eacute;e &agrave; <a href=\"https:\/\/defillama.com\/chain\/Cardano\">163,5 millions de dollars<\/a>, contre 100 millions de dollars au d&eacute;but du mois de f&eacute;vrier et 49 millions de dollars au d&eacute;but de l&rsquo;ann&eacute;e 2023.<\/p><p>Il s&rsquo;agit d&rsquo;un signe positif qui donne une id&eacute;e de la rapidit&eacute; avec laquelle l&rsquo;&eacute;cosyst&egrave;me d&rsquo;applications de Cardano se d&eacute;veloppe, avec l&rsquo;&eacute;change d&eacute;centralis&eacute; <a href=\"https:\/\/dappradar.com\/rankings\/protocol\/cardano\">Minswap ayant environ 67,75 millions de dollars en jetons<\/a> dans ses contrats intelligents &agrave; l&rsquo;heure actuelle.<\/p><p>Au total, la plateforme compte aujourd&rsquo;hui 1 221 projets construits sur son r&eacute;seau, ainsi que plus de 122 projets d&eacute;j&agrave; lanc&eacute;s.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/InputOutputHK\/status\/1645090450762596354\"><\/oembed><\/figure><p>Il convient aussi de noter que Cardano se classe r&eacute;guli&egrave;rement en t&ecirc;te de liste des blockchains en termes d&rsquo;activit&eacute; de d&eacute;veloppement, mesur&eacute;e en fonction du <a href=\"https:\/\/twitter.com\/ProofofGitHub\/status\/1646785398775922688\">nombre de commits (modifications) effectu&eacute;s sur GitHub<\/a>.<\/p><p>Cette situation laisse &agrave; entendre que si de nombreuses plateformes suscitent un vif int&eacute;r&ecirc;t, Cardano se construit tranquillement en arri&egrave;re-plan, atteignant un niveau de scalabilit&eacute; et de s&eacute;curit&eacute; que certains de ses rivaux n&rsquo;ont pas encore r&eacute;ussi &agrave; mettre en place.<\/p><p>Cardano est sur le point de lancer <strong>Hydra<\/strong>, sa solution de mise &agrave; l&rsquo;&eacute;chelle de la deuxi&egrave;me couche, qui augmentera son d&eacute;bit et r&eacute;duira ses frais de mani&egrave;re significative.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/marcosantiagoNY\/status\/1644860358195134466\"><\/oembed><\/figure><p>Le lancement complet d&rsquo;Hydra stimulera consid&eacute;rablement le d&eacute;veloppement et le d&eacute;ploiement des applications sur Cardano, ce qui permettra en retour de valoriser le r&eacute;seau en y int&eacute;grant des fonctionnalit&eacute;s plus attrayantes et accessibles.<\/p><p>Par cons&eacute;quent, il y a une r&eacute;elle possibilit&eacute; que l&rsquo;ADA puisse voir des gains continus au cours des prochaines semaines et des prochains mois, le poussant potentiellement au-del&agrave; de <strong>0,5 dollar<\/strong>.<\/p><p>De l&agrave;, un retour &agrave; des conditions plus haussi&egrave;res pourrait m&ecirc;me lui permettre d&rsquo;approcher les 1 dollar, ce qui repr&eacute;senterait un gain de <strong>127 %<\/strong> par rapport &agrave; son prix actuel.<\/p><p><a href=\"https:\/\/gridglass48.co\/box_75372a8eb9f669a1e2a6a7f8edeb2ce4\"><strong><u>Cliquez ici pour acheter ADA<\/u><\/strong><\/a><\/p><h2><strong>Est-ce le meilleur moment pour investir sur ADA ?<\/strong><\/h2><span class=\"replacer\"><\/span><p>Il semble bien qu&rsquo;apr&egrave;s une ann&eacute;e 2022 plut&ocirc;t calme, ADA soit d&eacute;sormais en bonne position pour enregistrer des gains significatifs.<\/p><p>Toutefois, ces gains peuvent encore prendre plusieurs mois &agrave; se mat&eacute;rialiser, de sorte que les traders &agrave; la recherche de rendements sup&eacute;rieurs &agrave; la moyenne sur le court terme pourraient bien pr&eacute;f&eacute;rer de trouver des projets alternatifs.<\/p><p>Les investisseurs int&eacute;ress&eacute;s n&rsquo;h&eacute;siteront pas &agrave; consulter nos pr&eacute;c&eacute;dents articles sur le sujet :<\/p><ul><li><a href=\"https:\/\/cryptonews.com\/fr\/news\/previsions-prix-dogecoin-doge-tweet-elon-musk-fait-flamber-le-prix-de-doge\/\">Pr&eacute;visions de prix pour Dogecoin (DOGE) : le dernier tweet d&rsquo;Elon Musk fait flamber le prix de DOGE<\/a><\/li><li><a href=\"https:\/\/cryptonews.com\/fr\/news\/deelance-leve-100-000-dollars-prevente-investissez-avant-hausse-prix-jeton\/\">DeeLance l&egrave;ve 100 000 dollars en pr&eacute;vente : investissez avant la hausse de prix du jeton<\/a><\/li><li><a href=\"https:\/\/cryptonews.com\/fr\/news\/battle-infinity-lance-son-programme-dambassadeurs-a-loccasion-de-lit-utsav-2023\/\">Battle Infinity lance son programme d&rsquo;ambassadeurs &agrave; l&rsquo;occasion de l&rsquo;IT UTSAV 2023<\/a><\/li><\/ul><p><i><sup>Avertissement : La section \u00ab\u00a0Industry Talk\u00a0\u00bb pr&eacute;sente les points de vue des acteurs du secteur de la crypto et ne fait pas partie du contenu &eacute;ditorial de Cryptonews.com.<\/sup><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Source : TradingViewLe prix de Cardano a grimp&eacute; de 8 % dans les derni&egrave;res 24 heures, atteignant un point haut de 0,437258 dollar apr&egrave;s la mise &agrave; jour r&eacute;ussie d&rsquo;Ethereum vers Shanghai, ce qui a stimul&eacute; l&rsquo;ensemble du march&eacute; crypto.&nbsp;Le prix actuel d&rsquo;ADA implique qu&rsquo;il a gagn&eacute; 14 % en une semaine et 27 % [&hellip;]<\/p>\n","protected":false},"author":127,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[],"editors":[2550],"sponsored_companies":[],"class_list":["post-105498","post","type-post","status-publish","format-standard","hentry","category-altcoin-news","category-news","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales<\/title>\n<meta name=\"description\" content=\"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d&#039;Ethereum vers Shanghai, ce qui a stimul\u00e9 l&#039;ensemble du march\u00e9 crypto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales\" \/>\n<meta property=\"og:description\" content=\"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d&#039;Ethereum vers Shanghai, ce qui a stimul\u00e9 l&#039;ensemble du march\u00e9 crypto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-15T20:11:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-20T16:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales\" \/>\n<meta name=\"twitter:description\" content=\"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d&#039;Ethereum vers Shanghai, ce qui a stimul\u00e9 l&#039;ensemble du march\u00e9 crypto.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/110328\/267258\/ada-price-chart.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales","description":"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d'Ethereum vers Shanghai, ce qui a stimul\u00e9 l'ensemble du march\u00e9 crypto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/","og_locale":"fr_FR","og_type":"article","og_title":"ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales","og_description":"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d'Ethereum vers Shanghai, ce qui a stimul\u00e9 l'ensemble du march\u00e9 crypto.","og_url":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/","og_site_name":"Cryptonews France","article_published_time":"2023-04-15T20:11:00+00:00","article_modified_time":"2023-07-20T16:40:25+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales","twitter_description":"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d'Ethereum vers Shanghai, ce qui a stimul\u00e9 l'ensemble du march\u00e9 crypto.","twitter_image":"https:\/\/cimg.co\/news\/110328\/267258\/ada-price-chart.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/"},"author":{"name":"simalleggex","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/642c28a932dc058143fefb2c230e873a"},"headline":"Pr\u00e9visions de prix pour ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales","datePublished":"2023-04-15T20:11:00+00:00","dateModified":"2023-07-20T16:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/"},"wordCount":1135,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg","articleSection":["Actualit\u00e9s Altcoin","News"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/","url":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/","name":"ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg","datePublished":"2023-04-15T20:11:00+00:00","dateModified":"2023-07-20T16:40:25+00:00","description":"Le prix de Cardano a grimp\u00e9 de 8 % dans les derni\u00e8res 24 heures, atteignant un point haut de 0,437258 dollar apr\u00e8s la mise \u00e0 jour r\u00e9ussie d'Ethereum vers Shanghai, ce qui a stimul\u00e9 l'ensemble du march\u00e9 crypto.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#primaryimage","url":"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg","contentUrl":"https:\/\/cimg.co\/news\/110328\/267263\/cardano-price-forecast-as.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/news\/previsions-de-prix-pour-ada-une-dynamique-a-la-hausse-tiree-par-les-whales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9visions de prix pour ADA : une dynamique \u00e0 la hausse tir\u00e9e par les whales"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=105498"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105498\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=105498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=105498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=105498"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=105498"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=105498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}