{"id":105493,"date":"2023-04-15T13:09:00","date_gmt":"2023-04-15T13:09:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=110431"},"modified":"2023-06-26T11:08:30","modified_gmt":"2023-06-26T11:08:30","slug":"partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/","title":{"rendered":"Partenariat de 60 millions de dollars entre EOS Network et DWF Labs"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg\" srcset width class=\"content-img\" alt=\"\"><figcaption>Source : Twitter\/Yves La Rose<\/figcaption><\/figure><p class=\"wp-block-paragraph\">DWF Labs et la Fondation du <a href=\"https:\/\/cryptonews.com\/fr\/exclusives\/lancement-version-beta-mainnet-eos-evm\/\"><strong>r&eacute;seau EOS<\/strong><\/a> (ENF) viennent de signer un partenariat strat&eacute;gique qui inclut un investissement &agrave; hauteur de plus de 60 millions de dollars.&nbsp;<\/p><p>Cela repr&eacute;sente le plus grand investissement jamais r&eacute;alis&eacute; par DWF Labs qui est &agrave; la fois un teneur de march&eacute; de crypto-monnaies et une soci&eacute;t&eacute; d&rsquo;investissement.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/BigBeardSamurai\/status\/1646513646091247616?s=20\"><\/oembed><\/figure><p>Son nouveau partenaire, le r&eacute;seau EOS est une plateforme de niveau 1 sp&eacute;cialis&eacute;e dans les jeux bas&eacute;s sur la blockchain (GameFi) et les applications d&eacute;centralis&eacute;es (DApps). Concr&egrave;tement, elle est con&ccedil;ue pour aider les d&eacute;veloppeurs dans la construction de jeux bas&eacute;s sur la blockchain et le d&eacute;ploiement d&rsquo;applications d&eacute;centralis&eacute;es.<\/p><h2>Un investissement de DWF Labs en vue d&rsquo;acc&eacute;l&eacute;rer l&rsquo;acceptation du r&eacute;seau EOS<\/h2><span class=\"replacer\"><\/span><p>L&rsquo;objectif de ce partenariat est d&rsquo;aider au renforcement du r&eacute;seau EOS et &agrave; son acception par le plus grand nombre. Pour y parvenir, DWF Labs se propose d&rsquo;investir 60 millions de dollars. Cet investissement se d&eacute;cline en deux points, notamment un achat de jetons EOS &agrave; hauteur de 45 millions de dollars.<\/p><p>En plus de cet achat, le teneur de march&eacute; a fait une promesse d&rsquo;investissement de 15 millions de dollars pour financer toute entreprise ou projet bas&eacute; sur EOS.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/BigBeardSamurai\/status\/1646513649002102787?s=20\"><\/oembed><\/figure><p>Le r&ocirc;le de la Fondation du r&eacute;seau EOS (ENF) est crucial dans l&rsquo;expansion du r&eacute;seau EOS. En effet, la fondation travaille &agrave; la coordination du soutien, &agrave; la cr&eacute;ation de boucles de r&eacute;troaction pour l&rsquo;innovation et &agrave; la participation de la communaut&eacute;. Pour y parvenir, la fondation &oelig;uvre dans le financement de l&rsquo;&eacute;cosyst&egrave;me EOS.<\/p><p>Avec ce partenariat, le r&eacute;seau EOS devrait rapidement se d&eacute;velopper et proposer plus de produits et services. Dans ce contexte, il a d&eacute;voil&eacute; d&eacute;voiler sa machine virtuelle Ethereum (EVM). Celle-ci se d&eacute;marque d&eacute;j&agrave; par sa vitesse qui surclasse celle de Polygon, Avalanche ou encore BSC. Cette machine virtuelle Ethereum r&eacute;ussit cet exploit en proposant plus de quatre fois plus de swaps par seconde.<\/p><h2>DWF Labs accro&icirc;t son investissement dans la blockchain et le Web3<\/h2><span class=\"replacer\"><\/span><p>Avec ce nouvel investissement, DWF Labs s&rsquo;identifie comme un investisseur s&eacute;rieux dans la blockchain. Le teneur de march&eacute; fait son apparition sur le march&eacute; en investissant pendant la p&eacute;riode de baisse g&eacute;n&eacute;ralis&eacute;e des crypto-monnaies.&nbsp;<\/p><p>En plus de ce partenariat, DWF Labs a auparavant investi 20 millions de dollars sur Synthetix, un protocole de liquidit&eacute; de produits d&eacute;riv&eacute;s. Dans le cadre de cet accord, DWF Labs s&rsquo;est aussi engag&eacute; &agrave; l&rsquo;achat de jetons SNX pour un montant de 5 millions de dollars.<\/p><p>Pour Andrei Grachev, un associ&eacute; directeur de DWF Labs, cet accordeur est b&eacute;n&eacute;fique pour la Finance d&eacute;centralis&eacute;e (DeFi) dans la mesure o&ugrave; il apportait des m&eacute;canismes de n&eacute;gociation rationalis&eacute;s.<\/p><p>Par ailleurs, DWF Labs aussi proc&eacute;d&eacute; &agrave; une collecte de fonds de 40 millions de dollars en faveur de Fetch.ai, un protocole de crypto-monnaie ax&eacute; sur l&rsquo;Intelligence Artificielle (IA).&nbsp;<\/p><p>Dans sa qu&ecirc;te de r&eacute;volutionner le Web 3, le teneur de march&eacute; a &eacute;galement sign&eacute; un <a href=\"https:\/\/cryptonews.com\/fr\/news\/partenariat-unizen-dwf-labs-revolutioniser-experience-utilisateur-web3-fr\/\"><strong>partenariat avec Unizen<\/strong><\/a>.<br>&nbsp;<\/p><p><i><sup>Avertissement : <\/sup><strong><sup>La section Industry Talk<\/sup><\/strong><sup> pr&eacute;sente des points de vue &eacute;manant des acteurs de l&rsquo;industrie de la crypto-monnaie et ne fait pas partie du contenu &eacute;ditorial de Cryptonews.com.<\/sup><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Source : Twitter\/Yves La RoseDWF Labs et la Fondation du r&eacute;seau EOS (ENF) viennent de signer un partenariat strat&eacute;gique qui inclut un investissement &agrave; hauteur de plus de 60 millions de dollars.&nbsp;Cela repr&eacute;sente le plus grand investissement jamais r&eacute;alis&eacute; par DWF Labs qui est &agrave; la fois un teneur de march&eacute; de crypto-monnaies et une [&hellip;]<\/p>\n","protected":false},"author":129,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2032],"sponsored_companies":[],"class_list":["post-105493","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-pauline-eyebe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs<\/title>\n<meta name=\"description\" content=\"EOS Network d\u00e9croche 60 millions de dollars d&#039;investissement et un partenariat avec DWF Labs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs\" \/>\n<meta property=\"og:description\" content=\"EOS Network d\u00e9croche 60 millions de dollars d&#039;investissement et un partenariat avec DWF Labs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-15T13:09:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:08:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs\" \/>\n<meta name=\"twitter:description\" content=\"EOS Network d\u00e9croche 60 millions de dollars d&#039;investissement et un partenariat avec DWF Labs.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs","description":"EOS Network d\u00e9croche 60 millions de dollars d'investissement et un partenariat avec DWF Labs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/","og_locale":"fr_FR","og_type":"article","og_title":"Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs","og_description":"EOS Network d\u00e9croche 60 millions de dollars d'investissement et un partenariat avec DWF Labs.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/","og_site_name":"Cryptonews France","article_published_time":"2023-04-15T13:09:00+00:00","article_modified_time":"2023-06-26T11:08:30+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs","twitter_description":"EOS Network d\u00e9croche 60 millions de dollars d'investissement et un partenariat avec DWF Labs.","twitter_image":"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/"},"author":{"name":"upeyebeqsk","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/9c70beb09a257825283d4ed565f77da5"},"headline":"Partenariat de 60 millions de dollars entre EOS Network et DWF Labs","datePublished":"2023-04-15T13:09:00+00:00","dateModified":"2023-06-26T11:08:30+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/"},"wordCount":672,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/","name":"Partenariat et investissement de 60 millions de dollars entre EOS Network et DWF Labs","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg","datePublished":"2023-04-15T13:09:00+00:00","dateModified":"2023-06-26T11:08:30+00:00","description":"EOS Network d\u00e9croche 60 millions de dollars d'investissement et un partenariat avec DWF Labs.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#primaryimage","url":"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg","contentUrl":"https:\/\/cimg.co\/news\/110431\/267468\/ftmwo8kaqaebnga.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/partenariat-eos-network-dwf-labs-60-millions-dollars-dinvestissement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Partenariat de 60 millions de dollars entre EOS Network et DWF Labs"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=105493"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105493\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=105493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=105493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=105493"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=105493"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=105493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}