{"id":105327,"date":"2023-04-04T12:59:00","date_gmt":"2023-04-04T12:59:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=109477"},"modified":"2023-06-26T11:06:43","modified_gmt":"2023-06-26T11:06:43","slug":"piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/","title":{"rendered":"Piratage d&rsquo;Euler Labs : le hacker restitue \u00ab\u00a0tous les actifs pirat\u00e9s\u00a0\u00bb"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/108658\/263709\/responsive-images\/adobestock-tomasz-biderma___media_library_original_1229_820.jpeg 1229w, https:\/\/cimg.co\/news\/108658\/263709\/responsive-images\/adobestock-tomasz-biderma___media_library_original_1200_801.jpeg 1200w, https:\/\/cimg.co\/news\/108658\/263709\/responsive-images\/adobestock-tomasz-biderma___media_library_original_900_600.jpeg 900w, https:\/\/cimg.co\/news\/108658\/263709\/responsive-images\/adobestock-tomasz-biderma___media_library_original_720_480.jpeg 720w, https:\/\/cimg.co\/news\/108658\/263709\/responsive-images\/adobestock-tomasz-biderma___media_library_original_600_400.jpeg 600w, https:\/\/cimg.co\/news\/108658\/263709\/responsive-images\/adobestock-tomasz-biderma___media_library_original_300_200.jpeg 300w\" sizes=\"100vw\" width=\"1229\" class=\"content-img\"><figcaption>Source : AdobeStock \/ Tomasz Bidermann<\/figcaption><\/figure><p class=\"wp-block-paragraph\"><a href=\"https:\/\/cryptonews.com\/fr\/news\/responsable-piratage-euler-finance-restitue-100-millions-dollars\/\"><strong>Euler Finance<\/strong><\/a> a convaincu son pirate de restituer la plupart des fonds dont il avait &eacute;t&eacute; d&eacute;poss&eacute;d&eacute;. En effet, la plateforme a fait l&rsquo;objet d&rsquo;un vol de 196 millions de dollars r&eacute;alis&eacute; gr&acirc;ce &agrave; une<strong> attaque de type \u00ab\u00a0flash loan\u00a0\u00bb.<\/strong>&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/CryptoZeroActu\/status\/1635332178749054976?s=20\"><\/oembed><\/figure><p><strong>La d&eacute;cision du pirate de restituer les fonds<\/strong> est le fruit de nombreux &eacute;changes qui ont dur&eacute; 23 jours et qui l&rsquo;ont finalement conduit &agrave; prendre la \u00ab\u00a0bonne d&eacute;cision\u00a0\u00bb.<\/p><h2>Rappel des faits relatifs au plus gros hack de crypto depuis le d&eacute;but de l&rsquo;ann&eacute;e 2023<\/h2><span class=\"replacer\"><\/span><p>Pour rappel,<strong> le pirate d&rsquo;Euler Finance<\/strong> a effectu&eacute; le 13 mars une multitude de transactions.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/crypto__mak\/status\/1635812826303594496?s=20\"><\/oembed><\/figure><p>Celles-ci ont permis de soutirer des millions de dollars sous la forme de diff&eacute;rents tokens, notamment Dai, USD Coin, l&rsquo;Ether stak&eacute; (StETH) et le WBTC (wrapped Bitcoin).<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" class=\" lazyload\" data-src=\"https:\/\/s3.cointelegraph.com\/uploads\/2023-04\/7324ab5e-73ee-4420-bb98-66e39a7f955c.png\" data-srcset=\"\"><figcaption>Fonds d&eacute;rob&eacute;s chez Euler Finance. Source : BlockSec<\/figcaption><\/figure><p>&nbsp;<\/p><p>L&rsquo;hacking a eu pour cons&eacute;quence de <strong>faire chuter la valeur totale des contrats intelligents d&rsquo;Euler Finance<\/strong>. Elle est ainsi pass&eacute;e de 311 millions de dollars &agrave; 10,37 millions de dollars. Par ailleurs, &agrave; la suite de ce piratage, 11 protocoles financiers d&eacute;centralis&eacute;s (DeFi) diff&eacute;rents ont d&eacute;clar&eacute; des pertes de fond et ont d&ucirc; geler leurs comptes. Parmi ces protocoles figurent Balancer, Yearn. Finance et Yield Protocol.<\/p><p>Au lendemain de l&rsquo;attaque, le 14 mars, Euler a mis en place des mesures proactives pour le recouvrement des fonds. Dans un premier temps, la plateforme a initi&eacute; <strong>la suspension de son module etoken <\/strong>qui &eacute;tait vuln&eacute;rable, ainsi que sa fonction de donation.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/eulerfinance\/status\/1635431834631766018?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1635431834631766018%7Ctwgr%5Eacd4d7bd7ee7b2dff027400dc718c85827241ea2%7Ctwcon%5Es1_c10&amp;ref_url=https%3A%2F%2Fcointelegraph.com%2Fnews%2Feuler-labs-hacker-returns-all-of-the-recoverable-funds-timeline\"><\/oembed><\/figure><p>Dans un deuxi&egrave;me temps, elle a <strong>fait appel &agrave; des soci&eacute;t&eacute;s d&rsquo;audit <\/strong>pour analyser les causes profondes de ce piratage.<\/p><h2>Des n&eacute;gociations intenses entre Euler et le pirate pour la restitution des fonds vol&eacute;s<\/h2><span class=\"replacer\"><\/span><p>Parall&egrave;lement, <strong>Euler a entrepris de contacter les pirates pour n&eacute;gocier une prime<\/strong>. Ainsi, le 15 mars, Euler a octroy&eacute; au pirate un d&eacute;lai pour la restitution de 90 % de l&rsquo;argent vol&eacute;. &Agrave; d&eacute;faut de restituer les fonds, la soci&eacute;t&eacute; proposerait une prime d&rsquo;un million de dollars pour toute information pouvant mener &agrave; l&rsquo;arrestation du pirate. Gr&acirc;ce &agrave; cet accord, le pirate a pu empocher la somme de 19,6 millions de dollars.<\/p><p>Cependant, le pirate a proc&eacute;d&eacute; &agrave; des transferts d&rsquo;argent comme bon lui semblait. Ainsi, <strong>une victime du piratage a re&ccedil;u 100 &eacute;thers<\/strong> de la part du pirate, apr&egrave;s l&rsquo;avoir persuad&eacute; d&rsquo;avoir perdu toutes ses &eacute;conomies au cours de cette op&eacute;ration. En quelques jours, le pirate s&rsquo;est engag&eacute; dans un processus de restitution de l&rsquo;argent vol&eacute;, sous la forme de diff&eacute;rents montants.<\/p><p>Face &agrave; la confusion des utilisateurs, Michael Bentley, <strong>le PDG d&rsquo;<\/strong><a href=\"https:\/\/cryptonews.com\/fr\/news\/des-portefeuilles-liees-piratage-200-millions-euler-axie-infinity\/\"><strong>Euler Laboratories<\/strong><\/a>, s&rsquo;est voulu rassurant. Il a fait savoir que dix audits ind&eacute;pendants avaient &eacute;t&eacute; men&eacute;s sur une p&eacute;riode de deux ans. Ces audits ont permis de d&eacute;terminer dans quelle mesure le processus &eacute;tait \u00ab\u00a0&agrave; faible risque\u00a0\u00bb et ne suscitait \u00ab\u00a0aucune inqui&eacute;tude persistante\u00a0\u00bb.<\/p><p>Le 21 mars, Euler d&eacute;cide de rompre les n&eacute;gociations et annonce une r&eacute;compense d&rsquo;un million de dollars pour <strong>toute information menant &agrave; l&rsquo;arrestation du pirate<\/strong>. &Agrave; partir du 25 mars, le pirate a proc&eacute;d&eacute; &agrave; des restitutions r&eacute;p&eacute;t&eacute;es des actifs vol&eacute;s en quantit&eacute;s significatives.<\/p><p>Le 4 avril, soit 23 jours apr&egrave;s le piratage, la r&eacute;compense d&rsquo;un million de dollars a &eacute;t&eacute; lev&eacute;e. Euler Financial a fait savoir que la totalit&eacute; de l&rsquo;argent vol&eacute; avait &eacute;t&eacute; r&eacute;cup&eacute;r&eacute;e. Par cons&eacute;quent, <a href=\"https:\/\/cryptonews.com\/fr\/news\/euler-finance-piratage-massif-195-millions-pret-eclair\/\"><strong>la plateforme Euler Financial <\/strong><\/a>a indiqu&eacute; que la prime d&rsquo;un million de dollars lanc&eacute;e ne prenait fin et qu&rsquo;elle ne recevrait plus d&rsquo;informations.&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/eulerfinance\/status\/1643027452388597765?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1643027452388597765%7Ctwgr%5Eacd4d7bd7ee7b2dff027400dc718c85827241ea2%7Ctwcon%5Es1_c10&amp;ref_url=https%3A%2F%2Fcointelegraph.com%2Fnews%2Feuler-labs-hacker-returns-all-of-the-recoverable-funds-timeline\"><\/oembed><\/figure><p>Elle estime en effet que l&rsquo;exploiteur a fait ce qu&rsquo;il fallait en restituant les fonds vol&eacute;s.<\/p><p>Pour conclure la restitution des fonds vol&eacute;s, <strong>le hacker a envoy&eacute; 12 millions de DAI et 10 580 ETH<\/strong> en plusieurs transactions. Le travail acharn&eacute; fourni par Euler Finance pour le recouvrement des fonds pirat&eacute; et le r&eacute;tablissement de la confiance des investisseurs a re&ccedil;u un accueil favorable de la part de la communaut&eacute; des cryptomonnaies.<\/p><p><strong>Pour am&eacute;liorer la s&eacute;curit&eacute; des ponts<\/strong>, Gnosis, a r&eacute;cemment d&eacute;ploy&eacute; un agr&eacute;gateur d&rsquo;oracle de hachage. Cet agr&eacute;gateur requiert la validation d&rsquo;un retrait via plus d&rsquo;un pont. L&rsquo;&eacute;quipe derri&egrave;re Gnosis est &eacute;galement &agrave; l&rsquo;origine de Gnosis Safe multisig et Gnosis Chain.<\/p><p>Selon Cointelegraph, plus de <strong>2 milliards de dollars ont &eacute;t&eacute; vol&eacute;s en 2021 et 2022<\/strong>. Ces vols sont principalement dus &agrave; des bugs et &agrave; des attaques sur les portefeuilles.<\/p>","protected":false},"excerpt":{"rendered":"<p>Source : AdobeStock \/ Tomasz BidermannEuler Finance a convaincu son pirate de restituer la plupart des fonds dont il avait &eacute;t&eacute; d&eacute;poss&eacute;d&eacute;. En effet, la plateforme a fait l&rsquo;objet d&rsquo;un vol de 196 millions de dollars r&eacute;alis&eacute; gr&acirc;ce &agrave; une attaque de type \u00ab\u00a0flash loan\u00a0\u00bb.&nbsp;La d&eacute;cision du pirate de restituer les fonds est le fruit [&hellip;]<\/p>\n","protected":false},"author":128,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2034],"sponsored_companies":[],"class_list":["post-105327","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-rose-bidzogo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piratage d&#039;Euler Labs : le hacker restitue &quot;tous les actifs pirat\u00e9s&quot;<\/title>\n<meta name=\"description\" content=\"L&#039;auteur du piratage d&#039;Euler Labs restitue &quot;tous les actifs vol\u00e9s&quot; : r\u00e9capitulatif des faits\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piratage d&#039;Euler Labs : le hacker restitue &quot;tous les actifs pirat\u00e9s&quot;\" \/>\n<meta property=\"og:description\" content=\"L&#039;auteur du piratage d&#039;Euler Labs restitue &quot;tous les actifs vol\u00e9s&quot; : r\u00e9capitulatif des faits\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-04T12:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Piratage d&#039;Euler Labs : le hacker restitue &quot;tous les actifs pirat\u00e9s&quot;\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;auteur du piratage d&#039;Euler Labs restitue &quot;tous les actifs vol\u00e9s&quot; : r\u00e9capitulatif des faits\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/s3.cointelegraph.com\/uploads\/2023-04\/7324ab5e-73ee-4420-bb98-66e39a7f955c.png\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piratage d'Euler Labs : le hacker restitue \"tous les actifs pirat\u00e9s\"","description":"L'auteur du piratage d'Euler Labs restitue \"tous les actifs vol\u00e9s\" : r\u00e9capitulatif des faits","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/","og_locale":"fr_FR","og_type":"article","og_title":"Piratage d'Euler Labs : le hacker restitue \"tous les actifs pirat\u00e9s\"","og_description":"L'auteur du piratage d'Euler Labs restitue \"tous les actifs vol\u00e9s\" : r\u00e9capitulatif des faits","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/","og_site_name":"Cryptonews France","article_published_time":"2023-04-04T12:59:00+00:00","article_modified_time":"2023-06-26T11:06:43+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Piratage d'Euler Labs : le hacker restitue \"tous les actifs pirat\u00e9s\"","twitter_description":"L'auteur du piratage d'Euler Labs restitue \"tous les actifs vol\u00e9s\" : r\u00e9capitulatif des faits","twitter_image":"https:\/\/s3.cointelegraph.com\/uploads\/2023-04\/7324ab5e-73ee-4420-bb98-66e39a7f955c.png","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/"},"author":{"name":"rosebidzogoofr","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/5b04c7d0cabf02282b92b484476a0784"},"headline":"Piratage d&rsquo;Euler Labs : le hacker restitue \u00ab\u00a0tous les actifs pirat\u00e9s\u00a0\u00bb","datePublished":"2023-04-04T12:59:00+00:00","dateModified":"2023-06-26T11:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/"},"wordCount":916,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/","name":"Piratage d'Euler Labs : le hacker restitue \"tous les actifs pirat\u00e9s\"","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg","datePublished":"2023-04-04T12:59:00+00:00","dateModified":"2023-06-26T11:06:43+00:00","description":"L'auteur du piratage d'Euler Labs restitue \"tous les actifs vol\u00e9s\" : r\u00e9capitulatif des faits","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#primaryimage","url":"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg","contentUrl":"https:\/\/cimg.co\/news\/108658\/263709\/adobestock-tomasz-biderma.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/piratage-deuler-labs-le-hacker-restitue-tous-les-actifs-recuperables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Piratage d&#8217;Euler Labs : le hacker restitue &#8220;tous les actifs pirat\u00e9s&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=105327"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105327\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=105327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=105327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=105327"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=105327"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=105327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}