{"id":105244,"date":"2023-03-29T19:17:00","date_gmt":"2023-03-29T19:17:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=109000"},"modified":"2023-06-26T11:08:31","modified_gmt":"2023-06-26T11:08:31","slug":"fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/","title":{"rendered":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg\" srcset=\"https:\/\/cimg.co\/news\/109000\/264282\/responsive-images\/capture-decran-2023-03-29___media_library_original_1200_703.jpg 1200w, https:\/\/cimg.co\/news\/109000\/264282\/responsive-images\/capture-decran-2023-03-29___media_library_original_900_527.jpg 900w, https:\/\/cimg.co\/news\/109000\/264282\/responsive-images\/capture-decran-2023-03-29___media_library_original_720_422.jpg 720w, https:\/\/cimg.co\/news\/109000\/264282\/responsive-images\/capture-decran-2023-03-29___media_library_original_600_352.jpg 600w, https:\/\/cimg.co\/news\/109000\/264282\/responsive-images\/capture-decran-2023-03-29___media_library_original_300_176.jpg 300w\" width=\"1200\" class=\"content-img\" alt=\"\"><figcaption>Source : Fight Out<\/figcaption><\/figure><p class=\"wp-block-paragraph\">Depuis plusieurs semaines, <a href=\"https:\/\/dns0.junctionrelay103.io\/b_Fightout_CryptonewsFR\">Fight Out<\/a> continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r&eacute;ussi &agrave; lever la somme record de <strong>6 millions de dollars<\/strong> dans le cadre de sa pr&eacute;vente, mais cette derni&egrave;re approche rapidement de sa conclusion.<\/p><p>Avec une date de fin pr&eacute;vue pour le <strong>1 avril &agrave; 00:00 UTC<\/strong>, il ne reste qu&rsquo;un peu moins de 72 heures pour que les derniers investisseurs puissent participer &agrave; la pr&eacute;vente. Pour rappel, le FGHT est un jeton ERC-20 bas&eacute; sur la blockchain Ethereum dont le prix est actuellement fix&eacute; &agrave; 0,0333 dollars, son listing est pr&eacute;vu sur les plateformes d&rsquo;&eacute;change pour le <strong>5 avril<\/strong>.<\/p><h2>L&rsquo;industrie du fitness bouscul&eacute;e par la r&eacute;volution Web3<\/h2><span class=\"replacer\"><\/span><p>Fight Out est une nouvelle plateforme <strong>move-to-earn<\/strong> (M2E) qui a pour ambition de r&eacute;mun&eacute;rer ses utilisateurs en fonction de leurs performances sportives. Le projet va &eacute;galement utiliser des avatars \u00ab\u00a0<strong>soul bound<\/strong>\u00a0\u00bb &agrave; savoir des NFTs qui seront li&eacute;s aux comptes des utilisateurs et qui seront donc non-&eacute;changeables. Ainsi, ces avatars auront pour but d&rsquo;illustrer les progr&egrave;s physiques des membres de la communaut&eacute;.<\/p><p>Le syst&egrave;me M2E et le m&eacute;tavers repr&eacute;sentent tous deux, &agrave; leur mani&egrave;re, l&rsquo;avenir de l&rsquo;industrie de la sant&eacute; et du fitness. Mais avant Fight Out, on ne pouvait pas trouver un projet qui ait l&rsquo;ambition de faire de cette vision futuriste une r&eacute;alit&eacute;.<\/p><p>Cette approche novatrice qui combine le principe du M2E avec le th&egrave;me du m&eacute;tavers provoque un fort int&eacute;r&ecirc;t sur les march&eacute;s, ce qui se traduit par une multitude de partenariats ainsi que le listing du jeton FGHT sur sept plateformes d&rsquo;&eacute;change. Celui-ci sera disponible sur <strong>XT.com, LBank, BKEX, Changelly Pro, BitForex, DigiFinex, <\/strong>et<strong> Uniswap.<\/strong><\/p><p>Les investisseurs qui poss&eacute;deront des jetons FGHT plac&eacute;s en staking pourront acc&eacute;der de mani&egrave;re gratuite au m&eacute;tavers de l&rsquo;application Fight Out. Il a &eacute;galement &eacute;t&eacute; annonc&eacute; r&eacute;cemment que chaque utilisateur poss&eacute;dant des jetons FGHT aura une chance de recevoir des r&eacute;compenses sp&eacute;ciales au sein de l&rsquo;application, notamment des sessions d&rsquo;entrainements personnalis&eacute;es avec des athl&egrave;tes professionnels.<\/p><p>Ces sportifs, pour la plupart issus du monde des sports de combat, agiront comme des ambassadeurs du projet afin d&rsquo;en faire la promotion. Parmi ces ambassadeurs on retrouve <strong>Savannah Marshall<\/strong>, l&rsquo;une des meilleures boxeuses &agrave; l&rsquo;&eacute;chelle internationale et qui affiche pr&egrave;s de 122 000 abonn&eacute;s sur Instagram, mais aussi les stars br&eacute;siliennes de l&rsquo;UFC <strong>Amanda Ribas<\/strong> et <strong>Talia Santos<\/strong> (respectivement 2,1 millions et 179 000 abonn&eacute;s sur Instagram).<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" width=\"1916\" class=\"content-img lazyload\" alt=\"\" data-src=\"https:\/\/cimg.co\/news\/109000\/264283\/capture-decran-2023-03-29.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/109000\/264283\/responsive-images\/capture-decran-2023-03-29___media_library_original_1916_954.jpg 1916w, https:\/\/cimg.co\/news\/109000\/264283\/responsive-images\/capture-decran-2023-03-29___media_library_original_1200_597.jpg 1200w, https:\/\/cimg.co\/news\/109000\/264283\/responsive-images\/capture-decran-2023-03-29___media_library_original_900_448.jpg 900w, https:\/\/cimg.co\/news\/109000\/264283\/responsive-images\/capture-decran-2023-03-29___media_library_original_720_358.jpg 720w, https:\/\/cimg.co\/news\/109000\/264283\/responsive-images\/capture-decran-2023-03-29___media_library_original_600_299.jpg 600w, https:\/\/cimg.co\/news\/109000\/264283\/responsive-images\/capture-decran-2023-03-29___media_library_original_300_149.jpg 300w\"><\/figure><h2>Fight Out : une nouvelle approche de l&rsquo;entrainement et du gaming<\/h2><span class=\"replacer\"><\/span><p>Le projet Fight Out est principalement focalis&eacute; sur une approche comp&eacute;titive et le fait de r&eacute;compenser les membres de la communaut&eacute; &agrave; la hauteur de leurs efforts. En outre, la plateforme offrira la possibilit&eacute; &agrave; ses utilisateurs de parier des jetons FGHT sur des comp&eacute;titions internationales ou des &eacute;v&eacute;nements sportifs, notamment certains des plus grands matchs de boxe.<\/p><p>Pour les utilisateurs qui ne sont pas int&eacute;ress&eacute;s par ces &eacute;v&eacute;nements, il sera aussi possible de jouer contre des amis dans le cadre d&rsquo;une comp&eacute;tition priv&eacute;e, ou simplement de rejoindre l&rsquo;un des groupes multijoueur disponibles sur la plateforme. Bien &eacute;videmment, les joueurs qui ne sont pas int&eacute;ress&eacute;s par la comp&eacute;tition pourront gagner des r&eacute;compenses en participant &agrave; des sessions d&rsquo;entrainement. Fight Out d&eacute;signe ce mod&egrave;le comme le <strong>train-to-earn<\/strong> (s&rsquo;entra&icirc;ner pour gagner).<\/p><p>Avec Fight Out, c&rsquo;est la premi&egrave;re fois qu&rsquo;un projet crypto fait le choix de connecter un &eacute;cosyst&egrave;me gaming focalis&eacute; sur le move-to-earn avec l&rsquo;univers <strong>des paris sportifs<\/strong>. Il s&rsquo;agit d&rsquo;un march&eacute; gigantesque et Fight Out s&rsquo;appr&ecirc;te &agrave; y faire son entr&eacute;e en proposant &agrave; la fois aux utilisateurs de mettre en place leurs propres combats et de tenir le r&ocirc;le du bookmaker.<\/p><p>Sur le plan pratique, la plateforme deviendra un centre de paris pour toutes sortes de matchs plus ou moins importants, comme celui de Jake Paul et Tommy Furry par exemple, sur lesquels les utilisateurs pourront miser des jetons FGHT.<\/p><h2>Derni&egrave;re chance pour profiter d&rsquo;un bonus sur l&rsquo;achat des jetons FGHT<\/h2><span class=\"replacer\"><\/span><p>Fight Out accorde un bonus sous la forme de jetons en fonction du montant de l&rsquo;investissement et de la p&eacute;riode de blocage s&eacute;lectionn&eacute;e par les investisseurs. Ce bonus peut atteindre la barre de <strong>67 % de jetons suppl&eacute;mentaires<\/strong> si les conditions ad&eacute;quates sont r&eacute;unies. Pour cela, il sera n&eacute;cessaire de r&eacute;aliser un investissement d&rsquo;un montant sup&eacute;rieur ou &eacute;gal &agrave; <strong>50 000 dollars <\/strong>et de choisir de placer les jetons en staking pendant une dur&eacute;e de <strong>36 mois.<\/strong><\/p><p>Les investisseurs pourront choisir de r&eacute;cup&eacute;rer leurs jetons imm&eacute;diatement sans la moindre p&eacute;riode de blocage, de fa&ccedil;on &agrave; recevoir vos FGHT avant les diff&eacute;rents listings sur les plateformes d&rsquo;&eacute;change. Il est aussi pr&eacute;vu de cr&eacute;er un programme de parrainage &agrave; hauteur de <strong>5 %<\/strong> en USDT.<\/p><p>Si vous d&eacute;sirez en savoir plus, n&rsquo;h&eacute;sitez pas &agrave; visiter le site officiel de <a href=\"https:\/\/www.fightout.com\/\">Fight Out<\/a> ou rejoindre le projet sur <a href=\"https:\/\/twitter.com\/FightOut_\">Twitter<\/a>, <a href=\"https:\/\/discord.io\/FightOut\">Discord<\/a> et <a href=\"https:\/\/t.me\/+3aU2ZsE30S40NDg8\">Telegram<\/a>.<\/p><p><i><sup>Avertissement : La section \u00ab\u00a0Industry Talk\u00a0\u00bb pr&eacute;sente les points de vue des acteurs du secteur de la crypto et ne fait pas partie du contenu &eacute;ditorial de Cryptonews.com.<\/sup><\/i><\/p>","protected":false},"excerpt":{"rendered":"<p>Source : Fight OutDepuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r&eacute;ussi &agrave; lever la somme record de 6 millions de dollars dans le cadre de sa pr&eacute;vente, mais cette derni&egrave;re approche rapidement de sa conclusion.Avec une date de fin pr&eacute;vue pour le 1 [&hellip;]<\/p>\n","protected":false},"author":127,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,14],"tags":[],"editors":[2550],"sponsored_companies":[],"class_list":["post-105244","post","type-post","status-publish","format-standard","hentry","category-news","category-industry-talk","editors-jurgen-hoffman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing<\/title>\n<meta name=\"description\" content=\"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing\" \/>\n<meta property=\"og:description\" content=\"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-29T19:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:08:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing\" \/>\n<meta name=\"twitter:description\" content=\"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing","description":"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/","og_locale":"fr_FR","og_type":"article","og_title":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing","og_description":"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.","og_url":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/","og_site_name":"Cryptonews France","article_published_time":"2023-03-29T19:17:00+00:00","article_modified_time":"2023-06-26T11:08:31+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing","twitter_description":"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.","twitter_image":"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/"},"author":{"name":"simalleggex","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/642c28a932dc058143fefb2c230e873a"},"headline":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing","datePublished":"2023-03-29T19:17:00+00:00","dateModified":"2023-06-26T11:08:31+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/"},"wordCount":1082,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg","articleSection":["News","Parole d'experts"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/","url":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/","name":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg","datePublished":"2023-03-29T19:17:00+00:00","dateModified":"2023-06-26T11:08:31+00:00","description":"Depuis plusieurs semaines, Fight Out continue de susciter un enthousiasme important de la part des investisseurs. Le projet a r\u00e9ussi \u00e0 lever la somme record de 6 millions de dollars dans le cadre de sa pr\u00e9vente, mais cette derni\u00e8re approche rapidement de sa conclusion.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#primaryimage","url":"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg","contentUrl":"https:\/\/cimg.co\/news\/109000\/264282\/capture-decran-2023-03-29.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/news\/fight-out-leve-6-millions-de-dollars-moins-de-72h-avant-la-fin-de-la-prevente-et-7-jours-avant-le-listing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Fight Out l\u00e8ve 6 millions de dollars : moins de 72h avant la fin de la pr\u00e9vente et 7 jours avant le listing"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=105244"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/105244\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=105244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=105244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=105244"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=105244"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=105244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}